{"id":71059,"date":"2022-10-10T10:22:50","date_gmt":"2022-10-10T08:22:50","guid":{"rendered":"https:\/\/www.area-press.eu\/comunicatistampa\/?p=71059"},"modified":"2022-10-09T22:08:52","modified_gmt":"2022-10-09T20:08:52","slug":"termoarredo-green-maarmo-al-cersaie-riciclo-di-materiali-di-scarto-e-risparmio-energetico","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicatistampa\/2022\/10\/10\/termoarredo-green-maarmo-al-cersaie-riciclo-di-materiali-di-scarto-e-risparmio-energetico\/","title":{"rendered":"TERMOARREDO GREEN, MAARMO AL CERSAIE: RICICLO DI MATERIALI DI SCARTO E RISPARMIO ENERGETICO"},"content":{"rendered":"<p><i><span style=\"font-weight: 400;\">Dal 26 al 30 settembre Maarmo sar\u00e0 presente al Cersaie. L\u2019azienda friulana \u00e8 specializzata nei termoarredi completamente riciclabili: nascono dalla polvere di marmo scartata dalla produzione e le vernici sono solo a base d\u2019acqua. Il responsabile divulgazione di Maarmo, Gianpaolo Pezzato: \u201cI nostri processi produttivi sono eseguiti a basse temperature, le quantit\u00e0 di energia usate sono minime\u201d. In fiera la presentazione in anteprima delle ultime novit\u00e0 e modelli<\/span><\/i><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Torna dal 26 al 30 settembre a Bologna il Cersaie, il Salone Internazionale della Ceramica per l&#8217;Architettura e dell&#8217;Arredobagno, uno degli appuntamenti internazionali pi\u00f9 importanti per chi si occupa di design, ceramiche e di arredo del bagno che, nell\u2019ultima edizione, ha visto la partecipazione di oltre 62.000 visitatori provenienti da tutto il mondo. In fiera sar\u00e0 presente anche Maarmo allo Stand 4 (Mall 29-30). L\u2019azienda friulana metter\u00e0 in mostra i propri prodotti (citiamo il Veneziaa, il Toscana e il Perfetto in tutte le loro varianti di colore e forme). Nell\u2019occasione del Cersaie, sar\u00e0 presentata anche una novit\u00e0 assoluta, un nuovo modello forgiato dall\u2019expertise del reparto R&amp;D.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cIl design e il rispetto per l\u2019ambiente dei nostri termoarredi sono per noi valori indissolubili volti a garantire comfort e benessere all\u2019interno non solo degli spazi abitativi ma anche di ogni ufficio e locale commerciale\u201d, spiega per l\u2019azienda il responsabile della divulgazione, Gianpaolo Pezzato. \u201cTutto ci\u00f2 grazie ad una tecnologia radiante sostenibile e brevettata che diffonde il calore per irraggiamento, col cos\u00ec detto \u201ceffetto pietra\u201d, distribuendolo in modo uniforme e dolcemente e limitando la circolazione della polvere e dei batteri\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Maarmo infatti come materia prima riutilizza e ricicla gli scarti della lavorazione del marmo, recuperati grazie ad un certosino lavoro di selezione nelle cave dell\u2019area veronese. La formula, sviluppata e perfezionata con pazienza nel reparto di Ricerca e Sviluppo di Vittorio Veneto, nel Trevigiano, ha permesso di generare una linea di termoarredi di design, che non necessita di una fase di cottura, ma di una dolce fase di stagionatura, che dura dalle quarantotto alle settantadue ore. Si passa poi alla verniciatura, realizzata esclusivamente con vernici a base d\u2019acqua, e all\u2019imballaggio, composto di materiali provenienti da cartone riciclato e certificato.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cTutti i prodotti, sia la versione elettrica che idronica, a fine vita, una volta tolti gli elementi strutturali riscaldanti, come il rame o le resistenze elettriche, possono essere rimacinati per rientrare nel ciclo produttivo\u201d, spiega ancora Pezzato. \u201cIn questo senso Maarmo agisce creando flussi circolari di materia, capaci cos\u00ec di rigenerarsi. Inoltre, essendo tutti i processi produttivi eseguiti a basse temperature, le quantit\u00e0 di energia usate sono minime. Per chiudere il ciclo green, sono state implementate due iniziative per abbattere l\u2019impatto ambientale: durante l\u2019evento fieristico non verranno utilizzati cataloghi cartacei, bens\u00ec un QR Code unico che rispetti l\u2019ambiente. Inoltre, grazie alla partnership con l\u2019amministrazione comunale di Chions, per ogni radiatore venduto piantiamo un albero all\u2019interno del parco su cui si affaccia la nostra factory. Cos\u00ec la terra pu\u00f2 respirare meglio grazie a noi\u201d.<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Un paradigma produttivo ed ecosostenibile unico nel suo genere, che adesso si sta imponendo all\u2019attenzione dei mercati. Dopo una fase iniziale di studio, lo scorso anno c\u2019\u00e8 stato\u00a0 il rafforzamento della compagine societaria, con l\u2019ingresso di nuovi imprenditori sia dell\u2019area pordenonese (Alain Bottos, Stefano Mascarin e Andrea Del Ben), che dell\u2019area trevigiana (Marco Caliandro e Gianpaolo Pezzato), per sostenere il progetto di crescita e sviluppo in Italia e nei mercati esteri. Superata la fase di start up, grazie al supporto ed al know how apportato dai nuovi partner, la produzione di Maarmo si sposta, attraverso un\u2019operazione di riqualificazione di un vecchio spazio produttivo abbandonato di quasi duemilacinquecento metri quadrati a Villotta di Chions, nel Pordenonese, circondato dai vitigni di Prosecco e gli aironi ed i cigni del Parco del Cornia.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>SCHEDE DI APPROFONDIMENTO<\/b><\/p>\n<p>&nbsp;<\/p>\n<p><b>LA STORIA DI MAARMO<\/b> <span style=\"font-weight: 400;\">Maarmo nasce nel 2017 e realizza termoarredi e scaldasalviette con processi produttivi improntati a riciclo e sostenibilit\u00e0. La sede produttiva dell\u2019impresa da settembre 2021 si trova a Villotta di Chions (PN). Una divisione ricerca e sviluppo opera a Vittorio Veneto (TV). Il 2021 ha visto il rafforzamento della compagine societaria, con l\u2019ingresso di nuovi imprenditori sia dell\u2019area pordenonese (Alain Bottos, Stefano Mascarin e Andrea Del Ben), che dell\u2019area trevigiana (Marco Caliandro e Gianpaolo Pezzato), per sostenere il progetto di crescita e sviluppo in Italia e nei mercati esteri. Ad oggi l\u2019azienda impiega 7 persone, oltre ad alcuni fornitori artigiani esterni, ed ha avviato collaborazioni con architetti e designer di tutta la Penisola. Maarmo punta sulla sostenibilit\u00e0 come valore fondante dell\u2019intera attivit\u00e0 produttiva. La materia prima utilizzata per i radiatori \u00e8 ricavata infatti dagli scarti di marmo. Tutti i termoarredi, sia la versione elettrica che idronica, a fine vita, una volta tolti gli elementi strutturali riscaldanti (ad esempio il rame o le resistenze elettriche) possono essere rimacinati per rientrare nel ciclo produttivo. In questo senso Maarmo agisce creando flussi circolari di materia, capaci di rigenerarsi. Inoltre, essendo tutti i processi produttivi eseguiti a basse temperature, le quantit\u00e0 di energia usate sono minime. Per chiudere il ciclo green, per ogni radiatore venduto l\u2019azienda pianta un albero. Per maggior informazioni <\/span><a href=\"http:\/\/www.maarmo.com\"><span style=\"font-weight: 400;\">www.maarmo.com<\/span><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><b>IL PROCESSO PRODUTTIVO DI MAARMO<\/b> <span style=\"font-weight: 400;\">Maarmo come materia prima riutilizza e ricicla gli scarti della lavorazione del marmo, recuperati grazie ad un certosino lavoro di selezione nelle cave dell\u2019area veronese. La formula ha permesso di generare una linea di termoarredi di design, che non necessita di una fase di cottura, ma di una dolce fase di stagionatura, che dura dalle quarantotto alle settantadue ore. Si passa poi alla verniciatura, realizzata esclusivamente con vernici a base d\u2019acqua. Il processo produttivo parte dalle polveri di marmo di scarto. Vengono lavorate come fossero farine di grano. All\u2019interno di grandi impastatrici, vengono miscelate ad acqua e altri additivi naturali. Ne deriva un prodotto semiliquido somigliante a yogurt. Questo viene steso manualmente su dei pannelli e all\u2019interno di esso vengono posate le canalette per il passaggio dell\u2019acqua calda (termoarredo idronico) oppure le resistenze elettriche (termoarredo elettrico). Una volta composto, il termoarredo viene fatto stagionare per 2 o 3 giorni, per una completa solidificazione del materiale. Non avviene nessuna fase di cottura dunque, ma solo una lenta stagionatura in un\u2019apposita stanza mantenuta a temperatura costante durante l\u2019inverno. D\u2019estate invece la stagionatura avviene all\u2019aria aperta, senza alcun dispendio energetico. Una volta stagionato, il termoarredo viene poi verniciato utilizzando esclusivamente vernici a base d\u2019acqua ed \u00e8 cos\u00ec pronto per la consegna al cliente. Materia prima riciclata, basso utilizzo di energia e componenti naturali: sono questi gli elementi \u201cgreen\u201d che contraddistinguono la produzione di questi termoarredi.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal 26 al 30 settembre Maarmo sar\u00e0 presente al Cersaie. L\u2019azienda friulana \u00e8 specializzata nei termoarredi completamente riciclabili: nascono dalla polvere di marmo scartata dalla produzione e le vernici sono solo a base d\u2019acqua. Il responsabile divulgazione di Maarmo, Gianpaolo Pezzato: \u201cI nostri processi produttivi sono eseguiti a basse temperature, le quantit\u00e0 di energia usate [&hellip;]<\/p>\n","protected":false},"author":7369,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-71059","post","type-post","status-publish","format-standard","hentry","category-eventi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TERMOARREDO GREEN, MAARMO AL CERSAIE: RICICLO DI MATERIALI DI SCARTO E RISPARMIO ENERGETICO<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TERMOARREDO GREEN, MAARMO AL CERSAIE: RICICLO DI MATERIALI DI SCARTO E RISPARMIO ENERGETICO\" \/>\n<meta property=\"og:description\" content=\"Dal 26 al 30 settembre Maarmo sar\u00e0 presente al Cersaie. L\u2019azienda friulana \u00e8 specializzata nei termoarredi completamente riciclabili: nascono dalla polvere di marmo scartata dalla produzione e le vernici sono solo a base d\u2019acqua. Il responsabile divulgazione di Maarmo, Gianpaolo Pezzato: \u201cI nostri processi produttivi sono eseguiti a basse temperature, le quantit\u00e0 di energia usate [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicatistampa\/2022\/10\/10\/termoarredo-green-maarmo-al-cersaie-riciclo-di-materiali-di-scarto-e-risparmio-energetico\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-10T08:22:50+00:00\" \/>\n<meta name=\"author\" content=\"paolop73\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"paolop73\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2022\\\/10\\\/10\\\/termoarredo-green-maarmo-al-cersaie-riciclo-di-materiali-di-scarto-e-risparmio-energetico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2022\\\/10\\\/10\\\/termoarredo-green-maarmo-al-cersaie-riciclo-di-materiali-di-scarto-e-risparmio-energetico\\\/\"},\"author\":{\"name\":\"paolop73\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/f326da2f25998c2315854e02da475d8a\"},\"headline\":\"TERMOARREDO GREEN, MAARMO AL CERSAIE: RICICLO DI MATERIALI DI SCARTO E RISPARMIO ENERGETICO\",\"datePublished\":\"2022-10-10T08:22:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2022\\\/10\\\/10\\\/termoarredo-green-maarmo-al-cersaie-riciclo-di-materiali-di-scarto-e-risparmio-energetico\\\/\"},\"wordCount\":1123,\"commentCount\":0,\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2022\\\/10\\\/10\\\/termoarredo-green-maarmo-al-cersaie-riciclo-di-materiali-di-scarto-e-risparmio-energetico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2022\\\/10\\\/10\\\/termoarredo-green-maarmo-al-cersaie-riciclo-di-materiali-di-scarto-e-risparmio-energetico\\\/\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2022\\\/10\\\/10\\\/termoarredo-green-maarmo-al-cersaie-riciclo-di-materiali-di-scarto-e-risparmio-energetico\\\/\",\"name\":\"TERMOARREDO GREEN, MAARMO AL CERSAIE: RICICLO DI MATERIALI DI SCARTO E RISPARMIO ENERGETICO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\"},\"datePublished\":\"2022-10-10T08:22:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/f326da2f25998c2315854e02da475d8a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2022\\\/10\\\/10\\\/termoarredo-green-maarmo-al-cersaie-riciclo-di-materiali-di-scarto-e-risparmio-energetico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2022\\\/10\\\/10\\\/termoarredo-green-maarmo-al-cersaie-riciclo-di-materiali-di-scarto-e-risparmio-energetico\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2022\\\/10\\\/10\\\/termoarredo-green-maarmo-al-cersaie-riciclo-di-materiali-di-scarto-e-risparmio-energetico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TERMOARREDO GREEN, MAARMO AL CERSAIE: RICICLO DI MATERIALI DI SCARTO E RISPARMIO ENERGETICO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\",\"name\":\"area-press.eu\",\"description\":\"comunicati stampa &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/f326da2f25998c2315854e02da475d8a\",\"name\":\"paolop73\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af7d042c9935705a0cf128368429b1b28e19db127fe3cf9ce2a446bba6fac191?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af7d042c9935705a0cf128368429b1b28e19db127fe3cf9ce2a446bba6fac191?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af7d042c9935705a0cf128368429b1b28e19db127fe3cf9ce2a446bba6fac191?s=96&d=mm&r=g\",\"caption\":\"paolop73\"},\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/author\\\/paolop73\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TERMOARREDO GREEN, MAARMO AL CERSAIE: RICICLO DI MATERIALI DI SCARTO E RISPARMIO ENERGETICO","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"TERMOARREDO GREEN, MAARMO AL CERSAIE: RICICLO DI MATERIALI DI SCARTO E RISPARMIO ENERGETICO","og_description":"Dal 26 al 30 settembre Maarmo sar\u00e0 presente al Cersaie. L\u2019azienda friulana \u00e8 specializzata nei termoarredi completamente riciclabili: nascono dalla polvere di marmo scartata dalla produzione e le vernici sono solo a base d\u2019acqua. Il responsabile divulgazione di Maarmo, Gianpaolo Pezzato: \u201cI nostri processi produttivi sono eseguiti a basse temperature, le quantit\u00e0 di energia usate [&hellip;]","og_url":"https:\/\/www.area-press.eu\/comunicatistampa\/2022\/10\/10\/termoarredo-green-maarmo-al-cersaie-riciclo-di-materiali-di-scarto-e-risparmio-energetico\/","og_site_name":"area-press.eu","article_published_time":"2022-10-10T08:22:50+00:00","author":"paolop73","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"paolop73","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2022\/10\/10\/termoarredo-green-maarmo-al-cersaie-riciclo-di-materiali-di-scarto-e-risparmio-energetico\/#article","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2022\/10\/10\/termoarredo-green-maarmo-al-cersaie-riciclo-di-materiali-di-scarto-e-risparmio-energetico\/"},"author":{"name":"paolop73","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/f326da2f25998c2315854e02da475d8a"},"headline":"TERMOARREDO GREEN, MAARMO AL CERSAIE: RICICLO DI MATERIALI DI SCARTO E RISPARMIO ENERGETICO","datePublished":"2022-10-10T08:22:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2022\/10\/10\/termoarredo-green-maarmo-al-cersaie-riciclo-di-materiali-di-scarto-e-risparmio-energetico\/"},"wordCount":1123,"commentCount":0,"articleSection":["Eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2022\/10\/10\/termoarredo-green-maarmo-al-cersaie-riciclo-di-materiali-di-scarto-e-risparmio-energetico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2022\/10\/10\/termoarredo-green-maarmo-al-cersaie-riciclo-di-materiali-di-scarto-e-risparmio-energetico\/","url":"https:\/\/www.area-press.eu\/comunicatistampa\/2022\/10\/10\/termoarredo-green-maarmo-al-cersaie-riciclo-di-materiali-di-scarto-e-risparmio-energetico\/","name":"TERMOARREDO GREEN, MAARMO AL CERSAIE: RICICLO DI MATERIALI DI SCARTO E RISPARMIO ENERGETICO","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website"},"datePublished":"2022-10-10T08:22:50+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/f326da2f25998c2315854e02da475d8a"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2022\/10\/10\/termoarredo-green-maarmo-al-cersaie-riciclo-di-materiali-di-scarto-e-risparmio-energetico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2022\/10\/10\/termoarredo-green-maarmo-al-cersaie-riciclo-di-materiali-di-scarto-e-risparmio-energetico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2022\/10\/10\/termoarredo-green-maarmo-al-cersaie-riciclo-di-materiali-di-scarto-e-risparmio-energetico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicatistampa\/"},{"@type":"ListItem","position":2,"name":"TERMOARREDO GREEN, MAARMO AL CERSAIE: RICICLO DI MATERIALI DI SCARTO E RISPARMIO ENERGETICO"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website","url":"https:\/\/www.area-press.eu\/comunicatistampa\/","name":"area-press.eu","description":"comunicati stampa &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicatistampa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/f326da2f25998c2315854e02da475d8a","name":"paolop73","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/af7d042c9935705a0cf128368429b1b28e19db127fe3cf9ce2a446bba6fac191?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af7d042c9935705a0cf128368429b1b28e19db127fe3cf9ce2a446bba6fac191?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af7d042c9935705a0cf128368429b1b28e19db127fe3cf9ce2a446bba6fac191?s=96&d=mm&r=g","caption":"paolop73"},"url":"https:\/\/www.area-press.eu\/comunicatistampa\/author\/paolop73\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/71059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/users\/7369"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/comments?post=71059"}],"version-history":[{"count":2,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/71059\/revisions"}],"predecessor-version":[{"id":71631,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/71059\/revisions\/71631"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/media?parent=71059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/categories?post=71059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/tags?post=71059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}