{"id":65158,"date":"2022-01-27T22:52:17","date_gmt":"2022-01-27T21:52:17","guid":{"rendered":"https:\/\/www.area-press.eu\/comunicatistampa\/?p=65158"},"modified":"2022-01-27T22:52:17","modified_gmt":"2022-01-27T21:52:17","slug":"marketing-etico-pubblicato-il-bilancio-sociale-del-manifesto-del-marketing-etico-2011-2021","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicatistampa\/2022\/01\/27\/marketing-etico-pubblicato-il-bilancio-sociale-del-manifesto-del-marketing-etico-2011-2021\/","title":{"rendered":"Marketing Etico: Pubblicato il bilancio sociale del Manifesto del Marketing Etico 2011 &#8211; 2021"},"content":{"rendered":"<p><em>Il Manifesto del Marketing Etico pubblica il bilancio sociale relativo al primo decennio di vita del documento redatto da Emmanuele Macaluso nel 2011, attualmente allo studio di universit\u00e0 e business school in Italia e all\u2019estero<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Lo scorso 11 novembre, il <strong>Manifesto del Marketing Etico<\/strong> ha compiuto 10 anni. Il Manifesto del Marketing Etico \u00e8 un documento formale composto da 11 articoli, <strong>scritto nel 2011<\/strong> dall\u2019<strong>esperto<\/strong> e <strong>docente<\/strong> di marketing <strong>Emmanuele Macaluso<\/strong>, nel quale sono indicate linee guida di comportamento e tecniche per progettare e attuare strategie di <strong>marketing applicando principi etici<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>Gli undici punti sono stati sviluppati osservando comportamenti e fattori tecnici in ambito reale e riscontrabile.\u00a0 Secondo l\u2019autore, l\u2019osservanza di questi punti portano ad un miglioramento immediato della qualit\u00e0 del rapporto tra coloro che immettono un prodotto\/servizio sul mercato e il mercato stesso. Con beneficio per entrambe le parti coinvolte nel processo commerciale\u00a0e\/o comunicativo.<\/p>\n<p>&nbsp;<\/p>\n<p>Nei 10 anni di vita, il Manifesto si \u00e8 evoluto, diventando anche una vera e propria <strong>campagna di sensibilizzazione<\/strong>,<strong> informazione e formazione<\/strong>. Con decine di incontri dal vivo, attivit\u00e0 media in radio e TV e centinaia di articoli di stampa in Italia e all\u2019estero, il Manifesto ha catturato l\u2019interesse dei consumatori, degli addetti ai lavori e di <strong>universit\u00e0<\/strong> e <strong>business school<\/strong> che lo hanno inserito nei programmi didattici.<\/p>\n<p>&nbsp;<\/p>\n<p>Un documento che con i suoi 10 anni di vita ha tracciato un solco sull\u2019argomento in Italia e in Europa, molto prima che la<strong> CSR<\/strong> e il <strong><em>green<\/em><\/strong> diventassero la \u201ctendenza\u201d odierna.<\/p>\n<p>&nbsp;<\/p>\n<p>Il \u201c<strong>Bilancio Sociale del Manifesto del Marketing Etico &#8211; decennio 2011 &#8211; 2021<\/strong>\u201d \u00e8 stato redatto dallo stesso Emmanuele Macaluso, sotto la supervisione del <strong>Comitato Etico Scientifico<\/strong> (<strong>Co.E.S.<\/strong>) del Manifesto.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c8 possibile scaricare grauitamente il bilancio sociale del Manifesto del Marketing Etico nell\u2019apposita sezione del sito ufficiale all\u2019indirizzo <a href=\"http:\/\/www.manifestodelmarketingetico.org\/bilanci%20sociali.html\">http:\/\/www.manifestodelmarketingetico.org\/bilanci%20sociali.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Manifesto del Marketing Etico pubblica il bilancio sociale relativo al primo decennio di vita del documento redatto da Emmanuele Macaluso nel 2011, attualmente allo studio di universit\u00e0 e business school in Italia e all\u2019estero &nbsp; Lo scorso 11 novembre, il Manifesto del Marketing Etico ha compiuto 10 anni. Il Manifesto del Marketing Etico \u00e8 [&hellip;]<\/p>\n","protected":false},"author":4938,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[18,3,4,19188],"tags":[3496,10621,10620,31663,3702,31664,15974,31281,31666,8338,31665,8339,3701,16707,11432,894],"class_list":["post-65158","post","type-post","status-publish","format-standard","hentry","category-altri-vari","category-arte-e-cultura","category-attualita-e-societa","category-volontariato-e-societa","tag-sociale","tag-bilancio","tag-bilancio-sociale","tag-comitato","tag-comunicazione","tag-docente","tag-emmanuele-macaluso","tag-ethical-marketing-manifesto","tag-ethics","tag-etico","tag-etique-du-marketing","tag-manifesto-del-marketing-etico","tag-marketing","tag-scientifico","tag-sostenibilita","tag-universita"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marketing Etico: Pubblicato il bilancio sociale del Manifesto del Marketing Etico 2011 - 2021 - area-press.eu<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marketing Etico: Pubblicato il bilancio sociale del Manifesto del Marketing Etico 2011 - 2021 - area-press.eu\" \/>\n<meta property=\"og:description\" content=\"Il Manifesto del Marketing Etico pubblica il bilancio sociale relativo al primo decennio di vita del documento redatto da Emmanuele Macaluso nel 2011, attualmente allo studio di universit\u00e0 e business school in Italia e all\u2019estero &nbsp; Lo scorso 11 novembre, il Manifesto del Marketing Etico ha compiuto 10 anni. Il Manifesto del Marketing Etico \u00e8 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicatistampa\/2022\/01\/27\/marketing-etico-pubblicato-il-bilancio-sociale-del-manifesto-del-marketing-etico-2011-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-27T21:52:17+00:00\" \/>\n<meta name=\"author\" content=\"cosmosmedia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cosmosmedia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2022\\\/01\\\/27\\\/marketing-etico-pubblicato-il-bilancio-sociale-del-manifesto-del-marketing-etico-2011-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2022\\\/01\\\/27\\\/marketing-etico-pubblicato-il-bilancio-sociale-del-manifesto-del-marketing-etico-2011-2021\\\/\"},\"author\":{\"name\":\"cosmosmedia\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/d5de351abeef1df46ae89e3c82eb6ccf\"},\"headline\":\"Marketing Etico: Pubblicato il bilancio sociale del Manifesto del Marketing Etico 2011 &#8211; 2021\",\"datePublished\":\"2022-01-27T21:52:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2022\\\/01\\\/27\\\/marketing-etico-pubblicato-il-bilancio-sociale-del-manifesto-del-marketing-etico-2011-2021\\\/\"},\"wordCount\":319,\"commentCount\":0,\"keywords\":[\"#sociale\",\"bilancio\",\"bilancio sociale\",\"comitato\",\"Comunicazione\",\"docente\",\"emmanuele macaluso\",\"Ethical Marketing Manifesto\",\"ethics\",\"etico\",\"etique du marketing\",\"manifesto del marketing etico\",\"Marketing\",\"scientifico\",\"sostenibilit\u00e0\",\"universit\u00e0\"],\"articleSection\":[\"Altri\\\/Vari\",\"Arte e Cultura\",\"Attualit\u00e0 e Societ\u00e0\",\"Volontariato e societ\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2022\\\/01\\\/27\\\/marketing-etico-pubblicato-il-bilancio-sociale-del-manifesto-del-marketing-etico-2011-2021\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2022\\\/01\\\/27\\\/marketing-etico-pubblicato-il-bilancio-sociale-del-manifesto-del-marketing-etico-2011-2021\\\/\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2022\\\/01\\\/27\\\/marketing-etico-pubblicato-il-bilancio-sociale-del-manifesto-del-marketing-etico-2011-2021\\\/\",\"name\":\"Marketing Etico: Pubblicato il bilancio sociale del Manifesto del Marketing Etico 2011 - 2021 - area-press.eu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\"},\"datePublished\":\"2022-01-27T21:52:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/d5de351abeef1df46ae89e3c82eb6ccf\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2022\\\/01\\\/27\\\/marketing-etico-pubblicato-il-bilancio-sociale-del-manifesto-del-marketing-etico-2011-2021\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2022\\\/01\\\/27\\\/marketing-etico-pubblicato-il-bilancio-sociale-del-manifesto-del-marketing-etico-2011-2021\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2022\\\/01\\\/27\\\/marketing-etico-pubblicato-il-bilancio-sociale-del-manifesto-del-marketing-etico-2011-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marketing Etico: Pubblicato il bilancio sociale del Manifesto del Marketing Etico 2011 &#8211; 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\",\"name\":\"area-press.eu\",\"description\":\"comunicati stampa &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/d5de351abeef1df46ae89e3c82eb6ccf\",\"name\":\"cosmosmedia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dab897c95700f34c5341a7f7dafb77fb04c9ebdda4b4b86decbbe6731e56a3cc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dab897c95700f34c5341a7f7dafb77fb04c9ebdda4b4b86decbbe6731e56a3cc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dab897c95700f34c5341a7f7dafb77fb04c9ebdda4b4b86decbbe6731e56a3cc?s=96&d=mm&r=g\",\"caption\":\"cosmosmedia\"},\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/author\\\/cosmosmedia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marketing Etico: Pubblicato il bilancio sociale del Manifesto del Marketing Etico 2011 - 2021 - area-press.eu","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Marketing Etico: Pubblicato il bilancio sociale del Manifesto del Marketing Etico 2011 - 2021 - area-press.eu","og_description":"Il Manifesto del Marketing Etico pubblica il bilancio sociale relativo al primo decennio di vita del documento redatto da Emmanuele Macaluso nel 2011, attualmente allo studio di universit\u00e0 e business school in Italia e all\u2019estero &nbsp; Lo scorso 11 novembre, il Manifesto del Marketing Etico ha compiuto 10 anni. Il Manifesto del Marketing Etico \u00e8 [&hellip;]","og_url":"https:\/\/www.area-press.eu\/comunicatistampa\/2022\/01\/27\/marketing-etico-pubblicato-il-bilancio-sociale-del-manifesto-del-marketing-etico-2011-2021\/","og_site_name":"area-press.eu","article_published_time":"2022-01-27T21:52:17+00:00","author":"cosmosmedia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"cosmosmedia","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2022\/01\/27\/marketing-etico-pubblicato-il-bilancio-sociale-del-manifesto-del-marketing-etico-2011-2021\/#article","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2022\/01\/27\/marketing-etico-pubblicato-il-bilancio-sociale-del-manifesto-del-marketing-etico-2011-2021\/"},"author":{"name":"cosmosmedia","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/d5de351abeef1df46ae89e3c82eb6ccf"},"headline":"Marketing Etico: Pubblicato il bilancio sociale del Manifesto del Marketing Etico 2011 &#8211; 2021","datePublished":"2022-01-27T21:52:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2022\/01\/27\/marketing-etico-pubblicato-il-bilancio-sociale-del-manifesto-del-marketing-etico-2011-2021\/"},"wordCount":319,"commentCount":0,"keywords":["#sociale","bilancio","bilancio sociale","comitato","Comunicazione","docente","emmanuele macaluso","Ethical Marketing Manifesto","ethics","etico","etique du marketing","manifesto del marketing etico","Marketing","scientifico","sostenibilit\u00e0","universit\u00e0"],"articleSection":["Altri\/Vari","Arte e Cultura","Attualit\u00e0 e Societ\u00e0","Volontariato e societ\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2022\/01\/27\/marketing-etico-pubblicato-il-bilancio-sociale-del-manifesto-del-marketing-etico-2011-2021\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2022\/01\/27\/marketing-etico-pubblicato-il-bilancio-sociale-del-manifesto-del-marketing-etico-2011-2021\/","url":"https:\/\/www.area-press.eu\/comunicatistampa\/2022\/01\/27\/marketing-etico-pubblicato-il-bilancio-sociale-del-manifesto-del-marketing-etico-2011-2021\/","name":"Marketing Etico: Pubblicato il bilancio sociale del Manifesto del Marketing Etico 2011 - 2021 - area-press.eu","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website"},"datePublished":"2022-01-27T21:52:17+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/d5de351abeef1df46ae89e3c82eb6ccf"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2022\/01\/27\/marketing-etico-pubblicato-il-bilancio-sociale-del-manifesto-del-marketing-etico-2011-2021\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2022\/01\/27\/marketing-etico-pubblicato-il-bilancio-sociale-del-manifesto-del-marketing-etico-2011-2021\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2022\/01\/27\/marketing-etico-pubblicato-il-bilancio-sociale-del-manifesto-del-marketing-etico-2011-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicatistampa\/"},{"@type":"ListItem","position":2,"name":"Marketing Etico: Pubblicato il bilancio sociale del Manifesto del Marketing Etico 2011 &#8211; 2021"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website","url":"https:\/\/www.area-press.eu\/comunicatistampa\/","name":"area-press.eu","description":"comunicati stampa &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicatistampa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/d5de351abeef1df46ae89e3c82eb6ccf","name":"cosmosmedia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/dab897c95700f34c5341a7f7dafb77fb04c9ebdda4b4b86decbbe6731e56a3cc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dab897c95700f34c5341a7f7dafb77fb04c9ebdda4b4b86decbbe6731e56a3cc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dab897c95700f34c5341a7f7dafb77fb04c9ebdda4b4b86decbbe6731e56a3cc?s=96&d=mm&r=g","caption":"cosmosmedia"},"url":"https:\/\/www.area-press.eu\/comunicatistampa\/author\/cosmosmedia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/65158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/users\/4938"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/comments?post=65158"}],"version-history":[{"count":1,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/65158\/revisions"}],"predecessor-version":[{"id":65159,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/65158\/revisions\/65159"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/media?parent=65158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/categories?post=65158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/tags?post=65158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}