{"id":56093,"date":"2021-01-22T03:01:16","date_gmt":"2021-01-22T02:01:16","guid":{"rendered":"https:\/\/www.area-press.eu\/comunicatistampa\/?p=56093"},"modified":"2021-01-22T03:01:16","modified_gmt":"2021-01-22T02:01:16","slug":"le-conserve-della-nonna-amplia-la-linea-dei-pesti","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicatistampa\/2021\/01\/22\/le-conserve-della-nonna-amplia-la-linea-dei-pesti\/","title":{"rendered":"Le Conserve della Nonna amplia la linea dei pesti"},"content":{"rendered":"<p align=\"JUSTIFY\"><span style=\"font-family: Verdana\"><span style=\"font-size: medium\"><i>Il brand modenese presenta nuove e sfiziose varianti di pesto, realizzati con materie prime rigorosamente italiane e altamente versatili<\/i><\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Verdana\"><span style=\"font-size: small\"><b>Le Conserve della Nonna e il mondo dei pesti<\/b><\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\">: una storia di passione, ricerca e intuizione che continua a crescere abbracciando le richieste di un segmento in forte espansione nonostante le contrazioni che il mercato sughi ha registrato su ampia scala nell&#8217;ultimo anno a causa dell&#8217;emergenza Covid. <\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\"><b>Lo storico brand<\/b><\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\"> nato nel 1973 a Ravarino (MO) e propriet\u00e0 del Gruppo FINI S.p.A. <\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\"><b>ha ampliato<\/b><\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\"> ulteriormente, con buoni riscontri sia in Italia che all&#8217;estero,<\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\"><b> la propria linea di pesti introducendo tre nuove referenze<\/b><\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\"> che in un&#8217;ottica di riscoperta mescolano sapientemente ingredienti del passato e della tradizione.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\"><span style=\"font-family: Verdana\"><span style=\"font-size: small\">Dal pi\u00f9 semplice al pi\u00f9 elaborato, <\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Verdana\"><span style=\"font-size: small\"><b>l&#8217;ampia gamma di pesti \u00e8 pensata per soddisfare ogni tipo di palato<\/b><\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Verdana\"><span style=\"font-size: small\"> attraverso ricette uniche, distintive e caratterizzate da un alto grado di versatilit\u00e0. I pesti de Le Conserve della Nonna si rivelano<\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Verdana\"><span style=\"font-size: small\"><b> ideali per differenti occasioni ed espressioni culinarie<\/b><\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Verdana\"><span style=\"font-size: small\">, per condire ed esaltare ogni tipologia di pasta, accompagnare secondi di carne e di pesce, e infine arricchire sfiziose tartine. <\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Verdana\"><span style=\"font-size: small\"><b>Un&#8217;ottima scelta per chi cerca <\/b><\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Verdana\"><span style=\"font-size: small\"><b>prodotti gustosi ma fatti con cura<\/b><\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Verdana\"><span style=\"font-size: small\">, capaci di rievocare i profumi, i sapori e le abitudini della cucina delle nonne, <\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Verdana\"><span style=\"font-size: small\"><b>senza glutine e senza conservanti<\/b><\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Verdana\"><span style=\"font-size: small\">. <\/span><\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Verdana\"><span style=\"font-size: small\">Tra le novit\u00e0 pi\u00f9 originali che il marchio modenese propone troviamo il pesto <\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\"><b>Cavolo Riccio e Mandorle<\/b><\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\">, dal sapore deciso e definito, realizzato con cavolo riccio italiano<\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\">;<\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\"><b> il <\/b><\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\"><b>Pesto all&#8217;Arrabbiata, <\/b><\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\">realizzato con pomodori essiccati al sole, una scelta perfetta per caricare di giusta piccantezza la pasta grazie alla presenza del peperoncino calabrese; il <\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\"><b>pesto di<\/b><\/span><\/span> <span style=\"font-family: Verdana\"><span style=\"font-size: small\"><b>rucola italiana e Grana Padano DOP<\/b><\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\">, dal sapore tradizionale, antico e intenso, ideale per la pasta ma anche per carne, pesce e frittate.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><a name=\"_GoBack1\"><\/a><span style=\"font-family: Verdana\"><span style=\"font-size: small\"><b>Le nuove referenze arricchiscono una linea variegata<\/b><\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\">, completa e apprezzata dal pubblico. <\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\"><b>Tra le altre ricette<\/b><\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\"> che compongono la gamma ricordiamo<\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\"> il<\/span><\/span><b> <\/b><span style=\"font-family: Verdana\"><span style=\"font-size: small\"><b>Pesto Broccoli e Cime di Rapa: <\/b><\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\">con verdure 100% italiane e un pizzico di peperoncino \u00e8 la soluzione ideale e veloce per condire e mettere in tavola un classico immortale come le orecchiette o realizzare fantasiose bruschette; il <\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\"><b>Pesto alla Genovese<\/b><\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\">, che racchiude tutto il profumo e il sapore del basilico italiano e si sposa perfettamente con le trofie e molti altri primi piatti italiani; un <\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\"><b>Pesto Rosso,<\/b><\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\"> preparato con gustosi pomodori essiccati, pinoli, basilico e ricotta. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Verdana\"><span style=\"font-size: small\">La linea inoltre propone il <\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\"><b>Trito Aglio, Olio e Peperoncino<\/b><\/span><\/span><span style=\"font-family: Verdana\"><span style=\"font-size: small\">, ricetta di grande semplicit\u00e0 ma impreziosita, da ingredienti selezionati come il peperoncino calabrese e l\u2019aglio di Voghiera DOP lavorati dal fresco, un salvacena per eccellenza da tenere sempre in dispensa. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Verdana\"><span style=\"font-size: small\">https:\/\/nonsolobuono.it\/conserve-della-nonna\/<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il brand modenese presenta nuove e sfiziose varianti di pesto, realizzati con materie prime rigorosamente italiane e altamente versatili Le Conserve della Nonna e il mondo dei pesti: una storia di passione, ricerca e intuizione che continua a crescere abbracciando le richieste di un segmento in forte espansione nonostante le contrazioni che il mercato sughi [&hellip;]<\/p>\n","protected":false},"author":3854,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[29],"tags":[12351,18388,28869,28868,772,2956,28867],"class_list":["post-56093","post","type-post","status-publish","format-standard","hentry","category-comunicati","tag-gruppo-fini","tag-le-conserve-della-nonna","tag-le-conserve-della-nonna-pesti","tag-le-conserve-della-nonna-sughi","tag-made-in-italy","tag-modena","tag-nuova-linea-pesti"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Conserve della Nonna amplia la linea dei pesti - area-press.eu<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Conserve della Nonna amplia la linea dei pesti - area-press.eu\" \/>\n<meta property=\"og:description\" content=\"Il brand modenese presenta nuove e sfiziose varianti di pesto, realizzati con materie prime rigorosamente italiane e altamente versatili Le Conserve della Nonna e il mondo dei pesti: una storia di passione, ricerca e intuizione che continua a crescere abbracciando le richieste di un segmento in forte espansione nonostante le contrazioni che il mercato sughi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicatistampa\/2021\/01\/22\/le-conserve-della-nonna-amplia-la-linea-dei-pesti\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-22T02:01:16+00:00\" \/>\n<meta name=\"author\" content=\"Borderline Agency\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Borderline Agency\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2021\\\/01\\\/22\\\/le-conserve-della-nonna-amplia-la-linea-dei-pesti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2021\\\/01\\\/22\\\/le-conserve-della-nonna-amplia-la-linea-dei-pesti\\\/\"},\"author\":{\"name\":\"Borderline Agency\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/5ad0cd4e4c489f331e91c7b230317da1\"},\"headline\":\"Le Conserve della Nonna amplia la linea dei pesti\",\"datePublished\":\"2021-01-22T02:01:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2021\\\/01\\\/22\\\/le-conserve-della-nonna-amplia-la-linea-dei-pesti\\\/\"},\"wordCount\":439,\"commentCount\":0,\"keywords\":[\"Gruppo Fini\",\"Le Conserve della Nonna\",\"Le Conserve della Nonna pesti\",\"Le Conserve della Nonna sughi\",\"made in Italy\",\"modena\",\"Nuova linea pesti\"],\"articleSection\":[\"Comunicati\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2021\\\/01\\\/22\\\/le-conserve-della-nonna-amplia-la-linea-dei-pesti\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2021\\\/01\\\/22\\\/le-conserve-della-nonna-amplia-la-linea-dei-pesti\\\/\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2021\\\/01\\\/22\\\/le-conserve-della-nonna-amplia-la-linea-dei-pesti\\\/\",\"name\":\"Le Conserve della Nonna amplia la linea dei pesti - area-press.eu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\"},\"datePublished\":\"2021-01-22T02:01:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/5ad0cd4e4c489f331e91c7b230317da1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2021\\\/01\\\/22\\\/le-conserve-della-nonna-amplia-la-linea-dei-pesti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2021\\\/01\\\/22\\\/le-conserve-della-nonna-amplia-la-linea-dei-pesti\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2021\\\/01\\\/22\\\/le-conserve-della-nonna-amplia-la-linea-dei-pesti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Conserve della Nonna amplia la linea dei pesti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\",\"name\":\"area-press.eu\",\"description\":\"comunicati stampa &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/5ad0cd4e4c489f331e91c7b230317da1\",\"name\":\"Borderline Agency\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/741fa053101610cb0be7dc835c116926549ae4ae2142ff35eac04d78fda61461?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/741fa053101610cb0be7dc835c116926549ae4ae2142ff35eac04d78fda61461?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/741fa053101610cb0be7dc835c116926549ae4ae2142ff35eac04d78fda61461?s=96&d=mm&r=g\",\"caption\":\"Borderline Agency\"},\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/author\\\/borderline-agency\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Conserve della Nonna amplia la linea dei pesti - area-press.eu","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Le Conserve della Nonna amplia la linea dei pesti - area-press.eu","og_description":"Il brand modenese presenta nuove e sfiziose varianti di pesto, realizzati con materie prime rigorosamente italiane e altamente versatili Le Conserve della Nonna e il mondo dei pesti: una storia di passione, ricerca e intuizione che continua a crescere abbracciando le richieste di un segmento in forte espansione nonostante le contrazioni che il mercato sughi [&hellip;]","og_url":"https:\/\/www.area-press.eu\/comunicatistampa\/2021\/01\/22\/le-conserve-della-nonna-amplia-la-linea-dei-pesti\/","og_site_name":"area-press.eu","article_published_time":"2021-01-22T02:01:16+00:00","author":"Borderline Agency","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Borderline Agency","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2021\/01\/22\/le-conserve-della-nonna-amplia-la-linea-dei-pesti\/#article","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2021\/01\/22\/le-conserve-della-nonna-amplia-la-linea-dei-pesti\/"},"author":{"name":"Borderline Agency","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/5ad0cd4e4c489f331e91c7b230317da1"},"headline":"Le Conserve della Nonna amplia la linea dei pesti","datePublished":"2021-01-22T02:01:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2021\/01\/22\/le-conserve-della-nonna-amplia-la-linea-dei-pesti\/"},"wordCount":439,"commentCount":0,"keywords":["Gruppo Fini","Le Conserve della Nonna","Le Conserve della Nonna pesti","Le Conserve della Nonna sughi","made in Italy","modena","Nuova linea pesti"],"articleSection":["Comunicati"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2021\/01\/22\/le-conserve-della-nonna-amplia-la-linea-dei-pesti\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2021\/01\/22\/le-conserve-della-nonna-amplia-la-linea-dei-pesti\/","url":"https:\/\/www.area-press.eu\/comunicatistampa\/2021\/01\/22\/le-conserve-della-nonna-amplia-la-linea-dei-pesti\/","name":"Le Conserve della Nonna amplia la linea dei pesti - area-press.eu","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website"},"datePublished":"2021-01-22T02:01:16+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/5ad0cd4e4c489f331e91c7b230317da1"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2021\/01\/22\/le-conserve-della-nonna-amplia-la-linea-dei-pesti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2021\/01\/22\/le-conserve-della-nonna-amplia-la-linea-dei-pesti\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2021\/01\/22\/le-conserve-della-nonna-amplia-la-linea-dei-pesti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicatistampa\/"},{"@type":"ListItem","position":2,"name":"Le Conserve della Nonna amplia la linea dei pesti"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website","url":"https:\/\/www.area-press.eu\/comunicatistampa\/","name":"area-press.eu","description":"comunicati stampa &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicatistampa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/5ad0cd4e4c489f331e91c7b230317da1","name":"Borderline Agency","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/741fa053101610cb0be7dc835c116926549ae4ae2142ff35eac04d78fda61461?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/741fa053101610cb0be7dc835c116926549ae4ae2142ff35eac04d78fda61461?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/741fa053101610cb0be7dc835c116926549ae4ae2142ff35eac04d78fda61461?s=96&d=mm&r=g","caption":"Borderline Agency"},"url":"https:\/\/www.area-press.eu\/comunicatistampa\/author\/borderline-agency\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/56093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/users\/3854"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/comments?post=56093"}],"version-history":[{"count":1,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/56093\/revisions"}],"predecessor-version":[{"id":56094,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/56093\/revisions\/56094"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/media?parent=56093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/categories?post=56093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/tags?post=56093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}