{"id":47914,"date":"2020-02-26T18:39:06","date_gmt":"2020-02-26T17:39:06","guid":{"rendered":"https:\/\/www.area-press.eu\/comunicatistampa\/?p=47914"},"modified":"2020-02-27T00:34:40","modified_gmt":"2020-02-26T23:34:40","slug":"parassiti-intestinali-dei-cani-cosa-sono-e-come-trattarli","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicatistampa\/2020\/02\/26\/parassiti-intestinali-dei-cani-cosa-sono-e-come-trattarli\/","title":{"rendered":"Parassiti intestinali dei cani, cosa sono e come trattarli"},"content":{"rendered":"<p><span style=\"font-family: verdana, geneva, sans-serif;\">I parassiti intestinali sono vermi di piccole dimensioni che si insediano nell&#8217;intestino del cane, dove si nutrono del sangue e del cibo ingerito. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif;\">In alcuni casi le loro larve possono migrare, infestando i polmoni e altri organi. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif;\">Una volta introdotti, questi piccoli organismi si riproducono; le uova e le larve vengono espulse con le feci, riversandosi nell&#8217;ambiente esterno e infettando altri ospiti. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif;\">I cani cuccioli sono i soggetti pi\u00f9 vulnerabili: i parassiti posso infestarli addirittura prima della nascita, raggiungendoli attraverso la placenta. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif;\">Tuttavia, a causa dell&#8217;alto tasso di contagiosit\u00e0 e dei numerosi veicoli di trasmissione, il cane pu\u00f2 essere colpito anche in et\u00e0 adulta. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif;\">Tre sono, in particolare, le tipologie di parassiti intestinali che interessano il cane: i nematodi (ascaridi, anchilostomi, tricuridi), i cestodi (tenie) e i protozoi (coccidi, giardia, toxoplasma gondii). <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif;\">Alcuni di questi organismi possono essere individuati ad occhio nudo: \u00e8 il caso degli ascaridi, vermi lunghi circa 8-10 cm simili a spaghetti cotti, la cui presenza \u00e8 ben visibile nelle feci del cane. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif;\">Altri, invece, come i tricuridi e i protozoi, possono essere rilevati solo attraverso esami accurati. Comune a tutte le parassitosi \u00e8 la sintomatologia: il cane infestato dimagrisce e soffre di vari disturbi gastrici (diarrea, vomito, inappetenza, spasmi e gonfiore addominale). <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif;\">In alcune circostanze possono sopraggiungere anche problemi respiratori. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif;\">Non sottovalutare mai questi segnali: se trascurata, una parassitosi pu\u00f2 degenerare in complicanze molto gravi e di difficile gestione. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif;\">Nei cuccioli, soggetti ancora molto vulnerabili, i parassiti possono causare anche il decesso: per questo, la sverminazione viene effettuata sempre a poche settimane dalla nascita. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif;\">Se quindi sospetti che il tuo cane sia stato infestato, rivolgiti immediatamente al veterinario. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif;\">Per prevenire infestazioni o reinfestazioni, cura in modo scrupoloso l&#8217;igiene domestica e tieni sotto controllo il tuo cane durante le passeggiate. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif;\">Impediscigli, in particolare, di leccare il terreno, dove potrebbero essere presenti residui fecali; di ingerire resti di cibo e di bere dalle pozzanghere. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif;\">Attenzione agli ospiti intermedi: il tuo cane, infatti, pu\u00f2 essere infettato anche tramite contatto con flebotomi e roditori. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif;\">Usa regolarmente un antiparassitario esterno contro pulci e zecche e controlla che il tuo amico non venga a contatto con topi e altri animaletti.<\/span><\/p>\n<h2><a href=\"https:\/\/www.ambvetaleandri.eu\/index.php\/blog\"><span style=\"font-family: verdana, geneva, sans-serif;\">Per saperne di pi\u00f9 &gt;&gt;<\/span><\/a><\/h2>\n<p><strong>Powered by free press releases service area-press.eu<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I parassiti intestinali sono vermi di piccole dimensioni che si insediano nell&#8217;intestino del cane, dove si nutrono del sangue e del cibo ingerito. In alcuni casi le loro larve possono migrare, infestando i polmoni e altri organi. Una volta introdotti, questi piccoli organismi si riproducono; le uova e le larve vengono espulse con le feci, [&hellip;]<\/p>\n","protected":false},"author":2944,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[29],"tags":[26441],"class_list":["post-47914","post","type-post","status-publish","format-standard","hentry","category-comunicati","tag-parassiti-del-cane"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Parassiti intestinali dei cani, cosa sono e come trattarli - area-press.eu<\/title>\n<meta name=\"description\" content=\"I parassiti intestinali sono vermi di piccole dimensioni che si insediano nell&#039;intestino del cane, dove si nutrono del sangue e del cibo ingerito.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parassiti intestinali dei cani, cosa sono e come trattarli\" \/>\n<meta property=\"og:description\" content=\"I parassiti intestinali sono vermi di piccole dimensioni che si insediano nell&#039;intestino del cane, dove si nutrono del sangue e del cibo ingerito.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicatistampa\/2020\/02\/26\/parassiti-intestinali-dei-cani-cosa-sono-e-come-trattarli\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-26T17:39:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-26T23:34:40+00:00\" \/>\n<meta name=\"author\" content=\"Veterinario Aleandri\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Parassiti intestinali dei cani, cosa sono e come trattarli\" \/>\n<meta name=\"twitter:description\" content=\"I parassiti intestinali sono vermi di piccole dimensioni che si insediano nell&#039;intestino del cane, dove si nutrono del sangue e del cibo ingerito.\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Veterinario Aleandri\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2020\\\/02\\\/26\\\/parassiti-intestinali-dei-cani-cosa-sono-e-come-trattarli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2020\\\/02\\\/26\\\/parassiti-intestinali-dei-cani-cosa-sono-e-come-trattarli\\\/\"},\"author\":{\"name\":\"Veterinario Aleandri\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/3b4a8cf33790667979d8603086264ac8\"},\"headline\":\"Parassiti intestinali dei cani, cosa sono e come trattarli\",\"datePublished\":\"2020-02-26T17:39:06+00:00\",\"dateModified\":\"2020-02-26T23:34:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2020\\\/02\\\/26\\\/parassiti-intestinali-dei-cani-cosa-sono-e-come-trattarli\\\/\"},\"wordCount\":378,\"commentCount\":0,\"keywords\":[\"parassiti del cane\"],\"articleSection\":[\"Comunicati\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2020\\\/02\\\/26\\\/parassiti-intestinali-dei-cani-cosa-sono-e-come-trattarli\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2020\\\/02\\\/26\\\/parassiti-intestinali-dei-cani-cosa-sono-e-come-trattarli\\\/\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2020\\\/02\\\/26\\\/parassiti-intestinali-dei-cani-cosa-sono-e-come-trattarli\\\/\",\"name\":\"Parassiti intestinali dei cani, cosa sono e come trattarli - area-press.eu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\"},\"datePublished\":\"2020-02-26T17:39:06+00:00\",\"dateModified\":\"2020-02-26T23:34:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/3b4a8cf33790667979d8603086264ac8\"},\"description\":\"I parassiti intestinali sono vermi di piccole dimensioni che si insediano nell'intestino del cane, dove si nutrono del sangue e del cibo ingerito.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2020\\\/02\\\/26\\\/parassiti-intestinali-dei-cani-cosa-sono-e-come-trattarli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2020\\\/02\\\/26\\\/parassiti-intestinali-dei-cani-cosa-sono-e-come-trattarli\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2020\\\/02\\\/26\\\/parassiti-intestinali-dei-cani-cosa-sono-e-come-trattarli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parassiti intestinali dei cani, cosa sono e come trattarli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\",\"name\":\"area-press.eu\",\"description\":\"comunicati stampa &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/3b4a8cf33790667979d8603086264ac8\",\"name\":\"Veterinario Aleandri\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c98f6fd97226af0272b2c0829ff5dfb3207531f0fb317213b177afc1a4f5a00e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c98f6fd97226af0272b2c0829ff5dfb3207531f0fb317213b177afc1a4f5a00e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c98f6fd97226af0272b2c0829ff5dfb3207531f0fb317213b177afc1a4f5a00e?s=96&d=mm&r=g\",\"caption\":\"Veterinario Aleandri\"},\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/author\\\/veterinario-aleandri\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parassiti intestinali dei cani, cosa sono e come trattarli - area-press.eu","description":"I parassiti intestinali sono vermi di piccole dimensioni che si insediano nell'intestino del cane, dove si nutrono del sangue e del cibo ingerito.","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Parassiti intestinali dei cani, cosa sono e come trattarli","og_description":"I parassiti intestinali sono vermi di piccole dimensioni che si insediano nell'intestino del cane, dove si nutrono del sangue e del cibo ingerito.","og_url":"https:\/\/www.area-press.eu\/comunicatistampa\/2020\/02\/26\/parassiti-intestinali-dei-cani-cosa-sono-e-come-trattarli\/","og_site_name":"area-press.eu","article_published_time":"2020-02-26T17:39:06+00:00","article_modified_time":"2020-02-26T23:34:40+00:00","author":"Veterinario Aleandri","twitter_card":"summary_large_image","twitter_title":"Parassiti intestinali dei cani, cosa sono e come trattarli","twitter_description":"I parassiti intestinali sono vermi di piccole dimensioni che si insediano nell'intestino del cane, dove si nutrono del sangue e del cibo ingerito.","twitter_misc":{"Scritto da":"Veterinario Aleandri","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2020\/02\/26\/parassiti-intestinali-dei-cani-cosa-sono-e-come-trattarli\/#article","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2020\/02\/26\/parassiti-intestinali-dei-cani-cosa-sono-e-come-trattarli\/"},"author":{"name":"Veterinario Aleandri","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/3b4a8cf33790667979d8603086264ac8"},"headline":"Parassiti intestinali dei cani, cosa sono e come trattarli","datePublished":"2020-02-26T17:39:06+00:00","dateModified":"2020-02-26T23:34:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2020\/02\/26\/parassiti-intestinali-dei-cani-cosa-sono-e-come-trattarli\/"},"wordCount":378,"commentCount":0,"keywords":["parassiti del cane"],"articleSection":["Comunicati"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2020\/02\/26\/parassiti-intestinali-dei-cani-cosa-sono-e-come-trattarli\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2020\/02\/26\/parassiti-intestinali-dei-cani-cosa-sono-e-come-trattarli\/","url":"https:\/\/www.area-press.eu\/comunicatistampa\/2020\/02\/26\/parassiti-intestinali-dei-cani-cosa-sono-e-come-trattarli\/","name":"Parassiti intestinali dei cani, cosa sono e come trattarli - area-press.eu","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website"},"datePublished":"2020-02-26T17:39:06+00:00","dateModified":"2020-02-26T23:34:40+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/3b4a8cf33790667979d8603086264ac8"},"description":"I parassiti intestinali sono vermi di piccole dimensioni che si insediano nell'intestino del cane, dove si nutrono del sangue e del cibo ingerito.","breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2020\/02\/26\/parassiti-intestinali-dei-cani-cosa-sono-e-come-trattarli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2020\/02\/26\/parassiti-intestinali-dei-cani-cosa-sono-e-come-trattarli\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2020\/02\/26\/parassiti-intestinali-dei-cani-cosa-sono-e-come-trattarli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicatistampa\/"},{"@type":"ListItem","position":2,"name":"Parassiti intestinali dei cani, cosa sono e come trattarli"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website","url":"https:\/\/www.area-press.eu\/comunicatistampa\/","name":"area-press.eu","description":"comunicati stampa &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicatistampa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/3b4a8cf33790667979d8603086264ac8","name":"Veterinario Aleandri","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c98f6fd97226af0272b2c0829ff5dfb3207531f0fb317213b177afc1a4f5a00e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c98f6fd97226af0272b2c0829ff5dfb3207531f0fb317213b177afc1a4f5a00e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c98f6fd97226af0272b2c0829ff5dfb3207531f0fb317213b177afc1a4f5a00e?s=96&d=mm&r=g","caption":"Veterinario Aleandri"},"url":"https:\/\/www.area-press.eu\/comunicatistampa\/author\/veterinario-aleandri\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/47914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/users\/2944"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/comments?post=47914"}],"version-history":[{"count":3,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/47914\/revisions"}],"predecessor-version":[{"id":47965,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/47914\/revisions\/47965"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/media?parent=47914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/categories?post=47914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/tags?post=47914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}