{"id":44003,"date":"2019-09-29T12:47:05","date_gmt":"2019-09-29T10:47:05","guid":{"rendered":"https:\/\/www.area-press.eu\/comunicatistampa\/?p=44003"},"modified":"2019-09-29T12:47:05","modified_gmt":"2019-09-29T10:47:05","slug":"giampaolo-sutto-la-guida-per-vincere-su-mutant-year-zero","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/09\/29\/giampaolo-sutto-la-guida-per-vincere-su-mutant-year-zero\/","title":{"rendered":"Giampaolo Sutto: la guida per vincere su Mutant Year Zero"},"content":{"rendered":"<p><em><strong>Si tratta di un titolo da non sottovalutare, dove agire con intelligenza \u00e8 fondamentale per scovare la strategia migliore. Ci sono per\u00f2 delle accortezze utili da tenere a mente per vincere divertendosi, senza troppa frustrazione: le suggerisce Giampaolo Sutto <a href=\"https:\/\/giampaolosutto.blogspot.com\/2019\/03\/mutant-year-zero-road-to-heaven-tutti-i.html\" title=\"Giampaolo Sutto: recensione mutant year zero\">sul suo blog dedicato al gaming<\/a>.<\/strong> <\/em><\/p>\n<h2>Giampaolo Sutto su Mutant Year Zero: una sfida gi\u00e0 dai primi livelli<\/h2>\n<p><em>&quot;Napoleone ci insegna che quando le forze nemiche sono soverchianti, la strategia ideale \u00e8 quella di separare le forze rivali ed affrontarle singolarmente, una tattica che nel gioco si traduce nell&#8217;uccidere pi\u00f9 avversari possibili in modalit\u00e0 stealth, uno alla volta, sfruttando la superiorit\u00e0 numerica&quot;<\/em>: \u00e8 il consiglio di <strong>Giampaolo Sutto<\/strong>, storico appassionato di videogiochi strategici e proprietario di un blog dedicato al gaming. In un recente post si \u00e8 occupato di Mutant Year Zero, titolo ispirato alla saga X-Com che offre un notevole livello di sfida. Come sottolineato da subito dall&#8217;appassionato, non si tratta di un gioco da prendere alla leggera. Non esistono &quot;livelli semplici&quot; ed \u00e8 necessario da subito agire con astuzia per uscirne vivi. Armi silenziate, come balestra e pistole con silenziatore, sono fondamentali per vincere: il consiglio di <strong>Giampaolo Sutto<\/strong> \u00e8 quello di potenziarle appena possibile, per neutralizzare il nemico prima che chiami rinforzi. \u00c8 importante anche essere parsimoniosi e utilizzare il negozio e l&#8217;officina con intelligenza, senza sprecare preziose risorse.<\/p>\n<h2>Giampaolo Sutto: prima i pi\u00f9 forti, ma passo per passo<\/h2>\n<p><em>&quot;Il gioco, sebbene non completamente lineare, ci obbliga in realt\u00e0 a procedere per passi&quot;<\/em>, spiega <strong><a href=\"https:\/\/giampaolosutto.blogspot.com\/2019\/03\/mutant-year-zero-road-to-heaven-tutti-i.html\" title=\"Giampaolo Sutto: soluzioni mutant year zero\">Giampaolo Sutto<\/a><\/strong>. <em>&quot;Per affrontare al meglio i nemici pi\u00f9 forti, bisogna cercare di ripulire tutti i livelli con npc di livello inferiore. Una strategia che se da un lato ci costringe a pensare con attenzione ogni nostra mossa, dall&#8217;altra rende maggiormente soddisfacente affrontare una battaglia senza prendere danni&quot;<\/em>. In Mutant Year Zero \u00e8 importante centellinare i medikit e combattere come se non ne fossimo a disposizione. Il vero segreto per vincere \u00e8 eliminare il maggior numero di nemici nel minor tempo possibile, senza far troppo affidamento sulle cure. Secondo <strong>Giampaolo Sutto<\/strong>, \u00e8 d&#8217;aiuto abbattere prima i nemici pi\u00f9 forti, togliendo di mezzo gli sciamani in primis, per impedir loro di chiamare rinforzi. Un altro utile consiglio \u00e8 quello di salvare spesso: succede pi\u00f9 volte di voler tornare sui propri passi per cambiare tattica o scegliere un&#8217;abilit\u00e0 migliore. Creare diversi salvataggi d\u00e0 l&#8217;opportunit\u00e0 di non ripetere continuamente battaglie gi\u00e0 vinte in precedenza. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si tratta di un titolo da non sottovalutare, dove agire con intelligenza \u00e8 fondamentale per scovare la strategia migliore. Ci sono per\u00f2 delle accortezze utili da tenere a mente per vincere divertendosi, senza troppa frustrazione: le suggerisce Giampaolo Sutto sul suo blog dedicato al gaming. Giampaolo Sutto su Mutant Year Zero: una sfida gi\u00e0 dai [&hellip;]<\/p>\n","protected":false},"author":40,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[29],"tags":[24641],"class_list":["post-44003","post","type-post","status-publish","format-standard","hentry","category-comunicati","tag-giampaolo-sutto-videogiochi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giampaolo Sutto: la guida per vincere su Mutant Year Zero - area-press.eu<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giampaolo Sutto: la guida per vincere su Mutant Year Zero - area-press.eu\" \/>\n<meta property=\"og:description\" content=\"Si tratta di un titolo da non sottovalutare, dove agire con intelligenza \u00e8 fondamentale per scovare la strategia migliore. Ci sono per\u00f2 delle accortezze utili da tenere a mente per vincere divertendosi, senza troppa frustrazione: le suggerisce Giampaolo Sutto sul suo blog dedicato al gaming. Giampaolo Sutto su Mutant Year Zero: una sfida gi\u00e0 dai [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/09\/29\/giampaolo-sutto-la-guida-per-vincere-su-mutant-year-zero\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-29T10:47:05+00:00\" \/>\n<meta name=\"author\" content=\"articolinews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"articolinews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/09\\\/29\\\/giampaolo-sutto-la-guida-per-vincere-su-mutant-year-zero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/09\\\/29\\\/giampaolo-sutto-la-guida-per-vincere-su-mutant-year-zero\\\/\"},\"author\":{\"name\":\"articolinews\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/ad84067b262ffdc236fd60721c3bc61b\"},\"headline\":\"Giampaolo Sutto: la guida per vincere su Mutant Year Zero\",\"datePublished\":\"2019-09-29T10:47:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/09\\\/29\\\/giampaolo-sutto-la-guida-per-vincere-su-mutant-year-zero\\\/\"},\"wordCount\":404,\"commentCount\":0,\"keywords\":[\"Giampaolo Sutto videogiochi\"],\"articleSection\":[\"Comunicati\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/09\\\/29\\\/giampaolo-sutto-la-guida-per-vincere-su-mutant-year-zero\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/09\\\/29\\\/giampaolo-sutto-la-guida-per-vincere-su-mutant-year-zero\\\/\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/09\\\/29\\\/giampaolo-sutto-la-guida-per-vincere-su-mutant-year-zero\\\/\",\"name\":\"Giampaolo Sutto: la guida per vincere su Mutant Year Zero - area-press.eu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\"},\"datePublished\":\"2019-09-29T10:47:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/ad84067b262ffdc236fd60721c3bc61b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/09\\\/29\\\/giampaolo-sutto-la-guida-per-vincere-su-mutant-year-zero\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/09\\\/29\\\/giampaolo-sutto-la-guida-per-vincere-su-mutant-year-zero\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/09\\\/29\\\/giampaolo-sutto-la-guida-per-vincere-su-mutant-year-zero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giampaolo Sutto: la guida per vincere su Mutant Year Zero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\",\"name\":\"area-press.eu\",\"description\":\"comunicati stampa &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/ad84067b262ffdc236fd60721c3bc61b\",\"name\":\"articolinews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9e2a264bab04e17dea24d937c9956304649a848cb73c46747a692ff1bdeb1cb7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9e2a264bab04e17dea24d937c9956304649a848cb73c46747a692ff1bdeb1cb7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9e2a264bab04e17dea24d937c9956304649a848cb73c46747a692ff1bdeb1cb7?s=96&d=mm&r=g\",\"caption\":\"articolinews\"},\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/author\\\/articolinews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giampaolo Sutto: la guida per vincere su Mutant Year Zero - area-press.eu","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Giampaolo Sutto: la guida per vincere su Mutant Year Zero - area-press.eu","og_description":"Si tratta di un titolo da non sottovalutare, dove agire con intelligenza \u00e8 fondamentale per scovare la strategia migliore. Ci sono per\u00f2 delle accortezze utili da tenere a mente per vincere divertendosi, senza troppa frustrazione: le suggerisce Giampaolo Sutto sul suo blog dedicato al gaming. Giampaolo Sutto su Mutant Year Zero: una sfida gi\u00e0 dai [&hellip;]","og_url":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/09\/29\/giampaolo-sutto-la-guida-per-vincere-su-mutant-year-zero\/","og_site_name":"area-press.eu","article_published_time":"2019-09-29T10:47:05+00:00","author":"articolinews","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"articolinews","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/09\/29\/giampaolo-sutto-la-guida-per-vincere-su-mutant-year-zero\/#article","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/09\/29\/giampaolo-sutto-la-guida-per-vincere-su-mutant-year-zero\/"},"author":{"name":"articolinews","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/ad84067b262ffdc236fd60721c3bc61b"},"headline":"Giampaolo Sutto: la guida per vincere su Mutant Year Zero","datePublished":"2019-09-29T10:47:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/09\/29\/giampaolo-sutto-la-guida-per-vincere-su-mutant-year-zero\/"},"wordCount":404,"commentCount":0,"keywords":["Giampaolo Sutto videogiochi"],"articleSection":["Comunicati"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2019\/09\/29\/giampaolo-sutto-la-guida-per-vincere-su-mutant-year-zero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/09\/29\/giampaolo-sutto-la-guida-per-vincere-su-mutant-year-zero\/","url":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/09\/29\/giampaolo-sutto-la-guida-per-vincere-su-mutant-year-zero\/","name":"Giampaolo Sutto: la guida per vincere su Mutant Year Zero - area-press.eu","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website"},"datePublished":"2019-09-29T10:47:05+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/ad84067b262ffdc236fd60721c3bc61b"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/09\/29\/giampaolo-sutto-la-guida-per-vincere-su-mutant-year-zero\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2019\/09\/29\/giampaolo-sutto-la-guida-per-vincere-su-mutant-year-zero\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/09\/29\/giampaolo-sutto-la-guida-per-vincere-su-mutant-year-zero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicatistampa\/"},{"@type":"ListItem","position":2,"name":"Giampaolo Sutto: la guida per vincere su Mutant Year Zero"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website","url":"https:\/\/www.area-press.eu\/comunicatistampa\/","name":"area-press.eu","description":"comunicati stampa &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicatistampa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/ad84067b262ffdc236fd60721c3bc61b","name":"articolinews","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/9e2a264bab04e17dea24d937c9956304649a848cb73c46747a692ff1bdeb1cb7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9e2a264bab04e17dea24d937c9956304649a848cb73c46747a692ff1bdeb1cb7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9e2a264bab04e17dea24d937c9956304649a848cb73c46747a692ff1bdeb1cb7?s=96&d=mm&r=g","caption":"articolinews"},"url":"https:\/\/www.area-press.eu\/comunicatistampa\/author\/articolinews\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/44003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/comments?post=44003"}],"version-history":[{"count":1,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/44003\/revisions"}],"predecessor-version":[{"id":44004,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/44003\/revisions\/44004"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/media?parent=44003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/categories?post=44003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/tags?post=44003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}