{"id":41965,"date":"2019-06-27T18:36:54","date_gmt":"2019-06-27T16:36:54","guid":{"rendered":"https:\/\/www.area-press.eu\/comunicatistampa\/?p=41965"},"modified":"2019-06-27T18:36:54","modified_gmt":"2019-06-27T16:36:54","slug":"bilancio-europeo-e-nuovo-obbligo-di-revisione","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/06\/27\/bilancio-europeo-e-nuovo-obbligo-di-revisione\/","title":{"rendered":"BILANCIO EUROPEO E NUOVO OBBLIGO DI REVISIONE"},"content":{"rendered":"<p><strong>Bilancio 2019: verifica nuovo obbligo S.r.l. Con GB<\/strong><\/p>\n<p>La recente riforma del fallimento ha modificato l&#8217;art.2477 del codice civile ed introdotto soglie modeste per la nomina dell&#8217;Organo di Controllo o del Revisore in numerose S.r.l. precedentemente esonerate.<br \/>\nA partire dall&#8217;approvazione del bilancio al 31-12-2018, le S.r.l. Che hanno diritto a presentare lo schema abbreviato devono comunque verificare con attenzione i nuovi parametri. Per questo motivo GB ha elaborato una tabella integrata con lo scopo di eseguire la verifica dimensionale e che permette allo stesso tempo, di modificare eventualmente, il Verbale dell&#8217;Assemblea per mettersi in regola. Riportiamo e approfondiamo, di seguito, quella che \u00e8 la normativa a cui abbiamo fatto riferimento prima:<\/p>\n<p>Il Codice della Crisi di impresa e dell&#8217;Insolvenza (CCI) ha introdotto anche nuovi obblighi in materia di nomina dell&#8217;organo di controllo nelle S.r.l., in particolare l&#8217;art.379 del D.Lgs.12 gennaio 2019, n.14 in GU n.38 del 14\/02\/19 che entra in vigore il 16\/03\/2019. Quali sono quindi le casistiche di nomina dell&#8217;Organo di Controllo\/revisore con cui \u00e8 necessario confrontarsi ad oggi? Le abbiamo riassunte in questo elenco:<br \/>\nSociet\u00e0 per Azioni s.p.a.<br \/>\nSociet\u00e0 in Accomandita per azioni S.a.p.a<br \/>\nSociet\u00e0 Cooperative (S.p.A o S.r.l.) che emettono strumenti finanziari non partecipativi (strumenti finanziari forniti di diritto finanziario e di diritto amministrativo \u2013 a seguito di apporti di soci e di terzi- escluso il diritto di voto nell&#8217;assemblea generale dei soci)<br \/>\nSociet\u00e0 Cooperative (S.p.A. O S.r.l.) che hanno i requisiti previsti per le S.r.l. Dall&#8217;art.2477 comma 3 (tutte le successive casistiche)<br \/>\nSociet\u00e0 tenute al bilancio consolidato<br \/>\nSociet\u00e0 controllanti di un&#8217;altra societ\u00e0 tenuta alla revisione legale dei conti (esempio S.r.l. Controllate di S.p.A.\/ S.a.p.A.)<\/p>\n<p>La novit\u00e0 \u00e8 rappresentata comunque dall&#8217;entrata, dopo la modifica del Codice della Crisi di Impresa e di Insolvenza, nel lotto delle casistiche appena lette, delle Societ\u00e0 che superano per due esercizi consecutivi almeno uno dei (nuovi e ridotti) limiti:<br \/>\n&#8211; Attivo S\/P non inferiore a 2.000.000 euro<br \/>\n&#8211; Ricavi A1 C\/E non inferiori a 2.000.000 euro<br \/>\n&#8211; Dipendenti occupati in media non inferiori a 10<\/p>\n<p>Da ricordare, in particolare, \u00e8 che l&#8217;obbligo di nomina dell&#8217;Organo di Controllo\/Revisione nel periodo transitorio, decorre dalla data di entrata in vigore del Codice, cio\u00e8 dal 16\/03\/19 e deve essere adempiuto entro nove mesi (16 dicembre 2019) insieme alla modifica dello Statuto\/Atto costitutivo, se necessaria.<\/p>\n<p>La revisione suggerisce di procedere subito alla nomina qualora lo Statuto sia sin da subito in linea con i nuovi obblighi anche prima di dicembre 2019, ad esempio, se fosse pronto gi\u00e0 in sede di approvazione del bilancio 2018 (marzo\/aprile 2019)<\/p>\n<p>Per questo motivo GB propone gi\u00e0 al momento dell&#8217;approvazione del bilancio 2018, la tabella per verificare l&#8217;esistenza del nuovo obbligo. Si potr\u00e0 inoltre, in caso di necessit\u00e0, allegare il Verbale di Assemblea dei soci di approvazione del bilancio, aggiungendo questo punto specifico anche nell&#8217; \u201cordine del giorno\u201d.<\/p>\n<p>Per essere in linea con la nuova normativa, la nomina dell&#8217;Organo di Controllo\/Revisore deve avvenire entro un mese dall&#8217;assemblea che approva il bilancio in cui vengono superati i limiti.<\/p>\n<p>Questo nuovo obbligo interessa quindi le S.r.l. \u201cnon piccole\u201d rispetto ai nuovi parametri, diversi sia da quelli dell&#8217;abbreviato sia da quelli per il bilancio micro-imprese, quindi intermedi. Per esempio, potremmo avere un bilancio abbreviato di S.r.l. Al 31.12.2019 con relazione obbligatoria dell\u2019Organo di controllo.<\/p>\n<p>Anche dalla disciplina di uscita dal regime, si evince la volont\u00e0 del legislatore di esercitare controllo sulle S.r.l. Il pi\u00f9 a lungo possibile: la nomina dell&#8217;Organo di Controllo\/Revisore termina solo quando per tre esercizi consecutivi non \u00e8 mai stato superato alcun limite.<\/p>\n<p><strong>Bilancio 2019: raddoppio limiti obbligo revisione S.r.l.<\/strong><\/p>\n<p>L&#8217;art.2477 comma 3 del Codice Civile \u00e8 stato modificato due volte nel corso del 2019: la prima volta dal Codice della crisi di impresa e la seconda volta dalla Legge di conversione del decreto Sblocca Cantieri. Quindi nel 2019 si sono susseguite tre diverse situazioni di obbligo con diversi limiti per la nomina del Collegio sindacale o del Revisore nelle S.r.l..<\/p>\n<p>A regime, cio\u00e8 dal 18\/0672019, in sede di approvazione del bilancio 2018 o successivo, le S.r.l. Devono verificare con attenzione i nuovi parametri che salgono a quota quattro milioni di attivo o di ricavi o a venti dipendenti.<\/p>\n<p>GB ha aggiornato la procedura ed elaborato una seconda tabella integrata che esegue la verifica dimensionale, consentendo di inserire in Verbale Assemblea (di approvazione del bilancio) i conteggi e l&#8217;eventuale nomina. Viene mantenuta la visualizzazione della tabella originaria ai fini del controllo sulla sussistenza dei limiti pregressi.<\/p>\n<p><strong>Normativa<\/strong><\/p>\n<p>Il codice della Crisi d&#8217;impresa e dell&#8217;insolvenza (art 379 del D.L.gs 14\/2019) in materia di nomina dell&#8217;organo di controllo nelle S.r.l. Ha introdotto obblighi in vigore dal 16\/03\/2019 al 17\/06\/2019, rideterminati in sede di conversione del DL 32\/2019 in G.U. 140 del 17\/06\/2019) che dal 18\/06\/2019 ha raddoppiato gli stessi limiti. Segue il doveroso riepilogo delle tre situazioni e i soggetti interessati dall&#8217;obbligo di revisione.<\/p>\n<p><strong>Sopravvenuta insussistenza dell&#8217;obbligo di nomina<\/strong><\/p>\n<p>Le S.r.l. Che, nel periodo dal 16\/03\/2019 al 17\/06\/2019, avessero nominato l&#8217;Organo di Controllo \/Revisore a causa del superamento dei limiti introdotti dal CCII (in occasione dell&#8217;approvazione del bilancio dell&#8217;esercizio 2018 e possedendo uno Statuto Sociale gi\u00e0 in linea con il codice) e ad oggi si trovino al di sotto dei limiti introdotti dalla Legge Sblocca Cantieri, si trovano in una situazione di incertezza normativa, che dottrina autorevole sta cercando di colmare. A societ\u00e0 che con riferimento al bilancio 2018 o successivi:<\/p>\n<p>1. Hanno superato i limiti introdotti con il CCII (2 milioni, 2 milioni, 10 dipendenti)<br \/>\n2. Hanno nominato un organo di controllo superiore nel periodo 16\/03\/2019- 17\/06\/2019)<br \/>\n3. Non superano gli attuali limiti dello Sblocca Cantieri (4 milioni, 4 milioni, 20 dipendenti)<\/p>\n<p>Revisore legale: C&#8217;\u00e8 la possibilit\u00e0 di revoca del Revisore (a condizione che preliminarmente il Consiglio di Amministrazione comunichi al Revisore che all&#8217;Assemblea \u00e8 stata proposta la revoca indicandone i motivi, ex D.M. 261\/2012)<\/p>\n<p>Collegio sindacale: C&#8217;\u00e8 l&#8217;obbligo di mantenimento del Collegio Sindacale o dei sindaci con funzione di revisione legale anche dopo il 18\/06\/2019 (in quanto nella legge di conversione dello Sblocca Cantieri manca la previsione di giusta causa di revoca presente invece in precedenti provvedimenti, come ad esempio il D.L. 91\/2014)<\/p>\n<p>I nostri articoli sul bilancio e sul <a href=\"https:\/\/www.softwarebilancio.it\/\">software obbligo revisione<\/a> sono disponibili presso il sito del programma BILANCIO EUROPEO GB.<\/p>\n<p>GBsoftware S.p.A. \u00e8 una software house nata dall&#8217;idea di un commercialista e dell&#8217;esperienza di uno studio attivo dal 1977. Siamo specializzati in software semplici per studi e imprese.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bilancio 2019: verifica nuovo obbligo S.r.l. Con GB La recente riforma del fallimento ha modificato l&#8217;art.2477 del codice civile ed introdotto soglie modeste per la nomina dell&#8217;Organo di Controllo o del Revisore in numerose S.r.l. precedentemente esonerate. A partire dall&#8217;approvazione del bilancio al 31-12-2018, le S.r.l. Che hanno diritto a presentare lo schema abbreviato devono [&hellip;]<\/p>\n","protected":false},"author":2930,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7,10],"tags":[23523,23835,23836,23834],"class_list":["post-41965","post","type-post","status-publish","format-standard","hentry","category-economia-e-finanza","category-informatica","tag-obbligo-revisione","tag-obbligo-revisione-srl","tag-programma-obbligo-revisione","tag-software-obbligo-revisione"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BILANCIO EUROPEO E NUOVO OBBLIGO DI REVISIONE - area-press.eu<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BILANCIO EUROPEO E NUOVO OBBLIGO DI REVISIONE - area-press.eu\" \/>\n<meta property=\"og:description\" content=\"Bilancio 2019: verifica nuovo obbligo S.r.l. Con GB La recente riforma del fallimento ha modificato l&#8217;art.2477 del codice civile ed introdotto soglie modeste per la nomina dell&#8217;Organo di Controllo o del Revisore in numerose S.r.l. precedentemente esonerate. A partire dall&#8217;approvazione del bilancio al 31-12-2018, le S.r.l. Che hanno diritto a presentare lo schema abbreviato devono [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/06\/27\/bilancio-europeo-e-nuovo-obbligo-di-revisione\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-27T16:36:54+00:00\" \/>\n<meta name=\"author\" content=\"GBsoftware S.p.A.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"GBsoftware S.p.A.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/06\\\/27\\\/bilancio-europeo-e-nuovo-obbligo-di-revisione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/06\\\/27\\\/bilancio-europeo-e-nuovo-obbligo-di-revisione\\\/\"},\"author\":{\"name\":\"GBsoftware S.p.A.\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/fe66ec56f60ea0c77353f3ec168961e5\"},\"headline\":\"BILANCIO EUROPEO E NUOVO OBBLIGO DI REVISIONE\",\"datePublished\":\"2019-06-27T16:36:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/06\\\/27\\\/bilancio-europeo-e-nuovo-obbligo-di-revisione\\\/\"},\"wordCount\":1073,\"commentCount\":0,\"keywords\":[\"obbligo revisione\",\"obbligo revisione SRL\",\"programma obbligo revisione\",\"software obbligo revisione\"],\"articleSection\":[\"Economia e Finanza\",\"Informatica\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/06\\\/27\\\/bilancio-europeo-e-nuovo-obbligo-di-revisione\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/06\\\/27\\\/bilancio-europeo-e-nuovo-obbligo-di-revisione\\\/\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/06\\\/27\\\/bilancio-europeo-e-nuovo-obbligo-di-revisione\\\/\",\"name\":\"BILANCIO EUROPEO E NUOVO OBBLIGO DI REVISIONE - area-press.eu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\"},\"datePublished\":\"2019-06-27T16:36:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/fe66ec56f60ea0c77353f3ec168961e5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/06\\\/27\\\/bilancio-europeo-e-nuovo-obbligo-di-revisione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/06\\\/27\\\/bilancio-europeo-e-nuovo-obbligo-di-revisione\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/06\\\/27\\\/bilancio-europeo-e-nuovo-obbligo-di-revisione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BILANCIO EUROPEO E NUOVO OBBLIGO DI REVISIONE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\",\"name\":\"area-press.eu\",\"description\":\"comunicati stampa &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/fe66ec56f60ea0c77353f3ec168961e5\",\"name\":\"GBsoftware S.p.A.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7500de9a915363293b88522ee4b9ac298a9fda6c3e835ab412ff428cbbfe843?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7500de9a915363293b88522ee4b9ac298a9fda6c3e835ab412ff428cbbfe843?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7500de9a915363293b88522ee4b9ac298a9fda6c3e835ab412ff428cbbfe843?s=96&d=mm&r=g\",\"caption\":\"GBsoftware S.p.A.\"},\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/author\\\/stefano1991\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BILANCIO EUROPEO E NUOVO OBBLIGO DI REVISIONE - area-press.eu","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"BILANCIO EUROPEO E NUOVO OBBLIGO DI REVISIONE - area-press.eu","og_description":"Bilancio 2019: verifica nuovo obbligo S.r.l. Con GB La recente riforma del fallimento ha modificato l&#8217;art.2477 del codice civile ed introdotto soglie modeste per la nomina dell&#8217;Organo di Controllo o del Revisore in numerose S.r.l. precedentemente esonerate. A partire dall&#8217;approvazione del bilancio al 31-12-2018, le S.r.l. Che hanno diritto a presentare lo schema abbreviato devono [&hellip;]","og_url":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/06\/27\/bilancio-europeo-e-nuovo-obbligo-di-revisione\/","og_site_name":"area-press.eu","article_published_time":"2019-06-27T16:36:54+00:00","author":"GBsoftware S.p.A.","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"GBsoftware S.p.A.","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/06\/27\/bilancio-europeo-e-nuovo-obbligo-di-revisione\/#article","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/06\/27\/bilancio-europeo-e-nuovo-obbligo-di-revisione\/"},"author":{"name":"GBsoftware S.p.A.","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/fe66ec56f60ea0c77353f3ec168961e5"},"headline":"BILANCIO EUROPEO E NUOVO OBBLIGO DI REVISIONE","datePublished":"2019-06-27T16:36:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/06\/27\/bilancio-europeo-e-nuovo-obbligo-di-revisione\/"},"wordCount":1073,"commentCount":0,"keywords":["obbligo revisione","obbligo revisione SRL","programma obbligo revisione","software obbligo revisione"],"articleSection":["Economia e Finanza","Informatica"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2019\/06\/27\/bilancio-europeo-e-nuovo-obbligo-di-revisione\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/06\/27\/bilancio-europeo-e-nuovo-obbligo-di-revisione\/","url":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/06\/27\/bilancio-europeo-e-nuovo-obbligo-di-revisione\/","name":"BILANCIO EUROPEO E NUOVO OBBLIGO DI REVISIONE - area-press.eu","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website"},"datePublished":"2019-06-27T16:36:54+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/fe66ec56f60ea0c77353f3ec168961e5"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/06\/27\/bilancio-europeo-e-nuovo-obbligo-di-revisione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2019\/06\/27\/bilancio-europeo-e-nuovo-obbligo-di-revisione\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/06\/27\/bilancio-europeo-e-nuovo-obbligo-di-revisione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicatistampa\/"},{"@type":"ListItem","position":2,"name":"BILANCIO EUROPEO E NUOVO OBBLIGO DI REVISIONE"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website","url":"https:\/\/www.area-press.eu\/comunicatistampa\/","name":"area-press.eu","description":"comunicati stampa &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicatistampa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/fe66ec56f60ea0c77353f3ec168961e5","name":"GBsoftware S.p.A.","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e7500de9a915363293b88522ee4b9ac298a9fda6c3e835ab412ff428cbbfe843?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e7500de9a915363293b88522ee4b9ac298a9fda6c3e835ab412ff428cbbfe843?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e7500de9a915363293b88522ee4b9ac298a9fda6c3e835ab412ff428cbbfe843?s=96&d=mm&r=g","caption":"GBsoftware S.p.A."},"url":"https:\/\/www.area-press.eu\/comunicatistampa\/author\/stefano1991\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/41965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/users\/2930"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/comments?post=41965"}],"version-history":[{"count":1,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/41965\/revisions"}],"predecessor-version":[{"id":41966,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/41965\/revisions\/41966"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/media?parent=41965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/categories?post=41965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/tags?post=41965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}