{"id":39233,"date":"2019-03-18T16:50:59","date_gmt":"2019-03-18T15:50:59","guid":{"rendered":"https:\/\/www.area-press.eu\/comunicatistampa\/?p=39233"},"modified":"2019-03-18T16:50:59","modified_gmt":"2019-03-18T15:50:59","slug":"caminetto-poetico-con-loredana-moreni-e-giuseppe-leccardi","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/03\/18\/caminetto-poetico-con-loredana-moreni-e-giuseppe-leccardi\/","title":{"rendered":"CAMINETTO POETICO: CON LOREDANA MORENI E GIUSEPPE LECCARDI"},"content":{"rendered":"<p>Milano \u2013 Gli amici della Cascina Linterno in collaborazione con la Fondazione Amici di Ron e con il Patrocinio del Municipio 7 di Milano presentano due libri con la presenza degli autori\u00a0 con la\u00a0 formula \u201cCaminetto Poetico\u201d : l&#8217;appuntamento \u00e8 per <strong>sabato 23 marzo alle ore 16.30<\/strong> nella storica Chiesetta di Cascina Linterno (Via Fratelli Zoia, 194 \u2013 Parco delle Cave \u2013 Milano): ospiti Loredana Moreni e Giuseppe Leccardi.<\/p>\n<p><strong>Loredana Moreni<\/strong> nasce a Brescia, negli anni 50 ma \u00e8 residente a Milano da sempre. La scrittura e l&#8217;arte sono state due passioni che non ha mai abbandonato e che l\u2019hanno portata a partecipare a diversi concorsi di poesie e racconti.<\/p>\n<p>La sua passione per lo scrivere raggiunge il culmine con la pubblicazione di <strong><em>&#8220;Racconti di luce amore e destino&#8221;<\/em><\/strong> cinque brevi racconti che pongono, al centro delle narrazioni, l&#8217;amore nel significato pi\u00f9 autentico e puro.<\/p>\n<p><strong>Giuseppe Leccardi<\/strong> nasce in un vivace centro rurale della \u201cBassa\u201d lodigiana, ma da cinquant\u2019anni vive a Milano. Appassionato di letteratura e poesia, scrive dall\u2019et\u00e0 adolescenziale ma solo da pochi anni ha estratto dal cassetto i suoi scritti ed ha pubblicato tre raccolte di versi: \u201cDiario poetico\u201d nel 2010, \u201cOltre ogni ragionevole incertezza\u201d nel 2011 e \u201cSettantadue\u201d nel 2018.<\/p>\n<p>Ha partecipato e vinto diversi concorsi di poesia, in particolare nel 2018 vince il \u201cPremio della critica\u201d al concorso internazionale di Arti Letterarie \u201cThesaurus La Brunella\u201d di Aulla per la sezione poesia edita.<\/p>\n<p>La cornice che ospiter\u00e0 l\u2019incontro \u00e8 unica nel suo genere: Cascina Linterno \u00e8 un monumento storico tutelato dal Ministero dei Beni Culturali, che la tradizione indica come dimora agreste di <strong>Francesco Petrarca<\/strong> che qui amava rifugiarsi per sfuggire alla gi\u00e0 allora caotica vita milanese.<\/p>\n<p>I posti sono limitati, \u00e8 dunque indispensabile prenotarsi, scrivendo ad amicidiron.pro@gmail.com oppure telefonando al numero 347-3433159 e chiedere di Laura Romanoni (responsabile segreteria)<\/p>\n<p>Per ulteriori informazioni visitare il sito: <a href=\"http:\/\/www.premiodipoesia.it\/\">www.premiodipoesia.it<\/a><br \/>\nPagina facebook amicidiron.concorsodipoesia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Milano \u2013 Gli amici della Cascina Linterno in collaborazione con la Fondazione Amici di Ron e con il Patrocinio del Municipio 7 di Milano presentano due libri con la presenza degli autori\u00a0 con la\u00a0 formula \u201cCaminetto Poetico\u201d : l&#8217;appuntamento \u00e8 per sabato 23 marzo alle ore 16.30 nella storica Chiesetta di Cascina Linterno (Via Fratelli [&hellip;]<\/p>\n","protected":false},"author":4722,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[17792,17791,22682,16005,22685,22684,22683,688,26,20442],"class_list":["post-39233","post","type-post","status-publish","format-standard","hentry","category-arte-e-cultura","tag-amici-di-ron","tag-caminetto-poetico","tag-cascina-linterno","tag-donatella-rampado","tag-francesco-petrarca","tag-giuseppe-leccardi","tag-loredana-moreni","tag-milano","tag-poesia","tag-renato-ongania"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CAMINETTO POETICO: CON LOREDANA MORENI E GIUSEPPE LECCARDI - area-press.eu<\/title>\n<meta name=\"description\" content=\"Gli amici della Cascina Linterno in collaborazione con la Fondazione Amici di Ron e con il Patrocinio del Municipio 7 di Milano presentano due libri alla presenza degli autori con la formula \u201cCaminetto Poetico\u201d\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CAMINETTO POETICO: CON LOREDANA MORENI E GIUSEPPE LECCARDI - area-press.eu\" \/>\n<meta property=\"og:description\" content=\"Gli amici della Cascina Linterno in collaborazione con la Fondazione Amici di Ron e con il Patrocinio del Municipio 7 di Milano presentano due libri alla presenza degli autori con la formula \u201cCaminetto Poetico\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/03\/18\/caminetto-poetico-con-loredana-moreni-e-giuseppe-leccardi\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-18T15:50:59+00:00\" \/>\n<meta name=\"author\" content=\"Elena Ronzoni\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elena Ronzoni\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/03\\\/18\\\/caminetto-poetico-con-loredana-moreni-e-giuseppe-leccardi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/03\\\/18\\\/caminetto-poetico-con-loredana-moreni-e-giuseppe-leccardi\\\/\"},\"author\":{\"name\":\"Elena Ronzoni\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/a379409daa9e1924d7b3ce7c4a7ae1df\"},\"headline\":\"CAMINETTO POETICO: CON LOREDANA MORENI E GIUSEPPE LECCARDI\",\"datePublished\":\"2019-03-18T15:50:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/03\\\/18\\\/caminetto-poetico-con-loredana-moreni-e-giuseppe-leccardi\\\/\"},\"wordCount\":313,\"commentCount\":0,\"keywords\":[\"Amici di Ron\",\"Caminetto Poetico\",\"Cascina Linterno\",\"Donatella Rampado\",\"Francesco Petrarca\",\"Giuseppe Leccardi\",\"Loredana Moreni\",\"milano\",\"Poesia\",\"Renato Ongania\"],\"articleSection\":[\"Arte e Cultura\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/03\\\/18\\\/caminetto-poetico-con-loredana-moreni-e-giuseppe-leccardi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/03\\\/18\\\/caminetto-poetico-con-loredana-moreni-e-giuseppe-leccardi\\\/\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/03\\\/18\\\/caminetto-poetico-con-loredana-moreni-e-giuseppe-leccardi\\\/\",\"name\":\"CAMINETTO POETICO: CON LOREDANA MORENI E GIUSEPPE LECCARDI - area-press.eu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\"},\"datePublished\":\"2019-03-18T15:50:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/a379409daa9e1924d7b3ce7c4a7ae1df\"},\"description\":\"Gli amici della Cascina Linterno in collaborazione con la Fondazione Amici di Ron e con il Patrocinio del Municipio 7 di Milano presentano due libri alla presenza degli autori con la formula \u201cCaminetto Poetico\u201d\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/03\\\/18\\\/caminetto-poetico-con-loredana-moreni-e-giuseppe-leccardi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/03\\\/18\\\/caminetto-poetico-con-loredana-moreni-e-giuseppe-leccardi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2019\\\/03\\\/18\\\/caminetto-poetico-con-loredana-moreni-e-giuseppe-leccardi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CAMINETTO POETICO: CON LOREDANA MORENI E GIUSEPPE LECCARDI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\",\"name\":\"area-press.eu\",\"description\":\"comunicati stampa &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/a379409daa9e1924d7b3ce7c4a7ae1df\",\"name\":\"Elena Ronzoni\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e01efba3da53e9749d969a1b7f70b5b0e8a8533e623f2a08ef1e98c90f17f39?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e01efba3da53e9749d969a1b7f70b5b0e8a8533e623f2a08ef1e98c90f17f39?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e01efba3da53e9749d969a1b7f70b5b0e8a8533e623f2a08ef1e98c90f17f39?s=96&d=mm&r=g\",\"caption\":\"Elena Ronzoni\"},\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/author\\\/elena-ronzoni\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CAMINETTO POETICO: CON LOREDANA MORENI E GIUSEPPE LECCARDI - area-press.eu","description":"Gli amici della Cascina Linterno in collaborazione con la Fondazione Amici di Ron e con il Patrocinio del Municipio 7 di Milano presentano due libri alla presenza degli autori con la formula \u201cCaminetto Poetico\u201d","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"CAMINETTO POETICO: CON LOREDANA MORENI E GIUSEPPE LECCARDI - area-press.eu","og_description":"Gli amici della Cascina Linterno in collaborazione con la Fondazione Amici di Ron e con il Patrocinio del Municipio 7 di Milano presentano due libri alla presenza degli autori con la formula \u201cCaminetto Poetico\u201d","og_url":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/03\/18\/caminetto-poetico-con-loredana-moreni-e-giuseppe-leccardi\/","og_site_name":"area-press.eu","article_published_time":"2019-03-18T15:50:59+00:00","author":"Elena Ronzoni","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Elena Ronzoni","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/03\/18\/caminetto-poetico-con-loredana-moreni-e-giuseppe-leccardi\/#article","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/03\/18\/caminetto-poetico-con-loredana-moreni-e-giuseppe-leccardi\/"},"author":{"name":"Elena Ronzoni","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/a379409daa9e1924d7b3ce7c4a7ae1df"},"headline":"CAMINETTO POETICO: CON LOREDANA MORENI E GIUSEPPE LECCARDI","datePublished":"2019-03-18T15:50:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/03\/18\/caminetto-poetico-con-loredana-moreni-e-giuseppe-leccardi\/"},"wordCount":313,"commentCount":0,"keywords":["Amici di Ron","Caminetto Poetico","Cascina Linterno","Donatella Rampado","Francesco Petrarca","Giuseppe Leccardi","Loredana Moreni","milano","Poesia","Renato Ongania"],"articleSection":["Arte e Cultura"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2019\/03\/18\/caminetto-poetico-con-loredana-moreni-e-giuseppe-leccardi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/03\/18\/caminetto-poetico-con-loredana-moreni-e-giuseppe-leccardi\/","url":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/03\/18\/caminetto-poetico-con-loredana-moreni-e-giuseppe-leccardi\/","name":"CAMINETTO POETICO: CON LOREDANA MORENI E GIUSEPPE LECCARDI - area-press.eu","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website"},"datePublished":"2019-03-18T15:50:59+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/a379409daa9e1924d7b3ce7c4a7ae1df"},"description":"Gli amici della Cascina Linterno in collaborazione con la Fondazione Amici di Ron e con il Patrocinio del Municipio 7 di Milano presentano due libri alla presenza degli autori con la formula \u201cCaminetto Poetico\u201d","breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/03\/18\/caminetto-poetico-con-loredana-moreni-e-giuseppe-leccardi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2019\/03\/18\/caminetto-poetico-con-loredana-moreni-e-giuseppe-leccardi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2019\/03\/18\/caminetto-poetico-con-loredana-moreni-e-giuseppe-leccardi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicatistampa\/"},{"@type":"ListItem","position":2,"name":"CAMINETTO POETICO: CON LOREDANA MORENI E GIUSEPPE LECCARDI"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website","url":"https:\/\/www.area-press.eu\/comunicatistampa\/","name":"area-press.eu","description":"comunicati stampa &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicatistampa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/a379409daa9e1924d7b3ce7c4a7ae1df","name":"Elena Ronzoni","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4e01efba3da53e9749d969a1b7f70b5b0e8a8533e623f2a08ef1e98c90f17f39?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4e01efba3da53e9749d969a1b7f70b5b0e8a8533e623f2a08ef1e98c90f17f39?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4e01efba3da53e9749d969a1b7f70b5b0e8a8533e623f2a08ef1e98c90f17f39?s=96&d=mm&r=g","caption":"Elena Ronzoni"},"url":"https:\/\/www.area-press.eu\/comunicatistampa\/author\/elena-ronzoni\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/39233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/users\/4722"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/comments?post=39233"}],"version-history":[{"count":1,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/39233\/revisions"}],"predecessor-version":[{"id":39234,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/39233\/revisions\/39234"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/media?parent=39233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/categories?post=39233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/tags?post=39233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}