{"id":28735,"date":"2018-01-31T02:27:32","date_gmt":"2018-01-31T01:27:32","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicatistampa\/?p=28735"},"modified":"2018-01-31T02:27:32","modified_gmt":"2018-01-31T01:27:32","slug":"un-red-carpet-di-stelle-enologiche-al-park-wine-stars","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicatistampa\/2018\/01\/31\/un-red-carpet-di-stelle-enologiche-al-park-wine-stars\/","title":{"rendered":"Un red carpet di stelle &#8220;enologiche&#8221; al Park Wine Stars"},"content":{"rendered":"<p>Nova Gorica, 29 gennaio 2018 &#8211; Torna il <strong>Park Wine Stars <\/strong>di Nova Gorica, la kermesse aperta al pubblico dedicata all\u2019eccellenza della produzione vitivinicola slovena: <strong>venerd\u00ec 2 febbraio alle 19:00 <\/strong>al <strong>Ristorante Tiffany del Park Casin\u00f2 &amp; Hotel<\/strong> 27 cantine, per un totale di 82 etichette, sfileranno su un <em>red carpet<\/em> d\u2019eccezione, accompagnate come sempre dalle magistrali creazioni culinarie degli Chef Hit.<\/p>\n<p>Giunto alla quarta edizione, il Park Wine Stars \u00e8 diventato ormai un punto di riferimento per tutti gli appassionati e gli addetti ai lavori che desiderano scoprire, o riscoprire, le <strong>realt\u00e0 vitivinicole pi\u00f9 significative della regione Primorska<\/strong>, zona costiera situata nella parte sudoccidentale della Slovenia, che comprende pi\u00f9 di 7.000 ettari di vigneti distribuiti su quattro distretti: <strong>Valle del Vipava, Istria Slovena, Gori\u0161ka Brda e Kras (Carso)<\/strong>. Un\u2019occasione privilegiata per fare il punto sulle tendenze del settore e sulle ultime novit\u00e0, confrontandosi con i responsabili delle cantine, pronti a raccontare personalmente i segreti dei loro capolavori.<\/p>\n<p>In linea con la collaudata formula dell\u2019evento, le degustazioni di vino saranno accompagnate da esperti sommelier e si potranno assaggiare squisite specialit\u00e0 gastronomiche preparate per l\u2019occasione da <strong>5 giovani Chef Hit<\/strong>, coordinati dai Maitre de Cuisine Marino Furlan e Matja\u017e \u0160inigoj. Ad allietare la serata i ritmi coinvolgenti del trio <strong>Three Steps to Heaven<\/strong> e le evoluzioni delle \u00e9toiles del corpo di ballo francese <strong>Bonsoir Paris<\/strong>, che porter\u00e0 a Nova Gorica l\u2019atmosfera magica della Ville Lumi\u00e8re.<\/p>\n<p>\u201cAnno dopo anno il Park Wine Stars si conferma un appuntamento irrinunciabile per celebrare l\u2019eccellenza enogastronomica slovena \u2013 <strong>ha dichiarato Marjan Pulec, responsabile marketing del Park Casin\u00f2 &amp; Hotel<\/strong>. Situati alla convergenza delle pi\u00f9 importanti regioni vitivinicole del Paese, Nova Gorica e il Park rappresentano la location ideale per ospitare un evento dedicato al territorio e alle sue ricchezze, in linea con la filosofia del Gruppo Hit. Per la quarta volta chiameremo a raccolta appassionati e produttori per condividere momenti ed emozioni indimenticabili all\u2019insegna della qualit\u00e0\u201d.<\/p>\n<p>La serata sar\u00e0 condotta da Andrea Flego. Biglietti a partire da 25 \u20ac (in prevendita) disponibili presso il Park Casin\u00f2 &amp; Hotel e sulla pagina <a href=\"http:\/\/www.thecasinopark.com\">www.thecasinopark.com<\/a>.<\/p>\n<p>Per informazioni: <a href=\"http:\/\/www.thecasinopark.com\">www.thecasinopark.com<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nova Gorica, 29 gennaio 2018 &#8211; Torna il Park Wine Stars di Nova Gorica, la kermesse aperta al pubblico dedicata all\u2019eccellenza della produzione vitivinicola slovena: venerd\u00ec 2 febbraio alle 19:00 al Ristorante Tiffany del Park Casin\u00f2 &amp; Hotel 27 cantine, per un totale di 82 etichette, sfileranno su un red carpet d\u2019eccezione, accompagnate come sempre [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8,9],"tags":[15799,18022,18023],"class_list":["post-28735","post","type-post","status-publish","format-standard","hentry","category-eventi","category-gastronomia","tag-gruppohit","tag-parkwinestars","tag-primorska"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un red carpet di stelle &quot;enologiche&quot; al Park Wine Stars - area-press.eu<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un red carpet di stelle &quot;enologiche&quot; al Park Wine Stars - area-press.eu\" \/>\n<meta property=\"og:description\" content=\"Nova Gorica, 29 gennaio 2018 &#8211; Torna il Park Wine Stars di Nova Gorica, la kermesse aperta al pubblico dedicata all\u2019eccellenza della produzione vitivinicola slovena: venerd\u00ec 2 febbraio alle 19:00 al Ristorante Tiffany del Park Casin\u00f2 &amp; Hotel 27 cantine, per un totale di 82 etichette, sfileranno su un red carpet d\u2019eccezione, accompagnate come sempre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicatistampa\/2018\/01\/31\/un-red-carpet-di-stelle-enologiche-al-park-wine-stars\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-31T01:27:32+00:00\" \/>\n<meta name=\"author\" content=\"mcsmarketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mcsmarketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2018\\\/01\\\/31\\\/un-red-carpet-di-stelle-enologiche-al-park-wine-stars\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2018\\\/01\\\/31\\\/un-red-carpet-di-stelle-enologiche-al-park-wine-stars\\\/\"},\"author\":{\"name\":\"mcsmarketing\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/daf4c322206ea348f92b0ec56bc9b03f\"},\"headline\":\"Un red carpet di stelle &#8220;enologiche&#8221; al Park Wine Stars\",\"datePublished\":\"2018-01-31T01:27:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2018\\\/01\\\/31\\\/un-red-carpet-di-stelle-enologiche-al-park-wine-stars\\\/\"},\"wordCount\":361,\"commentCount\":0,\"keywords\":[\"#gruppohit\",\"#parkwinestars\",\"#primorska\"],\"articleSection\":[\"Eventi\",\"Gastronomia\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2018\\\/01\\\/31\\\/un-red-carpet-di-stelle-enologiche-al-park-wine-stars\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2018\\\/01\\\/31\\\/un-red-carpet-di-stelle-enologiche-al-park-wine-stars\\\/\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2018\\\/01\\\/31\\\/un-red-carpet-di-stelle-enologiche-al-park-wine-stars\\\/\",\"name\":\"Un red carpet di stelle \\\"enologiche\\\" al Park Wine Stars - area-press.eu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\"},\"datePublished\":\"2018-01-31T01:27:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/daf4c322206ea348f92b0ec56bc9b03f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2018\\\/01\\\/31\\\/un-red-carpet-di-stelle-enologiche-al-park-wine-stars\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2018\\\/01\\\/31\\\/un-red-carpet-di-stelle-enologiche-al-park-wine-stars\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2018\\\/01\\\/31\\\/un-red-carpet-di-stelle-enologiche-al-park-wine-stars\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un red carpet di stelle &#8220;enologiche&#8221; al Park Wine Stars\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\",\"name\":\"area-press.eu\",\"description\":\"comunicati stampa &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/daf4c322206ea348f92b0ec56bc9b03f\",\"name\":\"mcsmarketing\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9bb3ac02d9ccd1a828bf30da494976852033a989c3ee1dde41b35a376691cbb5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9bb3ac02d9ccd1a828bf30da494976852033a989c3ee1dde41b35a376691cbb5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9bb3ac02d9ccd1a828bf30da494976852033a989c3ee1dde41b35a376691cbb5?s=96&d=mm&r=g\",\"caption\":\"mcsmarketing\"},\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/author\\\/mcsmarketing\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un red carpet di stelle \"enologiche\" al Park Wine Stars - area-press.eu","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Un red carpet di stelle \"enologiche\" al Park Wine Stars - area-press.eu","og_description":"Nova Gorica, 29 gennaio 2018 &#8211; Torna il Park Wine Stars di Nova Gorica, la kermesse aperta al pubblico dedicata all\u2019eccellenza della produzione vitivinicola slovena: venerd\u00ec 2 febbraio alle 19:00 al Ristorante Tiffany del Park Casin\u00f2 &amp; Hotel 27 cantine, per un totale di 82 etichette, sfileranno su un red carpet d\u2019eccezione, accompagnate come sempre [&hellip;]","og_url":"https:\/\/www.area-press.eu\/comunicatistampa\/2018\/01\/31\/un-red-carpet-di-stelle-enologiche-al-park-wine-stars\/","og_site_name":"area-press.eu","article_published_time":"2018-01-31T01:27:32+00:00","author":"mcsmarketing","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"mcsmarketing","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2018\/01\/31\/un-red-carpet-di-stelle-enologiche-al-park-wine-stars\/#article","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2018\/01\/31\/un-red-carpet-di-stelle-enologiche-al-park-wine-stars\/"},"author":{"name":"mcsmarketing","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/daf4c322206ea348f92b0ec56bc9b03f"},"headline":"Un red carpet di stelle &#8220;enologiche&#8221; al Park Wine Stars","datePublished":"2018-01-31T01:27:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2018\/01\/31\/un-red-carpet-di-stelle-enologiche-al-park-wine-stars\/"},"wordCount":361,"commentCount":0,"keywords":["#gruppohit","#parkwinestars","#primorska"],"articleSection":["Eventi","Gastronomia"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2018\/01\/31\/un-red-carpet-di-stelle-enologiche-al-park-wine-stars\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2018\/01\/31\/un-red-carpet-di-stelle-enologiche-al-park-wine-stars\/","url":"https:\/\/www.area-press.eu\/comunicatistampa\/2018\/01\/31\/un-red-carpet-di-stelle-enologiche-al-park-wine-stars\/","name":"Un red carpet di stelle \"enologiche\" al Park Wine Stars - area-press.eu","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website"},"datePublished":"2018-01-31T01:27:32+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/daf4c322206ea348f92b0ec56bc9b03f"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2018\/01\/31\/un-red-carpet-di-stelle-enologiche-al-park-wine-stars\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2018\/01\/31\/un-red-carpet-di-stelle-enologiche-al-park-wine-stars\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2018\/01\/31\/un-red-carpet-di-stelle-enologiche-al-park-wine-stars\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicatistampa\/"},{"@type":"ListItem","position":2,"name":"Un red carpet di stelle &#8220;enologiche&#8221; al Park Wine Stars"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website","url":"https:\/\/www.area-press.eu\/comunicatistampa\/","name":"area-press.eu","description":"comunicati stampa &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicatistampa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/daf4c322206ea348f92b0ec56bc9b03f","name":"mcsmarketing","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/9bb3ac02d9ccd1a828bf30da494976852033a989c3ee1dde41b35a376691cbb5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9bb3ac02d9ccd1a828bf30da494976852033a989c3ee1dde41b35a376691cbb5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9bb3ac02d9ccd1a828bf30da494976852033a989c3ee1dde41b35a376691cbb5?s=96&d=mm&r=g","caption":"mcsmarketing"},"url":"https:\/\/www.area-press.eu\/comunicatistampa\/author\/mcsmarketing\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/28735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/comments?post=28735"}],"version-history":[{"count":1,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/28735\/revisions"}],"predecessor-version":[{"id":28736,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/28735\/revisions\/28736"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/media?parent=28735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/categories?post=28735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/tags?post=28735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}