{"id":28125,"date":"2018-01-10T01:01:39","date_gmt":"2018-01-10T00:01:39","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicatistampa\/?p=28125"},"modified":"2018-01-10T01:01:39","modified_gmt":"2018-01-10T00:01:39","slug":"anticipazioni-sulla-nuova-edizione-di-save-milano-il-10-aprile-torna-lappuntamento-verticale-per-lindustria-iot-big-data-industry-4-0-efficienza-energetica-e-molto-altro","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicatistampa\/2018\/01\/10\/anticipazioni-sulla-nuova-edizione-di-save-milano-il-10-aprile-torna-lappuntamento-verticale-per-lindustria-iot-big-data-industry-4-0-efficienza-energetica-e-molto-altro\/","title":{"rendered":"Anticipazioni sulla nuova edizione di SAVE Milano  Il 10 aprile torna l\u2019appuntamento verticale per l\u2019industria: IoT, Big Data, Industry 4.0, Efficienza Energetica e molto altro"},"content":{"rendered":"<p>Il prossimo 10 aprile torna la nuova edizione di <strong>SAVE Milano,<\/strong> l\u2019evento verticale di riferimento per le soluzioni e applicazioni di Automazione, Strumentazione, Sensoristica.<\/p>\n<p>Spenti i riflettori sull\u2019eccellente due giorni veronese, che ha visto la partecipazione di oltre 7.400 operatori e pi\u00f9 di 220 aziende, la nuova edizione d\u00e0 appuntamento in primavera ad aziende e operatori qualificati che desiderano incontrarsi, aggiornarsi (grazie ai tanti momenti formativi), trovare nuovi spunti per i differenti mercati industriali, quali Energia, Ambiente, Food &amp; Beverage, Pharma, Chimica e Petrolchimica, Automotive, Gomma e Plastica &#8211; e fare business insieme.<\/p>\n<p>Una giornata per parlare di nuove soluzioni e applicazioni industriali nell\u2019era dei Big Data e della connettivit\u00e0, conoscere le sfide e le opportunit\u00e0 per l\u2019Industry 4.0 che siano punto di riferimento per l\u2019innovazione e per la competitivit\u00e0 dei mercati. Dal processo al manifatturiero, fino all\u2019asset management e alle frontiere della nuova predittiva, dall\u2019alimentare ai sistemi di visione, dalla sensoristica fino alle soluzioni specifiche per l\u2019efficienza energetica, e molto altro.<\/p>\n<p>L\u2019appuntamento meneghino, come sempre \u00e8 sviluppato sulle esigenze di aziende e operatori, prevede una serie di convegni sulle tematiche calde del momento, una parte espositiva con le aziende leader di settore e una sessione pomeridiana con numerosi workshop tecnico-applicativi e corsi di formazione pomeridiani a cura delle aziende partecipanti.<\/p>\n<p><strong>SAVE Milano<\/strong> \u00e8 organizzato da EIOM con il patrocinio di G.I.S.I. (Associazione Imprese Italiane di Strumentazione) che riconosce la mostra quale evento verticale di riferimento per l\u2019automazione e la strumentazione di processo, e la collaborazione e supporto tra gli altri di ANIPLA (Associazione Nazionale per l\u2019Automazione), che ne cura gli aspetti scientifici.<\/p>\n<p>La giornata verticale, per massimizzare le sinergie e le opportunit\u00e0, si svolge inoltre in concomitanza con <strong>MCM Milano<\/strong>, evento leader per la manutenzione industriale, e insieme a <strong>mcT Alimentare \/ Visione e Tracciabilit\u00e0<\/strong>, manifestazione di riferimento per il settore Food &amp; Beverage e la connessa logistica e tracciabilit\u00e0 industriale.<\/p>\n<p>Il programma sar\u00e0 presto disponibile sul sito <a href=\"http:\/\/www.exposave.com\/milano\">www.exposave.com\/milano<\/a> attraverso cui gli operatori interessati potranno anche preregistrarsi per accedere gratuitamente alla manifestazione, partecipare a convegni e workshop e usufruire di tutti i servizi offerti dagli sponsor (coffee break, buffet, attestato di partecipazione, eventuale documentazione scaricabile in PDF dopo gli eventi).<\/p>\n<p><strong>SAVE&lt;<\/strong> vi aspetta a Milano il 10 aprile e anticipa l\u2019edizione autunnale <strong>SAVE<\/strong> <strong>Mostra Convegno dedicata alle Soluzioni e Applicazioni Verticali di Automazione, Strumentazione, Sensori<\/strong> in programma il 17 e 18 ottobre a Veronafier<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il prossimo 10 aprile torna la nuova edizione di SAVE Milano, l\u2019evento verticale di riferimento per le soluzioni e applicazioni di Automazione, Strumentazione, Sensoristica. Spenti i riflettori sull\u2019eccellente due giorni veronese, che ha visto la partecipazione di oltre 7.400 operatori e pi\u00f9 di 220 aziende, la nuova edizione d\u00e0 appuntamento in primavera ad aziende e [&hellip;]<\/p>\n","protected":false},"author":4308,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[29],"tags":[],"class_list":["post-28125","post","type-post","status-publish","format-standard","hentry","category-comunicati"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anticipazioni sulla nuova edizione di SAVE Milano Il 10 aprile torna l\u2019appuntamento verticale per l\u2019industria: IoT, Big Data, Industry 4.0, Efficienza Energetica e molto altro - area-press.eu<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anticipazioni sulla nuova edizione di SAVE Milano Il 10 aprile torna l\u2019appuntamento verticale per l\u2019industria: IoT, Big Data, Industry 4.0, Efficienza Energetica e molto altro - area-press.eu\" \/>\n<meta property=\"og:description\" content=\"Il prossimo 10 aprile torna la nuova edizione di SAVE Milano, l\u2019evento verticale di riferimento per le soluzioni e applicazioni di Automazione, Strumentazione, Sensoristica. Spenti i riflettori sull\u2019eccellente due giorni veronese, che ha visto la partecipazione di oltre 7.400 operatori e pi\u00f9 di 220 aziende, la nuova edizione d\u00e0 appuntamento in primavera ad aziende e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicatistampa\/2018\/01\/10\/anticipazioni-sulla-nuova-edizione-di-save-milano-il-10-aprile-torna-lappuntamento-verticale-per-lindustria-iot-big-data-industry-4-0-efficienza-energetica-e-molto-altro\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-10T00:01:39+00:00\" \/>\n<meta name=\"author\" content=\"BeneEIOM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"BeneEIOM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2018\\\/01\\\/10\\\/anticipazioni-sulla-nuova-edizione-di-save-milano-il-10-aprile-torna-lappuntamento-verticale-per-lindustria-iot-big-data-industry-4-0-efficienza-energetica-e-molto-altro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2018\\\/01\\\/10\\\/anticipazioni-sulla-nuova-edizione-di-save-milano-il-10-aprile-torna-lappuntamento-verticale-per-lindustria-iot-big-data-industry-4-0-efficienza-energetica-e-molto-altro\\\/\"},\"author\":{\"name\":\"BeneEIOM\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/c80574eb1e5cf75f013a73aede5bed61\"},\"headline\":\"Anticipazioni sulla nuova edizione di SAVE Milano Il 10 aprile torna l\u2019appuntamento verticale per l\u2019industria: IoT, Big Data, Industry 4.0, Efficienza Energetica e molto altro\",\"datePublished\":\"2018-01-10T00:01:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2018\\\/01\\\/10\\\/anticipazioni-sulla-nuova-edizione-di-save-milano-il-10-aprile-torna-lappuntamento-verticale-per-lindustria-iot-big-data-industry-4-0-efficienza-energetica-e-molto-altro\\\/\"},\"wordCount\":429,\"commentCount\":0,\"articleSection\":[\"Comunicati\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2018\\\/01\\\/10\\\/anticipazioni-sulla-nuova-edizione-di-save-milano-il-10-aprile-torna-lappuntamento-verticale-per-lindustria-iot-big-data-industry-4-0-efficienza-energetica-e-molto-altro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2018\\\/01\\\/10\\\/anticipazioni-sulla-nuova-edizione-di-save-milano-il-10-aprile-torna-lappuntamento-verticale-per-lindustria-iot-big-data-industry-4-0-efficienza-energetica-e-molto-altro\\\/\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2018\\\/01\\\/10\\\/anticipazioni-sulla-nuova-edizione-di-save-milano-il-10-aprile-torna-lappuntamento-verticale-per-lindustria-iot-big-data-industry-4-0-efficienza-energetica-e-molto-altro\\\/\",\"name\":\"Anticipazioni sulla nuova edizione di SAVE Milano Il 10 aprile torna l\u2019appuntamento verticale per l\u2019industria: IoT, Big Data, Industry 4.0, Efficienza Energetica e molto altro - area-press.eu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\"},\"datePublished\":\"2018-01-10T00:01:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/c80574eb1e5cf75f013a73aede5bed61\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2018\\\/01\\\/10\\\/anticipazioni-sulla-nuova-edizione-di-save-milano-il-10-aprile-torna-lappuntamento-verticale-per-lindustria-iot-big-data-industry-4-0-efficienza-energetica-e-molto-altro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2018\\\/01\\\/10\\\/anticipazioni-sulla-nuova-edizione-di-save-milano-il-10-aprile-torna-lappuntamento-verticale-per-lindustria-iot-big-data-industry-4-0-efficienza-energetica-e-molto-altro\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2018\\\/01\\\/10\\\/anticipazioni-sulla-nuova-edizione-di-save-milano-il-10-aprile-torna-lappuntamento-verticale-per-lindustria-iot-big-data-industry-4-0-efficienza-energetica-e-molto-altro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anticipazioni sulla nuova edizione di SAVE Milano Il 10 aprile torna l\u2019appuntamento verticale per l\u2019industria: IoT, Big Data, Industry 4.0, Efficienza Energetica e molto altro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\",\"name\":\"area-press.eu\",\"description\":\"comunicati stampa &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/c80574eb1e5cf75f013a73aede5bed61\",\"name\":\"BeneEIOM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d9d7854d9684c34bf3e6dcce7f861797f6236ce273d44040d0caf9c7daa081da?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d9d7854d9684c34bf3e6dcce7f861797f6236ce273d44040d0caf9c7daa081da?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d9d7854d9684c34bf3e6dcce7f861797f6236ce273d44040d0caf9c7daa081da?s=96&d=mm&r=g\",\"caption\":\"BeneEIOM\"},\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/author\\\/beneeiom\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anticipazioni sulla nuova edizione di SAVE Milano Il 10 aprile torna l\u2019appuntamento verticale per l\u2019industria: IoT, Big Data, Industry 4.0, Efficienza Energetica e molto altro - area-press.eu","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Anticipazioni sulla nuova edizione di SAVE Milano Il 10 aprile torna l\u2019appuntamento verticale per l\u2019industria: IoT, Big Data, Industry 4.0, Efficienza Energetica e molto altro - area-press.eu","og_description":"Il prossimo 10 aprile torna la nuova edizione di SAVE Milano, l\u2019evento verticale di riferimento per le soluzioni e applicazioni di Automazione, Strumentazione, Sensoristica. Spenti i riflettori sull\u2019eccellente due giorni veronese, che ha visto la partecipazione di oltre 7.400 operatori e pi\u00f9 di 220 aziende, la nuova edizione d\u00e0 appuntamento in primavera ad aziende e [&hellip;]","og_url":"https:\/\/www.area-press.eu\/comunicatistampa\/2018\/01\/10\/anticipazioni-sulla-nuova-edizione-di-save-milano-il-10-aprile-torna-lappuntamento-verticale-per-lindustria-iot-big-data-industry-4-0-efficienza-energetica-e-molto-altro\/","og_site_name":"area-press.eu","article_published_time":"2018-01-10T00:01:39+00:00","author":"BeneEIOM","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"BeneEIOM","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2018\/01\/10\/anticipazioni-sulla-nuova-edizione-di-save-milano-il-10-aprile-torna-lappuntamento-verticale-per-lindustria-iot-big-data-industry-4-0-efficienza-energetica-e-molto-altro\/#article","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2018\/01\/10\/anticipazioni-sulla-nuova-edizione-di-save-milano-il-10-aprile-torna-lappuntamento-verticale-per-lindustria-iot-big-data-industry-4-0-efficienza-energetica-e-molto-altro\/"},"author":{"name":"BeneEIOM","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/c80574eb1e5cf75f013a73aede5bed61"},"headline":"Anticipazioni sulla nuova edizione di SAVE Milano Il 10 aprile torna l\u2019appuntamento verticale per l\u2019industria: IoT, Big Data, Industry 4.0, Efficienza Energetica e molto altro","datePublished":"2018-01-10T00:01:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2018\/01\/10\/anticipazioni-sulla-nuova-edizione-di-save-milano-il-10-aprile-torna-lappuntamento-verticale-per-lindustria-iot-big-data-industry-4-0-efficienza-energetica-e-molto-altro\/"},"wordCount":429,"commentCount":0,"articleSection":["Comunicati"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2018\/01\/10\/anticipazioni-sulla-nuova-edizione-di-save-milano-il-10-aprile-torna-lappuntamento-verticale-per-lindustria-iot-big-data-industry-4-0-efficienza-energetica-e-molto-altro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2018\/01\/10\/anticipazioni-sulla-nuova-edizione-di-save-milano-il-10-aprile-torna-lappuntamento-verticale-per-lindustria-iot-big-data-industry-4-0-efficienza-energetica-e-molto-altro\/","url":"https:\/\/www.area-press.eu\/comunicatistampa\/2018\/01\/10\/anticipazioni-sulla-nuova-edizione-di-save-milano-il-10-aprile-torna-lappuntamento-verticale-per-lindustria-iot-big-data-industry-4-0-efficienza-energetica-e-molto-altro\/","name":"Anticipazioni sulla nuova edizione di SAVE Milano Il 10 aprile torna l\u2019appuntamento verticale per l\u2019industria: IoT, Big Data, Industry 4.0, Efficienza Energetica e molto altro - area-press.eu","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website"},"datePublished":"2018-01-10T00:01:39+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/c80574eb1e5cf75f013a73aede5bed61"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2018\/01\/10\/anticipazioni-sulla-nuova-edizione-di-save-milano-il-10-aprile-torna-lappuntamento-verticale-per-lindustria-iot-big-data-industry-4-0-efficienza-energetica-e-molto-altro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2018\/01\/10\/anticipazioni-sulla-nuova-edizione-di-save-milano-il-10-aprile-torna-lappuntamento-verticale-per-lindustria-iot-big-data-industry-4-0-efficienza-energetica-e-molto-altro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2018\/01\/10\/anticipazioni-sulla-nuova-edizione-di-save-milano-il-10-aprile-torna-lappuntamento-verticale-per-lindustria-iot-big-data-industry-4-0-efficienza-energetica-e-molto-altro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicatistampa\/"},{"@type":"ListItem","position":2,"name":"Anticipazioni sulla nuova edizione di SAVE Milano Il 10 aprile torna l\u2019appuntamento verticale per l\u2019industria: IoT, Big Data, Industry 4.0, Efficienza Energetica e molto altro"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website","url":"https:\/\/www.area-press.eu\/comunicatistampa\/","name":"area-press.eu","description":"comunicati stampa &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicatistampa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/c80574eb1e5cf75f013a73aede5bed61","name":"BeneEIOM","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/d9d7854d9684c34bf3e6dcce7f861797f6236ce273d44040d0caf9c7daa081da?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d9d7854d9684c34bf3e6dcce7f861797f6236ce273d44040d0caf9c7daa081da?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d9d7854d9684c34bf3e6dcce7f861797f6236ce273d44040d0caf9c7daa081da?s=96&d=mm&r=g","caption":"BeneEIOM"},"url":"https:\/\/www.area-press.eu\/comunicatistampa\/author\/beneeiom\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/28125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/users\/4308"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/comments?post=28125"}],"version-history":[{"count":1,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/28125\/revisions"}],"predecessor-version":[{"id":28126,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/28125\/revisions\/28126"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/media?parent=28125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/categories?post=28125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/tags?post=28125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}