{"id":22356,"date":"2017-07-07T02:49:21","date_gmt":"2017-07-07T00:49:21","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicatistampa\/?p=22356"},"modified":"2017-07-07T02:49:21","modified_gmt":"2017-07-07T00:49:21","slug":"wm-capital-la-controllata-alexander-dr-fleming-sagl-presenta-il-box-della-salute","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/07\/07\/wm-capital-la-controllata-alexander-dr-fleming-sagl-presenta-il-box-della-salute\/","title":{"rendered":"WM CAPITAL: LA CONTROLLATA ALEXANDER DR FLEMING SAGL PRESENTA IL \u201cBOX DELLA SALUTE\u201d"},"content":{"rendered":"<p>LA TECNOLOGIA A SERVIZIO DEI  NUOVI SVILUPPI DEL SETTORE DELL\u2019HEALTHCARE<\/p>\n<p>Milano, 6 luglio 2017<\/p>\n<p>Alexander Dr Fleming Sagl, societ\u00e0 svizzera attiva nel settore healthcare con una rete di parafarmacie dei servizi, controllata da WM Capital Spa, quotata su AIM Italia, ha presentato oggi a Milano il Box della salute: check up medico completo in pochi minuti, consulenza di esperti e telemedicina sono gli elementi che contraddistinguono il nuovo progetto \u201cDr Fleming\u201d, che nasce dopo un\u2019attenta ricerca di mercato in campo elettromedicale per unire in un unico \u201cconcept\u201d il Box la tecnologia all\u2019avanguardia e dispositivi medici Made in Italy grazie alla collaborazione del Design Bertone.<\/p>\n<p>Fabio Pasquali, presidente e amministratore delegato di WM Capital Spa, societ\u00e0 quotata nel listino AIM di Borsa Italiana, specializzata nel Business Format Franchising, nonch\u00e9 proprietaria di Alexander Dr Fleming, ha dichiarato: \u201cL\u2019aumento della domanda di assistenza causato dall\u2019invecchiamento della popolazione occidentale, la compressione del tempo libero e una maggiore sensibilit\u00e0 verso i temi del benessere stanno provocando un mutamento del mercato che crediamo oggi sia pronto per una soluzione innovativa come il Box della Salute. I nuovi sviluppi nel settore dell\u2019healthcare si configurano non come una moda passeggera e, come tale effimera, quanto come un nuovo trend strutturato che si sta rafforzando e che nel futuro cambier\u00e0 radicalmente il campo della salute\u201d.<br \/>\nGiorgio Colombo, professore Universit\u00e0 di Pavia, dipartimento di Scienze del Farmaco, ha confermato i cambiamenti profondi non solo delle abitudini degli utenti ma anche degli stessi luoghi della salute. \u201cLa professione del farmacista \u00e8 la professione che, nell\u2019ambito sanitario, ha subito le trasformazioni pi\u00f9 importanti. Nel corso dei secoli, infatti, si \u00e8 passati dall\u2019essere lo speziale, al farmacista contemporaneo, in cui prevale l\u2019aspetto distributivo. Fino ad oggi, in cui si sta cercando di raggiungere l\u2019apice dell\u2019evoluzione, con lo sviluppo della \u201cfarmacia dei servizi\u201d. \u00c8 ormai nota la necessit\u00e0 di pagare il ticket su molte prestazioni sanitarie di base. Il contributo a carico del cittadino pu\u00f2 essere cos\u00ec significativo che \u00e8 diventato talmente oneroso che per alcune prestazioni &#8211; in particolari le pi\u00f9 semplici &#8211; a volte non esiste pi\u00f9 una grande differenza rispetto al costo richiesto da una struttura privata. In questo spazio si pu\u00f2 inserire la farmacia con il Box della Salute per rendere finalmente certificato, universale, validato e riconosciuto il pacchetto di servizi offerti capillarmente sul territorio\u201d.<\/p>\n<p>Aldo Cingolani, CEO di Bertone Design, ha dichiarato: \u201cSiamo orgogliosi di avere partecipato a un progetto cos\u00ec prestigioso. La cura del design e la funzionalit\u00e0 sono stati gli obiettivi principali di questo progetto\u201d.<\/p>\n<p>Il Box della Salute offre una variet\u00e0 di servizi che permettono, in pochi minuti, di avere un quadro completo della propria condizione di salute. Il dispositivo \u00e8 stato dotato delle migliori tecnologie sul mercato in grado, per esempio, di individuare un\u2019eventuale fibrillazione atriale, utile alla prevenzione degli ictus, o, grazie alla spirometria, valutare la presenza di asma bronchiale, fibrosi polmonare, fibrosi cistica e bronco pneumopatia cronica ostruttiva. Oltre alla misurazione di colesterolo e glicemia, nel Box si potr\u00e0 anche mappare i nei e i pattern sub-cutanei, controllare lo stato dell\u2019udito. Inoltre, nel Box della Salute potranno essere integrati servizi diversi, tra cui lo screening del DNA, in relazione sia alla domanda del mercato locale in cui si trova sia alle varie legislazioni regionali.<\/p>\n<p>La presenza di personale specializzato tramite telemedicina o in loco garantir\u00e0 la massima sicurezza e garanzia della correttezza dei risultati e sar\u00e0 a disposizione per consulenze di tipo specialistico.<\/p>\n<p>BERTONE DESIGN (www.bertonedesign.it)<br \/>\nLa Bertone, fondata nel 1912, \u00e8 una delle pi\u00f9 antiche e prestigiose firme del \u201cmade in Italy\u201d nel settore dell\u2019automobile e ne ha accompagnato l\u2019evoluzione tecnologica e stilistica attraverso il suo primo secolo di vita. Con le grandi fuoriserie, dagli esordi dell\u2019azienda agli anni Trenta, hanno entusiasmato il pubblico dei pi\u00f9 esigenti collezionisti e \u201cgetleman-driver\u201d. Sotto la guida di Nuccio, figlio del fondatore, la Bertone entra a vele spiegate negli anni Sessanta, cavalcando il \u201cboom\u201d economico con vetture destinate ad entrare nella storia, ancora una volta sintesi di alta sartoria e tecnologia d\u2019avanguardia. L\u2019evoluzione del settore automotive porta ad una ristrutturazione del gruppo. La Bertone design riparte dal valore del marchio, sotto la guida di Aldo Cingolani, con un team di grande esperienza realizzando progetti come il Frecciarossa 1000 per Trenitalia (2013), Project Zero in collaborazione con Augusta Westland (2013), ed i nuovi spazi espositivi per il Gruppo Graniti Fiandre (2014).<\/p>\n<p>Per maggiori informazioni: www.boxdellasalute.com <\/p>\n<p>Il comunicato stampa \u00e8 disponibile sui siti internet www.wmcapital.it e www.emarketstorage.com<\/p>\n<p>WM Capital (WMC:IM), WM Capital, specializzata nel Business Format Franchising, promuove la crescita delle imprese attraverso lo sviluppo di sistemi franchising in Italia e all\u2019estero, conferendo know-how industriale e operativo e mettendo a disposizione un network qualificato e internazionale. La societ\u00e0 opera nel settore Multimedia attraverso il brand AZ Franchising e nel settore Farmaceutico attraverso la controllata Alexander Dr. Fleming. WM Capital, grazie all\u2019esperienza acquisita nel franchising con lo sviluppo di oltre 600 format, seleziona modelli di business innovativi in settori con elevate potenzialit\u00e0 di crescita e supporta direttamente i sistemi a rete con progetti di sviluppo e possibilit\u00e0 concrete di creare valore nel tempo.<\/p>\n<p>Contatti<\/p>\n<p>WM CAPITAL<br \/>\nEmittente<br \/>\nVia Pontaccio, 2<br \/>\n20121 Milano<br \/>\nTel. +39 02 467781\t<\/p>\n<p>IR TOP CONSULTING<br \/>\nInvestor &amp; Media Relations<br \/>\nir@irtop.com\u2013 ufficiostampa@irtop.com<br \/>\nDomenico Gentile, Antonio Buozzi<br \/>\nVia C. Cant\u00f9, 1 \u2013 20123 Milano<br \/>\nTel. 02 45473884\/3<br \/>\nwww.aimnews.it<\/p>\n<p>BANCA FINNAT<br \/>\nNomAd<br \/>\nAlberto Verna<br \/>\na.verna@finnat.it<br \/>\nPiazza del Ges\u00f9, 49 &#8211; 00186 Roma<br \/>\nTel. +39 06 69933219<br \/>\nwww.finnat.it  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA TECNOLOGIA A SERVIZIO DEI NUOVI SVILUPPI DEL SETTORE DELL\u2019HEALTHCARE Milano, 6 luglio 2017 Alexander Dr Fleming Sagl, societ\u00e0 svizzera attiva nel settore healthcare con una rete di parafarmacie dei servizi, controllata da WM Capital Spa, quotata su AIM Italia, ha presentato oggi a Milano il Box della salute: check up medico completo in pochi [&hellip;]<\/p>\n","protected":false},"author":3367,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[29,8,14],"tags":[],"class_list":["post-22356","post","type-post","status-publish","format-standard","hentry","category-comunicati","category-eventi","category-salute-e-medicina"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WM CAPITAL: LA CONTROLLATA ALEXANDER DR FLEMING SAGL PRESENTA IL \u201cBOX DELLA SALUTE\u201d - area-press.eu<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WM CAPITAL: LA CONTROLLATA ALEXANDER DR FLEMING SAGL PRESENTA IL \u201cBOX DELLA SALUTE\u201d - area-press.eu\" \/>\n<meta property=\"og:description\" content=\"LA TECNOLOGIA A SERVIZIO DEI NUOVI SVILUPPI DEL SETTORE DELL\u2019HEALTHCARE Milano, 6 luglio 2017 Alexander Dr Fleming Sagl, societ\u00e0 svizzera attiva nel settore healthcare con una rete di parafarmacie dei servizi, controllata da WM Capital Spa, quotata su AIM Italia, ha presentato oggi a Milano il Box della salute: check up medico completo in pochi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/07\/07\/wm-capital-la-controllata-alexander-dr-fleming-sagl-presenta-il-box-della-salute\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-07T00:49:21+00:00\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/07\\\/07\\\/wm-capital-la-controllata-alexander-dr-fleming-sagl-presenta-il-box-della-salute\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/07\\\/07\\\/wm-capital-la-controllata-alexander-dr-fleming-sagl-presenta-il-box-della-salute\\\/\"},\"author\":{\"name\":\"Ufficio Stampa\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/31784a0e04e3574d8107e1598b191631\"},\"headline\":\"WM CAPITAL: LA CONTROLLATA ALEXANDER DR FLEMING SAGL PRESENTA IL \u201cBOX DELLA SALUTE\u201d\",\"datePublished\":\"2017-07-07T00:49:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/07\\\/07\\\/wm-capital-la-controllata-alexander-dr-fleming-sagl-presenta-il-box-della-salute\\\/\"},\"wordCount\":922,\"commentCount\":0,\"articleSection\":[\"Comunicati\",\"Eventi\",\"Salute e Medicina\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/07\\\/07\\\/wm-capital-la-controllata-alexander-dr-fleming-sagl-presenta-il-box-della-salute\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/07\\\/07\\\/wm-capital-la-controllata-alexander-dr-fleming-sagl-presenta-il-box-della-salute\\\/\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/07\\\/07\\\/wm-capital-la-controllata-alexander-dr-fleming-sagl-presenta-il-box-della-salute\\\/\",\"name\":\"WM CAPITAL: LA CONTROLLATA ALEXANDER DR FLEMING SAGL PRESENTA IL \u201cBOX DELLA SALUTE\u201d - area-press.eu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\"},\"datePublished\":\"2017-07-07T00:49:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/31784a0e04e3574d8107e1598b191631\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/07\\\/07\\\/wm-capital-la-controllata-alexander-dr-fleming-sagl-presenta-il-box-della-salute\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/07\\\/07\\\/wm-capital-la-controllata-alexander-dr-fleming-sagl-presenta-il-box-della-salute\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/07\\\/07\\\/wm-capital-la-controllata-alexander-dr-fleming-sagl-presenta-il-box-della-salute\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WM CAPITAL: LA CONTROLLATA ALEXANDER DR FLEMING SAGL PRESENTA IL \u201cBOX DELLA SALUTE\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\",\"name\":\"area-press.eu\",\"description\":\"comunicati stampa &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/31784a0e04e3574d8107e1598b191631\",\"name\":\"Ufficio Stampa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4670589d371d4d337d7f620b4a8cc52406b6d3384b891b84c98b6012652eb1bd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4670589d371d4d337d7f620b4a8cc52406b6d3384b891b84c98b6012652eb1bd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4670589d371d4d337d7f620b4a8cc52406b6d3384b891b84c98b6012652eb1bd?s=96&d=mm&r=g\",\"caption\":\"Ufficio Stampa\"},\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/author\\\/valentina-rossi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WM CAPITAL: LA CONTROLLATA ALEXANDER DR FLEMING SAGL PRESENTA IL \u201cBOX DELLA SALUTE\u201d - area-press.eu","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"WM CAPITAL: LA CONTROLLATA ALEXANDER DR FLEMING SAGL PRESENTA IL \u201cBOX DELLA SALUTE\u201d - area-press.eu","og_description":"LA TECNOLOGIA A SERVIZIO DEI NUOVI SVILUPPI DEL SETTORE DELL\u2019HEALTHCARE Milano, 6 luglio 2017 Alexander Dr Fleming Sagl, societ\u00e0 svizzera attiva nel settore healthcare con una rete di parafarmacie dei servizi, controllata da WM Capital Spa, quotata su AIM Italia, ha presentato oggi a Milano il Box della salute: check up medico completo in pochi [&hellip;]","og_url":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/07\/07\/wm-capital-la-controllata-alexander-dr-fleming-sagl-presenta-il-box-della-salute\/","og_site_name":"area-press.eu","article_published_time":"2017-07-07T00:49:21+00:00","author":"Ufficio Stampa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Ufficio Stampa","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/07\/07\/wm-capital-la-controllata-alexander-dr-fleming-sagl-presenta-il-box-della-salute\/#article","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/07\/07\/wm-capital-la-controllata-alexander-dr-fleming-sagl-presenta-il-box-della-salute\/"},"author":{"name":"Ufficio Stampa","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/31784a0e04e3574d8107e1598b191631"},"headline":"WM CAPITAL: LA CONTROLLATA ALEXANDER DR FLEMING SAGL PRESENTA IL \u201cBOX DELLA SALUTE\u201d","datePublished":"2017-07-07T00:49:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/07\/07\/wm-capital-la-controllata-alexander-dr-fleming-sagl-presenta-il-box-della-salute\/"},"wordCount":922,"commentCount":0,"articleSection":["Comunicati","Eventi","Salute e Medicina"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2017\/07\/07\/wm-capital-la-controllata-alexander-dr-fleming-sagl-presenta-il-box-della-salute\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/07\/07\/wm-capital-la-controllata-alexander-dr-fleming-sagl-presenta-il-box-della-salute\/","url":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/07\/07\/wm-capital-la-controllata-alexander-dr-fleming-sagl-presenta-il-box-della-salute\/","name":"WM CAPITAL: LA CONTROLLATA ALEXANDER DR FLEMING SAGL PRESENTA IL \u201cBOX DELLA SALUTE\u201d - area-press.eu","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website"},"datePublished":"2017-07-07T00:49:21+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/31784a0e04e3574d8107e1598b191631"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/07\/07\/wm-capital-la-controllata-alexander-dr-fleming-sagl-presenta-il-box-della-salute\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2017\/07\/07\/wm-capital-la-controllata-alexander-dr-fleming-sagl-presenta-il-box-della-salute\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/07\/07\/wm-capital-la-controllata-alexander-dr-fleming-sagl-presenta-il-box-della-salute\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicatistampa\/"},{"@type":"ListItem","position":2,"name":"WM CAPITAL: LA CONTROLLATA ALEXANDER DR FLEMING SAGL PRESENTA IL \u201cBOX DELLA SALUTE\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website","url":"https:\/\/www.area-press.eu\/comunicatistampa\/","name":"area-press.eu","description":"comunicati stampa &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicatistampa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/31784a0e04e3574d8107e1598b191631","name":"Ufficio Stampa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4670589d371d4d337d7f620b4a8cc52406b6d3384b891b84c98b6012652eb1bd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4670589d371d4d337d7f620b4a8cc52406b6d3384b891b84c98b6012652eb1bd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4670589d371d4d337d7f620b4a8cc52406b6d3384b891b84c98b6012652eb1bd?s=96&d=mm&r=g","caption":"Ufficio Stampa"},"url":"https:\/\/www.area-press.eu\/comunicatistampa\/author\/valentina-rossi\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/22356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/users\/3367"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/comments?post=22356"}],"version-history":[{"count":1,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/22356\/revisions"}],"predecessor-version":[{"id":22357,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/22356\/revisions\/22357"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/media?parent=22356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/categories?post=22356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/tags?post=22356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}