{"id":22075,"date":"2017-06-28T22:44:28","date_gmt":"2017-06-28T20:44:28","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicatistampa\/?p=22075"},"modified":"2017-06-28T22:44:28","modified_gmt":"2017-06-28T20:44:28","slug":"rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/06\/28\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\/","title":{"rendered":"Rai servizio pubblico: Fabio Fazio e la Rai un valore, non un costo"},"content":{"rendered":"<p><i><b>Aldo Cazzullo su Fazio e la RAI<\/b>: \u201cCredo che, quando si stabilisce o si discute il compenso di una persona, non ci si debba chiedere quanto costa, ma quanto vale (\u2026)\u201d.<\/i><\/p>\n<figure class=\"tmblr-full\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/68.media.tumblr.com\/d300d7132bede071eb72a9cb637aa9e2\/tumblr_inline_os7ohjtbwy1um6t4y_500.jpg\" width=\"500\" height=\"262\" \/><\/figure>\n<p><i><br \/>\nCaro Aldo,<br \/>\nmi piacerebbe conoscere la sua opinione sul caso Fazio. Pu\u00f2, deve, il servizio pubblico accettare di pagare un suo \u00abpezzo pregiato\u00bb fior di milioni aumentando il compenso precedente? Avrei voluto vedere se Fazio, andando altrove, si sarebbe portato con s\u00e9 i suoi fan.<br \/>\n<b>Valentina Micillo<\/b>, Milano<\/p>\n<p>Cara Valentina,<br \/>\nHo ricevuto molte lettere sul tema, alcune decisamente pi\u00f9 assertive della sua. Credo che, quando si stabilisce o si discute il compenso di una persona, non ci si debba chiedere quanto costa, ma quanto vale. Fabio Fazio vale molto, e non solo perch\u00e9 le sue trasmissioni incassano molta pubblicit\u00e0, e quindi si ripagano e fanno anzi guadagnare la Rai: per essere concreti, RaiTre perde 15 milioni, ma RaiUno ne guadagna 22.<\/p>\n<p>Per anni Fazio \u00e8 stato l\u2019unico a riuscire a fare una trasmissione di libri in prima serata (al mattino c\u2019\u00e8 quella ormai storica di Corrado Augias). Le trasmissioni di libri non funzionano se hanno un approccio penitenziale, se comunicano questo messaggio: \u00abOra basta guardare sciocchezze, mettiti in ginocchio sui ceci, allaccia il cilicio e diventa migliore\u00bb. Cos\u00ec la gente cambia canale. Se invece il messaggio dice in sostanza \u00abstasera parliamo della vita, ridiamo, ci emozioniamo, ci indigniamo, e se vi interessa c\u2019\u00e8 questo libro\u00bb, allora una parte significativa di pubblico risponde. In questo modo Fazio non solo ha portato in tv David Grossman e Daniel Pennac, Abraham Yehoshua e Emmanuel Carr\u00e8re, Umberto Eco e Mario Vargas Llosa, insomma i pi\u00f9 importanti scrittori del nostro tempo; ha dato loro un pubblico che in altre trasmissioni non avrebbero avuto. Questo non significa condividere tutto quello che Fazio fa o pensa. Ad esempio su Roberto Saviano ho un\u2019opinione diversa dalla sua. Per\u00f2 credo che Fazio interpreti in modo corretto quel che dovrebbe fare il servizio pubblico.<\/p>\n<p>Si parla spesso di dedicare una rete alla cultura, togliendole la pubblicit\u00e0. Sarebbe un esperimento interessante. Ma credo che un canale culturale dovrebbe comunque puntare ad avere un pubblico ampio. Abbiamo, con rare eccezioni, una classe di accademici che disprezzano la divulgazione perch\u00e9 disprezzano il popolo, anzi il volgo, e sono convinti di essere giudicati tanto pi\u00f9 bravi quanto pi\u00f9 sono oscuri. Questo aumenta il ruolo e la responsabilit\u00e0 della tv pubblica nella divulgazione e quindi nella formazione, come sostiene da sempre Piero Angela. Ora suo figlio Alberto ne ha raccolto il testimone. Il problema della Rai \u00e8 avere pi\u00f9 Alberto Angela e pi\u00f9 Fabio Fazio; non meno.<\/p>\n<p><\/i><\/p>\n<p><b>Fonte: \u00a0<\/b><a href=\"http:\/\/t.umblr.com\/redirect?z=http%3A%2F%2Fwww.corriere.it%2Flodicoalcorriere%2Findex%2F27-06-2017%2Findex.shtml&amp;t=ODJkZmZiNzNlYTU3NmViNTE5NmQ2YTIxZTQ5Y2Q5ZDM5OGM1ZWMwYyx5VmVucWwxQQ%3D%3D&amp;b=t%3Aqqaa_03gXObPkgr_Jarv2A&amp;p=https%3A%2F%2Fitaliabrandgroup.tumblr.com%2Fpost%2F162319159242%2Ffabio-fazio-e-la-rai-un-valore-non-un-costo&amp;m=1\">Corriere della Sera<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aldo Cazzullo su Fazio e la RAI: \u201cCredo che, quando si stabilisce o si discute il compenso di una persona, non ci si debba chiedere quanto costa, ma quanto vale (\u2026)\u201d. Caro Aldo, mi piacerebbe conoscere la sua opinione sul caso Fazio. Pu\u00f2, deve, il servizio pubblico accettare di pagare un suo \u00abpezzo pregiato\u00bb fior [&hellip;]<\/p>\n","protected":false},"author":4354,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[13974,3886,14063,13488],"class_list":["post-22075","post","type-post","status-publish","format-standard","hentry","category-attualita-e-societa","tag-fabio-fazio-rai","tag-rai","tag-rai-fazio-cazzullo","tag-rai-servizio-pubblico"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rai servizio pubblico: Fabio Fazio e la Rai un valore, non un costo - area-press.eu<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rai servizio pubblico: Fabio Fazio e la Rai un valore, non un costo - area-press.eu\" \/>\n<meta property=\"og:description\" content=\"Aldo Cazzullo su Fazio e la RAI: \u201cCredo che, quando si stabilisce o si discute il compenso di una persona, non ci si debba chiedere quanto costa, ma quanto vale (\u2026)\u201d. Caro Aldo, mi piacerebbe conoscere la sua opinione sul caso Fazio. Pu\u00f2, deve, il servizio pubblico accettare di pagare un suo \u00abpezzo pregiato\u00bb fior [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/06\/28\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-28T20:44:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/68.media.tumblr.com\/d300d7132bede071eb72a9cb637aa9e2\/tumblr_inline_os7ohjtbwy1um6t4y_500.jpg\" \/>\n<meta name=\"author\" content=\"ItaliaBrandGroup\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ItaliaBrandGroup\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/06\\\/28\\\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/06\\\/28\\\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\\\/\"},\"author\":{\"name\":\"ItaliaBrandGroup\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/93a6799478b5431d2ff4ef55261a4e6d\"},\"headline\":\"Rai servizio pubblico: Fabio Fazio e la Rai un valore, non un costo\",\"datePublished\":\"2017-06-28T20:44:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/06\\\/28\\\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\\\/\"},\"wordCount\":448,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/06\\\/28\\\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/68.media.tumblr.com\\\/d300d7132bede071eb72a9cb637aa9e2\\\/tumblr_inline_os7ohjtbwy1um6t4y_500.jpg\",\"keywords\":[\"Fabio Fazio Rai\",\"Rai\",\"RAI Fazio Cazzullo\",\"RAI servizio pubblico\"],\"articleSection\":[\"Attualit\u00e0 e Societ\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/06\\\/28\\\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/06\\\/28\\\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\\\/\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/06\\\/28\\\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\\\/\",\"name\":\"Rai servizio pubblico: Fabio Fazio e la Rai un valore, non un costo - area-press.eu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/06\\\/28\\\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/06\\\/28\\\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/68.media.tumblr.com\\\/d300d7132bede071eb72a9cb637aa9e2\\\/tumblr_inline_os7ohjtbwy1um6t4y_500.jpg\",\"datePublished\":\"2017-06-28T20:44:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/93a6799478b5431d2ff4ef55261a4e6d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/06\\\/28\\\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/06\\\/28\\\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/06\\\/28\\\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/68.media.tumblr.com\\\/d300d7132bede071eb72a9cb637aa9e2\\\/tumblr_inline_os7ohjtbwy1um6t4y_500.jpg\",\"contentUrl\":\"https:\\\/\\\/68.media.tumblr.com\\\/d300d7132bede071eb72a9cb637aa9e2\\\/tumblr_inline_os7ohjtbwy1um6t4y_500.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/06\\\/28\\\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rai servizio pubblico: Fabio Fazio e la Rai un valore, non un costo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\",\"name\":\"area-press.eu\",\"description\":\"comunicati stampa &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/93a6799478b5431d2ff4ef55261a4e6d\",\"name\":\"ItaliaBrandGroup\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cec91a04faa7795259764297e533534607d8b270d814942c7f7cccc8c2809d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cec91a04faa7795259764297e533534607d8b270d814942c7f7cccc8c2809d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4cec91a04faa7795259764297e533534607d8b270d814942c7f7cccc8c2809d4?s=96&d=mm&r=g\",\"caption\":\"ItaliaBrandGroup\"},\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/author\\\/italiabrandgroup\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rai servizio pubblico: Fabio Fazio e la Rai un valore, non un costo - area-press.eu","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Rai servizio pubblico: Fabio Fazio e la Rai un valore, non un costo - area-press.eu","og_description":"Aldo Cazzullo su Fazio e la RAI: \u201cCredo che, quando si stabilisce o si discute il compenso di una persona, non ci si debba chiedere quanto costa, ma quanto vale (\u2026)\u201d. Caro Aldo, mi piacerebbe conoscere la sua opinione sul caso Fazio. Pu\u00f2, deve, il servizio pubblico accettare di pagare un suo \u00abpezzo pregiato\u00bb fior [&hellip;]","og_url":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/06\/28\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\/","og_site_name":"area-press.eu","article_published_time":"2017-06-28T20:44:28+00:00","og_image":[{"url":"https:\/\/68.media.tumblr.com\/d300d7132bede071eb72a9cb637aa9e2\/tumblr_inline_os7ohjtbwy1um6t4y_500.jpg","type":"","width":"","height":""}],"author":"ItaliaBrandGroup","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ItaliaBrandGroup","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/06\/28\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\/#article","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/06\/28\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\/"},"author":{"name":"ItaliaBrandGroup","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/93a6799478b5431d2ff4ef55261a4e6d"},"headline":"Rai servizio pubblico: Fabio Fazio e la Rai un valore, non un costo","datePublished":"2017-06-28T20:44:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/06\/28\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\/"},"wordCount":448,"commentCount":0,"image":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/06\/28\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\/#primaryimage"},"thumbnailUrl":"https:\/\/68.media.tumblr.com\/d300d7132bede071eb72a9cb637aa9e2\/tumblr_inline_os7ohjtbwy1um6t4y_500.jpg","keywords":["Fabio Fazio Rai","Rai","RAI Fazio Cazzullo","RAI servizio pubblico"],"articleSection":["Attualit\u00e0 e Societ\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2017\/06\/28\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/06\/28\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\/","url":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/06\/28\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\/","name":"Rai servizio pubblico: Fabio Fazio e la Rai un valore, non un costo - area-press.eu","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/06\/28\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\/#primaryimage"},"image":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/06\/28\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\/#primaryimage"},"thumbnailUrl":"https:\/\/68.media.tumblr.com\/d300d7132bede071eb72a9cb637aa9e2\/tumblr_inline_os7ohjtbwy1um6t4y_500.jpg","datePublished":"2017-06-28T20:44:28+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/93a6799478b5431d2ff4ef55261a4e6d"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/06\/28\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2017\/06\/28\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/06\/28\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\/#primaryimage","url":"https:\/\/68.media.tumblr.com\/d300d7132bede071eb72a9cb637aa9e2\/tumblr_inline_os7ohjtbwy1um6t4y_500.jpg","contentUrl":"https:\/\/68.media.tumblr.com\/d300d7132bede071eb72a9cb637aa9e2\/tumblr_inline_os7ohjtbwy1um6t4y_500.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/06\/28\/rai-servizio-pubblico-fabio-fazio-e-la-rai-un-valore-non-un-costo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicatistampa\/"},{"@type":"ListItem","position":2,"name":"Rai servizio pubblico: Fabio Fazio e la Rai un valore, non un costo"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website","url":"https:\/\/www.area-press.eu\/comunicatistampa\/","name":"area-press.eu","description":"comunicati stampa &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicatistampa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/93a6799478b5431d2ff4ef55261a4e6d","name":"ItaliaBrandGroup","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4cec91a04faa7795259764297e533534607d8b270d814942c7f7cccc8c2809d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4cec91a04faa7795259764297e533534607d8b270d814942c7f7cccc8c2809d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4cec91a04faa7795259764297e533534607d8b270d814942c7f7cccc8c2809d4?s=96&d=mm&r=g","caption":"ItaliaBrandGroup"},"url":"https:\/\/www.area-press.eu\/comunicatistampa\/author\/italiabrandgroup\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/22075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/users\/4354"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/comments?post=22075"}],"version-history":[{"count":1,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/22075\/revisions"}],"predecessor-version":[{"id":22076,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/22075\/revisions\/22076"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/media?parent=22075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/categories?post=22075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/tags?post=22075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}