{"id":16369,"date":"2017-01-17T17:41:38","date_gmt":"2017-01-17T16:41:38","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicatistampa\/?p=16369"},"modified":"2017-01-17T17:41:38","modified_gmt":"2017-01-17T16:41:38","slug":"1926-1939-litalia-che-affonda-appuntamento-a-cori-con-la-storia-dellantifascismo","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/17\/1926-1939-litalia-che-affonda-appuntamento-a-cori-con-la-storia-dellantifascismo\/","title":{"rendered":"1926-1939, l\u2019Italia che affonda Appuntamento a Cori con la storia dell\u2019antifascismo"},"content":{"rendered":"<p><strong>Sabato 21 Gennaio, alle ore 17:00, presso la Sala conferenze del Museo della Citt\u00e0 e del Territorio di Cori, se ne parler\u00e0 con il prof. Ugo Mancini, uno dei maggiori esperti in materia.<\/strong><\/p>\n<p>Sabato 21 Gennaio, alle ore 17:00, torna a Cori l\u2019appuntamento con la storia locale. Presso la Sala conferenze del Museo della Citt\u00e0 e del Territorio, il professor <strong>Ugo Mancini<\/strong>, presidente della sezione Anpi di Genzano, presenter\u00e0 il suo ultimo libro \u201c<strong>1926-1939, L\u2019ITALIA AFFONDA. <\/strong><strong>Ragioni e vicende degli antifascisti a Roma e nei Castelli Romani\u201d<\/strong> pubblicato da Infinito Edizioni.<\/p>\n<p>L\u2019evento, organizzato dall\u2019<strong>Associazione Famigliari Vittime dei Bombardamenti di \u2018Propaganda Fide\u2019 ONLUS<\/strong>, \u00e8 patrocinato dal <strong>Comune di Cori<\/strong>. Porteranno i saluti istituzionali il Sindaco di Cori <strong>Tommaso Conti<\/strong> e la Presidente della ONLUS <strong>Ada Scalchi<\/strong>. La presentazione \u00e8 affidata allo scrittore e saggista <strong>Pietro Vitelli<\/strong>. Moderatrice dell\u2019incontro la professoressa e autrice <strong>Secondina Marafini<\/strong>.<\/p>\n<p>Roma e la sua provincia hanno dato una spinta decisiva al movimento antifascista, con grande contributo di sangue. Questo libro, firmato da uno dei maggiori esperti della materia per il 70\u00b0 anniversario della fine della Seconda Guerra Mondiale, <strong>racconta le vite di perseguitati e persecutori<\/strong>, tracciando una inquietante linea nera che porta fino agli attuali rigurgiti nazionalistici e xenofobi.<\/p>\n<p>Il fascismo \u00e8 stata una <strong>tragica esperienza<\/strong>, frutto di un <strong>bisogno di autoritarismo maturato dalle masse<\/strong>, senza il cui beneplacito non ci sarebbe mai stata una dittatura fascista. Contro di essa nacque un <strong>movimento antifascista<\/strong>, per anni perseguitato e minoritario, clandestino, apparentemente vicino alla sconfitta, ma destinato a incrementare la sua forza man mano che il regime perdeva consenso.<\/p>\n<p><strong>Ugo Mancini<\/strong> insegna storia e filosofia al liceo classico Ugo Foscolo di Albano Laziale e storia contemporanea all&#8217;Universit\u00e0 della Terza et\u00e0 di Ariccia. Ha collaborato con le Universit\u00e0 di Roma La Sapienza e Tor Vergata, con il Museo Storico della Liberazione di Roma. \u00c8 autore di pubblicazioni letterarie, ma soprattutto di articoli, monografie, saggi e manuali scolastici di carattere storico.<\/p>\n<p><a href=\"http:\/\/ufficiostampaolmr.wix.com\/marcocastaldi\">Marco Castaldi<\/a><\/p>\n<p><a href=\"http:\/\/ufficiostampaolmr.wix.com\/marcocastaldi\">Addetto Stampa &amp; OLMR<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabato 21 Gennaio, alle ore 17:00, presso la Sala conferenze del Museo della Citt\u00e0 e del Territorio di Cori, se ne parler\u00e0 con il prof. Ugo Mancini, uno dei maggiori esperti in materia. Sabato 21 Gennaio, alle ore 17:00, torna a Cori l\u2019appuntamento con la storia locale. Presso la Sala conferenze del Museo della Citt\u00e0 [&hellip;]<\/p>\n","protected":false},"author":659,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-16369","post","type-post","status-publish","format-standard","hentry","category-eventi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>1926-1939, l\u2019Italia che affonda Appuntamento a Cori con la storia dell\u2019antifascismo - area-press.eu<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1926-1939, l\u2019Italia che affonda Appuntamento a Cori con la storia dell\u2019antifascismo - area-press.eu\" \/>\n<meta property=\"og:description\" content=\"Sabato 21 Gennaio, alle ore 17:00, presso la Sala conferenze del Museo della Citt\u00e0 e del Territorio di Cori, se ne parler\u00e0 con il prof. Ugo Mancini, uno dei maggiori esperti in materia. Sabato 21 Gennaio, alle ore 17:00, torna a Cori l\u2019appuntamento con la storia locale. Presso la Sala conferenze del Museo della Citt\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/17\/1926-1939-litalia-che-affonda-appuntamento-a-cori-con-la-storia-dellantifascismo\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-17T16:41:38+00:00\" \/>\n<meta name=\"author\" content=\"MarcoCastaldi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"MarcoCastaldi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/01\\\/17\\\/1926-1939-litalia-che-affonda-appuntamento-a-cori-con-la-storia-dellantifascismo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/01\\\/17\\\/1926-1939-litalia-che-affonda-appuntamento-a-cori-con-la-storia-dellantifascismo\\\/\"},\"author\":{\"name\":\"MarcoCastaldi\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/1498a199e083856d2143af73c8c83e3d\"},\"headline\":\"1926-1939, l\u2019Italia che affonda Appuntamento a Cori con la storia dell\u2019antifascismo\",\"datePublished\":\"2017-01-17T16:41:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/01\\\/17\\\/1926-1939-litalia-che-affonda-appuntamento-a-cori-con-la-storia-dellantifascismo\\\/\"},\"wordCount\":336,\"commentCount\":0,\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/01\\\/17\\\/1926-1939-litalia-che-affonda-appuntamento-a-cori-con-la-storia-dellantifascismo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/01\\\/17\\\/1926-1939-litalia-che-affonda-appuntamento-a-cori-con-la-storia-dellantifascismo\\\/\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/01\\\/17\\\/1926-1939-litalia-che-affonda-appuntamento-a-cori-con-la-storia-dellantifascismo\\\/\",\"name\":\"1926-1939, l\u2019Italia che affonda Appuntamento a Cori con la storia dell\u2019antifascismo - area-press.eu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\"},\"datePublished\":\"2017-01-17T16:41:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/1498a199e083856d2143af73c8c83e3d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/01\\\/17\\\/1926-1939-litalia-che-affonda-appuntamento-a-cori-con-la-storia-dellantifascismo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/01\\\/17\\\/1926-1939-litalia-che-affonda-appuntamento-a-cori-con-la-storia-dellantifascismo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/01\\\/17\\\/1926-1939-litalia-che-affonda-appuntamento-a-cori-con-la-storia-dellantifascismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"1926-1939, l\u2019Italia che affonda Appuntamento a Cori con la storia dell\u2019antifascismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\",\"name\":\"area-press.eu\",\"description\":\"comunicati stampa &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/1498a199e083856d2143af73c8c83e3d\",\"name\":\"MarcoCastaldi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5a0d370d2ed97c587ca06b2b1651cad1bdeec1c292dc18492ccf71dfc4171a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5a0d370d2ed97c587ca06b2b1651cad1bdeec1c292dc18492ccf71dfc4171a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5a0d370d2ed97c587ca06b2b1651cad1bdeec1c292dc18492ccf71dfc4171a3?s=96&d=mm&r=g\",\"caption\":\"MarcoCastaldi\"},\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/author\\\/marcocastaldi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1926-1939, l\u2019Italia che affonda Appuntamento a Cori con la storia dell\u2019antifascismo - area-press.eu","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"1926-1939, l\u2019Italia che affonda Appuntamento a Cori con la storia dell\u2019antifascismo - area-press.eu","og_description":"Sabato 21 Gennaio, alle ore 17:00, presso la Sala conferenze del Museo della Citt\u00e0 e del Territorio di Cori, se ne parler\u00e0 con il prof. Ugo Mancini, uno dei maggiori esperti in materia. Sabato 21 Gennaio, alle ore 17:00, torna a Cori l\u2019appuntamento con la storia locale. Presso la Sala conferenze del Museo della Citt\u00e0 [&hellip;]","og_url":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/17\/1926-1939-litalia-che-affonda-appuntamento-a-cori-con-la-storia-dellantifascismo\/","og_site_name":"area-press.eu","article_published_time":"2017-01-17T16:41:38+00:00","author":"MarcoCastaldi","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"MarcoCastaldi","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/17\/1926-1939-litalia-che-affonda-appuntamento-a-cori-con-la-storia-dellantifascismo\/#article","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/17\/1926-1939-litalia-che-affonda-appuntamento-a-cori-con-la-storia-dellantifascismo\/"},"author":{"name":"MarcoCastaldi","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/1498a199e083856d2143af73c8c83e3d"},"headline":"1926-1939, l\u2019Italia che affonda Appuntamento a Cori con la storia dell\u2019antifascismo","datePublished":"2017-01-17T16:41:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/17\/1926-1939-litalia-che-affonda-appuntamento-a-cori-con-la-storia-dellantifascismo\/"},"wordCount":336,"commentCount":0,"articleSection":["Eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/17\/1926-1939-litalia-che-affonda-appuntamento-a-cori-con-la-storia-dellantifascismo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/17\/1926-1939-litalia-che-affonda-appuntamento-a-cori-con-la-storia-dellantifascismo\/","url":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/17\/1926-1939-litalia-che-affonda-appuntamento-a-cori-con-la-storia-dellantifascismo\/","name":"1926-1939, l\u2019Italia che affonda Appuntamento a Cori con la storia dell\u2019antifascismo - area-press.eu","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website"},"datePublished":"2017-01-17T16:41:38+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/1498a199e083856d2143af73c8c83e3d"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/17\/1926-1939-litalia-che-affonda-appuntamento-a-cori-con-la-storia-dellantifascismo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/17\/1926-1939-litalia-che-affonda-appuntamento-a-cori-con-la-storia-dellantifascismo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/17\/1926-1939-litalia-che-affonda-appuntamento-a-cori-con-la-storia-dellantifascismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicatistampa\/"},{"@type":"ListItem","position":2,"name":"1926-1939, l\u2019Italia che affonda Appuntamento a Cori con la storia dell\u2019antifascismo"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website","url":"https:\/\/www.area-press.eu\/comunicatistampa\/","name":"area-press.eu","description":"comunicati stampa &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicatistampa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/1498a199e083856d2143af73c8c83e3d","name":"MarcoCastaldi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a5a0d370d2ed97c587ca06b2b1651cad1bdeec1c292dc18492ccf71dfc4171a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a5a0d370d2ed97c587ca06b2b1651cad1bdeec1c292dc18492ccf71dfc4171a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a5a0d370d2ed97c587ca06b2b1651cad1bdeec1c292dc18492ccf71dfc4171a3?s=96&d=mm&r=g","caption":"MarcoCastaldi"},"url":"https:\/\/www.area-press.eu\/comunicatistampa\/author\/marcocastaldi\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/16369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/users\/659"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/comments?post=16369"}],"version-history":[{"count":1,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/16369\/revisions"}],"predecessor-version":[{"id":16370,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/16369\/revisions\/16370"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/media?parent=16369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/categories?post=16369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/tags?post=16369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}