{"id":16064,"date":"2017-01-09T00:34:14","date_gmt":"2017-01-08T23:34:14","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicatistampa\/?p=16064"},"modified":"2017-01-09T00:34:14","modified_gmt":"2017-01-08T23:34:14","slug":"la-farfalla-dombra-e-non-chiamatelo-fantasy","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/09\/la-farfalla-dombra-e-non-chiamatelo-fantasy\/","title":{"rendered":"\u201cLa Farfalla d\u2019Ombra\u201d &#8230;E non chiamatelo fantasy!"},"content":{"rendered":"<p>\t<!-- @page { margin: 2cm } P { margin-bottom: 0.21cm } -->\t<\/p>\n<p><em>Non solo abbigliamento su misura e servizi fotografici: dal calderone di Steam Butterfly emerge il romanzo \u201cLa Farfalla d\u2019Ombra\u201d.<\/em><\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.notiziabile.it\/images\/newsroom\/copertinaebook_n.jpg\" alt=\"Cover de \u201cLa Farfalla d\u2019Ombra\u201d\" \/><\/p>\n<p>Tutto comincia il giorno delle nozze di Yalihta, matrimonio combinato dalla madre con un uomo ben pi\u00f9 anziano ma ricco, e il suo destino sembra essere gi\u00e0 irrevocabilmente scritto, a met\u00e0 tra prole e lavori all\u2019uncinetto. Invece finisce col ritrovarsi braccata e ferita, ben lontana dagli agi e dalle comodit\u00e0 della sua casa, e si salva solo grazie al soccorso di due cavalieri, che sono soltanto i primi di una serie di straordinari personaggi che animeranno la sua esistenza.<br \/>\nDa innocente giovinetta, passando dalla vita di strada, conosce il vizio del bere, impara svariati mestieri, vive i primi amori, guida un gruppo di fanatici antivampiri, per diventare infine vampira ella stessa.<br \/>\nSar\u00e0 il protagonista maschile del romanzo, Lord Malesh Ruben De Vaurien, un antico vampiro, ad accompagnarla nell\u2019ultimo capitolo della sua vita umana; egli le doner\u00e0 la vita eterna, una nuova esistenza in cui Yalihta sar\u00e0 predatrice, ma questo non la render\u00e0 immune ai dolori e alle delusioni degli umani.<br \/>\nImmancabile presenza al fianco di Yalihta \u00e8 una farfalla blu di nome Ita, uscita direttamente da una visione creata dal Mago, che mago non \u00e8; proprio per questa piccola creatura alata, Yalihta viene ribattezzata con il nome di \u201cFarfalla d\u2019Ombra\u201d.<br \/>\n\u201cLa Farfalla d\u2019Ombra\u201d non \u00e8 un romance, anche se l\u2019amore, in forme talvolta bizzarre, vi fa capolino; non \u00e8 propriamente un fantasy, nonostante la presenza di vampiri; non \u00e8 un horror; non \u00e8 erotico, sebbene vi siano momenti carichi di una particolare tensione sessuale&#8230;<\/p>\n<p>\u201cLa Farfalla d\u2019Ombra\u201d \u00e8 una storia, narrata attraverso gli occhi e la voce di chi l\u2019ha vissuta.<\/p>\n<p><strong>\u201cLa Farfalla d\u2019Ombra\u201d, di Yali Ou Ametistha<\/strong><\/p>\n<p>Formati Kindle e cartaceo: <a href=\"https:\/\/www.amazon.it\/dp\/B01N5K7AMP\">https:\/\/www.amazon.it\/dp\/B01N5K7AMP<\/a><\/p>\n<p>Formato Kobo: <a href=\"https:\/\/www.kobo.com\/it\/it\/ebook\/la-farfalla-d-ombra\">https:\/\/www.kobo.com\/it\/it\/ebook\/la-farfalla-d-ombra<\/a><\/p>\n<p><em>Due parole sull\u2019autrice.<\/em><br \/>\n<em>Yali Ou Ametistha nasce a Venaria Reale nel 1977. \u00c8 fotografa, stilista, costumista, grafica, appassionata di marketing, lettrice e scrittrice. Possiede due diplomi: uno come maestro d\u2019arte e l\u2019altro come disegnatrice di moda e costume. Nel corso degli anni, ottiene varie specializzazioni tra cui: fotografia, ripresa e montaggio video, disegno e studio dei tessuti, canto, marketing e grafica. Raccoglie tutte le competenze che ha accumulato e si butta nel mondo del lavoro. Viaggia, ma ritorna a Torino, la citt\u00e0 in cui ha vissuto da quando \u00e8 nata. Dopo aver fatto esperienza nei settori pi\u00f9 disparati, molla tutto, si trasferisce a Firenze e comincia a costruire il mondo di Steam Butterfly, un multilab dove nascono abiti da sposa, costumi d\u2019epoca, cappelli stravaganti, servizi fotografici, copertine di libri\u2026 e libri.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Non solo abbigliamento su misura e servizi fotografici: dal calderone di Steam Butterfly emerge il romanzo \u201cLa Farfalla d\u2019Ombra\u201d. Tutto comincia il giorno delle nozze di Yalihta, matrimonio combinato dalla madre con un uomo ben pi\u00f9 anziano ma ricco, e il suo destino sembra essere gi\u00e0 irrevocabilmente scritto, a met\u00e0 tra prole e lavori all\u2019uncinetto. [&hellip;]<\/p>\n","protected":false},"author":3811,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[29],"tags":[],"class_list":["post-16064","post","type-post","status-publish","format-standard","hentry","category-comunicati"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cLa Farfalla d\u2019Ombra\u201d ...E non chiamatelo fantasy! - area-press.eu<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cLa Farfalla d\u2019Ombra\u201d ...E non chiamatelo fantasy! - area-press.eu\" \/>\n<meta property=\"og:description\" content=\"Non solo abbigliamento su misura e servizi fotografici: dal calderone di Steam Butterfly emerge il romanzo \u201cLa Farfalla d\u2019Ombra\u201d. Tutto comincia il giorno delle nozze di Yalihta, matrimonio combinato dalla madre con un uomo ben pi\u00f9 anziano ma ricco, e il suo destino sembra essere gi\u00e0 irrevocabilmente scritto, a met\u00e0 tra prole e lavori all\u2019uncinetto. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/09\/la-farfalla-dombra-e-non-chiamatelo-fantasy\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-08T23:34:14+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.notiziabile.it\/images\/newsroom\/copertinaebook_n.jpg\" \/>\n<meta name=\"author\" content=\"ireneemme\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"ireneemme\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/01\\\/09\\\/la-farfalla-dombra-e-non-chiamatelo-fantasy\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/01\\\/09\\\/la-farfalla-dombra-e-non-chiamatelo-fantasy\\\/\"},\"author\":{\"name\":\"ireneemme\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/748a58c930a6edc3741ae395784568c5\"},\"headline\":\"\u201cLa Farfalla d\u2019Ombra\u201d &#8230;E non chiamatelo fantasy!\",\"datePublished\":\"2017-01-08T23:34:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/01\\\/09\\\/la-farfalla-dombra-e-non-chiamatelo-fantasy\\\/\"},\"wordCount\":452,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/01\\\/09\\\/la-farfalla-dombra-e-non-chiamatelo-fantasy\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.notiziabile.it\\\/images\\\/newsroom\\\/copertinaebook_n.jpg\",\"articleSection\":[\"Comunicati\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/01\\\/09\\\/la-farfalla-dombra-e-non-chiamatelo-fantasy\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/01\\\/09\\\/la-farfalla-dombra-e-non-chiamatelo-fantasy\\\/\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/01\\\/09\\\/la-farfalla-dombra-e-non-chiamatelo-fantasy\\\/\",\"name\":\"\u201cLa Farfalla d\u2019Ombra\u201d ...E non chiamatelo fantasy! - area-press.eu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/01\\\/09\\\/la-farfalla-dombra-e-non-chiamatelo-fantasy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/01\\\/09\\\/la-farfalla-dombra-e-non-chiamatelo-fantasy\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.notiziabile.it\\\/images\\\/newsroom\\\/copertinaebook_n.jpg\",\"datePublished\":\"2017-01-08T23:34:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/748a58c930a6edc3741ae395784568c5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/01\\\/09\\\/la-farfalla-dombra-e-non-chiamatelo-fantasy\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/01\\\/09\\\/la-farfalla-dombra-e-non-chiamatelo-fantasy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/01\\\/09\\\/la-farfalla-dombra-e-non-chiamatelo-fantasy\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.notiziabile.it\\\/images\\\/newsroom\\\/copertinaebook_n.jpg\",\"contentUrl\":\"http:\\\/\\\/www.notiziabile.it\\\/images\\\/newsroom\\\/copertinaebook_n.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2017\\\/01\\\/09\\\/la-farfalla-dombra-e-non-chiamatelo-fantasy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cLa Farfalla d\u2019Ombra\u201d &#8230;E non chiamatelo fantasy!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\",\"name\":\"area-press.eu\",\"description\":\"comunicati stampa &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/748a58c930a6edc3741ae395784568c5\",\"name\":\"ireneemme\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d2312e940438bd8021706fe7be8dd6976b5ac4a4caec29a309200b42edb8315?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d2312e940438bd8021706fe7be8dd6976b5ac4a4caec29a309200b42edb8315?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d2312e940438bd8021706fe7be8dd6976b5ac4a4caec29a309200b42edb8315?s=96&d=mm&r=g\",\"caption\":\"ireneemme\"},\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/author\\\/ireneemme\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cLa Farfalla d\u2019Ombra\u201d ...E non chiamatelo fantasy! - area-press.eu","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"\u201cLa Farfalla d\u2019Ombra\u201d ...E non chiamatelo fantasy! - area-press.eu","og_description":"Non solo abbigliamento su misura e servizi fotografici: dal calderone di Steam Butterfly emerge il romanzo \u201cLa Farfalla d\u2019Ombra\u201d. Tutto comincia il giorno delle nozze di Yalihta, matrimonio combinato dalla madre con un uomo ben pi\u00f9 anziano ma ricco, e il suo destino sembra essere gi\u00e0 irrevocabilmente scritto, a met\u00e0 tra prole e lavori all\u2019uncinetto. [&hellip;]","og_url":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/09\/la-farfalla-dombra-e-non-chiamatelo-fantasy\/","og_site_name":"area-press.eu","article_published_time":"2017-01-08T23:34:14+00:00","og_image":[{"url":"http:\/\/www.notiziabile.it\/images\/newsroom\/copertinaebook_n.jpg","type":"","width":"","height":""}],"author":"ireneemme","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"ireneemme","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/09\/la-farfalla-dombra-e-non-chiamatelo-fantasy\/#article","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/09\/la-farfalla-dombra-e-non-chiamatelo-fantasy\/"},"author":{"name":"ireneemme","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/748a58c930a6edc3741ae395784568c5"},"headline":"\u201cLa Farfalla d\u2019Ombra\u201d &#8230;E non chiamatelo fantasy!","datePublished":"2017-01-08T23:34:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/09\/la-farfalla-dombra-e-non-chiamatelo-fantasy\/"},"wordCount":452,"commentCount":0,"image":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/09\/la-farfalla-dombra-e-non-chiamatelo-fantasy\/#primaryimage"},"thumbnailUrl":"http:\/\/www.notiziabile.it\/images\/newsroom\/copertinaebook_n.jpg","articleSection":["Comunicati"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/09\/la-farfalla-dombra-e-non-chiamatelo-fantasy\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/09\/la-farfalla-dombra-e-non-chiamatelo-fantasy\/","url":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/09\/la-farfalla-dombra-e-non-chiamatelo-fantasy\/","name":"\u201cLa Farfalla d\u2019Ombra\u201d ...E non chiamatelo fantasy! - area-press.eu","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/09\/la-farfalla-dombra-e-non-chiamatelo-fantasy\/#primaryimage"},"image":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/09\/la-farfalla-dombra-e-non-chiamatelo-fantasy\/#primaryimage"},"thumbnailUrl":"http:\/\/www.notiziabile.it\/images\/newsroom\/copertinaebook_n.jpg","datePublished":"2017-01-08T23:34:14+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/748a58c930a6edc3741ae395784568c5"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/09\/la-farfalla-dombra-e-non-chiamatelo-fantasy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/09\/la-farfalla-dombra-e-non-chiamatelo-fantasy\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/09\/la-farfalla-dombra-e-non-chiamatelo-fantasy\/#primaryimage","url":"http:\/\/www.notiziabile.it\/images\/newsroom\/copertinaebook_n.jpg","contentUrl":"http:\/\/www.notiziabile.it\/images\/newsroom\/copertinaebook_n.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2017\/01\/09\/la-farfalla-dombra-e-non-chiamatelo-fantasy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicatistampa\/"},{"@type":"ListItem","position":2,"name":"\u201cLa Farfalla d\u2019Ombra\u201d &#8230;E non chiamatelo fantasy!"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website","url":"https:\/\/www.area-press.eu\/comunicatistampa\/","name":"area-press.eu","description":"comunicati stampa &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicatistampa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/748a58c930a6edc3741ae395784568c5","name":"ireneemme","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5d2312e940438bd8021706fe7be8dd6976b5ac4a4caec29a309200b42edb8315?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5d2312e940438bd8021706fe7be8dd6976b5ac4a4caec29a309200b42edb8315?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5d2312e940438bd8021706fe7be8dd6976b5ac4a4caec29a309200b42edb8315?s=96&d=mm&r=g","caption":"ireneemme"},"url":"https:\/\/www.area-press.eu\/comunicatistampa\/author\/ireneemme\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/16064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/users\/3811"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/comments?post=16064"}],"version-history":[{"count":1,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/16064\/revisions"}],"predecessor-version":[{"id":16068,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/16064\/revisions\/16068"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/media?parent=16064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/categories?post=16064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/tags?post=16064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}