{"id":14843,"date":"2016-12-03T11:57:59","date_gmt":"2016-12-03T10:57:59","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicatistampa\/?p=14843"},"modified":"2016-12-03T11:57:59","modified_gmt":"2016-12-03T10:57:59","slug":"educazione-alimentare-e-mangiar-sano-a-cori","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicatistampa\/2016\/12\/03\/educazione-alimentare-e-mangiar-sano-a-cori\/","title":{"rendered":"Educazione alimentare e mangiar sano a Cori"},"content":{"rendered":"<p><strong>Olivicoltura ed enogastronomia entro la cornice storico-monumentale di Sant\u2019Oliva, tra cultura, folklore, musica polifonica corale<\/strong><\/p>\n<p>Le giornate del 3 e 4 Dicembre dell\u2019evento <strong>\u2018Cori: dell\u2019Olio e delle Olive\u2019 2016<\/strong> saranno occasione per entrare in contatto con gli olivicoltori del <strong>territorio di Cori, che cade nella zona di produzione olearia laziale a marchio DOP Colline Pontine,<\/strong> ed educare il pubblico alla cultura dell\u2019olio di qualit\u00e0. L\u2019incantevole scenario del Complesso Monumentale di Sant\u2019Oliva si prester\u00e0 anche a tutti i buon gustai e amanti del mangiare sano.<\/p>\n<p>Sabato mattina (10:30) a Palazzetto Luciani si volgeranno le <strong>degustazioni guidate ed informate dell\u2019olio extravergine di oliva e dell\u2019oliva da mensa Gaeta e Itrana Bianca<\/strong>, riproposte anche domenica pomeriggio (16:00). Nella mattinata gli assaggiatori professionisti del Capol accoglieranno gli studenti per una seduta di educazione alimentare.<\/p>\n<p>I bambini del servizio aggiuntivo comunale \u2018Il Bruco Verde\u2019 e le classi quinte dell\u2019istituto comprensivo \u2018Cesare Chiominto\u2019 andranno a \u2018<strong>Scuola di olio extravergine di oliva\u2019<\/strong>. Impareranno come nasce e come si riconosce un vero EVOO. Reciteranno poesie, intoneranno canti ed esporranno i loro disegni a tema nel loggiato del Chiostro di Sant\u2019Oliva.<\/p>\n<p>Domenica mattina (10:30) nella Sala Conferenze del Museo della Citt\u00e0 e del Territorio di Cori si svolger\u00e0 il <strong>convegno<\/strong> \u2018<strong>Olio da itrana un grande alleato per preservare la salute.<\/strong> <strong>L\u2019analisi organolettica nel percorso di valorizzazione dell\u2019olio extra<\/strong> <strong>vergine<\/strong> <strong>della cultivar itrana\u2019, <\/strong>con interventi di esperti del settore e rappresentanti istituzionali. Verranno presentati anche i risultati della recente ricerca sulle qualit\u00e0 antitumorali dell\u2019EVOO.<\/p>\n<p>Le due serate (20:00) di <strong>Street Food<\/strong> saranno un inno agli ottimi abbinamenti olio\/cibo della cucina corese. Negli spazi dedicati sar\u00e0 possibile cenare con menu tipici a prezzo fisso. Protagonisti saranno l\u2019<strong>olio EVO<\/strong>,<strong> da sempre ingrediente principe delle<\/strong> ricette locali, e il <strong>Nero Buono di Cori<\/strong>, <strong>antichissimo vitigno autoctono, <\/strong>dalle documentate e peculiari caratteristiche qualitative, <strong>con cui si producono vini rossi di elevatissima qualit\u00e0. <\/strong><\/p>\n<p>Da non perdere inoltre. <strong>Visite guidate gratuite del Museo <\/strong>(Sabato 15:30 domenica 16:00). <strong>Seminario \u2018<\/strong><strong>Esperienza religiosa e istituzioni ecclesiastiche nella Cori<\/strong> <strong>medievale. Acquisizione e suggestioni storiografiche\u2019<\/strong> e <strong>presentazione Fondo Banfuso<\/strong> (Sabato 16:30 sala conferenze Museo). <strong>Esibizione degli sbandieratori<\/strong> (Domenica 12:30 piazza S.Oliva). <strong>7^ Rassegna di polifonia corale \u201cHenning Nielsen\u201d<\/strong> (Domenica 18:00 Chiesa di S.Oliva).<\/p>\n<p><em><a href=\"http:\/\/ufficiostampaolmr.wix.com\/marcocastaldi\">Marco Castaldi<\/a><\/em><\/p>\n<p><em><a href=\"http:\/\/ufficiostampaolmr.wix.com\/marcocastaldi\">Addetto Stampa &amp; OLMR<\/a><\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Olivicoltura ed enogastronomia entro la cornice storico-monumentale di Sant\u2019Oliva, tra cultura, folklore, musica polifonica corale Le giornate del 3 e 4 Dicembre dell\u2019evento \u2018Cori: dell\u2019Olio e delle Olive\u2019 2016 saranno occasione per entrare in contatto con gli olivicoltori del territorio di Cori, che cade nella zona di produzione olearia laziale a marchio DOP Colline Pontine, [&hellip;]<\/p>\n","protected":false},"author":659,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-14843","post","type-post","status-publish","format-standard","hentry","category-eventi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Educazione alimentare e mangiar sano a Cori - area-press.eu<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Educazione alimentare e mangiar sano a Cori - area-press.eu\" \/>\n<meta property=\"og:description\" content=\"Olivicoltura ed enogastronomia entro la cornice storico-monumentale di Sant\u2019Oliva, tra cultura, folklore, musica polifonica corale Le giornate del 3 e 4 Dicembre dell\u2019evento \u2018Cori: dell\u2019Olio e delle Olive\u2019 2016 saranno occasione per entrare in contatto con gli olivicoltori del territorio di Cori, che cade nella zona di produzione olearia laziale a marchio DOP Colline Pontine, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicatistampa\/2016\/12\/03\/educazione-alimentare-e-mangiar-sano-a-cori\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-03T10:57:59+00:00\" \/>\n<meta name=\"author\" content=\"MarcoCastaldi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"MarcoCastaldi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2016\\\/12\\\/03\\\/educazione-alimentare-e-mangiar-sano-a-cori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2016\\\/12\\\/03\\\/educazione-alimentare-e-mangiar-sano-a-cori\\\/\"},\"author\":{\"name\":\"MarcoCastaldi\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/1498a199e083856d2143af73c8c83e3d\"},\"headline\":\"Educazione alimentare e mangiar sano a Cori\",\"datePublished\":\"2016-12-03T10:57:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2016\\\/12\\\/03\\\/educazione-alimentare-e-mangiar-sano-a-cori\\\/\"},\"wordCount\":380,\"commentCount\":0,\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2016\\\/12\\\/03\\\/educazione-alimentare-e-mangiar-sano-a-cori\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2016\\\/12\\\/03\\\/educazione-alimentare-e-mangiar-sano-a-cori\\\/\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2016\\\/12\\\/03\\\/educazione-alimentare-e-mangiar-sano-a-cori\\\/\",\"name\":\"Educazione alimentare e mangiar sano a Cori - area-press.eu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\"},\"datePublished\":\"2016-12-03T10:57:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/1498a199e083856d2143af73c8c83e3d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2016\\\/12\\\/03\\\/educazione-alimentare-e-mangiar-sano-a-cori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2016\\\/12\\\/03\\\/educazione-alimentare-e-mangiar-sano-a-cori\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2016\\\/12\\\/03\\\/educazione-alimentare-e-mangiar-sano-a-cori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Educazione alimentare e mangiar sano a Cori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\",\"name\":\"area-press.eu\",\"description\":\"comunicati stampa &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/1498a199e083856d2143af73c8c83e3d\",\"name\":\"MarcoCastaldi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5a0d370d2ed97c587ca06b2b1651cad1bdeec1c292dc18492ccf71dfc4171a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5a0d370d2ed97c587ca06b2b1651cad1bdeec1c292dc18492ccf71dfc4171a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5a0d370d2ed97c587ca06b2b1651cad1bdeec1c292dc18492ccf71dfc4171a3?s=96&d=mm&r=g\",\"caption\":\"MarcoCastaldi\"},\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/author\\\/marcocastaldi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Educazione alimentare e mangiar sano a Cori - area-press.eu","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Educazione alimentare e mangiar sano a Cori - area-press.eu","og_description":"Olivicoltura ed enogastronomia entro la cornice storico-monumentale di Sant\u2019Oliva, tra cultura, folklore, musica polifonica corale Le giornate del 3 e 4 Dicembre dell\u2019evento \u2018Cori: dell\u2019Olio e delle Olive\u2019 2016 saranno occasione per entrare in contatto con gli olivicoltori del territorio di Cori, che cade nella zona di produzione olearia laziale a marchio DOP Colline Pontine, [&hellip;]","og_url":"https:\/\/www.area-press.eu\/comunicatistampa\/2016\/12\/03\/educazione-alimentare-e-mangiar-sano-a-cori\/","og_site_name":"area-press.eu","article_published_time":"2016-12-03T10:57:59+00:00","author":"MarcoCastaldi","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"MarcoCastaldi","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2016\/12\/03\/educazione-alimentare-e-mangiar-sano-a-cori\/#article","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2016\/12\/03\/educazione-alimentare-e-mangiar-sano-a-cori\/"},"author":{"name":"MarcoCastaldi","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/1498a199e083856d2143af73c8c83e3d"},"headline":"Educazione alimentare e mangiar sano a Cori","datePublished":"2016-12-03T10:57:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2016\/12\/03\/educazione-alimentare-e-mangiar-sano-a-cori\/"},"wordCount":380,"commentCount":0,"articleSection":["Eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2016\/12\/03\/educazione-alimentare-e-mangiar-sano-a-cori\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2016\/12\/03\/educazione-alimentare-e-mangiar-sano-a-cori\/","url":"https:\/\/www.area-press.eu\/comunicatistampa\/2016\/12\/03\/educazione-alimentare-e-mangiar-sano-a-cori\/","name":"Educazione alimentare e mangiar sano a Cori - area-press.eu","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website"},"datePublished":"2016-12-03T10:57:59+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/1498a199e083856d2143af73c8c83e3d"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2016\/12\/03\/educazione-alimentare-e-mangiar-sano-a-cori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2016\/12\/03\/educazione-alimentare-e-mangiar-sano-a-cori\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2016\/12\/03\/educazione-alimentare-e-mangiar-sano-a-cori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicatistampa\/"},{"@type":"ListItem","position":2,"name":"Educazione alimentare e mangiar sano a Cori"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website","url":"https:\/\/www.area-press.eu\/comunicatistampa\/","name":"area-press.eu","description":"comunicati stampa &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicatistampa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/1498a199e083856d2143af73c8c83e3d","name":"MarcoCastaldi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a5a0d370d2ed97c587ca06b2b1651cad1bdeec1c292dc18492ccf71dfc4171a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a5a0d370d2ed97c587ca06b2b1651cad1bdeec1c292dc18492ccf71dfc4171a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a5a0d370d2ed97c587ca06b2b1651cad1bdeec1c292dc18492ccf71dfc4171a3?s=96&d=mm&r=g","caption":"MarcoCastaldi"},"url":"https:\/\/www.area-press.eu\/comunicatistampa\/author\/marcocastaldi\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/14843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/users\/659"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/comments?post=14843"}],"version-history":[{"count":1,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/14843\/revisions"}],"predecessor-version":[{"id":14844,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/14843\/revisions\/14844"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/media?parent=14843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/categories?post=14843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/tags?post=14843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}