{"id":14640,"date":"2016-11-30T15:22:39","date_gmt":"2016-11-30T14:22:39","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicatistampa\/?p=14640"},"modified":"2016-11-30T15:22:39","modified_gmt":"2016-11-30T14:22:39","slug":"carta-certificata-ecologica-per-lufficio","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicatistampa\/2016\/11\/30\/carta-certificata-ecologica-per-lufficio\/","title":{"rendered":"Carta certificata ecologica per l&#8217;ufficio"},"content":{"rendered":"<p>Avere un occhio di riguardo per la nostra salute e l&#8217;ambiente che ci circonda significa anche potere <a href=\"http:\/\/cartaufficio.weebly.com\/\">scegliere di acquistare carta riciclata<\/a> o certificata per ufficio, mobili ecologici in ufficio.<br \/>\n&#8220;La carta \u00e8 un driver molto importante della deforestazione in alcune regioni. Attenzione alla carta importata e certificata! &#8220;Avvisa il WWF. &#8220;Anche se la foresta locale aumenta la superficie, abbiamo bisogno di importare legno per i nostri mobili e la loro costruzione. Questo legno pu\u00f2 essere proveniente da fonti illegali o che operano non da partecipante responsabile infatti, aumenta la deforestazione &#8220;, dice l&#8217;Ong.<br \/>\nE &#8216;per queste ragioni che dobbiamo comprare carta certificata o riciclata di questo tipo:<br \/>\n100% di carta riciclata o Evercopy CHATELLES ECO2 +.<br \/>\n55% di carta riciclata &#8211; 45% PEFC CHATELLES certificati NATURA.<br \/>\n30% di carta riciclata &#8211; 70% certificata FSC Inacopia FUSION.<br \/>\nE se dovessimo trovare tre buone ragioni per comprare carta riciclata per l&#8217;ufficio ?<br \/>\n1. Il riciclaggio \u00e8 evitare lo spreco di una risorsa naturale. Bruciare la carta, \u00e8 come bruciare una foresta. La carta pu\u00f2 essere riciclata fino a 5 volte!<br \/>\n2. La produzione di carta riciclata consuma due volte meno energia e 3 volte meno acqua. Pertanto minori emissioni di CO2.<br \/>\n3. Acquistare carta riciclata \u00e8 sviluppare l&#8217;economia circolare e l&#8217;occupazione locale: raccolta, la cernita, la fabbricazione, il trasporto, il marketing &#8230;<br \/>\nLa scarsa qualit\u00e0 dell&#8217;aria interna \u00e8 causata da sostanze inquinanti da riscaldamento, materiali da costruzione, arredamento e prodotti per la pulizia e per la casa. Una soluzione urgente: utilizzare prodotti per la pulizia e detergenti verdi e biologici.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avere un occhio di riguardo per la nostra salute e l&#8217;ambiente che ci circonda significa anche potere scegliere di acquistare carta riciclata o certificata per ufficio, mobili ecologici in ufficio. &#8220;La carta \u00e8 un driver molto importante della deforestazione in alcune regioni. Attenzione alla carta importata e certificata! &#8220;Avvisa il WWF. &#8220;Anche se la foresta [&hellip;]<\/p>\n","protected":false},"author":170,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-14640","post","type-post","status-publish","format-standard","hentry","category-aziendali"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carta certificata ecologica per l&#039;ufficio - area-press.eu<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta certificata ecologica per l&#039;ufficio - area-press.eu\" \/>\n<meta property=\"og:description\" content=\"Avere un occhio di riguardo per la nostra salute e l&#8217;ambiente che ci circonda significa anche potere scegliere di acquistare carta riciclata o certificata per ufficio, mobili ecologici in ufficio. &#8220;La carta \u00e8 un driver molto importante della deforestazione in alcune regioni. Attenzione alla carta importata e certificata! &#8220;Avvisa il WWF. &#8220;Anche se la foresta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicatistampa\/2016\/11\/30\/carta-certificata-ecologica-per-lufficio\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-30T14:22:39+00:00\" \/>\n<meta name=\"author\" content=\"merellir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"merellir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2016\\\/11\\\/30\\\/carta-certificata-ecologica-per-lufficio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2016\\\/11\\\/30\\\/carta-certificata-ecologica-per-lufficio\\\/\"},\"author\":{\"name\":\"merellir\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/343b4d61076bc37f37be1512158f7145\"},\"headline\":\"Carta certificata ecologica per l&#8217;ufficio\",\"datePublished\":\"2016-11-30T14:22:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2016\\\/11\\\/30\\\/carta-certificata-ecologica-per-lufficio\\\/\"},\"wordCount\":245,\"commentCount\":0,\"articleSection\":[\"Aziendali\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2016\\\/11\\\/30\\\/carta-certificata-ecologica-per-lufficio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2016\\\/11\\\/30\\\/carta-certificata-ecologica-per-lufficio\\\/\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2016\\\/11\\\/30\\\/carta-certificata-ecologica-per-lufficio\\\/\",\"name\":\"Carta certificata ecologica per l'ufficio - area-press.eu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\"},\"datePublished\":\"2016-11-30T14:22:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/343b4d61076bc37f37be1512158f7145\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2016\\\/11\\\/30\\\/carta-certificata-ecologica-per-lufficio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2016\\\/11\\\/30\\\/carta-certificata-ecologica-per-lufficio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/2016\\\/11\\\/30\\\/carta-certificata-ecologica-per-lufficio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carta certificata ecologica per l&#8217;ufficio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#website\",\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/\",\"name\":\"area-press.eu\",\"description\":\"comunicati stampa &amp; press release\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/#\\\/schema\\\/person\\\/343b4d61076bc37f37be1512158f7145\",\"name\":\"merellir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d3d79c36dbe87999cf3070b87dac773df5f04b18fa0d478fd9dcf849b3616a1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d3d79c36dbe87999cf3070b87dac773df5f04b18fa0d478fd9dcf849b3616a1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d3d79c36dbe87999cf3070b87dac773df5f04b18fa0d478fd9dcf849b3616a1?s=96&d=mm&r=g\",\"caption\":\"merellir\"},\"url\":\"https:\\\/\\\/www.area-press.eu\\\/comunicatistampa\\\/author\\\/merellir\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carta certificata ecologica per l'ufficio - area-press.eu","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Carta certificata ecologica per l'ufficio - area-press.eu","og_description":"Avere un occhio di riguardo per la nostra salute e l&#8217;ambiente che ci circonda significa anche potere scegliere di acquistare carta riciclata o certificata per ufficio, mobili ecologici in ufficio. &#8220;La carta \u00e8 un driver molto importante della deforestazione in alcune regioni. Attenzione alla carta importata e certificata! &#8220;Avvisa il WWF. &#8220;Anche se la foresta [&hellip;]","og_url":"https:\/\/www.area-press.eu\/comunicatistampa\/2016\/11\/30\/carta-certificata-ecologica-per-lufficio\/","og_site_name":"area-press.eu","article_published_time":"2016-11-30T14:22:39+00:00","author":"merellir","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"merellir","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2016\/11\/30\/carta-certificata-ecologica-per-lufficio\/#article","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2016\/11\/30\/carta-certificata-ecologica-per-lufficio\/"},"author":{"name":"merellir","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/343b4d61076bc37f37be1512158f7145"},"headline":"Carta certificata ecologica per l&#8217;ufficio","datePublished":"2016-11-30T14:22:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2016\/11\/30\/carta-certificata-ecologica-per-lufficio\/"},"wordCount":245,"commentCount":0,"articleSection":["Aziendali"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2016\/11\/30\/carta-certificata-ecologica-per-lufficio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2016\/11\/30\/carta-certificata-ecologica-per-lufficio\/","url":"https:\/\/www.area-press.eu\/comunicatistampa\/2016\/11\/30\/carta-certificata-ecologica-per-lufficio\/","name":"Carta certificata ecologica per l'ufficio - area-press.eu","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website"},"datePublished":"2016-11-30T14:22:39+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/343b4d61076bc37f37be1512158f7145"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2016\/11\/30\/carta-certificata-ecologica-per-lufficio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicatistampa\/2016\/11\/30\/carta-certificata-ecologica-per-lufficio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/2016\/11\/30\/carta-certificata-ecologica-per-lufficio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicatistampa\/"},{"@type":"ListItem","position":2,"name":"Carta certificata ecologica per l&#8217;ufficio"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#website","url":"https:\/\/www.area-press.eu\/comunicatistampa\/","name":"area-press.eu","description":"comunicati stampa &amp; press release","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicatistampa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicatistampa\/#\/schema\/person\/343b4d61076bc37f37be1512158f7145","name":"merellir","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/1d3d79c36dbe87999cf3070b87dac773df5f04b18fa0d478fd9dcf849b3616a1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1d3d79c36dbe87999cf3070b87dac773df5f04b18fa0d478fd9dcf849b3616a1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d3d79c36dbe87999cf3070b87dac773df5f04b18fa0d478fd9dcf849b3616a1?s=96&d=mm&r=g","caption":"merellir"},"url":"https:\/\/www.area-press.eu\/comunicatistampa\/author\/merellir\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/14640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/users\/170"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/comments?post=14640"}],"version-history":[{"count":1,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/14640\/revisions"}],"predecessor-version":[{"id":14641,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/posts\/14640\/revisions\/14641"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/media?parent=14640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/categories?post=14640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicatistampa\/wp-json\/wp\/v2\/tags?post=14640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}