{"id":75355,"date":"2014-10-08T00:00:00","date_gmt":"2014-10-07T22:00:00","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicati\/antonio-preziosi-radiocronaca-di-una-crisi-vizi-e-virtu-di-una-professione\/"},"modified":"2014-10-08T00:00:00","modified_gmt":"2014-10-07T22:00:00","slug":"antonio-preziosi-radiocronaca-di-una-crisi-vizi-e-virtu-di-una-professione","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicati\/antonio-preziosi-radiocronaca-di-una-crisi-vizi-e-virtu-di-una-professione\/","title":{"rendered":"Antonio Preziosi, &#8220;Radiocronaca di una crisi\u201d, vizi e virt\u00f9 di una professione"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><\/p>\n<p style=\"box-sizing: border-box; margin: 0px 0px 17px; padding: 0px; font-size: 14px; line-height: 1.6; border: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; vertical-align: baseline; color: #222222;\"><em style=\"box-sizing: border-box; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: inherit; font-variant: inherit; font-weight: inherit; vertical-align: baseline;\"><strong style=\"box-sizing: border-box; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: inherit; font-style: inherit; font-variant: inherit; vertical-align: baseline;\">L&rsquo;informazione<\/strong>, uno strumento sempre pi&ugrave; importante, in modo particolare per raccontare l&rsquo;Italia e l&rsquo;Europa della <strong style=\"box-sizing: border-box; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: inherit; font-style: inherit; font-variant: inherit; vertical-align: baseline;\">crisi<\/strong>. Un&rsquo;analisi per capire il peso dei media in campo economico e per fornire gli strumenti utili a superare la crisi. In &ldquo;<strong style=\"box-sizing: border-box; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: inherit; font-style: inherit; font-variant: inherit; vertical-align: baseline;\">Radiocronaca di una crisi<\/strong>&rdquo;, di <strong style=\"box-sizing: border-box; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: inherit; font-style: inherit; font-variant: inherit; vertical-align: baseline;\">Antonio Preziosi<\/strong>, vizi e virt&ugrave; di una professione che si propone di raccontare i fatti in modo chiaro e completo, in grado di condizionare i comportamenti sociali.<\/em><\/p>\n<p style=\"box-sizing: border-box; margin: 0px 0px 17px; padding: 0px; font-size: 14px; line-height: 1.6; border: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; vertical-align: baseline; color: #222222;\"><em style=\"box-sizing: border-box; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: inherit; font-variant: inherit; font-weight: inherit; vertical-align: baseline;\"><img decoding=\"async\" class=\"alignnone size-full wp-image-2742\" style=\"box-sizing: border-box; max-width: 100%; height: auto; margin: 17px 17px 17px 0px; padding: 0px; outline: 0px; font-family: inherit; font-size: inherit; font-style: inherit; font-variant: inherit; font-weight: inherit; line-height: inherit; vertical-align: baseline;\" src=\"http:\/\/www.dailyfocus.net\/wp-content\/uploads\/2014\/10\/Antonio-Preziosi-Radiocronaca-di-una-crisi.jpg\" alt=\"Antonio Preziosi Radiocronaca di una crisi\" \/><br style=\"box-sizing: border-box;\" \/><\/em><\/p>\n<p style=\"box-sizing: border-box; margin: 0px 0px 17px; padding: 0px; font-size: 14px; line-height: 1.6; border: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; vertical-align: baseline; color: #222222;\">Qual &egrave; il <strong style=\"box-sizing: border-box; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: inherit; font-style: inherit; font-variant: inherit; vertical-align: baseline;\">ruolo giocato dall&rsquo;informazione<\/strong> negli ultimi anni? &Egrave; questa la domanda da cui si parte per capire il peso dei media in campo economico. Vizi e virt&ugrave; di una professione che si propone di raccontare i fatti in modo chiaro e completo, in grado di condizionare i comportamenti sociali.<\/p>\n<p style=\"box-sizing: border-box; margin: 0px 0px 17px; padding: 0px; font-size: 14px; line-height: 1.6; border: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; vertical-align: baseline; color: #222222;\">Se l&rsquo;occhio di bue dell&rsquo;informazione non avesse illuminato la crisi e non l&rsquo;avesse spiegata ad ogni cittadino, questa sarebbe finita nell&rsquo;oblio e diventata ancora pi&ugrave; drammatica e pericolosa. L&rsquo;informazione &egrave; dunque anche e soprattutto uno strumento di alfabetizzazione per rendere consapevoli i cittadini e i loro comportamenti.<\/p>\n<p style=\"box-sizing: border-box; margin: 0px 0px 17px; padding: 0px; font-size: 14px; line-height: 1.6; border: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; vertical-align: baseline; color: #222222;\">Offrire la &ldquo;cassetta degli attrezzi&rdquo; per comprendere e utilizzare le misure che possono aiutare a superare la crisi significa incidere sulla realt&agrave;, sul passaggio dalla crisi finanziaria alla ripresa economica. Un&rsquo;analisi che ci porta verso una nuova Europa: riorganizzazione della politica, della pubblica amministrazione, del bilancio dello Stato, delle attivit&agrave; produttive pubbliche e private e soprattutto di un sistema di Welfare &ldquo;europeo&rdquo; che non viva l&rsquo;interesse nazionale come un limite.<\/p>\n<p style=\"box-sizing: border-box; margin: 0px 0px 17px; padding: 0px; font-size: 14px; line-height: 1.6; border: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; vertical-align: baseline; color: #222222;\">Un&rsquo;agenda politica che supera i confini nazionali e che scavalcando le barriere delle ideologie guarda davvero al bene comune di tutti. &ldquo;<strong style=\"box-sizing: border-box; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: inherit; font-style: inherit; font-variant: inherit; vertical-align: baseline;\">Radiocronaca di un crisi<\/strong>&rdquo;, di <strong style=\"box-sizing: border-box; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: inherit; font-style: inherit; font-variant: inherit; vertical-align: baseline;\">Antonio Preziosi<\/strong>, con la premessa di Antonio Catrical&agrave; e la prefazione di Alberto Quadrio Curzio.<\/p>\n<p><em style=\"box-sizing: border-box; line-height: 14px; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; font-size: 14px; vertical-align: baseline; color: #222222;\"><\/em><img decoding=\"async\" class=\"alignnone size-full wp-image-2743\" style=\"box-sizing: border-box; max-width: 100%; height: auto; margin: 0px; padding: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; font-size: 14px; line-height: 14px; vertical-align: baseline; color: #222222;\" src=\"http:\/\/www.dailyfocus.net\/wp-content\/uploads\/2014\/10\/Il-ruolo-dell%E2%80%99informazione-negli-anni-della-crisi_480.jpg\" alt=\"Il ruolo dell&rsquo;informazione negli anni della crisi_480\" \/><\/p>\n<p style=\"box-sizing: border-box; margin: 0px 0px 17px; padding: 0px; font-size: 14px; line-height: 1.6; border: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; vertical-align: baseline; color: #222222;\">Antonio Preziosi &egrave; un giornalista italiano. E&rsquo; stato direttore di Rai Radio Uno e del GR Rai.<\/p>\n<p style=\"box-sizing: border-box; margin: 0px 0px 17px; padding: 0px; font-size: 14px; line-height: 1.6; border: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; vertical-align: baseline; color: #222222;\"><strong style=\"box-sizing: border-box; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: inherit; font-style: inherit; font-variant: inherit; vertical-align: baseline;\">FONTE<\/strong>: <a style=\"box-sizing: border-box; color: #0177b4; text-decoration: none; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-family: inherit; font-size: inherit; font-style: inherit; font-variant: inherit; font-weight: inherit; vertical-align: baseline;\" title=\"Antonio Preziosi Radiocronaca di una crisi\" href=\"http:\/\/www.eri.rai.it\/internaLibro.aspx?idlibro=977\" target=\"_blank\">Eri Rai<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;informazione, uno strumento sempre pi&ugrave; importante, in modo particolare per raccontare l&rsquo;Italia e l&rsquo;Europa della crisi. Un&rsquo;analisi per capire il peso dei media in campo economico e per fornire gli strumenti utili a superare la crisi. In &ldquo;Radiocronaca di una crisi&rdquo;, di Antonio Preziosi, vizi e virt&ugrave; di una professione che si propone di raccontare [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7635],"tags":[76911,77025,77024],"class_list":["post-75355","post","type-post","status-publish","format-standard","hentry","category-attualita","tag-antonio-preziosi","tag-antonio-preziosi-rai","tag-preziosi-direttore"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Antonio Preziosi, &quot;Radiocronaca di una crisi\u201d, vizi e virt\u00f9 di una professione - area-press.eu - comunicati<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.area-press.eu\/comunicati\/antonio-preziosi-radiocronaca-di-una-crisi-vizi-e-virtu-di-una-professione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Antonio Preziosi, &quot;Radiocronaca di una crisi\u201d, vizi e virt\u00f9 di una professione - area-press.eu - comunicati\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;informazione, uno strumento sempre pi&ugrave; importante, in modo particolare per raccontare l&rsquo;Italia e l&rsquo;Europa della crisi. Un&rsquo;analisi per capire il peso dei media in campo economico e per fornire gli strumenti utili a superare la crisi. In &ldquo;Radiocronaca di una crisi&rdquo;, di Antonio Preziosi, vizi e virt&ugrave; di una professione che si propone di raccontare [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicati\/antonio-preziosi-radiocronaca-di-una-crisi-vizi-e-virtu-di-una-professione\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu - comunicati\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-07T22:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione area-press.eu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione area-press.eu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/antonio-preziosi-radiocronaca-di-una-crisi-vizi-e-virtu-di-una-professione\/\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/antonio-preziosi-radiocronaca-di-una-crisi-vizi-e-virtu-di-una-professione\/\",\"name\":\"Antonio Preziosi, \\\"Radiocronaca di una crisi\u201d, vizi e virt\u00f9 di una professione - area-press.eu - comunicati\",\"isPartOf\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/antonio-preziosi-radiocronaca-di-una-crisi-vizi-e-virtu-di-una-professione\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/antonio-preziosi-radiocronaca-di-una-crisi-vizi-e-virtu-di-una-professione\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.dailyfocus.net\/wp-content\/uploads\/2014\/10\/Antonio-Preziosi-Radiocronaca-di-una-crisi.jpg\",\"datePublished\":\"2014-10-07T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/antonio-preziosi-radiocronaca-di-una-crisi-vizi-e-virtu-di-una-professione\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.area-press.eu\/comunicati\/antonio-preziosi-radiocronaca-di-una-crisi-vizi-e-virtu-di-una-professione\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/antonio-preziosi-radiocronaca-di-una-crisi-vizi-e-virtu-di-una-professione\/#primaryimage\",\"url\":\"http:\/\/www.dailyfocus.net\/wp-content\/uploads\/2014\/10\/Antonio-Preziosi-Radiocronaca-di-una-crisi.jpg\",\"contentUrl\":\"http:\/\/www.dailyfocus.net\/wp-content\/uploads\/2014\/10\/Antonio-Preziosi-Radiocronaca-di-una-crisi.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/antonio-preziosi-radiocronaca-di-una-crisi-vizi-e-virtu-di-una-professione\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.area-press.eu\/comunicati\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Antonio Preziosi, &#8220;Radiocronaca di una crisi\u201d, vizi e virt\u00f9 di una professione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/\",\"name\":\"area-press.eu - comunicati\",\"description\":\"Press releases e comunicati stampa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\",\"name\":\"Redazione area-press.eu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"caption\":\"Redazione area-press.eu\"},\"url\":\"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Antonio Preziosi, \"Radiocronaca di una crisi\u201d, vizi e virt\u00f9 di una professione - area-press.eu - comunicati","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.area-press.eu\/comunicati\/antonio-preziosi-radiocronaca-di-una-crisi-vizi-e-virtu-di-una-professione\/","og_locale":"it_IT","og_type":"article","og_title":"Antonio Preziosi, \"Radiocronaca di una crisi\u201d, vizi e virt\u00f9 di una professione - area-press.eu - comunicati","og_description":"L&rsquo;informazione, uno strumento sempre pi&ugrave; importante, in modo particolare per raccontare l&rsquo;Italia e l&rsquo;Europa della crisi. Un&rsquo;analisi per capire il peso dei media in campo economico e per fornire gli strumenti utili a superare la crisi. In &ldquo;Radiocronaca di una crisi&rdquo;, di Antonio Preziosi, vizi e virt&ugrave; di una professione che si propone di raccontare [&hellip;]","og_url":"https:\/\/www.area-press.eu\/comunicati\/antonio-preziosi-radiocronaca-di-una-crisi-vizi-e-virtu-di-una-professione\/","og_site_name":"area-press.eu - comunicati","article_published_time":"2014-10-07T22:00:00+00:00","author":"Redazione area-press.eu","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione area-press.eu","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicati\/antonio-preziosi-radiocronaca-di-una-crisi-vizi-e-virtu-di-una-professione\/","url":"https:\/\/www.area-press.eu\/comunicati\/antonio-preziosi-radiocronaca-di-una-crisi-vizi-e-virtu-di-una-professione\/","name":"Antonio Preziosi, \"Radiocronaca di una crisi\u201d, vizi e virt\u00f9 di una professione - area-press.eu - comunicati","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.area-press.eu\/comunicati\/antonio-preziosi-radiocronaca-di-una-crisi-vizi-e-virtu-di-una-professione\/#primaryimage"},"image":{"@id":"https:\/\/www.area-press.eu\/comunicati\/antonio-preziosi-radiocronaca-di-una-crisi-vizi-e-virtu-di-una-professione\/#primaryimage"},"thumbnailUrl":"http:\/\/www.dailyfocus.net\/wp-content\/uploads\/2014\/10\/Antonio-Preziosi-Radiocronaca-di-una-crisi.jpg","datePublished":"2014-10-07T22:00:00+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicati\/antonio-preziosi-radiocronaca-di-una-crisi-vizi-e-virtu-di-una-professione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicati\/antonio-preziosi-radiocronaca-di-una-crisi-vizi-e-virtu-di-una-professione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicati\/antonio-preziosi-radiocronaca-di-una-crisi-vizi-e-virtu-di-una-professione\/#primaryimage","url":"http:\/\/www.dailyfocus.net\/wp-content\/uploads\/2014\/10\/Antonio-Preziosi-Radiocronaca-di-una-crisi.jpg","contentUrl":"http:\/\/www.dailyfocus.net\/wp-content\/uploads\/2014\/10\/Antonio-Preziosi-Radiocronaca-di-una-crisi.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicati\/antonio-preziosi-radiocronaca-di-una-crisi-vizi-e-virtu-di-una-professione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Antonio Preziosi, &#8220;Radiocronaca di una crisi\u201d, vizi e virt\u00f9 di una professione"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicati\/#website","url":"https:\/\/www.area-press.eu\/comunicati\/","name":"area-press.eu - comunicati","description":"Press releases e comunicati stampa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4","name":"Redazione area-press.eu","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","caption":"Redazione area-press.eu"},"url":"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/75355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=75355"}],"version-history":[{"count":0,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/75355\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=75355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=75355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=75355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}