{"id":72925,"date":"2014-06-13T00:00:00","date_gmt":"2014-06-12T22:00:00","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicati\/lundquist-csr-online-awards-terna-si-conferma-nella-top-ten\/"},"modified":"2014-06-13T00:00:00","modified_gmt":"2014-06-12T22:00:00","slug":"lundquist-csr-online-awards-terna-si-conferma-nella-top-ten","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicati\/lundquist-csr-online-awards-terna-si-conferma-nella-top-ten\/","title":{"rendered":"Lundquist, CSR Online Awards, Terna si conferma nella Top Ten"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><\/p>\n<p style=\"box-sizing: border-box; margin: 0px 0px 17px; padding: 0px; font-size: 14px; line-height: 1.6; border: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; vertical-align: baseline; color: #222222;\"><em style=\"box-sizing: border-box; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: inherit; font-variant: inherit; font-weight: inherit; vertical-align: baseline;\">CSR Online Awards, Terna si conferma tra i primi dieci siti italiani corporate nelle comunicazione online per i contenuti di responsabilit&agrave; sociale, con un rating di 46,5 punti. Si tratta di un importante riconoscimento, validato da Lundquist, la pi&ugrave; autorevole societ&agrave; di web rating in Europa. La comunicazione di Corporate Social Responsibility di Terna &egrave; risultata vincente per fruibilit&agrave;, velocit&agrave; e completezza dell&rsquo;informazione ed &egrave; stata misurata attraverso un&rsquo;analisi su sette cosiddetti &ldquo;pilastri&rdquo; emersi dall&rsquo;indagine annuale sulla CSR, condotta sugli stakeholder.<\/em><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-2471\" style=\"box-sizing: border-box; max-width: 100%; height: auto; margin: 0px; padding: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; font-size: 14px; line-height: 14px; vertical-align: baseline; color: #222222;\" src=\"http:\/\/www.dailyfocus.net\/wp-content\/uploads\/2014\/06\/Terna-CSR-awards.jpg\" alt=\"Terna CSR awards\" \/><\/p>\n<p style=\"box-sizing: border-box; margin: 0px 0px 17px; padding: 0px; font-size: 14px; line-height: 1.6; border: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; vertical-align: baseline; color: #222222;\">La piattaforma web del Gruppo Terna, <a style=\"box-sizing: border-box; color: #0177b4; text-decoration: none; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-family: inherit; font-size: inherit; font-style: inherit; font-variant: inherit; font-weight: inherit; vertical-align: baseline;\" title=\"Terna\" href=\"http:\/\/www.dailyfocus.net\/lundquist-csr-online-awards-terna-vince-nella-comunicazione-e-si-conferma-nella-top-ten\/www.terna.it\" target=\"_blank\" class=\"broken_link\"><strong style=\"box-sizing: border-box; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: inherit; font-style: inherit; font-variant: inherit; vertical-align: baseline;\">www.terna.it<\/strong><\/a> , si conferma tra i primi dieci siti italiani corporate nella comunicazione online per i contenuti di responsabilit&agrave; sociale, con un rating di 46,5 punti. Si tratta di un riconoscimento importante, validato da Lundquist, la pi&ugrave; autorevole societ&agrave; di web rating in Europa.<\/p>\n<p style=\"box-sizing: border-box; margin: 0px 0px 17px; padding: 0px; font-size: 14px; line-height: 1.6; border: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; vertical-align: baseline; color: #222222;\">Un successo che acquisisce maggior valore se si considera che l&rsquo;azienda elettrica col suo decimo posto si colloca davanti a primarie aziende sul mercato e nonostante la completa riorganizzazione del questionario del CSR Online Awards, i cui parametri, oltre che pi&ugrave; numerosi, sono divenuti anche pi&ugrave; stringenti rispetto al passato.<\/p>\n<p style=\"box-sizing: border-box; margin: 0px 0px 17px; padding: 0px; font-size: 14px; line-height: 1.6; border: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; vertical-align: baseline; color: #222222;\">Alessandra Bardo, Responsabile Web, Internet editing &amp; New Media di Terna: &ldquo;La comunicazione di Corporate Social Responsibility di Terna, &egrave; risultata vincente per fruibilit&agrave;, velocit&agrave; e completezza dell&rsquo;informazione ed &egrave; stata misurata attraverso un&rsquo;analisi su sette cosiddetti pilastri emersi dall&rsquo;indagine annuale sulla CSR, condotta sugli stakeholder&rdquo;. Dall&rsquo;indagine sulla CSR condotta sugli stakeholder, inoltre, &egrave; emerso che le Aziende investono soprattutto nel report annuale: gli stakeholder e gli utenti, invece, vogliono aggiornamenti pi&ugrave; frequenti e per questo li cercano costantemente online.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-2368\" style=\"box-sizing: border-box; max-width: 100%; height: auto; margin: 0px; padding: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; font-size: 14px; line-height: 14px; vertical-align: baseline; color: #222222;\" src=\"http:\/\/www.dailyfocus.net\/wp-content\/uploads\/2014\/05\/Logo-Terna.jpg\" alt=\"Logo Terna\" \/><\/p>\n<p style=\"box-sizing: border-box; margin: 0px 0px 17px; padding: 0px; font-size: 14px; line-height: 1.6; border: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; vertical-align: baseline; color: #222222;\"><strong style=\"box-sizing: border-box; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: inherit; font-style: inherit; font-variant: inherit; vertical-align: baseline;\">In concreto la valutazione &egrave; stata effettuata tenendo conto dei seguenti parametri:<\/strong><\/p>\n<p style=\"box-sizing: border-box; margin: 0px 0px 17px; padding: 0px; font-size: 14px; line-height: 1.6; border: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; vertical-align: baseline; color: #222222;\"><strong style=\"box-sizing: border-box; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: inherit; font-style: inherit; font-variant: inherit; vertical-align: baseline;\">concretezza<\/strong>, che misura la performance su una serie di informazioni ambientali, sociali e di governance, dalle politiche e le linee guida fino ai dati e agli obiettivi<\/p>\n<p style=\"box-sizing: border-box; margin: 0px 0px 17px; padding: 0px; font-size: 14px; line-height: 1.6; border: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; vertical-align: baseline; color: #222222;\"><strong style=\"box-sizing: border-box; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: inherit; font-style: inherit; font-variant: inherit; vertical-align: baseline;\">esaustivit&agrave;<\/strong> misura il livello di divulgazione, oltre alle informazioni di base (ad esempio sul coinvolgimento degli stakeholder e sui risultati riguardo gli obiettivi passati).<\/p>\n<p style=\"box-sizing: border-box; margin: 0px 0px 17px; padding: 0px; font-size: 14px; line-height: 1.6; border: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; vertical-align: baseline; color: #222222;\"><strong style=\"box-sizing: border-box; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: inherit; font-style: inherit; font-variant: inherit; vertical-align: baseline;\">ongoing<\/strong> misura la presenza di applicativi per tenere regolarmente aggiornati gli stakeholder e di permettere loro di commentare e ricevere feedback (es. news, blog, registrazione ad alert via email).<\/p>\n<p style=\"box-sizing: border-box; margin: 0px 0px 17px; padding: 0px; font-size: 14px; line-height: 1.6; border: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; vertical-align: baseline; color: #222222;\"><strong style=\"box-sizing: border-box; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: inherit; font-style: inherit; font-variant: inherit; vertical-align: baseline;\">user friendly<\/strong> valuta la navigabilit&agrave; e la leggibilit&agrave; delle pagine, le funzionalit&agrave; di ricerca e l&rsquo;uso di grafici, torte e diagrammi. Valuta anche i formati utilizzati per la reportistica.<\/p>\n<p style=\"box-sizing: border-box; margin: 0px 0px 17px; padding: 0px; font-size: 14px; line-height: 1.6; border: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; vertical-align: baseline; color: #222222;\"><strong style=\"box-sizing: border-box; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: inherit; font-style: inherit; font-variant: inherit; vertical-align: baseline;\">social<\/strong> valuta come si utilizzano i social media per ascoltare e coinvolgere su argomenti di CSR con frequenza dei post, uso di diversi tipi di contenuti (video, foto), numero dei follower\/like\/iscritti ecc<\/p>\n<p style=\"box-sizing: border-box; margin: 0px 0px 17px; padding: 0px; font-size: 14px; line-height: 1.6; border: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; vertical-align: baseline; color: #222222;\"><strong style=\"box-sizing: border-box; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: inherit; font-style: inherit; font-variant: inherit; vertical-align: baseline;\">integrazione<\/strong> valuta se i messaggi di CSR trasversali a tutto il sito web corporate, con focus sull&rsquo;utilizzo di contenuto non-testuale. Homepage, e sezioni IR, risorse umane, prodotto\/innovazione<\/p>\n<p style=\"box-sizing: border-box; margin: 0px 0px 17px; padding: 0px; font-size: 14px; line-height: 1.6; border: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; vertical-align: baseline; color: #222222;\"><strong style=\"box-sizing: border-box; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: inherit; font-style: inherit; font-variant: inherit; vertical-align: baseline;\">unicit&agrave;<\/strong> valuta l&rsquo;uso del digitale con lo storytelling, le immagini e i video che coinvolga in modo originale sui temi pi&ugrave; importanti e dimostri cosa significala strategia nella quotidianit&agrave; e nei contesti concreti.<\/p>\n<p style=\"box-sizing: border-box; margin: 0px 0px 17px; padding: 0px; font-size: 14px; line-height: 1.6; border: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; vertical-align: baseline; color: #222222;\"><a style=\"box-sizing: border-box; color: #0177b4; text-decoration: none; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-family: inherit; font-size: inherit; font-style: inherit; font-variant: inherit; font-weight: inherit; vertical-align: baseline;\" href=\"http:\/\/marcominghetti.nova100.ilsole24ore.com\/2014\/05\/28\/i-risultati-dai-csr-online-awards-italy-2014\/\" target=\"_blank\">http:\/\/marcominghetti.nova100.ilsole24ore.com\/2014\/05\/28\/i-risultati-dai-csr-online-awards-italy-2014\/<\/a><\/p>\n<p style=\"box-sizing: border-box; margin: 0px 0px 17px; padding: 0px; font-size: 14px; line-height: 1.6; border: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; vertical-align: baseline; color: #222222;\"><a style=\"box-sizing: border-box; color: #0177b4; text-decoration: none; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-family: inherit; font-size: inherit; font-style: inherit; font-variant: inherit; font-weight: inherit; vertical-align: baseline;\" href=\"http:\/\/www.lundquist.it\/lundquist-research-sustainability-social-media-covered-newspaper-il-sole?cat_slug=whats-on%2Fnews\" target=\"_blank\" class=\"broken_link\">http:\/\/www.lundquist.it\/lundquist-research-sustainability-social-media-covered-newspaper-il-sole?cat_slug=whats-on%2Fnews<\/a><\/p>\n<p style=\"box-sizing: border-box; margin: 0px 0px 17px; padding: 0px; font-size: 14px; line-height: 1.6; border: 0px; outline: 0px; font-family: 'Helvetica Neue', HelveticaNeue, Helvetica, Arial, 'Lucida Grande', sans-serif; vertical-align: baseline; color: #222222;\"><strong style=\"box-sizing: border-box; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-size: inherit; font-style: inherit; font-variant: inherit; vertical-align: baseline;\">FONTE<\/strong>: <a style=\"box-sizing: border-box; color: #0177b4; text-decoration: none; line-height: inherit; margin: 0px; padding: 0px; border: 0px; outline: 0px; font-family: inherit; font-size: inherit; font-style: inherit; font-variant: inherit; font-weight: inherit; vertical-align: baseline;\" title=\"CSR Online Awards di Lundquist, Terna si conferma nella Top Ten\" href=\"http:\/\/webmagazine.terna.it\/PrimoPiano\/CSR_Online_Awards_di_Lundquist_Terna_si_conferma_nella.aspx\" target=\"_blank\" class=\"broken_link\">Terna<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CSR Online Awards, Terna si conferma tra i primi dieci siti italiani corporate nelle comunicazione online per i contenuti di responsabilit&agrave; sociale, con un rating di 46,5 punti. Si tratta di un importante riconoscimento, validato da Lundquist, la pi&ugrave; autorevole societ&agrave; di web rating in Europa. La comunicazione di Corporate Social Responsibility di Terna &egrave; [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7562],"tags":[44,75161,75159,75160],"class_list":["post-72925","post","type-post","status-publish","format-standard","hentry","category-economia_finanza","tag-terna","tag-terna-comunicazione","tag-terna-csr-awards","tag-terna-lundquist"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lundquist, CSR Online Awards, Terna si conferma nella Top Ten - area-press.eu - comunicati<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.area-press.eu\/comunicati\/lundquist-csr-online-awards-terna-si-conferma-nella-top-ten\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lundquist, CSR Online Awards, Terna si conferma nella Top Ten - area-press.eu - comunicati\" \/>\n<meta property=\"og:description\" content=\"CSR Online Awards, Terna si conferma tra i primi dieci siti italiani corporate nelle comunicazione online per i contenuti di responsabilit&agrave; sociale, con un rating di 46,5 punti. Si tratta di un importante riconoscimento, validato da Lundquist, la pi&ugrave; autorevole societ&agrave; di web rating in Europa. La comunicazione di Corporate Social Responsibility di Terna &egrave; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicati\/lundquist-csr-online-awards-terna-si-conferma-nella-top-ten\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu - comunicati\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-12T22:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione area-press.eu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione area-press.eu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/lundquist-csr-online-awards-terna-si-conferma-nella-top-ten\/\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/lundquist-csr-online-awards-terna-si-conferma-nella-top-ten\/\",\"name\":\"Lundquist, CSR Online Awards, Terna si conferma nella Top Ten - area-press.eu - comunicati\",\"isPartOf\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/lundquist-csr-online-awards-terna-si-conferma-nella-top-ten\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/lundquist-csr-online-awards-terna-si-conferma-nella-top-ten\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.dailyfocus.net\/wp-content\/uploads\/2014\/06\/Terna-CSR-awards.jpg\",\"datePublished\":\"2014-06-12T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/lundquist-csr-online-awards-terna-si-conferma-nella-top-ten\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.area-press.eu\/comunicati\/lundquist-csr-online-awards-terna-si-conferma-nella-top-ten\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/lundquist-csr-online-awards-terna-si-conferma-nella-top-ten\/#primaryimage\",\"url\":\"http:\/\/www.dailyfocus.net\/wp-content\/uploads\/2014\/06\/Terna-CSR-awards.jpg\",\"contentUrl\":\"http:\/\/www.dailyfocus.net\/wp-content\/uploads\/2014\/06\/Terna-CSR-awards.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/lundquist-csr-online-awards-terna-si-conferma-nella-top-ten\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.area-press.eu\/comunicati\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lundquist, CSR Online Awards, Terna si conferma nella Top Ten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/\",\"name\":\"area-press.eu - comunicati\",\"description\":\"Press releases e comunicati stampa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\",\"name\":\"Redazione area-press.eu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"caption\":\"Redazione area-press.eu\"},\"url\":\"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lundquist, CSR Online Awards, Terna si conferma nella Top Ten - area-press.eu - comunicati","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.area-press.eu\/comunicati\/lundquist-csr-online-awards-terna-si-conferma-nella-top-ten\/","og_locale":"it_IT","og_type":"article","og_title":"Lundquist, CSR Online Awards, Terna si conferma nella Top Ten - area-press.eu - comunicati","og_description":"CSR Online Awards, Terna si conferma tra i primi dieci siti italiani corporate nelle comunicazione online per i contenuti di responsabilit&agrave; sociale, con un rating di 46,5 punti. Si tratta di un importante riconoscimento, validato da Lundquist, la pi&ugrave; autorevole societ&agrave; di web rating in Europa. La comunicazione di Corporate Social Responsibility di Terna &egrave; [&hellip;]","og_url":"https:\/\/www.area-press.eu\/comunicati\/lundquist-csr-online-awards-terna-si-conferma-nella-top-ten\/","og_site_name":"area-press.eu - comunicati","article_published_time":"2014-06-12T22:00:00+00:00","author":"Redazione area-press.eu","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione area-press.eu","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicati\/lundquist-csr-online-awards-terna-si-conferma-nella-top-ten\/","url":"https:\/\/www.area-press.eu\/comunicati\/lundquist-csr-online-awards-terna-si-conferma-nella-top-ten\/","name":"Lundquist, CSR Online Awards, Terna si conferma nella Top Ten - area-press.eu - comunicati","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.area-press.eu\/comunicati\/lundquist-csr-online-awards-terna-si-conferma-nella-top-ten\/#primaryimage"},"image":{"@id":"https:\/\/www.area-press.eu\/comunicati\/lundquist-csr-online-awards-terna-si-conferma-nella-top-ten\/#primaryimage"},"thumbnailUrl":"http:\/\/www.dailyfocus.net\/wp-content\/uploads\/2014\/06\/Terna-CSR-awards.jpg","datePublished":"2014-06-12T22:00:00+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicati\/lundquist-csr-online-awards-terna-si-conferma-nella-top-ten\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicati\/lundquist-csr-online-awards-terna-si-conferma-nella-top-ten\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicati\/lundquist-csr-online-awards-terna-si-conferma-nella-top-ten\/#primaryimage","url":"http:\/\/www.dailyfocus.net\/wp-content\/uploads\/2014\/06\/Terna-CSR-awards.jpg","contentUrl":"http:\/\/www.dailyfocus.net\/wp-content\/uploads\/2014\/06\/Terna-CSR-awards.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicati\/lundquist-csr-online-awards-terna-si-conferma-nella-top-ten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Lundquist, CSR Online Awards, Terna si conferma nella Top Ten"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicati\/#website","url":"https:\/\/www.area-press.eu\/comunicati\/","name":"area-press.eu - comunicati","description":"Press releases e comunicati stampa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4","name":"Redazione area-press.eu","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","caption":"Redazione area-press.eu"},"url":"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/72925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=72925"}],"version-history":[{"count":0,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/72925\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=72925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=72925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=72925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}