{"id":71643,"date":"2014-05-05T00:00:00","date_gmt":"2014-05-04T22:00:00","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicati\/un-fisico-pulito-dentro-il-moderno-concetto-di-salute-by-lucia-giacani-e-mateusz-chmura\/"},"modified":"2014-05-05T00:00:00","modified_gmt":"2014-05-04T22:00:00","slug":"un-fisico-pulito-dentro-il-moderno-concetto-di-salute-by-lucia-giacani-e-mateusz-chmura","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicati\/un-fisico-pulito-dentro-il-moderno-concetto-di-salute-by-lucia-giacani-e-mateusz-chmura\/","title":{"rendered":"Un \u201cfisico\u201d pulito dentro. Il moderno concetto di salute by Lucia Giacani e Mateusz Chmura"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><\/p>\n<p style=\"margin: 0px; padding: 0px 0px 16px; color: #545454; font-family: Arial, Verdana, sans-serif; font-size: 13px; line-height: 18px;\" align=\"center\"><a style=\"cursor: pointer; outline: none; text-decoration: none; color: #296c91;\" href=\"http:\/\/blog.fotolia.com\/it\/files\/2014\/05\/ridotta.jpg\" class=\"broken_link\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4729\" style=\"border: 1px solid #eaeaea; clear: both; display: block; margin-left: auto; margin-right: auto; padding: 4px; max-width: 600px; margin-bottom: 12px;\" src=\"http:\/\/blog.fotolia.com\/it\/files\/2014\/05\/ridotta-1024x695.jpg\" alt=\"ridotta\" width=\"574\" height=\"389\" \/><\/a><\/p>\n<p style=\"margin: 0px; padding: 0px 0px 16px; color: #545454; font-family: Arial, Verdana, sans-serif; font-size: 13px; line-height: 18px;\"><strong>Per la terza edizione della TEN Collection, Fotolia ha rinnovato totalmente il format: invece di 10 artisti, uno ogni mese, per questa nuova stagione ha riunito 5 coppie di artisti &ndash; un fotografo e un artista digitale per coppia &ndash; di fama internazionale. Senza aver mai avuto contatti lavorativi, e con radici culturali e background linguistici diversi, le coppie vengono chiamate a creare un lavoro che rappresenti la loro visione del futuro. Una fotografa italiana, Lucia Giacani e un artista digitale polacco Mateusz Chmura, aka MatCloud, sono i protagonisti del secondo appuntamento TEN di quest&rsquo;anno. Il PSD della loro creazione intitolata &ldquo;Clean Inside&rdquo; pu&ograve; essere scaricato gratuitamente per 24 ore, venerd&igrave; 9 maggio su <\/strong><a style=\"cursor: pointer; outline: none; text-decoration: none; color: #296c91;\" href=\"http:\/\/www.tenbyfotolia.com\/\" target=\"_blank\" class=\"broken_link\"><strong>www.tenbyfotolia.com<\/strong><\/a><strong> <\/strong><\/p>\n<p style=\"margin: 0px; padding: 0px 0px 16px; color: #545454; font-family: Arial, Verdana, sans-serif; font-size: 13px; line-height: 18px;\"><strong> <\/strong><span style=\"color: #339966;\"><strong>&ldquo;Clean Inside&rdquo; il culto del corpo perfetto<br \/><\/strong><\/span>&ldquo;Che cosa potremmo arrivare a sacrificare per un corpo in perfetta salute e qual &egrave; la linea di confine da non superare? Questo &egrave; il punto nodale di &ldquo;Clean Inside&rdquo;. I nostri artisti TEN credono che il raggiungimento di uno &ldquo;stile di vita sano&rdquo; sia diventato un culto, dove il concetto di corpo ideale e di uno stile di vita puro sia costantemente sponsorizzato da politici, dottori e media.<\/p>\n<p style=\"margin: 0px; padding: 0px 0px 16px; color: #545454; font-family: Arial, Verdana, sans-serif; font-size: 13px; line-height: 18px;\">&ldquo;<em>Al giorno d&rsquo;oggi la preghiera &egrave; stata rimpiazzata da diete disintossicanti&ndash; tutto in nome della purificazione da un ambiente inquinato che danneggia i nostri corpi<\/em>&rdquo;, spiega MatCloud. <em>&ldquo;La protagonista della creazione soffre quasi come una martire, mostrando i suoi organi quasi come fossero un badge, una medaglia di devozione o il Sacro Cuore<\/em>&ldquo;dice Lucia Giacani. MatCloud ha creato l&rsquo;effetto &ldquo;ghiaccio&rdquo; sovrapponendo texture e livelli esterni.&rdquo;<\/p>\n<p style=\"margin: 0px; padding: 0px 0px 16px; color: #545454; font-family: Arial, Verdana, sans-serif; font-size: 13px; line-height: 18px;\"><span style=\"color: #339966;\"> <strong>Due talenti complementari<br \/><\/strong><\/span>La collaborazione tra i due artisti ha creato un&rsquo;ispirazione reciproca. Lucia, residente a Milano e fotografa freelance, ha colto l&rsquo;occasione per realizzare alcune sue idee creative. &ldquo;<em>Prima di partecipare alla TEN avevo gi&agrave; delle idee in mente ma avevo bisogno di un artista 3D. La TEN Collection &egrave; arrivata nel momento giusto<\/em>.&rdquo;<\/p>\n<p style=\"margin: 0px; padding: 0px 0px 16px; color: #545454; font-family: Arial, Verdana, sans-serif; font-size: 13px; line-height: 18px;\">La differenza culturale ha aggiunto forza creativa a questo progetto. Per MatCloud, questo scambio di tecniche ed esperienze ha innescato un nuovo livello di creativit&agrave; completamente diverso. &ldquo;<em>Lucia e io stiamo gi&agrave; discutendo di altre idee da sviluppare in futuro e siamo davvero eccitati dall&rsquo;idea di iniziare a lavorarci insieme.<\/em>&rdquo;<\/p>\n<p style=\"margin: 0px; padding: 0px 0px 16px; color: #545454; font-family: Arial, Verdana, sans-serif; font-size: 13px; line-height: 18px; text-align: center;\"><strong style=\"color: #339966; font-family: Verdana, Arial, Helvetica, sans-serif; font-size: 10px;\">Sugli artisti<\/strong><\/p>\n<p style=\"margin: 0px; padding: 0px 0px 16px;\"><strong>Lucia Giacani, l&rsquo;interfaccia della moda e del surrealismo<\/strong><\/p>\n<p style=\"margin: 0px; padding: 0px 0px 16px;\">Lucia Giacani &egrave; una fotografa freelance residente a Milano, la passione della fotografia le &egrave; stata tramandata dal padre.<br \/>La sua crescita professionale, si &egrave; sviluppata durante l&rsquo;adolescenza, quando scattava foto agli amici nei dintorni di Jesi. Anni dopo, Lucia ha fatto conoscere il suo mondo su riviste come Vanity Fair, Vogue Pelle e Gioielli. La cultura italiana &egrave; molto radicata in lei e nei suoi lavori, e crede che proprio il suo paese le abbia dato la determinazione di restare concentrata e mai<\/p>\n<p style=\"margin: 0px; padding: 0px 0px 16px;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-4732\" style=\"border: 1px solid #eaeaea; display: inline; float: left; margin-right: 24px; margin-top: 4px; padding: 4px; max-width: 600px; margin-bottom: 12px;\" src=\"http:\/\/blog.fotolia.com\/it\/files\/2014\/05\/TENS3_FB_02_L.GiacaniM.Chmura_artwork_600x557.jpg\" alt=\"TENS3_FB_02_L.Giacani&amp;M.Chmura_artwork_600x557\" width=\"360\" height=\"334\" \/> dare nulla per scontato. Come ogni fotografo, vive in un mondo surreale, dove il subconscio &egrave; alla base del suo lavoro, lasciandosi ispirare dal Simbolismo, dall&rsquo;Espressionismo, dal Surrealismo e da altri artisti come Francesca Woodman, Steven Klein e Tim Walker.<\/p>\n<p style=\"margin: 0px; padding: 0px 0px 16px;\"><span style=\"line-height: 19px;\"><strong>Mateusz Chmura, l&rsquo;artista con la testa tra le nuvole<\/strong><br \/>Mateusz Chmura, conosciuto come MatCloud (la traduzione del suo cognome significa nuvola), ammette che spesso ha la testa tra le nuvole. &ldquo;<\/span><em style=\"line-height: 19px;\">Mi piace astrarmi da tutto, andare oltre il presente, verso l&rsquo;infinto e l&rsquo;universo. Un po&rsquo; come le nuvole diciamo&hellip;<\/em><span style=\"line-height: 19px;\">&rdquo;<\/span><\/p>\n<p style=\"margin: 0px; padding: 0px 0px 16px;\">L&rsquo;artista polacco &egrave; cresciuto frequentando la National Opera di Varsavia, dove suo padre lavorava, gli oggetti di scena e i diversi accessori hanno alimentato la giovane mente e l&rsquo;immaginazione di Mateusz. &ldquo;<em>L&rsquo;ambiente che mi circondava ha avuto un forte impatto sulla mia immaginazione e mi ha aiutato a sviluppare la mia creativit&agrave; gi&agrave; in et&agrave; molto giovane. Ogni giorno venivo costantemente ispirato da questo<\/em>.&rdquo;<\/p>\n<p style=\"margin: 0px; padding: 0px 0px 16px;\">Oggi MatCloud &egrave; un artista freelance multidisciplinare &ndash; graphic designer, product designer, direttore artistico, fotografo &ndash; che ama lavorare a temi fantastici e reali, presenti in tutti i suoi lavori e nelle sue pubblicazioni. L&rsquo;artista unisce tutte queste tecniche per ottenere il risultato finale delle sue creazioni: espressioni tangibili di idee immateriali.<\/p>\n<p style=\"margin: 0px; padding: 0px 0px 16px; color: #545454; font-family: Arial, Verdana, sans-serif; font-size: 13px; line-height: 18px;\"><span style=\"color: #339966;\"><strong><br \/>Impariamo dagli artisti<br \/><\/strong><\/span> Impariamo dagli artisti e scopriamo i processi creativi, tecniche e trucchi su <a style=\"cursor: pointer; outline: none; text-decoration: none; color: #296c91;\" href=\"http:\/\/www.tenbyfotolia.com\/\" target=\"_blank\" class=\"broken_link\">www.tenbyfotolia.com<\/a>attraverso il video tutorial disponibile il 9 maggio. Il 9 maggio sar&agrave; inoltre scaricabile gratuitamente il PSD &ldquo;Clean Inside&rdquo; che verr&agrave; rilasciato completo di tutti i livelli, filtri e setting utilizzati. Le immagini scattate durante la preparazione dell&rsquo;opera saranno disponibili alla vendita su fotolia.com.<\/p>\n<p style=\"margin: 0px; padding: 0px 0px 16px; color: #545454; font-family: Arial, Verdana, sans-serif; font-size: 13px; line-height: 18px; text-align: center;\"><strong style=\"color: #339966;\">TEN Season 3 contest<br \/><\/strong><span style=\"color: #339966;\"><strong>Sfida Lucia Giacani e Mateusz Chmura dal 12 Maggio!<\/strong><\/span><\/p>\n<p style=\"margin: 0px; padding: 0px 0px 16px; color: #545454; font-family: Arial, Verdana, sans-serif; font-size: 13px; line-height: 18px; text-align: center;\" align=\"center\">Dal 12 maggio un contest internazionale per artisti grafici e fotografi sar&agrave; lanciato su Facebook e postato su <a style=\"cursor: pointer; outline: none; text-decoration: none; color: #296c91;\" href=\"http:\/\/www.tenbyfotolia.com-\/\" target=\"_blank\" class=\"broken_link\">www.tenbyfotolia.com<br \/><\/a> Chiunque, professionisti e amatori potranno partecipare e sfidare i nostri artisti. I grafici dovranno inviare la loro libera interpretazione della creazione di Mateusz Chmura; I Fotografi dovranno caricare il loro scatto migliore seguendo lo stile di Lucia Giacani, spiegato nel video tutorial.<\/p>\n<p style=\"margin: 0px; padding: 0px 0px 16px; color: #545454; font-family: Arial, Verdana, sans-serif; font-size: 13px; line-height: 18px;\">I vincitori riceveranno dei fantastici premi, tra i quali tablet Wacom, abbonamenti a Adobe Creative Cloud, stampanti Roland VersaStudio BN-20, riflettori Wescott e voucher Exaprint.<\/p>\n<p style=\"margin: 0px; padding: 0px 0px 16px; color: #545454; font-family: Arial, Verdana, sans-serif; font-size: 13px; line-height: 18px;\">Il contest sar&agrave; aperto sino al 31 maggio e sar&agrave; disponibile su <a style=\"cursor: pointer; outline: none; text-decoration: none; color: #296c91;\" href=\"https:\/\/www.facebook.com\/TenCollection\" target=\"_blank\" class=\"broken_link\">Facebook<\/a>. Le opere caricate saranno votate dai fan della TEN Collection e da una giuria di esperti. I vincitori saranno annunciati il 9 giugno 2014.<\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: .0001pt;\"><strong><span style=\"text-decoration: underline;\"><span style=\"font-size: 9.0pt; mso-bidi-font-size: 10.0pt; line-height: 115%; mso-bidi-font-family: Tahoma;\">Contatti Stampa<\/span><\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: .0001pt;\"><span style=\"font-size: 10.0pt; mso-bidi-font-size: 11.0pt; line-height: 115%; mso-bidi-font-family: Calibri; color: #2da527; mso-fareast-language: IT; mso-no-proof: yes;\"> <\/span><span style=\"font-size: 10.0pt; mso-bidi-font-size: 11.0pt; line-height: 115%; mso-bidi-font-family: Calibri; color: #2da527;\"> <\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: .0001pt;\"><span style=\"font-size: 9.0pt; mso-bidi-font-size: 10.0pt; line-height: 115%; mso-bidi-font-family: Calibri; mso-ansi-language: EN-US;\" lang=\"EN-US\">Giorgia Millena<br \/> Press Officer and Media Relations<br \/> <\/span><a href=\"mailto:giorgia.millena@fotolia.com\"><span style=\"font-size: 9.0pt; mso-bidi-font-size: 10.0pt; line-height: 115%; mso-bidi-font-family: Calibri; mso-ansi-language: EN-US;\" lang=\"EN-US\">giorgia.millena@fotolia.com<\/span><\/a><span style=\"font-size: 10.0pt; mso-bidi-font-size: 11.0pt; line-height: 115%; mso-ansi-language: EN-US;\" lang=\"EN-US\"><br \/> <\/span><span style=\"font-size: 9.0pt; mso-bidi-font-size: 10.0pt; line-height: 115%; mso-bidi-font-family: Calibri; mso-ansi-language: EN-US;\" lang=\"EN-US\">t. 06-929.570.26<span style=\"color: #2da527;\"> <\/span><\/span><\/p>\n<p style=\"margin: 0px; padding: 0px 0px 16px; color: #545454; font-family: Arial, Verdana, sans-serif; font-size: 13px; line-height: 18px;\">\n<p class=\"MsoNormal\" style=\"margin: 3pt 0cm; border: none; padding: 0cm;\"><strong><em><span style=\"text-decoration: underline;\"><span style=\"font-size: 10.0pt; mso-bidi-font-family: Tahoma;\">Su Fotolia:<br \/> <\/span><\/span><\/em><\/strong><span style=\"font-size: 10.0pt; mso-bidi-font-family: Calibri;\">Leader in Europa nel mercato Microstock, Fotolia offre una collezione online di pi&ugrave; di 26 milioni di foto, illustrazioni vettoriali e video HD in licenza Royalty Free, a prezzi micro. <br \/> Nata nel 2004 da imprenditori francesi, Fotolia ha lo scopo di dare un accesso democratico alle immagini e offre dei contenuti professionali a partire da 0,74 &euro;, per tutti i tipi di utilizzo, su tutti i supporti, senza limiti di tempo o limiti geografici, e questo indipendentemente dal numero di diffusioni. <br \/> Specialista nella fornitura di risorse creative ad uso professionale, Fotolia affianca l&#8217;offerta di immagini e video di artisti indipendenti da tutto il mondo a portfolio di agenzie fotografiche internazionali. I suoi clienti sono professionisti della comunicazione e del design, agenzie grafiche e pubblicitarie, gruppi editoriali e case editrici, universit&agrave; ed enti locali ed internazionali, e piccole, medie e grandi imprese di tutti i settori di attivit&agrave;. Fotolia conta oggi oltre 4 milioni di utenti nel mondo. I suoi servizi sono attivi in 14 lingue, e in 22 paesi dove Fotolia &egrave; fisicamente presente. <\/span><span style=\"font-size: 10.0pt; mso-bidi-font-family: Calibri; mso-ansi-language: EN-US;\" lang=\"EN-US\">Per altre informazioni: <\/span><a href=\"http:\/\/it.fotolia.com\/MediaCenter\" class=\"broken_link\"><span style=\"font-size: 10.0pt;\">http:\/\/it.fotolia.com\/MediaCenter<\/span><\/a><strong><em><span style=\"text-decoration: underline;\"><\/span><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La TEN Collection di Fotolia presenta la seconda coppia di artisti internazionali.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7553],"tags":[9108,7966,54429,54430,57515],"class_list":["post-71643","post","type-post","status-publish","format-standard","hentry","category-comunicati_stampa","tag-arte-digitale","tag-fotografia","tag-fotolia","tag-ten-collection","tag-tenbyfotolia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un \u201cfisico\u201d pulito dentro. Il moderno concetto di salute by Lucia Giacani e Mateusz Chmura - area-press.eu - comunicati<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.area-press.eu\/comunicati\/un-fisico-pulito-dentro-il-moderno-concetto-di-salute-by-lucia-giacani-e-mateusz-chmura\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un \u201cfisico\u201d pulito dentro. Il moderno concetto di salute by Lucia Giacani e Mateusz Chmura - area-press.eu - comunicati\" \/>\n<meta property=\"og:description\" content=\"La TEN Collection di Fotolia presenta la seconda coppia di artisti internazionali.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicati\/un-fisico-pulito-dentro-il-moderno-concetto-di-salute-by-lucia-giacani-e-mateusz-chmura\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu - comunicati\" \/>\n<meta property=\"article:published_time\" content=\"2014-05-04T22:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione area-press.eu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione area-press.eu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/un-fisico-pulito-dentro-il-moderno-concetto-di-salute-by-lucia-giacani-e-mateusz-chmura\/\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/un-fisico-pulito-dentro-il-moderno-concetto-di-salute-by-lucia-giacani-e-mateusz-chmura\/\",\"name\":\"Un \u201cfisico\u201d pulito dentro. Il moderno concetto di salute by Lucia Giacani e Mateusz Chmura - area-press.eu - comunicati\",\"isPartOf\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/un-fisico-pulito-dentro-il-moderno-concetto-di-salute-by-lucia-giacani-e-mateusz-chmura\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/un-fisico-pulito-dentro-il-moderno-concetto-di-salute-by-lucia-giacani-e-mateusz-chmura\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/blog.fotolia.com\/it\/files\/2014\/05\/ridotta-1024x695.jpg\",\"datePublished\":\"2014-05-04T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/un-fisico-pulito-dentro-il-moderno-concetto-di-salute-by-lucia-giacani-e-mateusz-chmura\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.area-press.eu\/comunicati\/un-fisico-pulito-dentro-il-moderno-concetto-di-salute-by-lucia-giacani-e-mateusz-chmura\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/un-fisico-pulito-dentro-il-moderno-concetto-di-salute-by-lucia-giacani-e-mateusz-chmura\/#primaryimage\",\"url\":\"http:\/\/blog.fotolia.com\/it\/files\/2014\/05\/ridotta-1024x695.jpg\",\"contentUrl\":\"http:\/\/blog.fotolia.com\/it\/files\/2014\/05\/ridotta-1024x695.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/un-fisico-pulito-dentro-il-moderno-concetto-di-salute-by-lucia-giacani-e-mateusz-chmura\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.area-press.eu\/comunicati\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un \u201cfisico\u201d pulito dentro. Il moderno concetto di salute by Lucia Giacani e Mateusz Chmura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/\",\"name\":\"area-press.eu - comunicati\",\"description\":\"Press releases e comunicati stampa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\",\"name\":\"Redazione area-press.eu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"caption\":\"Redazione area-press.eu\"},\"url\":\"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un \u201cfisico\u201d pulito dentro. Il moderno concetto di salute by Lucia Giacani e Mateusz Chmura - area-press.eu - comunicati","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.area-press.eu\/comunicati\/un-fisico-pulito-dentro-il-moderno-concetto-di-salute-by-lucia-giacani-e-mateusz-chmura\/","og_locale":"it_IT","og_type":"article","og_title":"Un \u201cfisico\u201d pulito dentro. Il moderno concetto di salute by Lucia Giacani e Mateusz Chmura - area-press.eu - comunicati","og_description":"La TEN Collection di Fotolia presenta la seconda coppia di artisti internazionali.","og_url":"https:\/\/www.area-press.eu\/comunicati\/un-fisico-pulito-dentro-il-moderno-concetto-di-salute-by-lucia-giacani-e-mateusz-chmura\/","og_site_name":"area-press.eu - comunicati","article_published_time":"2014-05-04T22:00:00+00:00","author":"Redazione area-press.eu","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione area-press.eu","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicati\/un-fisico-pulito-dentro-il-moderno-concetto-di-salute-by-lucia-giacani-e-mateusz-chmura\/","url":"https:\/\/www.area-press.eu\/comunicati\/un-fisico-pulito-dentro-il-moderno-concetto-di-salute-by-lucia-giacani-e-mateusz-chmura\/","name":"Un \u201cfisico\u201d pulito dentro. Il moderno concetto di salute by Lucia Giacani e Mateusz Chmura - area-press.eu - comunicati","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.area-press.eu\/comunicati\/un-fisico-pulito-dentro-il-moderno-concetto-di-salute-by-lucia-giacani-e-mateusz-chmura\/#primaryimage"},"image":{"@id":"https:\/\/www.area-press.eu\/comunicati\/un-fisico-pulito-dentro-il-moderno-concetto-di-salute-by-lucia-giacani-e-mateusz-chmura\/#primaryimage"},"thumbnailUrl":"http:\/\/blog.fotolia.com\/it\/files\/2014\/05\/ridotta-1024x695.jpg","datePublished":"2014-05-04T22:00:00+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicati\/un-fisico-pulito-dentro-il-moderno-concetto-di-salute-by-lucia-giacani-e-mateusz-chmura\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicati\/un-fisico-pulito-dentro-il-moderno-concetto-di-salute-by-lucia-giacani-e-mateusz-chmura\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicati\/un-fisico-pulito-dentro-il-moderno-concetto-di-salute-by-lucia-giacani-e-mateusz-chmura\/#primaryimage","url":"http:\/\/blog.fotolia.com\/it\/files\/2014\/05\/ridotta-1024x695.jpg","contentUrl":"http:\/\/blog.fotolia.com\/it\/files\/2014\/05\/ridotta-1024x695.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicati\/un-fisico-pulito-dentro-il-moderno-concetto-di-salute-by-lucia-giacani-e-mateusz-chmura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Un \u201cfisico\u201d pulito dentro. Il moderno concetto di salute by Lucia Giacani e Mateusz Chmura"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicati\/#website","url":"https:\/\/www.area-press.eu\/comunicati\/","name":"area-press.eu - comunicati","description":"Press releases e comunicati stampa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4","name":"Redazione area-press.eu","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","caption":"Redazione area-press.eu"},"url":"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/71643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=71643"}],"version-history":[{"count":0,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/71643\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=71643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=71643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=71643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}