{"id":69774,"date":"2014-02-14T00:00:00","date_gmt":"2014-02-13T23:00:00","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicati\/terre-damerica-il-blog-del-giornalista-alver-metalli\/"},"modified":"2014-02-14T00:00:00","modified_gmt":"2014-02-13T23:00:00","slug":"terre-damerica-il-blog-del-giornalista-alver-metalli","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicati\/terre-damerica-il-blog-del-giornalista-alver-metalli\/","title":{"rendered":"Terre d&#8217;America, il blog del giornalista Alver Metalli."},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><\/p>\n<p>Il primo Papa argentino, i problemi dell&#8217;America Latina, la Chiesa in Sudamerica. Il blog <a href=\"http:\/\/www.terredamerica.com\/\" target=\"_blank\">Terre d&#8217;America<\/a> di Alver Metalli nasce dall&#8217;esigenza di conoscere di pi&ugrave; questa realt&agrave;. Quotidianamente vengono pubblicate notizie e approfondimenti sulla societ&agrave;, cultura e politica dei Paesi dell&#8217;America Latina. Alver Metalli, giornalista e scrittore, ha vissuto in Argentina, Messico, Uruguay. Attualmente risiede a Buenos Aires. &Egrave; autore dei saggi: Cronache centroamericane (1988), L&rsquo;America Latina del secolo XXI (2007), Il Papa e il Filosofo (2013). Ha pubblicato i romanzi: L&rsquo;eredit&agrave; di Madama (2001), Lupo siberiano (2004), Gli dei inutili (2008), L&rsquo;ombra dei Guadalupes (2010), La veccha ferrovia inglese (2011), Il giorno del giudizio (2011), L&rsquo;Uomo dell&rsquo;acqua (2012). Il blog &#8211; racconta l&#8217;autore &#8211; si propone di fornire al lettore italiano notizie e analisi &#8220;mirate&#8221; a fatti ed eventi che hanno l&#8217;America Latina come epicentro, ma di cui si discute anche in Italia. Quindi completa quanto gi&agrave; &egrave; noto, lo amplia quando necessario, lo colloca nell&#8217;orizzonte dei processi tipicamente latinoamericani e lo corregge quando fosse distorto. Tenter&ograve; anche qualche analisi di prospettiva. Senza escludere di proporre anche notizie che possono avere risvolti rilevanti anche in Italia ma rimaste sconosciute ai media e al pubblico in generale. Con il Papa argentino evidentemente il momento &egrave; favorevole&#8221;. Il blog &egrave; stato realizzato da GUEST.it, ed esiste sia nella versione italiana &#8220;Terre d&#8217;America&#8221; che spagnola <a href=\"http:\/\/www.tierrasdeamerica.com\/\" target=\"_blank\">Tierras De America<\/a>, per il pubblico latinoamericano. Gli argomenti trattati sono tanti: Politica, Societ&agrave;, Cultura, Storia, Chiesa e Documenti. GUEST.it srl &egrave; specializzata nella realizzazione <a href=\"http:\/\/www.guest.it\/\" target=\"_blank\">siti internet Rimini Riccione<\/a>. Se anche tu vuoi realizzare il tuo progetto online, visita il sito web: www.guest.it. Oppure chiama lo 0541.649292 o scrivete a info@guest.it<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il blog di Alver Metalli, Terre d&#8217;America, va online in italiano e nella sua versione spagnola Tierras De America.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7584],"tags":[67232,72066,49164,72064,72065,30720],"class_list":["post-69774","post","type-post","status-publish","format-standard","hentry","category-aziendali","tag-guest-it-srl","tag-progetto-web-rimini-riccione","tag-siti-internet-rimini-riccione","tag-terre-damerica","tag-tierras-de-america","tag-web-agency-riccione"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Terre d&#039;America, il blog del giornalista Alver Metalli. - area-press.eu - comunicati<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.area-press.eu\/comunicati\/terre-damerica-il-blog-del-giornalista-alver-metalli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terre d&#039;America, il blog del giornalista Alver Metalli. - area-press.eu - comunicati\" \/>\n<meta property=\"og:description\" content=\"Il blog di Alver Metalli, Terre d&#039;America, va online in italiano e nella sua versione spagnola Tierras De America.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicati\/terre-damerica-il-blog-del-giornalista-alver-metalli\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu - comunicati\" \/>\n<meta property=\"article:published_time\" content=\"2014-02-13T23:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione area-press.eu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione area-press.eu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/terre-damerica-il-blog-del-giornalista-alver-metalli\/\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/terre-damerica-il-blog-del-giornalista-alver-metalli\/\",\"name\":\"Terre d'America, il blog del giornalista Alver Metalli. - area-press.eu - comunicati\",\"isPartOf\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\"},\"datePublished\":\"2014-02-13T23:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/terre-damerica-il-blog-del-giornalista-alver-metalli\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.area-press.eu\/comunicati\/terre-damerica-il-blog-del-giornalista-alver-metalli\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/terre-damerica-il-blog-del-giornalista-alver-metalli\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.area-press.eu\/comunicati\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terre d&#8217;America, il blog del giornalista Alver Metalli.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/\",\"name\":\"area-press.eu - comunicati\",\"description\":\"Press releases e comunicati stampa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\",\"name\":\"Redazione area-press.eu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"caption\":\"Redazione area-press.eu\"},\"url\":\"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Terre d'America, il blog del giornalista Alver Metalli. - area-press.eu - comunicati","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.area-press.eu\/comunicati\/terre-damerica-il-blog-del-giornalista-alver-metalli\/","og_locale":"it_IT","og_type":"article","og_title":"Terre d'America, il blog del giornalista Alver Metalli. - area-press.eu - comunicati","og_description":"Il blog di Alver Metalli, Terre d'America, va online in italiano e nella sua versione spagnola Tierras De America.","og_url":"https:\/\/www.area-press.eu\/comunicati\/terre-damerica-il-blog-del-giornalista-alver-metalli\/","og_site_name":"area-press.eu - comunicati","article_published_time":"2014-02-13T23:00:00+00:00","author":"Redazione area-press.eu","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione area-press.eu","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicati\/terre-damerica-il-blog-del-giornalista-alver-metalli\/","url":"https:\/\/www.area-press.eu\/comunicati\/terre-damerica-il-blog-del-giornalista-alver-metalli\/","name":"Terre d'America, il blog del giornalista Alver Metalli. - area-press.eu - comunicati","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#website"},"datePublished":"2014-02-13T23:00:00+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicati\/terre-damerica-il-blog-del-giornalista-alver-metalli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicati\/terre-damerica-il-blog-del-giornalista-alver-metalli\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicati\/terre-damerica-il-blog-del-giornalista-alver-metalli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Terre d&#8217;America, il blog del giornalista Alver Metalli."}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicati\/#website","url":"https:\/\/www.area-press.eu\/comunicati\/","name":"area-press.eu - comunicati","description":"Press releases e comunicati stampa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4","name":"Redazione area-press.eu","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","caption":"Redazione area-press.eu"},"url":"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/69774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=69774"}],"version-history":[{"count":0,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/69774\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=69774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=69774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=69774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}