{"id":69649,"date":"2014-03-04T00:00:00","date_gmt":"2014-03-03T23:00:00","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicati\/carlo-ozzella-al-momento-della-resa-e-il-singolo-estratto-dallalbum-il-lato-sbagliato-della-strada\/"},"modified":"2020-08-10T00:03:37","modified_gmt":"2020-08-09T22:03:37","slug":"carlo-ozzella-al-momento-della-resa-e-il-singolo-estratto-dallalbum-il-lato-sbagliato-della-strada","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicati\/carlo-ozzella-al-momento-della-resa-e-il-singolo-estratto-dallalbum-il-lato-sbagliato-della-strada\/","title":{"rendered":"CARLO OZZELLA: AL MOMENTO DELLA RESA \u00e8 il singolo estratto dall\u2019album \u201cIL LATO SBAGLIATO DELLA STRADA\u201d"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><\/p>\n<p style=\"margin-bottom: 0cm; line-height: 100%;\" align=\"JUSTIFY\"><span style=\"line-height: 100%; font-size: x-small;\"><strong>AL MOMENTO DELLA RESA: <\/strong><\/span><span style=\"line-height: 100%; font-size: x-small;\">uno scenario incombente di &#8220;guerriglia&#8221;, di rivolta per le strade, in cui la gente comune, stanca di sentirsi oppressa, manovrata, presa in giro, dai signori della finanza e della politica, da &#8220;chi ha voluto avere sempre tutto&#8221;, decide di dare libero sfogo alla propria rabbia e di ribellarsi. In qualche modo &egrave; qualcosa che poi &egrave; davvero successo, bene o male che se ne possa pensare. E potrebbe ripetersi ancora, in maniera pi&ugrave; intensa. Potrebbe andare peggio questa volta. Quando non si ha pi&ugrave; niente da perdere. La rivolta non &egrave; violenza, e si fa anche (non solo) con la musica e le canzoni.<\/span><\/p>\n<p style=\"margin-bottom: 0cm; line-height: 100%;\" align=\"JUSTIFY\">\n<p style=\"margin-bottom: 0cm; line-height: 100%;\" align=\"JUSTIFY\"><span style=\"font-size: x-small;\">Il Lato Sbagliato Della Strada&rdquo; &egrave; un disco che racconta i nostri tempi, i chiaroscuri del presente, le sue incertezze, la rabbia, la speranza, la redenzione. E&rsquo; un album che parla di crisi, ma non in modo astratto: &egrave; la crisi che stiamo vivendo in questi anni, che ognuno ha davanti agli occhi e sulla pelle giorno per giorno. Il racconto si muove da una dimensione strettamente individuale fino ad allargare lo sguardo su un orizzonte pi&ugrave; vasto, sociale, condiviso. E cos&igrave; dalla frustrazione per le aspettative mancate (LA TUA ULTIMA OCCASIONE), i sogni disattesi (FULL GRACE), l&rsquo;attenzione si sposta su temi attuali e dolorosi: il tema del lavoro e dell&rsquo;emigrazione (VITE IN GIOCO), il fallimento della politica e il malaffare che spesso l&rsquo;accompagna (THROUGH THE STORM, L&rsquo;OMBRA), i demoni che si nascondono dietro il lato oscuro della finanza e dell&rsquo;economia, giocando con la vita e i destini delle persone (AL MOMENTO DELLA RESA).<\/span><\/p>\n<p style=\"margin-bottom: 0cm; line-height: 100%;\" align=\"JUSTIFY\"><a name=\"_GoBack\"><\/a> <span style=\"font-size: x-small;\">Ma nel disco non c&rsquo;&egrave; solo rassegnazione e rabbia: c&rsquo;&egrave; spazio anche per la reazione, la rivolta e per il coraggio di affrontare nemici e paure: ci si &ldquo;brucia l&rsquo;anima&rdquo; in FULL GRACE, per riavere indietro il proprio sogno interrotto, si scende per strada in AL MOMENTO DELLA RESA, &ldquo;&egrave; stato bello accarezzare la notte&rdquo; in NOTTURNO. Riconoscere la propria condizione e quella di chi ci sta accanto, sul &ldquo;lato sbagliato della strada&rdquo; appunto, vuol dire avere forza, vuol dire non sentirsi soli, persi: &egrave; il primo passo verso il riscatto. Il tutto all&rsquo;insegna di un unico, fondamentale concetto: &ldquo;comunque vada, siamo vivi stanotte&rdquo; (COMUNQUE VADA). Siamo qui, siamo vivi, questa &egrave; la vita che ci &egrave; stata consegnata: &egrave; doveroso fare il massimo per darle un senso. Musicalmente il disco ha sonorit&agrave; tipicamente rock, di matrice americana, ma con influenze anche della tradizione cantautorale italiana, fatta di attenzione alla melodia e grande cura dei testi.<\/span><\/p>\n<p style=\"margin-bottom: 0cm; line-height: 100%;\" align=\"JUSTIFY\">\n<p style=\"margin-bottom: 0cm; line-height: 100%;\" align=\"JUSTIFY\"><span style=\"font-size: x-small;\">Carlo Ozzella nasce a Milano il 21 Settembre 1981. Da sempre appassionato di musica, inizia a suonare la chitarra all&#8217;et&agrave; di 11 anni. A 13 anni scrive la sua prima canzone, d&#8217;amore ovviamente&#8230; In quel periodo ascolta principalmente i cantautori italiani, De Andr&eacute;, De Gregori, Guccini, che restano ancora oggi una grande passione e un punto di riferimento altissimo nel suo orizzonte musicale. Nel 1996 avviene la svolta: al Festival di Sanremo vede per la prima volta Bruce Springsteen, ospite sul palco dell&#8217;Ariston, che esegue una magnifica &#8220;The Ghost Of Tom Joad&#8221;. Incuriosito, si procura un &#8220;Greatest Hits&#8221;: &egrave; la folgorazione. Da quel momento in poi l&#8217;esperienza musicale di Carlo &egrave; segnata. Oltre a masticare l&#8217;intera discografia del Boss comincia ad estendere il suo interesse verso tutta la musica americana ed inglese che ruota attorno al rock, alle sue origini e alle sue diramazioni. <\/span><span style=\"font-size: x-small;\"><span lang=\"en-US\">Elvis, Roy Orbison, Jerry Lee Lewis, Chuck Berry, Bob Dylan, Neil Young, i Beatles, i Rolling Stones, tutto viene scoperto ed assimilato. <\/span><\/span><span style=\"font-size: x-small;\">Nel 1997 entra nella sua prima band, gli URLO ROCK, che di fatto restano in piedi solo fino alla prima esibizione in un oratorio. Dopo una serie di concerti come solista, accompagnato da chitarra e armonica, nasce la DUSTY ROAD BAND, un trio acustico con cui incide&#8221;DEMO 12\/98&#8243;. Nel Settembre del 1999 entra a far parte dei BLUESTEPS, la band che un anno dopo cambier&agrave; il suo nome in&#8230; BARBABLUES! Il feeling &egrave; immediato e la band si afferma ben presto come potentissima macchina da live show, anche grazie alla straordinaria intesa e amicizia che subito si instaura tra i musicisti.<\/span><\/p>\n<p style=\"margin-bottom: 0cm; line-height: 100%;\" align=\"JUSTIFY\"><span style=\"font-size: x-small;\">Altre piccole esperienze vengono poi percorse in parallelo: quella con gli ALLAN COCCHIN&#8217;S PROJECT, con gli AREA 51.<\/span><\/p>\n<p style=\"margin-bottom: 0cm; line-height: 100%;\" align=\"JUSTIFY\"><span style=\"font-size: x-small;\">Nel 2005 entra a far parte di una tribute band di Bruce Springsteen, la 57TH STREET BAND. Si apre un altro importante capitolo della sua vita. In quell&#8217;occasione infatti conosce Claudio Lauria, virtuoso sassofonista con cui mette in piedi il gruppo acustico THE ACOUSTIC SIDE. Si apre cos&igrave; un periodo di intensissima attivit&agrave; live, accompagnato da queste due band e dai sempre pi&ugrave; straordinari BARBABLUES. Si arriva quindi al Dicembre 2008: i BARBABLUES, fino a questo momento consolidata cover band, entrano nei mitici AVAKIAN RECORDING STUDIOS per registrare il loro primo EP, &#8220;Dove Comincia La Notte&#8221;, sei canzoni tutte firmate da Carlo Ozzella. Nel 2013, esce il nuovo album intitolato &ldquo;Il Lato Sbagliato Della Strada&rdquo;. Nel frattempo comunque prosegue incessante anche l&#8217;attivit&agrave; live. Ancora una volta, non rimane che dire&#8230; <\/span><span style=\"font-size: x-small;\"><span lang=\"en-US\">TO BE CONTINUED!<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; line-height: 100%;\" lang=\"en-US\" align=\"JUSTIFY\">\n<p style=\"margin-bottom: 0cm; line-height: 100%;\" align=\"JUSTIFY\"><span style=\"color: #0000ff;\"><span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.carloozzella.com\/\"><span style=\"font-size: x-small;\"><span lang=\"en-US\">http:\/\/www.carloozzella.com\/<\/span><\/span><\/a><\/span><\/span><span style=\"font-size: xx-small;\"><span lang=\"en-US\"> <\/span><\/span><span style=\"color: #0000ff;\"><span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.barbablues.it\/\"><span style=\"font-size: x-small;\"><span lang=\"en-US\">http:\/\/www.barbablues.it\/<\/span><\/span><\/a><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; line-height: 100%;\" align=\"JUSTIFY\"><span style=\"color: #0000ff;\"><span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.facebook.com\/pages\/Carlo-Ozzella\/328676633825010\" class=\"broken_link\"><span style=\"font-size: x-small;\"><span lang=\"en-US\">https:\/\/www.facebook.com\/pages\/Carlo-Ozzella\/328676633825010<\/span><\/span><\/a><\/span><\/span><span style=\"font-size: xx-small;\"><span lang=\"en-US\"> <\/span><\/span><span style=\"color: #0000ff;\"><span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.facebook.com\/carlo.ozzella\"><span style=\"font-size: x-small;\"><span lang=\"en-US\">https:\/\/www.facebook.com\/carlo.ozzella<\/span><\/span><\/a><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; line-height: 100%;\" align=\"JUSTIFY\"><span style=\"color: #0000ff;\"><span style=\"text-decoration: underline;\"><a href=\"https:\/\/twitter.com\/OzzellaCarlo\"><span style=\"font-size: x-small;\"><span lang=\"en-US\">https:\/\/twitter.com\/OzzellaCarlo<\/span><\/span><\/a><\/span><\/span><span style=\"font-size: xx-small;\"><span lang=\"en-US\"> <\/span><\/span><span style=\"color: #0000ff;\"><span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.youtube.com\/channel\/UCbpV94gNNUR7Nwb5IwA_UVg?feature=c4-feed-u\"><span style=\"font-size: x-small;\"><span lang=\"en-US\">http:\/\/www.youtube.com\/channel\/UCbpV94gNNUR7Nwb5IwA_UVg?feature=c4-feed-u<\/span><\/span><\/a><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; line-height: 100%;\" align=\"JUSTIFY\"><span style=\"color: #0000ff;\"><span style=\"text-decoration: underline;\"><a href=\"https:\/\/soundcloud.com\/carlo-ozzella\"><span style=\"font-size: x-small;\"><span lang=\"en-US\">https:\/\/soundcloud.com\/carlo-ozzella<\/span><\/span><\/a><\/span><\/span><span style=\"font-size: xx-small;\"><span lang=\"en-US\"> <\/span><\/span><span style=\"color: #0000ff;\"><span style=\"text-decoration: underline;\"><a href=\"http:\/\/carloozzellabarbablues.zimbalam.com\/\" class=\"broken_link\"><span style=\"font-size: x-small;\"><span lang=\"en-US\">http:\/\/carloozzellabarbablues.zimbalam.com\/<\/span><\/span><\/a><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; line-height: 100%;\" lang=\"en-US\" align=\"JUSTIFY\">\n<\/p>\n<p style=\"margin-bottom: 0cm; line-height: 100%;\" align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-size: small;\"><strong>L&rsquo;AltopArlAnte <\/strong><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-size: x-small;\"><strong> PromoRadio ||| PromoVideo||| PromoStampa&amp;Web <\/strong><\/span><\/span><span style=\"color: #0000ff;\"><span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.laltoparlante.it\/\">www.laltoparlante.it<\/a><\/span><\/span><span style=\"color: #0000ff;\"><span style=\"text-decoration: underline;\"><span style=\"font-size: x-small;\"> <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-size: x-small;\"><strong>&#8211; 348.3650978<\/strong><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Accompagnato dalla band BARBABLUES, il chitarrista e songwriter milanese propone il suo rock d\u2019autore intenso e vitale, carico di immediatezza e appeal, di ritmo ed incisivit\u00e0<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7603],"tags":[],"class_list":["post-69649","post","type-post","status-publish","format-standard","hentry","category-musica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CARLO OZZELLA: AL MOMENTO DELLA RESA \u00e8 il singolo estratto dall\u2019album \u201cIL LATO SBAGLIATO DELLA STRADA\u201d - area-press.eu - comunicati<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.area-press.eu\/comunicati\/carlo-ozzella-al-momento-della-resa-e-il-singolo-estratto-dallalbum-il-lato-sbagliato-della-strada\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CARLO OZZELLA: AL MOMENTO DELLA RESA \u00e8 il singolo estratto dall\u2019album \u201cIL LATO SBAGLIATO DELLA STRADA\u201d - area-press.eu - comunicati\" \/>\n<meta property=\"og:description\" content=\"Accompagnato dalla band BARBABLUES, il chitarrista e songwriter milanese propone il suo rock d\u2019autore intenso e vitale, carico di immediatezza e appeal, di ritmo ed incisivit\u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicati\/carlo-ozzella-al-momento-della-resa-e-il-singolo-estratto-dallalbum-il-lato-sbagliato-della-strada\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu - comunicati\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-03T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-09T22:03:37+00:00\" \/>\n<meta name=\"author\" content=\"Redazione area-press.eu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione area-press.eu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/carlo-ozzella-al-momento-della-resa-e-il-singolo-estratto-dallalbum-il-lato-sbagliato-della-strada\/\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/carlo-ozzella-al-momento-della-resa-e-il-singolo-estratto-dallalbum-il-lato-sbagliato-della-strada\/\",\"name\":\"CARLO OZZELLA: AL MOMENTO DELLA RESA \u00e8 il singolo estratto dall\u2019album \u201cIL LATO SBAGLIATO DELLA STRADA\u201d - area-press.eu - comunicati\",\"isPartOf\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\"},\"datePublished\":\"2014-03-03T23:00:00+00:00\",\"dateModified\":\"2020-08-09T22:03:37+00:00\",\"author\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/carlo-ozzella-al-momento-della-resa-e-il-singolo-estratto-dallalbum-il-lato-sbagliato-della-strada\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.area-press.eu\/comunicati\/carlo-ozzella-al-momento-della-resa-e-il-singolo-estratto-dallalbum-il-lato-sbagliato-della-strada\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/carlo-ozzella-al-momento-della-resa-e-il-singolo-estratto-dallalbum-il-lato-sbagliato-della-strada\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.area-press.eu\/comunicati\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CARLO OZZELLA: AL MOMENTO DELLA RESA \u00e8 il singolo estratto dall\u2019album \u201cIL LATO SBAGLIATO DELLA STRADA\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/\",\"name\":\"area-press.eu - comunicati\",\"description\":\"Press releases e comunicati stampa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\",\"name\":\"Redazione area-press.eu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"caption\":\"Redazione area-press.eu\"},\"url\":\"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CARLO OZZELLA: AL MOMENTO DELLA RESA \u00e8 il singolo estratto dall\u2019album \u201cIL LATO SBAGLIATO DELLA STRADA\u201d - area-press.eu - comunicati","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.area-press.eu\/comunicati\/carlo-ozzella-al-momento-della-resa-e-il-singolo-estratto-dallalbum-il-lato-sbagliato-della-strada\/","og_locale":"it_IT","og_type":"article","og_title":"CARLO OZZELLA: AL MOMENTO DELLA RESA \u00e8 il singolo estratto dall\u2019album \u201cIL LATO SBAGLIATO DELLA STRADA\u201d - area-press.eu - comunicati","og_description":"Accompagnato dalla band BARBABLUES, il chitarrista e songwriter milanese propone il suo rock d\u2019autore intenso e vitale, carico di immediatezza e appeal, di ritmo ed incisivit\u00e0","og_url":"https:\/\/www.area-press.eu\/comunicati\/carlo-ozzella-al-momento-della-resa-e-il-singolo-estratto-dallalbum-il-lato-sbagliato-della-strada\/","og_site_name":"area-press.eu - comunicati","article_published_time":"2014-03-03T23:00:00+00:00","article_modified_time":"2020-08-09T22:03:37+00:00","author":"Redazione area-press.eu","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione area-press.eu","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicati\/carlo-ozzella-al-momento-della-resa-e-il-singolo-estratto-dallalbum-il-lato-sbagliato-della-strada\/","url":"https:\/\/www.area-press.eu\/comunicati\/carlo-ozzella-al-momento-della-resa-e-il-singolo-estratto-dallalbum-il-lato-sbagliato-della-strada\/","name":"CARLO OZZELLA: AL MOMENTO DELLA RESA \u00e8 il singolo estratto dall\u2019album \u201cIL LATO SBAGLIATO DELLA STRADA\u201d - area-press.eu - comunicati","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#website"},"datePublished":"2014-03-03T23:00:00+00:00","dateModified":"2020-08-09T22:03:37+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicati\/carlo-ozzella-al-momento-della-resa-e-il-singolo-estratto-dallalbum-il-lato-sbagliato-della-strada\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicati\/carlo-ozzella-al-momento-della-resa-e-il-singolo-estratto-dallalbum-il-lato-sbagliato-della-strada\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicati\/carlo-ozzella-al-momento-della-resa-e-il-singolo-estratto-dallalbum-il-lato-sbagliato-della-strada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"CARLO OZZELLA: AL MOMENTO DELLA RESA \u00e8 il singolo estratto dall\u2019album \u201cIL LATO SBAGLIATO DELLA STRADA\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicati\/#website","url":"https:\/\/www.area-press.eu\/comunicati\/","name":"area-press.eu - comunicati","description":"Press releases e comunicati stampa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4","name":"Redazione area-press.eu","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","caption":"Redazione area-press.eu"},"url":"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/69649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=69649"}],"version-history":[{"count":1,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/69649\/revisions"}],"predecessor-version":[{"id":84756,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/69649\/revisions\/84756"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=69649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=69649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=69649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}