{"id":69441,"date":"2014-03-05T00:00:00","date_gmt":"2014-03-04T23:00:00","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicati\/disco-inutile-e-il-brano-e-il-disco-che-segna-il-ritorno-di-mgz\/"},"modified":"2014-03-05T00:00:00","modified_gmt":"2014-03-04T23:00:00","slug":"disco-inutile-e-il-brano-e-il-disco-che-segna-il-ritorno-di-mgz","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicati\/disco-inutile-e-il-brano-e-il-disco-che-segna-il-ritorno-di-mgz\/","title":{"rendered":"DISCO INUTILE \u00e8 il brano e il disco che segna il ritorno di MGZ"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"CENTER\">\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\">\n<p style=\"margin-bottom: 0cm; widows: 0; orphans: 0;\" align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: medium;\"><em><strong>Soltanto il Profeta pu&ograve; indicarti UNA strada. Che non &egrave; unica ma possibile. Non &egrave; magica ma divertente. Soltanto il Profeta pu&ograve; regalarti i suoi preziosi CONSIGLI INUTILI<\/strong><\/em><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\">\n<p style=\"margin-bottom: 0cm; widows: 0; orphans: 0;\" align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">Adorabile terrestre! Le tue giornate sono vuote e faticose? L&#8217;amore ha cambiato indirizzo? Odi il tuo lavoro, la tua citt&agrave;, la tua epoca e credi di valere molto di pi&ugrave;? Ti senti prigioniero nei rituali sbiaditi del tuo ridicolo pianeta? Oppure tutto scorre e funziona magnificamente, ma hai un rumorino nella mente? <\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 0; orphans: 0;\" align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">Non farti risucchiare dal Nulla, ma sintonizzati con la Buru-Parola del Profeta MGZ nel Disco pi&ugrave; Inutile e fondamentale della storia galattica. UN DISCO CHE TI ADERISCE E CREDE IN TE. Un disco incredibilmente sano e MODERNO. Un disco che suona in testa anche se dormi. <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>DISCO INUTILE: UN DISCO CHE TI AMA!<\/strong><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 0; orphans: 0;\" align=\"JUSTIFY\">\n<p style=\"margin-bottom: 0cm; widows: 0; orphans: 0;\" align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">Non sei solo tu a non averne pi&ugrave; voglia, a rimbalzare senza meta, a litigare con te stesso. Non sei solo tu ad avere fretta anche se il futuro scricchiola, a porti mille domande, a fare gniik gruup blllll blll aarghhh oops tippitippipamm, a provare tanta paura&#8230; brrrrrrr. Tu <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>NON SEI SOLO<\/strong><\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">! Anche il Profeta s&#8217;INCAZZA come te in un mondo malsano.<\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 0; orphans: 0;\" align=\"JUSTIFY\">\n<p style=\"margin-bottom: 0cm; widows: 0; orphans: 0;\" align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><em>&#8220;<\/em><\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><em><strong>un mondo perduto e senza memoria<\/strong><\/em><\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><em>, che corre veloce ma non sa viaggiare, un mondo ferito che sputa sentenze, <\/em><\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><em><strong>che sembra dormire ma piange nel buio<\/strong><\/em><\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><em>.&#8221;<\/em><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 0; orphans: 0;\" align=\"JUSTIFY\">\n<p style=\"margin-bottom: 0cm; widows: 0; orphans: 0;\" align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>CONSIGLI INUTILI<\/strong><\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">: <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>Ama pi&ugrave; che puoi &#8211; Esci tutte le sere &#8211; Tocca tutto e tutti &#8211; Vivi nel buruburu &#8211; Non inseguire niente ma cammina &#8211; Non urlare ma fai Din Don &#8211; Gioca &#8211; Ridi a testa in gi&ugrave; &#8211; Esplora l&#8217;Universo &#8211; Mantieni stati di alterazione consapevole &#8211; Respira spesso &#8211; Ricordati di godere!<\/strong><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\">\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>MGZ<\/strong><\/span><\/span><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"> <\/span><\/span><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">viene avvistato per la prima volta sulla Terra intorno alla met&agrave; degli anni &rsquo;90. Il sedicente &ldquo;<\/span><\/span><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>Profeta<\/strong><\/span><\/span><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">&rdquo; afferma di giungere dal Pianeta <\/span><\/span><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>Burulandia<\/strong><\/span><\/span><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"> e di essere atterrato qui per una non meglio precisata &ldquo;missione&rdquo;. <\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">Si rende ben presto conto che le canzoni sono una delle strade per arrivare pi&ugrave; velocemente al cuore della gente, e si improvviva rockstar, mutuando look, movenze e filastrocche dagli improbabili protagonisti delle trasmissioni televisive intergalattiche della sua mirabolante infanzia. <\/span><\/span><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>&ldquo;muovete le manine\/ muovete le antennine\/ giro giro tondo\/ cambiamo il mondo&#8221;<\/strong><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">La costante <\/span><\/span><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>empatia<\/strong><\/span><\/span><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"> che egli avverte per il genere umano, lo spinge a condividerne le esperienze in maniera viscerale, fino a confondersi tra la folla e diventare &ldquo;<\/span><\/span><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>UNO DI NOI<\/strong><\/span><\/span><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">&rdquo;. A questo punto, da &ldquo;testimone&rdquo; e possibile &#8220;salvatore&rdquo;, finisce per farsi travolgere dagli eventi, perdendone completamente il senso (o il senno?), e divenendo altres&igrave;, affermano alcuni, decisamente pi&ugrave; simpatico. <\/span><\/span><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>&#8220;sopravvivo senza motivo\/ prima ero gentile ora sono cattivo\/ sopravvivo senza uno scopo\/ perch&egrave; non mi sparo, te lo spiego dopo&#8221; <\/strong><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">Dopo un improvviso ritiro ludico-spirituale, parcheggiato nell&#8217;universo tra videogiochi e cinegiornali di un&rsquo;epoca lontana, MGZ non resiste all&rsquo;accorato richiamo dell&rsquo;<\/span><\/span><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>Umanit&agrave;<\/strong><\/span><\/span><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"> <\/span><\/span><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>dolente<\/strong><\/span><\/span><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"> e torna a rendersi visibile invocando la &ldquo;<\/span><\/span><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>felicit&agrave; consapevole<\/strong><\/span><\/span><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">&rdquo; in un mondo mai prima cos&igrave; &ldquo;brutto&rdquo; ma proprio per questo bisognoso di partecipazione e socialit&agrave;. <\/span><\/span><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>&ldquo;mi sento bene.. mi sento bene.. mi sento bene bene bene bene bene!&rdquo;<\/strong><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">Da quel giorno l&#8217;Astronave del Profeta esplora instancabile il globo terrestre alla ricerca di esseri meritevoli di un soggiorno su Burulandia, dove tutti sono uguali, immortali, liberi e felici. <\/span><\/span><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>&ldquo;Vivo in una bolla\/ la mia notte pi&ugrave; bella\/ con la gente che balla\/ nel mio mondo che brilla&rdquo;.<\/strong><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\"><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">MGZ sta anche ragalando agli adorati umani un sogno di pace e volutt&agrave;, diffondendo tra loro la Grande Energia dell&#8217; &#8220;<\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>Amore Libero<\/strong><\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">&#8220;! <\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>&#8220;lasciam dormire famiglia e benpensanti\/ mettiam la sveglia e godiamo tutti quanti!&#8221;<\/strong><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\"><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">MGZ ha diffuso nel Pianeta Terra 4 cd &ldquo;<\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>da domani Cambio Vita<\/strong><\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">&rdquo; (Wide), &ldquo;<\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>Non riesco pi&ugrave; a starmene tranquillo<\/strong><\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">&rdquo; (Alternative), &#8220;<\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>Ho visto tempi migliori<\/strong><\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">&#8221; (Green Fog), &#8220;<\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>La Bolla-Greatest Hits<\/strong><\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">&#8221; (BigRamona). Ha realizzato diversi spettacoli insieme al collettivo teatrale &ldquo;<\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>Le Signore<\/strong><\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">&rdquo; (regia Grazia Stella). Ha collaborato, tra gli altri, con <\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>Madaski <\/strong><\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">e gli <\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>Africa Unite <\/strong><\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">e con i<\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong> Mutoid West Company <\/strong><\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">di Pisa. E&rsquo; stato &ldquo;The Being&rdquo; nel &ldquo;Frau Frankenstein&rdquo; per il Gran Teatro <\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>La Fenice di Venezia<\/strong><\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">. Ha cantato con Zazzo e i <\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>Negazione. <\/strong><\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">Ha preso parte ai programmi tv &ldquo;Music Zoo&rdquo; e &ldquo;Space Girls&rdquo;. E&rsquo; presente con un suo brano nella colonna sonora dei film &ldquo;Preferisco il rumore del mare&rdquo; di <\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>Mimmo Calopresti<\/strong><\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"> (53&deg; Festival Cannes). Ha condiviso il palco con Roy Paci, Blue Vertigo, CSI, Mad Professor, Not Moving, Tying Tiffany, Meganoidi e molti altri. La band che lo ha accompagnato ha visto alternarsi alle chitarre Tax, Dome La Muerte, Bob Stones, Steven Guitar e attualmente <\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>Richy Zen<\/strong><\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">, fino all&#8217;incontro con <\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>DJ Brainzuk<\/strong><\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"> (musiche, arrangiamenti, programmazioni) con il quale da tempo condivide l&#8217;intera attivit&agrave;. Nell&#8217;ultimo show messo in scena, &#8220;La Bolla Tour&#8221;, le scenografie sono di <\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>Ruben Esposito<\/strong><\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">, i nuovi costumi di <\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>rorror<\/strong><\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"> e alle danze scintillano le <\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>Buru Buru Girls<\/strong><\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">. <\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\"><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">Nel <\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>2014<\/strong><\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"> sono in arrivo un <\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>nuovo album<\/strong><\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"> e un <\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"><strong>nuovo spettacolo<\/strong><\/span><\/span><\/span><span style=\"color: #242424;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">, colorati da miriadi di macchine sonore, ballerine psichedeliche, musicisti alieni e Good Buru Vibrations !!!<\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\">\n<p style=\"margin-bottom: 0.35cm;\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">Il brano &#8220;Disco Inutile&#8221; &egrave; stato realizzato da MGZ (voci, arrangiamento) e brainzuk (programmazione, arrangiamento). Registrato e missato da brainzuk @ MetalGrooveStudio, Bergeggi 2013. Masterizzato da Alberto Cutolo @ Massive Arts Studios, Milano 2013. <\/span><\/span><\/p>\n<p style=\"margin-bottom: 0.35cm;\"><span style=\"color: #0000ff;\"><span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.mgz.it\/\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">http:\/\/www.mgz.it\/<\/span><\/span><\/a><\/span><\/span><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"> <\/span><\/span><span style=\"color: #0000ff;\"><span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.facebook.com\/MGZprofeta\"><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\">https:\/\/www.facebook.com\/MGZprofeta<\/span><\/span><\/a><\/span><\/span><span style=\"font-family: Calibri;\"><span style=\"font-size: x-small;\"> <\/span><\/span><\/p>\n<p style=\"margin-bottom: 0.35cm;\">\n<\/p>\n<p style=\"margin-bottom: 0cm;\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: small;\"><strong>L&rsquo;AltopArlAnte <\/strong><\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: x-small;\"><strong> PromoRadio ||| PromoVideo||| PromoStampa&amp;Web <\/strong><\/span><\/span><\/span><span style=\"color: #0000ff;\"><span style=\"text-decoration: underline;\"><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: x-small;\"><a href=\"http:\/\/www.laltoparlante.it\/\">www.laltoparlante.it<\/a> <\/span><\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: x-small;\"><strong>&#8211; 348.3650978<\/strong><\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Burulandia, anno del Profeta 2014<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7603],"tags":[],"class_list":["post-69441","post","type-post","status-publish","format-standard","hentry","category-musica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>DISCO INUTILE \u00e8 il brano e il disco che segna il ritorno di MGZ - area-press.eu - comunicati<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.area-press.eu\/comunicati\/disco-inutile-e-il-brano-e-il-disco-che-segna-il-ritorno-di-mgz\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DISCO INUTILE \u00e8 il brano e il disco che segna il ritorno di MGZ - area-press.eu - comunicati\" \/>\n<meta property=\"og:description\" content=\"Burulandia, anno del Profeta 2014\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicati\/disco-inutile-e-il-brano-e-il-disco-che-segna-il-ritorno-di-mgz\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu - comunicati\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-04T23:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione area-press.eu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione area-press.eu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/disco-inutile-e-il-brano-e-il-disco-che-segna-il-ritorno-di-mgz\/\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/disco-inutile-e-il-brano-e-il-disco-che-segna-il-ritorno-di-mgz\/\",\"name\":\"DISCO INUTILE \u00e8 il brano e il disco che segna il ritorno di MGZ - area-press.eu - comunicati\",\"isPartOf\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\"},\"datePublished\":\"2014-03-04T23:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/disco-inutile-e-il-brano-e-il-disco-che-segna-il-ritorno-di-mgz\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.area-press.eu\/comunicati\/disco-inutile-e-il-brano-e-il-disco-che-segna-il-ritorno-di-mgz\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/disco-inutile-e-il-brano-e-il-disco-che-segna-il-ritorno-di-mgz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.area-press.eu\/comunicati\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DISCO INUTILE \u00e8 il brano e il disco che segna il ritorno di MGZ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/\",\"name\":\"area-press.eu - comunicati\",\"description\":\"Press releases e comunicati stampa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\",\"name\":\"Redazione area-press.eu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"caption\":\"Redazione area-press.eu\"},\"url\":\"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DISCO INUTILE \u00e8 il brano e il disco che segna il ritorno di MGZ - area-press.eu - comunicati","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.area-press.eu\/comunicati\/disco-inutile-e-il-brano-e-il-disco-che-segna-il-ritorno-di-mgz\/","og_locale":"it_IT","og_type":"article","og_title":"DISCO INUTILE \u00e8 il brano e il disco che segna il ritorno di MGZ - area-press.eu - comunicati","og_description":"Burulandia, anno del Profeta 2014","og_url":"https:\/\/www.area-press.eu\/comunicati\/disco-inutile-e-il-brano-e-il-disco-che-segna-il-ritorno-di-mgz\/","og_site_name":"area-press.eu - comunicati","article_published_time":"2014-03-04T23:00:00+00:00","author":"Redazione area-press.eu","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione area-press.eu","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicati\/disco-inutile-e-il-brano-e-il-disco-che-segna-il-ritorno-di-mgz\/","url":"https:\/\/www.area-press.eu\/comunicati\/disco-inutile-e-il-brano-e-il-disco-che-segna-il-ritorno-di-mgz\/","name":"DISCO INUTILE \u00e8 il brano e il disco che segna il ritorno di MGZ - area-press.eu - comunicati","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#website"},"datePublished":"2014-03-04T23:00:00+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicati\/disco-inutile-e-il-brano-e-il-disco-che-segna-il-ritorno-di-mgz\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicati\/disco-inutile-e-il-brano-e-il-disco-che-segna-il-ritorno-di-mgz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicati\/disco-inutile-e-il-brano-e-il-disco-che-segna-il-ritorno-di-mgz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"DISCO INUTILE \u00e8 il brano e il disco che segna il ritorno di MGZ"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicati\/#website","url":"https:\/\/www.area-press.eu\/comunicati\/","name":"area-press.eu - comunicati","description":"Press releases e comunicati stampa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4","name":"Redazione area-press.eu","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","caption":"Redazione area-press.eu"},"url":"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/69441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=69441"}],"version-history":[{"count":0,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/69441\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=69441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=69441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=69441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}