{"id":68379,"date":"2013-11-05T00:00:00","date_gmt":"2013-11-04T23:00:00","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicati\/lugana-doc-3-bicchieri-del-gambero-rosso-questanno\/"},"modified":"2013-11-05T00:00:00","modified_gmt":"2013-11-04T23:00:00","slug":"lugana-doc-3-bicchieri-del-gambero-rosso-questanno","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicati\/lugana-doc-3-bicchieri-del-gambero-rosso-questanno\/","title":{"rendered":"Lugana Doc, 3 bicchieri del Gambero Rosso quest&#8217;anno!"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><\/p>\n<p class=\"MsoNormal\">La fine dell&rsquo;estate e l&rsquo;avvicinarsi dell&rsquo;autunno sono un periodo di forte fermento per il mondo del vino. Anche i produttori di Lugana hanno salutato la fine della bella stagione con il bellissimo evento &ldquo;Armonie senza Tempo&rdquo; che quest&rsquo;anno si &egrave; svolto nella suggestiva cornice di Desenzano del Garda (BS), riscuotendo sempre maggior successo e affluenza di pubblico.<\/p>\n<p class=\"MsoNormal\">Dopo i festeggiamenti si &egrave; passati al duro lavoro della vendemmia, che per le cause climatiche dei mesi precedenti quest&rsquo;anno &egrave; stata leggermente tardiva, con un&rsquo;ottima qualit&agrave; che porter&agrave; ad un vino straordinario.<\/p>\n<p class=\"MsoNormal\">La dedizione con cui i produttori seguono il &ldquo;loro vino&rdquo; nel corso degli anni ha portato ad ottimi risultati, ed &egrave; cos&igrave; che questo 2013 ha portato ben quattro Lugana ad aggiudicarsi i <strong>3 bicchieri<\/strong> della <strong>Guida del Gambero Rosso<\/strong>:<\/p>\n<p class=\"MsoNormal\" style=\"margin-left: 36.0pt; text-indent: -18.0pt; mso-list: l0 level1 lfo1; tab-stops: list 36.0pt;\">&#8211;<span style=\"font-size: 7pt; font-family: 'Times New Roman';\"> <\/span><strong>Lugana Brolettino 2011 C&agrave; dei Frati<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin-left: 36.0pt; text-indent: -18.0pt; mso-list: l0 level1 lfo1; tab-stops: list 36.0pt;\">&#8211;<span style=\"font-size: 7pt; font-family: 'Times New Roman';\"> <\/span><strong>Lugana Fabio Contato 2011 &#8211; Provenza <\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin-left: 36.0pt; text-indent: -18.0pt; mso-list: l0 level1 lfo1; tab-stops: list 36.0pt;\">&#8211;<span style=\"font-size: 7pt; font-family: 'Times New Roman';\"> <\/span><strong>Lugana Superiore Molceo 2011 &ndash; Ottella<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin-left: 36.0pt; text-indent: -18.0pt; mso-list: l0 level1 lfo1; tab-stops: list 36.0pt;\">&#8211;<span style=\"font-size: 7pt; font-family: 'Times New Roman';\"> <\/span><strong>Lugana Molin 2012 Provenza &#8211; C&agrave; Maiol<\/strong><\/p>\n<p class=\"MsoNormal\">Quest&rsquo;ultimo &egrave; un vino fresco<strong>,<\/strong> avvenimento, quest&rsquo;assegnazione, che accade per la prima volta per questa tipologia e quindi ancor pi&ugrave; merito ai produttori che sono in grado di dare importanza ad una produzione molto recente.<\/p>\n<p class=\"MsoNormal\">Soddisfazioni che nel corso del tempo hanno portato il Lugana in un mercato importante, grazie anche al capillare lavoro del Consorzio di Tutela che ha fatto conoscere nel mondo il nome di questo armonico e caratteristico vino. Dal Vinitaly di Verona al Wineexpo di Bordeaux si &egrave; potuto degustare ed apprezzare un vino pregiato, ma, che fino a qualche anno fa, era conosciuto da pochi.<\/p>\n<p class=\"MsoNormal\">L&rsquo;attivit&agrave; del Consorzio prosegue con due importanti eventi che ci saranno nei prossimi giorni: dal 9 al 11 Novembre il <strong>Wine Festival di Merano (BZ),<\/strong> uno degli eventi pi&ugrave; esclusivi nel mondo, dove sar&agrave; presente il meglio della produzione enologica nazionale ed internazionale che saranno ospitati nelle magnifiche sale del Kurhaus, edificio storico nel pieno centro della cittadina bolzanina.<\/p>\n<p class=\"MsoNormal\">Dal 16 al 18 Novembre <strong>Golosaria a Milano<\/strong>, rassegna di cultura e gusto promossa dal Club di Papillon. La location del 2013 sar&agrave; SuperStudioPi&ugrave;, dove si trovano 8000 mq di spazi esclusivi nel quartiere milanese del design.<\/p>\n<p class=\"MsoNormal\">I continui successi del lavoro di un gruppo di persone legate al territorio e al loro prodotto, di vitigni seguiti con dedizione e preparazione porteranno sicuramente ad ulteriori successi ed apprezzamenti non solo in Italia ma in tutto il mondo del vino, &egrave; cos&igrave; che il Lugana diverr&agrave; pi&ugrave; conosciuto e stimato.<\/p>\n<p class=\"MsoNormal\"><a href=\"http:\/\/www.facebook.com\/consorzioluganadoc\">www.facebook.com\/consorzioluganadoc<\/a><\/p>\n<p class=\"MsoNormal\">Novella Donelli &#8211; ufficio stampa Jit<br \/> tel. 0456171550<br \/> <a href=\"mailto:novella@justintimesrl.it\">novella@justintimesrl.it<\/a><br \/> <a href=\"http:\/\/justintimesrl.wordpress.com\/\">http:\/\/justintimesrl.wordpress.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La fine dell&rsquo;estate e l&rsquo;avvicinarsi dell&rsquo;autunno sono un periodo di forte fermento per il mondo del vino. Anche i produttori di Lugana hanno salutato la fine della bella stagione con il bellissimo evento &ldquo;Armonie senza Tempo&rdquo; che quest&rsquo;anno si &egrave; svolto nella suggestiva cornice di Desenzano del Garda (BS), riscuotendo sempre maggior successo e affluenza [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7585],"tags":[55093,55094,47061,60322,70490,24493,70491,55096,70492,55097,70493,70494],"class_list":["post-68379","post","type-post","status-publish","format-standard","hentry","category-eventi","tag-consorzio-lugana","tag-consorzio-tutela","tag-desenzano-del-garda","tag-eventi-lugana-2013","tag-eventi-vino-2013","tag-gambero-rosso","tag-guida-vini-2014","tag-lugana","tag-lugana-brolettino-2011-ca-dei-frati","tag-lugana-doc","tag-lugana-fabio-contato-2011-provenza","tag-lugana-molin-2012-provenza-ca"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lugana Doc, 3 bicchieri del Gambero Rosso quest&#039;anno! - area-press.eu - comunicati<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.area-press.eu\/comunicati\/lugana-doc-3-bicchieri-del-gambero-rosso-questanno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lugana Doc, 3 bicchieri del Gambero Rosso quest&#039;anno! - area-press.eu - comunicati\" \/>\n<meta property=\"og:description\" content=\"La fine dell&rsquo;estate e l&rsquo;avvicinarsi dell&rsquo;autunno sono un periodo di forte fermento per il mondo del vino. Anche i produttori di Lugana hanno salutato la fine della bella stagione con il bellissimo evento &ldquo;Armonie senza Tempo&rdquo; che quest&rsquo;anno si &egrave; svolto nella suggestiva cornice di Desenzano del Garda (BS), riscuotendo sempre maggior successo e affluenza [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicati\/lugana-doc-3-bicchieri-del-gambero-rosso-questanno\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu - comunicati\" \/>\n<meta property=\"article:published_time\" content=\"2013-11-04T23:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione area-press.eu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione area-press.eu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/lugana-doc-3-bicchieri-del-gambero-rosso-questanno\/\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/lugana-doc-3-bicchieri-del-gambero-rosso-questanno\/\",\"name\":\"Lugana Doc, 3 bicchieri del Gambero Rosso quest'anno! - area-press.eu - comunicati\",\"isPartOf\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\"},\"datePublished\":\"2013-11-04T23:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/lugana-doc-3-bicchieri-del-gambero-rosso-questanno\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.area-press.eu\/comunicati\/lugana-doc-3-bicchieri-del-gambero-rosso-questanno\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/lugana-doc-3-bicchieri-del-gambero-rosso-questanno\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.area-press.eu\/comunicati\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lugana Doc, 3 bicchieri del Gambero Rosso quest&#8217;anno!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/\",\"name\":\"area-press.eu - comunicati\",\"description\":\"Press releases e comunicati stampa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\",\"name\":\"Redazione area-press.eu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"caption\":\"Redazione area-press.eu\"},\"url\":\"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lugana Doc, 3 bicchieri del Gambero Rosso quest'anno! - area-press.eu - comunicati","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.area-press.eu\/comunicati\/lugana-doc-3-bicchieri-del-gambero-rosso-questanno\/","og_locale":"it_IT","og_type":"article","og_title":"Lugana Doc, 3 bicchieri del Gambero Rosso quest'anno! - area-press.eu - comunicati","og_description":"La fine dell&rsquo;estate e l&rsquo;avvicinarsi dell&rsquo;autunno sono un periodo di forte fermento per il mondo del vino. Anche i produttori di Lugana hanno salutato la fine della bella stagione con il bellissimo evento &ldquo;Armonie senza Tempo&rdquo; che quest&rsquo;anno si &egrave; svolto nella suggestiva cornice di Desenzano del Garda (BS), riscuotendo sempre maggior successo e affluenza [&hellip;]","og_url":"https:\/\/www.area-press.eu\/comunicati\/lugana-doc-3-bicchieri-del-gambero-rosso-questanno\/","og_site_name":"area-press.eu - comunicati","article_published_time":"2013-11-04T23:00:00+00:00","author":"Redazione area-press.eu","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione area-press.eu","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicati\/lugana-doc-3-bicchieri-del-gambero-rosso-questanno\/","url":"https:\/\/www.area-press.eu\/comunicati\/lugana-doc-3-bicchieri-del-gambero-rosso-questanno\/","name":"Lugana Doc, 3 bicchieri del Gambero Rosso quest'anno! - area-press.eu - comunicati","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#website"},"datePublished":"2013-11-04T23:00:00+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicati\/lugana-doc-3-bicchieri-del-gambero-rosso-questanno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicati\/lugana-doc-3-bicchieri-del-gambero-rosso-questanno\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicati\/lugana-doc-3-bicchieri-del-gambero-rosso-questanno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Lugana Doc, 3 bicchieri del Gambero Rosso quest&#8217;anno!"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicati\/#website","url":"https:\/\/www.area-press.eu\/comunicati\/","name":"area-press.eu - comunicati","description":"Press releases e comunicati stampa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4","name":"Redazione area-press.eu","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","caption":"Redazione area-press.eu"},"url":"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/68379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=68379"}],"version-history":[{"count":0,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/68379\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=68379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=68379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=68379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}