{"id":68096,"date":"2013-10-23T00:00:00","date_gmt":"2013-10-22T22:00:00","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicati\/qnap-presenta-i-nuovi-turbo-nas-professionali-serie-ts-x70\/"},"modified":"2013-10-23T00:00:00","modified_gmt":"2013-10-22T22:00:00","slug":"qnap-presenta-i-nuovi-turbo-nas-professionali-serie-ts-x70","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicati\/qnap-presenta-i-nuovi-turbo-nas-professionali-serie-ts-x70\/","title":{"rendered":"QNAP presenta i nuovi Turbo NAS professionali serie TS-x70"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><\/p>\n<p><p class=\"MsoNormal\" style=\"text-align: justify; line-height: 20.0pt; mso-line-height-rule: exactly;\"><span style=\"font-family: Arial; mso-ansi-language: IT;\">QNAP&reg;<span class=\"apple-converted-space\"> <\/span>Systems, Inc. presenta oggi la nuova gamma di prodotti professionali Turbo NAS serie TS-x70 <span style=\"color: #0d0d0d;\">che comprende tre nuovi modelli con supporto per 4, 6 e 8 dischi, la soluzione migliore per venire incontro alla crescente domanda di storage delle aziende.<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; line-height: 20.0pt; mso-line-height-rule: exactly;\"><span style=\"font-family: Arial; color: #0d0d0d; mso-ansi-language: IT;\">Le aziende sono alla costante ricerca di maggior spazio di archiviazione. I prodotti della serie <strong style=\"mso-bidi-font-weight: normal;\">TS-x70<\/strong> di <strong style=\"mso-bidi-font-weight: normal;\">QNAP<\/strong> sono caratterizzati da un&rsquo;architettura scalabile che permette di espandere ulteriormente lo spazio disponibile grazie alle <strong style=\"mso-bidi-font-weight: normal;\">unit&agrave; di espansione RAID<\/strong> (REXP-1200U-RP \/ REXP-1600U-RP) che permettono di ampliare lo spazio di archiviazione fino a <strong style=\"mso-bidi-font-weight: normal;\">100TB<\/strong>. In questo modo &egrave; sempre possibile aggiornare il proprio sistema di storage in base alle reali necessit&agrave;.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; line-height: 20.0pt; mso-line-height-rule: exactly;\"><span style=\"font-family: Arial; color: #0d0d0d; mso-ansi-language: IT;\"> Sul fronte hardware, la serie TS-x70 &egrave; carattrerizzata da <strong style=\"mso-bidi-font-weight: normal;\">processori Intel Dual-core da 2.6 GHz<\/strong>, <strong style=\"mso-bidi-font-weight: normal;\">2GB di RAM DDR3<\/strong> e ben quattro porte di rete <strong style=\"mso-bidi-font-weight: normal;\">Gigabit LAN<\/strong>, caratteristiche tecniche che rendono questi modelli estremamente performante in ambito aziendale, soprattutto per le quotidiane attivit&agrave; di archiviazione, copia e spostamento dei dati. &ldquo;I test interni di QNAP hanno fatto registrare <strong style=\"mso-bidi-font-weight: normal;\">trasferimenti dati di 450MB\/sec in scrittura e 423MB\/sec in lettura<\/strong> in un tipico ambiente Windows in modalit&agrave; network trunking&rdquo; afferma Jason Hsu, product manager di QNAP. &ldquo;Inoltre, la serie TS-x70 include il supporto alla connettivit&agrave; di rete ad alta velocit&agrave; 10GbE ideale per applicazioni di editing video HD in tempo reale e per i data center&rdquo; aggiunge Hsu.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; line-height: 20.0pt; mso-line-height-rule: exactly;\"><span style=\"font-family: Arial; color: #0d0d0d; mso-ansi-language: IT;\">L&rsquo;utilizzo e la gestione della serie TS-x70 &egrave; resa agevole dal <strong style=\"mso-bidi-font-weight: normal;\">nuovo sistema operativo QTS 4.0<\/strong>. L&rsquo;intuitiva interfaccia semplifica il lavoro dei responsabili IT aziendali, rendendone semplice la gestione, il monitoraggio e la possibilit&agrave; di lanciare pi&ugrave; processi contemporaneamente. Il nuovo QTS 4.0 offre inoltre tutta una serie di applicazioni per la gestione, la condivisione ed il backup dei file, applicazioni multimediali oltre alla possibilit&agrave; di monitoraggio di telecamere IP, trasformando il NAS in un vero e proprio sistema di <strong style=\"mso-bidi-font-weight: normal;\">video sorveglianza<\/strong>.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; line-height: 20.0pt; mso-line-height-rule: exactly;\"><span style=\"font-family: Arial; mso-ansi-language: IT;\">Sul fronte della virtualizzazione i prodotti serie TS-x70, oltre a poter essere utilizzati in ambienti via iSCSI\/IP-SAN, sono certificati VMware&reg;<span class=\"apple-converted-space\"> <\/span>vSphere&trade; e Citrix&reg;<span class=\"apple-converted-space\"> <\/span>XenServer&trade;<span class=\"apple-converted-space\">, <\/span>e sono compatibili con Microsoft&reg; Hyper-V&trade; e Windows Server 2012. E&rsquo; inoltre supportato VMware VAAI e QNAP vSphere Client plug-in.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; line-height: 20.0pt; mso-line-height-rule: exactly;\"><span style=\"font-family: Arial; mso-ansi-language: IT;\">I prodotti della serie TS-x70 sono ideali come sistema centralizzato di storage per le PMI ed aziende di grandi dimensioni e sono compatibili con sistemi Windows&reg;, Mac&reg;, e Linux\/UNIX. Sono supportati i servizi Windows AD e LDAP e possono essere integrati con Windows ACL (Access Control List), <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; line-height: 20.0pt; mso-line-height-rule: exactly;\"><span style=\"font-family: Arial; mso-ansi-language: IT;\">La serie TS-x70 offre anche utili strumenti per il backup di sistemi Windows users e Mac grazie a QNAP NetBak Replicator ed il supporto per Apple Time. E&rsquo; inoltre inclusa la Replica Remota in Tempo Reale (RTRR), il backup su sistemi di cloud storage inclusi Amazon&reg; S3, ElephantDrive&reg;, Symform&reg;<span class=\"apple-converted-space\"> <\/span>e Google&reg;<span class=\"apple-converted-space\"> <\/span>Drive ed il supporto per software di backup come Veeam&reg; Backup &amp; Replication e Acronis&reg; True Image. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; line-height: 20.0pt; mso-line-height-rule: exactly;\"><span style=\"font-family: Arial; mso-ansi-language: IT;\">E&rsquo; inoltre incluso il nuovo App Center che offre ulteriori applicazioni per espandere le funzionalit&agrave; del sistema. E&rsquo; possibile scaricare ed installare ulteriori applicazioni direttamente dalla comoda interfaccia di gestione. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"line-height: 20.0pt; mso-line-height-rule: exactly; mso-pagination: widow-orphan; mso-outline-level: 1;\"><strong><span style=\"font-family: Arial; mso-font-kerning: 0pt;\" lang=\"EN-US\">Specifiche tecniche dei nuovi modelli<\/span><\/strong><\/p>\n<\/p>\n<ul>\n<li><span style=\"font-family: Wingdings; mso-fareast-font-family: Wingdings; mso-bidi-font-family: Wingdings; mso-font-kerning: 0pt; mso-ansi-language: IT;\"><span style=\"mso-list: Ignore;\"><\/span><\/span><span style=\"font-family: Arial; mso-font-kerning: 0pt; mso-ansi-language: IT;\">TS-870: 8-dischi, formato tower, Processore Intel Dual-core a 2.6 GHz, 2GB di RAM DDR3, 4x Porte Gigabit LAN, Connettivit&agrave; 10GbE, supporto per dischi fissi \/ SSD SATA 6Gbps, hot-swap, 2x Porte USB 3.0, Porta HDMI;<\/span><\/li>\n<li><span style=\"font-family: Arial; mso-font-kerning: 0pt; mso-ansi-language: IT;\">TS-670: 6-dischi, formato tower, Processore Intel Dual-core a 2.6 GHz, 2GB di RAM DDR3, 4x Porte Gigabit LAN, Connettivit&agrave; 10GbE, supporto per dischi fissi \/ SSD SATA 6Gbps, hot-swap, 2x Porte USB 3.0, Porta HDMI;<\/span><span style=\"font-family: Wingdings; mso-fareast-font-family: Wingdings; mso-bidi-font-family: Wingdings; color: #0d0d0d; mso-font-kerning: 0pt; mso-ansi-language: IT;\"><span style=\"mso-list: Ignore;\"><span style=\"font: 7.0pt &quot;Times New Roman&quot;;\"> <br \/><\/span><\/span><\/span><\/li>\n<li><span style=\"font-family: Wingdings; mso-fareast-font-family: Wingdings; mso-bidi-font-family: Wingdings; color: #0d0d0d; mso-font-kerning: 0pt; mso-ansi-language: IT;\"><span style=\"mso-list: Ignore;\"><\/span><\/span><span style=\"font-family: Arial; mso-font-kerning: 0pt; mso-ansi-language: IT;\">TS-470: 4-dischi, formato tower, Processore Intel Dual-core a 2.6 GHz,<span style=\"color: #0d0d0d;\"> 2GB di RAM DDR3, 4x Porte Gigabit LAN, Connettivit&agrave; 10GbE, supporto per dischi fissi \/ SSD SATA 6Gbps, hot-swap, 2x Porte USB 3.0, Porta HDMI.<\/span><\/span><\/li>\n<\/ul>\n<p><p class=\"MsoNormal\" style=\"line-height: 20.0pt; mso-line-height-rule: exactly; mso-pagination: widow-orphan; mso-outline-level: 1;\"><span style=\"font-family: Arial; color: #0d0d0d; mso-font-kerning: 0pt; mso-ansi-language: IT;\"> <\/span><strong><span style=\"font-family: Arial; color: #0d0d0d; mso-font-kerning: 0pt; mso-ansi-language: IT;\">Disponibilit&agrave;<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"line-height: 20.0pt; mso-line-height-rule: exactly; mso-pagination: widow-orphan;\"><span style=\"font-family: Arial; color: #0d0d0d; mso-font-kerning: 0pt; mso-ansi-language: IT;\">La serie TS-x70 Turbo NAS &egrave; disponibile da subito. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"line-height: 20.0pt; mso-line-height-rule: exactly; mso-pagination: widow-orphan;\"><span style=\"font-family: Arial; color: #0d0d0d; mso-font-kerning: 0pt; mso-ansi-language: IT;\">Per maggiori informazioni sui prodotti Turbo NAS di QNAP e per sapere dove acquistare i prodotti vi invitiamo a visitare il sito <\/span><span style=\"mso-ansi-language: IT;\"><a href=\"http:\/\/www.qnap.com\/\" class=\"broken_link\"><span style=\"font-family: Arial; color: #0000ee; mso-font-kerning: 0pt; text-decoration: none; text-underline: none;\">www.qnap.com<\/span><\/a><\/span><span style=\"font-family: Arial; color: #0d0d0d; mso-font-kerning: 0pt; mso-ansi-language: IT;\">.<\/span><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>QNAP&reg; Systems, Inc. presenta oggi la nuova gamma di prodotti professionali Turbo NAS serie TS-x70 che comprende tre nuovi modelli con supporto per 4, 6 e 8 dischi, la soluzione migliore per venire incontro alla crescente domanda di storage delle aziende. Le aziende sono alla costante ricerca di maggior spazio di archiviazione. I prodotti della [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7553],"tags":[4290,70207],"class_list":["post-68096","post","type-post","status-publish","format-standard","hentry","category-comunicati_stampa","tag-qnap","tag-ts-x70"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>QNAP presenta i nuovi Turbo NAS professionali serie TS-x70 - area-press.eu - comunicati<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.area-press.eu\/comunicati\/qnap-presenta-i-nuovi-turbo-nas-professionali-serie-ts-x70\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"QNAP presenta i nuovi Turbo NAS professionali serie TS-x70 - area-press.eu - comunicati\" \/>\n<meta property=\"og:description\" content=\"QNAP&reg; Systems, Inc. presenta oggi la nuova gamma di prodotti professionali Turbo NAS serie TS-x70 che comprende tre nuovi modelli con supporto per 4, 6 e 8 dischi, la soluzione migliore per venire incontro alla crescente domanda di storage delle aziende. Le aziende sono alla costante ricerca di maggior spazio di archiviazione. I prodotti della [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicati\/qnap-presenta-i-nuovi-turbo-nas-professionali-serie-ts-x70\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu - comunicati\" \/>\n<meta property=\"article:published_time\" content=\"2013-10-22T22:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione area-press.eu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione area-press.eu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/qnap-presenta-i-nuovi-turbo-nas-professionali-serie-ts-x70\/\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/qnap-presenta-i-nuovi-turbo-nas-professionali-serie-ts-x70\/\",\"name\":\"QNAP presenta i nuovi Turbo NAS professionali serie TS-x70 - area-press.eu - comunicati\",\"isPartOf\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\"},\"datePublished\":\"2013-10-22T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/qnap-presenta-i-nuovi-turbo-nas-professionali-serie-ts-x70\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.area-press.eu\/comunicati\/qnap-presenta-i-nuovi-turbo-nas-professionali-serie-ts-x70\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/qnap-presenta-i-nuovi-turbo-nas-professionali-serie-ts-x70\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.area-press.eu\/comunicati\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"QNAP presenta i nuovi Turbo NAS professionali serie TS-x70\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/\",\"name\":\"area-press.eu - comunicati\",\"description\":\"Press releases e comunicati stampa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\",\"name\":\"Redazione area-press.eu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"caption\":\"Redazione area-press.eu\"},\"url\":\"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"QNAP presenta i nuovi Turbo NAS professionali serie TS-x70 - area-press.eu - comunicati","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.area-press.eu\/comunicati\/qnap-presenta-i-nuovi-turbo-nas-professionali-serie-ts-x70\/","og_locale":"it_IT","og_type":"article","og_title":"QNAP presenta i nuovi Turbo NAS professionali serie TS-x70 - area-press.eu - comunicati","og_description":"QNAP&reg; Systems, Inc. presenta oggi la nuova gamma di prodotti professionali Turbo NAS serie TS-x70 che comprende tre nuovi modelli con supporto per 4, 6 e 8 dischi, la soluzione migliore per venire incontro alla crescente domanda di storage delle aziende. Le aziende sono alla costante ricerca di maggior spazio di archiviazione. I prodotti della [&hellip;]","og_url":"https:\/\/www.area-press.eu\/comunicati\/qnap-presenta-i-nuovi-turbo-nas-professionali-serie-ts-x70\/","og_site_name":"area-press.eu - comunicati","article_published_time":"2013-10-22T22:00:00+00:00","author":"Redazione area-press.eu","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione area-press.eu","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicati\/qnap-presenta-i-nuovi-turbo-nas-professionali-serie-ts-x70\/","url":"https:\/\/www.area-press.eu\/comunicati\/qnap-presenta-i-nuovi-turbo-nas-professionali-serie-ts-x70\/","name":"QNAP presenta i nuovi Turbo NAS professionali serie TS-x70 - area-press.eu - comunicati","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#website"},"datePublished":"2013-10-22T22:00:00+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicati\/qnap-presenta-i-nuovi-turbo-nas-professionali-serie-ts-x70\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicati\/qnap-presenta-i-nuovi-turbo-nas-professionali-serie-ts-x70\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicati\/qnap-presenta-i-nuovi-turbo-nas-professionali-serie-ts-x70\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"QNAP presenta i nuovi Turbo NAS professionali serie TS-x70"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicati\/#website","url":"https:\/\/www.area-press.eu\/comunicati\/","name":"area-press.eu - comunicati","description":"Press releases e comunicati stampa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4","name":"Redazione area-press.eu","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","caption":"Redazione area-press.eu"},"url":"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/68096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=68096"}],"version-history":[{"count":0,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/68096\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=68096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=68096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=68096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}