{"id":65903,"date":"2013-07-22T00:00:00","date_gmt":"2013-07-21T22:00:00","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicati\/il-manager-salvo-nugnes-parla-dellevento-dellanno-la-mostra-di-amanda-lear-alla-milano-art-gallery\/"},"modified":"2013-07-22T00:00:00","modified_gmt":"2013-07-21T22:00:00","slug":"il-manager-salvo-nugnes-parla-dellevento-dellanno-la-mostra-di-amanda-lear-alla-milano-art-gallery","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicati\/il-manager-salvo-nugnes-parla-dellevento-dellanno-la-mostra-di-amanda-lear-alla-milano-art-gallery\/","title":{"rendered":"Il manager Salvo Nugnes parla dell\u2019evento dell\u2019anno: la mostra di Amanda Lear alla Milano Art Gallery"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><\/p>\n<p><p class=\"MsoNormal\" style=\"mso-pagination: none; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 13.0pt; font-family: Arial; color: #1a1a1a;\">Il 31 Luglio, Amanda Lear, celebre attrice, pittrice, presentatrice televisiva francese e cantautrice, inaugurer&agrave; la sua mostra personale presso la &ldquo;<a href=\"http:\/\/www.milanoartgallery.it\/\"><em><span style=\"color: #0739c8; text-decoration: none; text-underline: none;\">Milano Art Gallery Spazio Culturale<\/span><\/em><\/a>&rdquo;. Per l&rsquo;occasione il manager di illustri personaggi della cultura, Salvo Nugnes, Direttore di <a href=\"http:\/\/www.promoterarte.it\/\" class=\"broken_link\"><em><span style=\"color: #0739c8; text-decoration: none; text-underline: none;\">Promoter Arte<\/span><\/em><\/a><em> <\/em>, &egrave; stato intervistato per parlare della celebre regina dello spettacolo.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"mso-pagination: none; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 13.0pt; font-family: Arial; color: #1a1a1a;\"> <\/span><\/p>\n<p class=\"MsoNormal\" style=\"mso-pagination: none; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 13.0pt; font-family: Arial; color: #1a1a1a;\">1) QUANDO SI TERRA&#8217; LA MOSTRA PERSONALE DI AMANDA LEAR ALLA &#8220;MILANO ART GALLERY&#8221;?<\/span><\/p>\n<p class=\"MsoNormal\" style=\"mso-pagination: none; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 13.0pt; font-family: Arial; color: #1a1a1a;\">Abbiamo concordato con Amanda di allestire la sua prestigiosa mostra personale dal titolo &#8220;<em>Visioni<\/em>&#8221; a partire dal 31 Luglio prossimo, nel contesto della storica &#8220;<a href=\"http:\/\/www.milanoartgallery.it\/\"><em><span style=\"color: #0739c8; text-decoration: none; text-underline: none;\">Milano Art Gallery Spazio Culturale<\/span><\/em><\/a>&#8221; di cui sono Direttore, che si trova nel cuore di Milano, a due passi dal Duomo, in via Alessi 11. &Egrave; previsto un importante vernissage inaugurale alla presenza di illustri personaggi, vip e autorit&agrave; istituzionali che parteciperanno all&#8217;evento. L&#8217;ingresso al pubblico &egrave; libero.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"mso-pagination: none; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 13.0pt; font-family: Arial; color: #1a1a1a;\"> <\/span><\/p>\n<p class=\"MsoNormal\" style=\"mso-pagination: none; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 13.0pt; font-family: Arial; color: #1a1a1a;\">2) LA LEAR HA GIA&#8217; VISITATO DI PERSONA LA GALLERIA?<\/span><\/p>\n<p class=\"MsoNormal\" style=\"mso-pagination: none; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 13.0pt; font-family: Arial; color: #1a1a1a;\">Amanda &egrave; venuta appositamente in galleria per visionare lo spazio di persona ed &egrave; rimasta molto compiaciuta della location. Insieme abbiamo individuato la soluzione ottimale di allestimento e la collocazione pi&ugrave; congeniale per valorizzare al meglio le sue opere. Poi approfittando di un&#8217;intervista fatta a &#8220;<em>Verissimo<\/em>&#8221; da Silvia Toffanin ha voluto annunciare in anteprima la mostra invitando tutti a visitarla. L&rsquo;attesa &egrave; gi&agrave; trepidante per questo appuntamento cos&igrave; speciale e per noi &egrave; un onore festeggiare insieme a lei anche il compleanno simbolico della galleria che cade proprio nella data del 31 luglio. Un duplice evento imperdibile!<\/span><\/p>\n<p class=\"MsoNormal\" style=\"mso-pagination: none; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 13.0pt; font-family: Arial; color: #1a1a1a;\"> <\/span><\/p>\n<p class=\"MsoNormal\" style=\"mso-pagination: none; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 13.0pt; font-family: Arial; color: #1a1a1a;\">3) QUALI OPERE VERRANNO ESPOSTE IN MOSTRA?<\/span><\/p>\n<p class=\"MsoNormal\" style=\"mso-pagination: none; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 13.0pt; font-family: Arial; color: #1a1a1a;\">Mi sono recato in Francia, dove attualmente abita Amanda e abbiamo selezionato una vasta ed eterogenea produzione di dipinti di elevato impatto suggestivo emozionale. Amanda coniuga il talento artistico innato al prorompente estro creativo e dimostra anche una personalit&agrave; molto profonda. &Egrave; una donna di intenso spessore emotivo e spiccata sensibilit&agrave; e riesce a trasmettere queste virt&ugrave; insite nelle sua indole, imprimendole sulle tele.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"mso-pagination: none; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 13.0pt; font-family: Arial; color: #1a1a1a;\"> <\/span><\/p>\n<p class=\"MsoNormal\" style=\"mso-pagination: none; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 13.0pt; font-family: Arial; color: #1a1a1a;\">4) LE OPERE SARANNO ANCHE ACQUISTABILI?<\/span><\/p>\n<p class=\"MsoNormal\" style=\"mso-pagination: none; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 13.0pt; font-family: Arial; color: #1a1a1a;\">Certamente, abbiamo la possibilit&agrave; di commercializzare queste opere durante la mostra e ci sar&agrave; un listino prezzi specifico, elaborato per l&#8217;occasione. Sar&agrave; un&#8217;ottima opportunit&agrave; di investimento per i numerosi estimatori di Amanda, ma anche per i collezionisti ed appassionati d&#8217;arte in generale.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"mso-pagination: none; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 13.0pt; font-family: Arial; color: #1a1a1a;\"> <\/span><\/p>\n<p class=\"MsoNormal\" style=\"mso-pagination: none; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 13.0pt; font-family: Arial; color: #1a1a1a;\">5) COSA APPREZZA NELLO STILE ARTISTICO DELLA LEAR?<\/span><\/p>\n<p class=\"MsoNormal\" style=\"mso-pagination: none; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 13.0pt; font-family: Arial; color: #1a1a1a;\">Senza dubbio mi hanno colpito la spontaneit&agrave; espressiva e il camaleontico e poliedrico trasformismo nella ricerca stilistica che la rendono eclettica ed originale. Poi emerge l&#8217;appassionata voglia di mettersi in gioco, poich&eacute; da tutti &egrave; conosciuta come la musa e icona ispiratrice del maestro Salvador Dal&igrave;, ma ha voluto affermarsi come talentuosa artista evidenziando un altro interessante aspetto della sua significativa presenza nel mondo dell&#8217;arte e ancora una volta ci ha regalato piacevoli e sorprendenti emozioni<\/span><\/p>\n<p class=\"MsoNormal\" style=\"mso-pagination: none; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 13.0pt; font-family: Arial; color: #1a1a1a;\"> <\/span><\/p>\n<p class=\"MsoNormal\" style=\"mso-pagination: none; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 13.0pt; font-family: Arial; color: #1a1a1a;\">6) HA AVUTO MODO DI ASSISTERE AD UNA PERFORMANCE TEATRALE DELLA LEAR?<\/span><\/p>\n<p class=\"MsoNormal\" style=\"mso-pagination: none; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 13.0pt; font-family: Arial; color: #1a1a1a;\">Ho assistito alla strepitosa interpretazione di &#8220;<em>Lady Oscar<\/em>&#8221; il bellissimo spettacolo che Amanda sta portando in tour nei principali teatri francesi e che la vede protagonista indiscussa. Anche in questo ambito Amanda dimostra il proprio valore nella grande capacit&agrave; interpretativa, nel brillante carisma e nella viscerale passione. Ha saputo reiventarsi e trasformarsi nel ruolo di attrice regina del palcoscenico e sta ottenendo un meritato successo, &egrave; acclamata dal pubblico e benvoluta dalla critica di settore. La considero una donna straordinaria, dalle mille risorse che affronta la vita al motto di &#8220;testa alta e profumo francese&#8221;.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"mso-pagination: none; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 13.0pt; font-family: Arial; color: #18366d;\"> <\/span><span style=\"font-size: 13.0pt; font-family: Arial; color: #1a1a1a;\"><\/span><\/p>\n<p class=\"MsoNormal\" style=\"mso-pagination: none; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 13.0pt; font-family: Arial; color: #18366d;\"> <\/span><span style=\"font-size: 13.0pt; font-family: Arial; color: #1a1a1a;\"><\/span><\/p>\n<p class=\"MsoNormal\"><span style=\"font-size: 13.0pt; font-family: Arial; color: #18366d;\"> <\/span><\/p>\n<p class=\"MsoNormal\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 31 Luglio, Amanda Lear, celebre attrice, pittrice, presentatrice televisiva francese e cantautrice, inaugurer&agrave; la sua mostra personale presso la &ldquo;Milano Art Gallery Spazio Culturale&rdquo;. Per l&rsquo;occasione il manager di illustri personaggi della cultura, Salvo Nugnes, Direttore di Promoter Arte , &egrave; stato intervistato per parlare della celebre regina dello spettacolo. 1) QUANDO SI TERRA&#8217; [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7621],"tags":[59290,62905,62906,6034],"class_list":["post-65903","post","type-post","status-publish","format-standard","hentry","category-arte_cultura","tag-agenzia-promoter","tag-amanda-lear","tag-milano-art-gallery","tag-salvo-nugnes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Il manager Salvo Nugnes parla dell\u2019evento dell\u2019anno: la mostra di Amanda Lear alla Milano Art Gallery - area-press.eu - comunicati<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.area-press.eu\/comunicati\/il-manager-salvo-nugnes-parla-dellevento-dellanno-la-mostra-di-amanda-lear-alla-milano-art-gallery\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il manager Salvo Nugnes parla dell\u2019evento dell\u2019anno: la mostra di Amanda Lear alla Milano Art Gallery - area-press.eu - comunicati\" \/>\n<meta property=\"og:description\" content=\"Il 31 Luglio, Amanda Lear, celebre attrice, pittrice, presentatrice televisiva francese e cantautrice, inaugurer&agrave; la sua mostra personale presso la &ldquo;Milano Art Gallery Spazio Culturale&rdquo;. Per l&rsquo;occasione il manager di illustri personaggi della cultura, Salvo Nugnes, Direttore di Promoter Arte , &egrave; stato intervistato per parlare della celebre regina dello spettacolo. 1) QUANDO SI TERRA&#8217; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicati\/il-manager-salvo-nugnes-parla-dellevento-dellanno-la-mostra-di-amanda-lear-alla-milano-art-gallery\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu - comunicati\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-21T22:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione area-press.eu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione area-press.eu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/il-manager-salvo-nugnes-parla-dellevento-dellanno-la-mostra-di-amanda-lear-alla-milano-art-gallery\/\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/il-manager-salvo-nugnes-parla-dellevento-dellanno-la-mostra-di-amanda-lear-alla-milano-art-gallery\/\",\"name\":\"Il manager Salvo Nugnes parla dell\u2019evento dell\u2019anno: la mostra di Amanda Lear alla Milano Art Gallery - area-press.eu - comunicati\",\"isPartOf\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\"},\"datePublished\":\"2013-07-21T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/il-manager-salvo-nugnes-parla-dellevento-dellanno-la-mostra-di-amanda-lear-alla-milano-art-gallery\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.area-press.eu\/comunicati\/il-manager-salvo-nugnes-parla-dellevento-dellanno-la-mostra-di-amanda-lear-alla-milano-art-gallery\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/il-manager-salvo-nugnes-parla-dellevento-dellanno-la-mostra-di-amanda-lear-alla-milano-art-gallery\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.area-press.eu\/comunicati\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il manager Salvo Nugnes parla dell\u2019evento dell\u2019anno: la mostra di Amanda Lear alla Milano Art Gallery\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/\",\"name\":\"area-press.eu - comunicati\",\"description\":\"Press releases e comunicati stampa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\",\"name\":\"Redazione area-press.eu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"caption\":\"Redazione area-press.eu\"},\"url\":\"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il manager Salvo Nugnes parla dell\u2019evento dell\u2019anno: la mostra di Amanda Lear alla Milano Art Gallery - area-press.eu - comunicati","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.area-press.eu\/comunicati\/il-manager-salvo-nugnes-parla-dellevento-dellanno-la-mostra-di-amanda-lear-alla-milano-art-gallery\/","og_locale":"it_IT","og_type":"article","og_title":"Il manager Salvo Nugnes parla dell\u2019evento dell\u2019anno: la mostra di Amanda Lear alla Milano Art Gallery - area-press.eu - comunicati","og_description":"Il 31 Luglio, Amanda Lear, celebre attrice, pittrice, presentatrice televisiva francese e cantautrice, inaugurer&agrave; la sua mostra personale presso la &ldquo;Milano Art Gallery Spazio Culturale&rdquo;. Per l&rsquo;occasione il manager di illustri personaggi della cultura, Salvo Nugnes, Direttore di Promoter Arte , &egrave; stato intervistato per parlare della celebre regina dello spettacolo. 1) QUANDO SI TERRA&#8217; [&hellip;]","og_url":"https:\/\/www.area-press.eu\/comunicati\/il-manager-salvo-nugnes-parla-dellevento-dellanno-la-mostra-di-amanda-lear-alla-milano-art-gallery\/","og_site_name":"area-press.eu - comunicati","article_published_time":"2013-07-21T22:00:00+00:00","author":"Redazione area-press.eu","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione area-press.eu","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicati\/il-manager-salvo-nugnes-parla-dellevento-dellanno-la-mostra-di-amanda-lear-alla-milano-art-gallery\/","url":"https:\/\/www.area-press.eu\/comunicati\/il-manager-salvo-nugnes-parla-dellevento-dellanno-la-mostra-di-amanda-lear-alla-milano-art-gallery\/","name":"Il manager Salvo Nugnes parla dell\u2019evento dell\u2019anno: la mostra di Amanda Lear alla Milano Art Gallery - area-press.eu - comunicati","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#website"},"datePublished":"2013-07-21T22:00:00+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicati\/il-manager-salvo-nugnes-parla-dellevento-dellanno-la-mostra-di-amanda-lear-alla-milano-art-gallery\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicati\/il-manager-salvo-nugnes-parla-dellevento-dellanno-la-mostra-di-amanda-lear-alla-milano-art-gallery\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicati\/il-manager-salvo-nugnes-parla-dellevento-dellanno-la-mostra-di-amanda-lear-alla-milano-art-gallery\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Il manager Salvo Nugnes parla dell\u2019evento dell\u2019anno: la mostra di Amanda Lear alla Milano Art Gallery"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicati\/#website","url":"https:\/\/www.area-press.eu\/comunicati\/","name":"area-press.eu - comunicati","description":"Press releases e comunicati stampa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4","name":"Redazione area-press.eu","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","caption":"Redazione area-press.eu"},"url":"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/65903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=65903"}],"version-history":[{"count":0,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/65903\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=65903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=65903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=65903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}