{"id":64167,"date":"2013-05-31T00:00:00","date_gmt":"2013-05-30T22:00:00","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicati\/nuovo-sito-per-il-ristorante-il-palazzo-di-santagata-feltria\/"},"modified":"2013-05-31T00:00:00","modified_gmt":"2013-05-30T22:00:00","slug":"nuovo-sito-per-il-ristorante-il-palazzo-di-santagata-feltria","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicati\/nuovo-sito-per-il-ristorante-il-palazzo-di-santagata-feltria\/","title":{"rendered":"Nuovo sito per il ristorante Il Palazzo di Sant&#8217;Agata Feltria."},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><\/p>\n<p>Il <a href=\"http:\/\/www.ristoranteilpalazzo.com\/\" target=\"_blank\">Ristorante Il Palazzo<\/a> di Sant&#8217;Agata Feltria mescola i piaceri della cucina tradizionale romagnola con i sapori tipici del sottobosco. Grazie alla sua posizione, &egrave; l&#8217;ideale per trascorrere una giornata immersi nel verde e lontani dal caos della citt&agrave;. Il Palazzo &egrave; aperto da oltre vent&#8217;anni, nato prima come trattoria poi successivamente trasformato in ristorante. Qui troverai una cucina tradizionale, caratterizzata dai sapori tipici del sottobosco: il tartufo bianco dell&#8217;Appennino Romagnolo e i funghi, porcini o prugnoli, a seconda dei periodi dell&#8217;anno. I primi piatti sono fatti in casa, a mano: gli spaghetti alla chitarra e i ripiegati al tartufo, uno dei pezzi forte della cucina. Cos&igrave; come gli antipasti e i dolci. Leggi online i men&ugrave;, i piatti e le ricette per prepararli in casa. Al ristorante Il Palazzo non c&#8217;&egrave; solo la tradizione, ma anche l&#8217;innovazione. Lo dimostra la forte presenza online: Facebook, Tripadvisor e adesso anche Youtube, con le videoricette. Potrai condividere le tue foto dei piatti e dei momenti trascorsi al ristorante sulla fan page ufficiale del Palazzo oppure, se ci sei stato a pranzo, lascia la tua recensione su Tripadvisor. Ti sei innamorato delle tagliatelle strigoli e prugnoli? Da oggi la signora Mirella ti spiega come fare a prepararle a casa tua, passo dopo passo, su Youtube. Il sito web &egrave; realizzato da GUEST, <a href=\"http:\/\/www.guest.it\/\" target=\"_blank\">web agency di Riccione<\/a>, che dal 1995 realizza siti internet dinamici, studiati in base alle esigenze di ogni cliente. Internet &egrave; il luogo migliore per reperire o veicolare informazioni e il sito web il mezzo pi&ugrave; idoneo per farsi trovare. Se anche il tuo sito ha bisogno di una rinfrescata, non lasciarti sfuggire questa possibilit&agrave;. GUEST si occupa anche di comunicazione online e web reputation. Non tutti hanno la possibilit&agrave; di avere il proprio Ufficio Stampa. Per questo GUEST ha pensato al pacchetto di servizi &ldquo;Websitter&rdquo;. Scopri di cosa si tratta. Per informazioni o per un preventivo gratuito, contatta GUEST al numero 0541.649292 oppure invia un&rsquo;email a info@guest.it<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuovo sito per il ristorante Il Palazzo di Sant&#8217;Agata Feltria realizzato dalla web agency GUEST srl.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7559],"tags":[11731,65353,65352,65354],"class_list":["post-64167","post","type-post","status-publish","format-standard","hentry","category-turismo","tag-guest-srl","tag-ristorante-palazzo","tag-ristorante-palazzo-santagata-feltria","tag-ristorante-santagata-feltria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nuovo sito per il ristorante Il Palazzo di Sant&#039;Agata Feltria. - area-press.eu - comunicati<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.area-press.eu\/comunicati\/nuovo-sito-per-il-ristorante-il-palazzo-di-santagata-feltria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuovo sito per il ristorante Il Palazzo di Sant&#039;Agata Feltria. - area-press.eu - comunicati\" \/>\n<meta property=\"og:description\" content=\"Nuovo sito per il ristorante Il Palazzo di Sant&#039;Agata Feltria realizzato dalla web agency GUEST srl.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicati\/nuovo-sito-per-il-ristorante-il-palazzo-di-santagata-feltria\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu - comunicati\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-30T22:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione area-press.eu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione area-press.eu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/nuovo-sito-per-il-ristorante-il-palazzo-di-santagata-feltria\/\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/nuovo-sito-per-il-ristorante-il-palazzo-di-santagata-feltria\/\",\"name\":\"Nuovo sito per il ristorante Il Palazzo di Sant'Agata Feltria. - area-press.eu - comunicati\",\"isPartOf\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\"},\"datePublished\":\"2013-05-30T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/nuovo-sito-per-il-ristorante-il-palazzo-di-santagata-feltria\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.area-press.eu\/comunicati\/nuovo-sito-per-il-ristorante-il-palazzo-di-santagata-feltria\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/nuovo-sito-per-il-ristorante-il-palazzo-di-santagata-feltria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.area-press.eu\/comunicati\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuovo sito per il ristorante Il Palazzo di Sant&#8217;Agata Feltria.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/\",\"name\":\"area-press.eu - comunicati\",\"description\":\"Press releases e comunicati stampa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\",\"name\":\"Redazione area-press.eu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"caption\":\"Redazione area-press.eu\"},\"url\":\"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuovo sito per il ristorante Il Palazzo di Sant'Agata Feltria. - area-press.eu - comunicati","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.area-press.eu\/comunicati\/nuovo-sito-per-il-ristorante-il-palazzo-di-santagata-feltria\/","og_locale":"it_IT","og_type":"article","og_title":"Nuovo sito per il ristorante Il Palazzo di Sant'Agata Feltria. - area-press.eu - comunicati","og_description":"Nuovo sito per il ristorante Il Palazzo di Sant'Agata Feltria realizzato dalla web agency GUEST srl.","og_url":"https:\/\/www.area-press.eu\/comunicati\/nuovo-sito-per-il-ristorante-il-palazzo-di-santagata-feltria\/","og_site_name":"area-press.eu - comunicati","article_published_time":"2013-05-30T22:00:00+00:00","author":"Redazione area-press.eu","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione area-press.eu","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicati\/nuovo-sito-per-il-ristorante-il-palazzo-di-santagata-feltria\/","url":"https:\/\/www.area-press.eu\/comunicati\/nuovo-sito-per-il-ristorante-il-palazzo-di-santagata-feltria\/","name":"Nuovo sito per il ristorante Il Palazzo di Sant'Agata Feltria. - area-press.eu - comunicati","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#website"},"datePublished":"2013-05-30T22:00:00+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicati\/nuovo-sito-per-il-ristorante-il-palazzo-di-santagata-feltria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicati\/nuovo-sito-per-il-ristorante-il-palazzo-di-santagata-feltria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicati\/nuovo-sito-per-il-ristorante-il-palazzo-di-santagata-feltria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Nuovo sito per il ristorante Il Palazzo di Sant&#8217;Agata Feltria."}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicati\/#website","url":"https:\/\/www.area-press.eu\/comunicati\/","name":"area-press.eu - comunicati","description":"Press releases e comunicati stampa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4","name":"Redazione area-press.eu","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","caption":"Redazione area-press.eu"},"url":"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/64167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=64167"}],"version-history":[{"count":0,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/64167\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=64167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=64167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=64167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}