{"id":6361,"date":"2009-06-08T00:00:00","date_gmt":"2009-06-07T22:00:00","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicati\/arte-dei-segni-per-dare-significato-alla-parola-valentino-candiani-in-mostra-a-milano\/"},"modified":"2009-06-08T00:00:00","modified_gmt":"2009-06-07T22:00:00","slug":"arte-dei-segni-per-dare-significato-alla-parola-valentino-candiani-in-mostra-a-milano","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicati\/arte-dei-segni-per-dare-significato-alla-parola-valentino-candiani-in-mostra-a-milano\/","title":{"rendered":"Arte dei Segni per dare significato alla Parola: Valentino Candiani in mostra a Milano"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><br \/>\nLa scrittura \u00e8 una delle pi\u00f9 grandi conquiste dell\u2019uomo. Antichissima, originata dai primi segni preistorici. Oggi le opere di Valentino Candiani tornano all\u2019origine della scrittura, ai caratteri cuneiformi, attraverso un\u2019arte rivoluzionaria che esprime con grande suggestione il potere evocativo della scrittura e della parola. <\/p>\n<p>Le sue opere, sculture e pannelli di graphic design, sono create con segni che sono originale mezzo espressivo in s\u00e9 e, allo stesso tempo, sono contenuto perch\u00e9 contengono parole di grande significato.<\/p>\n<p>Sono realizzate utilizzando l\u2019unicit\u00e0 dell\u2019impronta tipografica, la geometria, la monocromia come sintesi di tutti i colori. Sono il risultato di un processo mentale volto alla \u201csottrazione\u201d e al rapporto di interazione tra pieno e vuoto, al limite dell\u2019astrattismo. E grazie a questo processo, si presentano indipendenti da mode o tendenze, pulite da ogni inquinamento visivo, mettendo al centro il loro contenuto.<\/p>\n<p>Si tratta di un \u201cmoderno carattere primitivo\u201d, un nuovo canone estetico applicato a parole che fanno parte di un\u2019antropologia minimalista. Opere che non aggrediscono il fruitore, ma lo guidano in una nuova riflessione interiore.<\/p>\n<p>Valentino Candiani, artista milanese, si \u00e8 affermato professionalmente nel graphic design e nella fotografia negli anni pi\u00f9 recenti, prima di dedicarsi a un percorso di ricerca artistica che coniugasse design e lettering in forme espressive originali e di grande impatto emozionale.<\/p>\n<p>\u201cSkariphaomai\u201d \u00e8 la prima mostra frutto di questo percorso, che unisce le sculture e i pannelli di Valentino Candiani nati secondo questa sua nuova concezione. Un\u2019esposizione originale promossa dall\u2019agenzia di comunicazione Imageware e allestita in anteprima presso la sua sede di via Moretto da Brescia a Milano. <\/p>\n<p>Le opere in mostra si distinguono in alcuni filoni principali: i cinque sensi \u2013 vista, udito, tatto, olfatto, gusto &#8211; i quattro elementi &#8211; acqua, terra, aria, fuoco &#8211; le emozioni: amore e odio \u2013 e i concetti topici tempo e luce. <\/p>\n<p>Il titolo della manifestazione \u201cSkariphaomai\u201d &#8211; \u201cscalfisco in superficie\u201d in greco antico \u2013 porta in s\u00e9 una duplice valenza, perch\u00e9 riferita all\u2019epoca in cui i segni venivano incisi sui materiali come pietra, terracotta o legno e perch\u00e9 origine comune, dal punto di vista etimologico, di parole come il latino scribere, il francese \u00e9crire, il tedesco schreiben. <\/p>\n<p>E il ricorso all\u2019origine della scrittura universale si ritrova anche nella scelta di Candiani dell\u2019inglese come lingua base per i suoi segni: l\u2019inglese, che oggi nel mondo virtuale di Internet assume le qualit\u00e0 utopiche del progetto esperanto, prende il ruolo che in epoca classica era del latino.<\/p>\n<p>\u201cSiamo rimasti impressionati dalle opere di Valentino Candiani sia per la suggestione visiva che creano e per la forza comunicativa che trasferiscono sia per la portata di vera avanguardia dello stile espressivo con cui sono state concepite e realizzate\u201d, afferma Marco Franceschi, Amministratore Delegato di Imageware.<\/p>\n<p>\u201cAbbiamo chiesto, quindi, a questo artista originale e di grande talento di presentare la sua mostra presso la nostra sede, orgogliosi di poter ospitare una forma d\u2019arte che mette al centro il potere della parola. Come consulenti di comunicazione, vediamo particolarmente forte la sua suggestione, il potere dello strumento che anche noi abbiamo a disposizione, la parola; comunicare, in fondo, significa proprio mettere in condivisione un significato che nasce da un segno\u201d.<\/p>\n<p>La mostra sar\u00e0 aperta al pubblico dal 12 al 24 giugno tutti i giorni feriali dalle 14.00 alle 19.00 presso la sede di Imageware in via Moretto da Brescia 22 a Milano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Scrittura come forma d\u2019arte trova nuovo significato nelle opere di Valentino Candiani: segni rivoluzionari che sono nuovo canone estetico in s\u00e9 e, al contempo, espressione di parole topiche appartenenti a un\u2019antropologia minimalista e universale.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7553],"tags":[],"class_list":["post-6361","post","type-post","status-publish","format-standard","hentry","category-comunicati_stampa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arte dei Segni per dare significato alla Parola: Valentino Candiani in mostra a Milano - area-press.eu - comunicati<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.area-press.eu\/comunicati\/arte-dei-segni-per-dare-significato-alla-parola-valentino-candiani-in-mostra-a-milano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arte dei Segni per dare significato alla Parola: Valentino Candiani in mostra a Milano - area-press.eu - comunicati\" \/>\n<meta property=\"og:description\" content=\"La Scrittura come forma d\u2019arte trova nuovo significato nelle opere di Valentino Candiani: segni rivoluzionari che sono nuovo canone estetico in s\u00e9 e, al contempo, espressione di parole topiche appartenenti a un\u2019antropologia minimalista e universale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicati\/arte-dei-segni-per-dare-significato-alla-parola-valentino-candiani-in-mostra-a-milano\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu - comunicati\" \/>\n<meta property=\"article:published_time\" content=\"2009-06-07T22:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione area-press.eu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione area-press.eu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/arte-dei-segni-per-dare-significato-alla-parola-valentino-candiani-in-mostra-a-milano\/\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/arte-dei-segni-per-dare-significato-alla-parola-valentino-candiani-in-mostra-a-milano\/\",\"name\":\"Arte dei Segni per dare significato alla Parola: Valentino Candiani in mostra a Milano - area-press.eu - comunicati\",\"isPartOf\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\"},\"datePublished\":\"2009-06-07T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/arte-dei-segni-per-dare-significato-alla-parola-valentino-candiani-in-mostra-a-milano\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.area-press.eu\/comunicati\/arte-dei-segni-per-dare-significato-alla-parola-valentino-candiani-in-mostra-a-milano\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/arte-dei-segni-per-dare-significato-alla-parola-valentino-candiani-in-mostra-a-milano\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.area-press.eu\/comunicati\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arte dei Segni per dare significato alla Parola: Valentino Candiani in mostra a Milano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/\",\"name\":\"area-press.eu - comunicati\",\"description\":\"Press releases e comunicati stampa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\",\"name\":\"Redazione area-press.eu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"caption\":\"Redazione area-press.eu\"},\"url\":\"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arte dei Segni per dare significato alla Parola: Valentino Candiani in mostra a Milano - area-press.eu - comunicati","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.area-press.eu\/comunicati\/arte-dei-segni-per-dare-significato-alla-parola-valentino-candiani-in-mostra-a-milano\/","og_locale":"it_IT","og_type":"article","og_title":"Arte dei Segni per dare significato alla Parola: Valentino Candiani in mostra a Milano - area-press.eu - comunicati","og_description":"La Scrittura come forma d\u2019arte trova nuovo significato nelle opere di Valentino Candiani: segni rivoluzionari che sono nuovo canone estetico in s\u00e9 e, al contempo, espressione di parole topiche appartenenti a un\u2019antropologia minimalista e universale.","og_url":"https:\/\/www.area-press.eu\/comunicati\/arte-dei-segni-per-dare-significato-alla-parola-valentino-candiani-in-mostra-a-milano\/","og_site_name":"area-press.eu - comunicati","article_published_time":"2009-06-07T22:00:00+00:00","author":"Redazione area-press.eu","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione area-press.eu","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicati\/arte-dei-segni-per-dare-significato-alla-parola-valentino-candiani-in-mostra-a-milano\/","url":"https:\/\/www.area-press.eu\/comunicati\/arte-dei-segni-per-dare-significato-alla-parola-valentino-candiani-in-mostra-a-milano\/","name":"Arte dei Segni per dare significato alla Parola: Valentino Candiani in mostra a Milano - area-press.eu - comunicati","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#website"},"datePublished":"2009-06-07T22:00:00+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicati\/arte-dei-segni-per-dare-significato-alla-parola-valentino-candiani-in-mostra-a-milano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicati\/arte-dei-segni-per-dare-significato-alla-parola-valentino-candiani-in-mostra-a-milano\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicati\/arte-dei-segni-per-dare-significato-alla-parola-valentino-candiani-in-mostra-a-milano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Arte dei Segni per dare significato alla Parola: Valentino Candiani in mostra a Milano"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicati\/#website","url":"https:\/\/www.area-press.eu\/comunicati\/","name":"area-press.eu - comunicati","description":"Press releases e comunicati stampa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4","name":"Redazione area-press.eu","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","caption":"Redazione area-press.eu"},"url":"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/6361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=6361"}],"version-history":[{"count":0,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/6361\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=6361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=6361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=6361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}