{"id":6343,"date":"2009-06-09T00:00:00","date_gmt":"2009-06-08T22:00:00","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicati\/al-via-su-menstyle-it-la-kermesse-della-moda-maschile\/"},"modified":"2009-06-09T00:00:00","modified_gmt":"2009-06-08T22:00:00","slug":"al-via-su-menstyle-it-la-kermesse-della-moda-maschile","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicati\/al-via-su-menstyle-it-la-kermesse-della-moda-maschile\/","title":{"rendered":"Al via su MenStyle.it la kermesse della moda maschile"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><br \/>\nDal 16 al 29 giugno la moda maschile ha un solo indirizzo, quello di MenStyle.it \u2013 www.menstyle.it\/moda \u2013 checon lo Speciale Moda Uomo P\/E 2010 seguir\u00e0 day by day l\u2019atteso appuntamento proponendo ai suoi lettori gli aspetti pi\u00f9 esclusivi delle nuove collezioni. <\/p>\n<p>La redazione di MenStyle.it sar\u00e0 come sempre in prima fila per tutta la durata degli eventi documentando non solo le sfilate, i backstage e i party pi\u00f9 ambiti ma anticipando, attraverso le interviste ai protagonisti della moda maschile e al popolo del fashion, i nuovi trend di domani. Con articoli e commenti autorevoli, un palinsesto completo e aggiornamenti costanti dalle pi\u00f9 importanti manifestazioni, lo Speciale Moda Uomo si preannuncia una kermesse irrinunciabile per i fashion victim e gli appassionati. <\/p>\n<p>Il viaggio di MenStyle.it inizia a Firenze, con la 76\u00b0 edizione di Pitti Immagine Uomo (16-19 giugno). E\u2019 nella splendida cornice del Giardino di Boboli che la sera del 17 giugno il designer giapponese Jun Takahashi, creative director di Undercover, presenter\u00e0 in anteprima assoluta la sua menswear collection S\/S 2010, con una performance che vedr\u00e0 protagonista il suo stile inconfondibile. MenStyle.it non poteva mancare e documenter\u00e0 lo straordinario evento con un\u2019esclusiva video-intervista al designer, che per la prima volta sfila in Italia con il suo marchio.<br \/>\nDallo stilista alla protagonista che ha fatto della moda la sua vita, il passo \u00e8 breve. Cos\u00ec MenStyle.it si sposta a Who\u2019s on next, il concorso per la ricerca di nuovi talenti nel fashion maschile ideato da Franca Sozzani &#8211; Direttore dei mensili L\u2019Uomo Vogue e Vogue Italia \u2013 alla quale viene dedicata un\u2019intervista in cui racconta la nuova edizione.<\/p>\n<p>La kermesse fiorentina prosegue online con gallery fotografiche, articoli e interviste, senza perdere di vista la community di visitatori che con i loro look, contribuiscono a dare nuovi suggerimenti e spunti su stili e tendenze.<br \/>\nIl 20 giugno si parte alla volta di Milano che fino al 23 sar\u00e0 la capitale incontrastata della moda maschile, dalla quale gli utenti di MenStyle.it possono godersi online le sfilate pi\u00f9 prestigiose, le videointerviste sempre aggiornate, rilasciate dagli stilisti e dalle celebrity prendendo idee e spunti dallo street style. E l\u2019occhio &#8211; non poi tanto indiscreto &#8211; della redazione si spinge fino alle prime file delle passerelle, passando dai party pi\u00f9 esclusivi per commentare in modo ironico e divertente con articoli e post sui blog, i look delle celebrity, disponibili anche su Facebook e Twitter.<\/p>\n<p>Nei giorni effervescenti e caotici della moda, non sono solo le nuove collezioni a fare da protagoniste, ma gli occhi del pubblico sono puntati anche su chi ha la responsabilit\u00e0 di interpretare i capi che indossa, ovvero i top model. MenStyle.it si spinge cos\u00ec nella loro vite, cercando di scoprire i loro interessi, le loro passioni e i loro sogni.<br \/>\nDal 25 al 29 giugno si replica a Parigi, dove i giornalisti di MenStyle.it sono impegnati a seguire le sfilate dei pi\u00f9 grandi stilisti, da Herm\u00e8s a Yves Saint Laurent. Il tempo in questi casi non basta mai, e conoscendo bene la quantit\u00e0 di eventi che da un capo all\u2019altro della ville lumi\u00e8re si susseguono, la redazione propone ai suoi lettori un \u201cr\u00e9sum\u00e9\u201d di fine giornata: con tono ironico e a tratti dissacrante vengono commentate e proposte le idee pi\u00f9 originali e gli outfit pi\u00f9 pratici che meglio si prestano a essere indossati anche nella vita quotidiana, lontano dai flash delle passerelle. <\/p>\n<p>\u201cDa moda intesa come show ad how-to: la quantit\u00e0 di informazioni proposte e le news aggiornate in tempo reale dai luoghi dove la moda maschile si fa e si vive, da Firenze a Parigi, \u2013 dichiara Margherita Pogliani, Direttore di MenStyle.it \u2013 contribuisce a rendere il nostro Speciale Sfilate unico e diverso dalle altre proposte online. Il successo che a ogni stagione registriamo su MenStyle.it crediamo sia da attribuire anche alla capacit\u00e0 di sviluppare stimoli e idee coinvolgenti per gli utenti, portandoli nel cuore della moda ma anche mostrando loro gli aspetti pi\u00f9 inusuali e facendoli sentire protagonisti di un mondo a volte troppo esclusivo\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Interviste esclusive, sfilate in tempo reale, inediti dietro le quinte, cronache e gossip dai luoghi pi\u00f9 glamour<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7553],"tags":[],"class_list":["post-6343","post","type-post","status-publish","format-standard","hentry","category-comunicati_stampa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Al via su MenStyle.it la kermesse della moda maschile - area-press.eu - comunicati<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.area-press.eu\/comunicati\/al-via-su-menstyle-it-la-kermesse-della-moda-maschile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al via su MenStyle.it la kermesse della moda maschile - area-press.eu - comunicati\" \/>\n<meta property=\"og:description\" content=\"Interviste esclusive, sfilate in tempo reale, inediti dietro le quinte, cronache e gossip dai luoghi pi\u00f9 glamour\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicati\/al-via-su-menstyle-it-la-kermesse-della-moda-maschile\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu - comunicati\" \/>\n<meta property=\"article:published_time\" content=\"2009-06-08T22:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione area-press.eu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione area-press.eu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/al-via-su-menstyle-it-la-kermesse-della-moda-maschile\/\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/al-via-su-menstyle-it-la-kermesse-della-moda-maschile\/\",\"name\":\"Al via su MenStyle.it la kermesse della moda maschile - area-press.eu - comunicati\",\"isPartOf\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\"},\"datePublished\":\"2009-06-08T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/al-via-su-menstyle-it-la-kermesse-della-moda-maschile\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.area-press.eu\/comunicati\/al-via-su-menstyle-it-la-kermesse-della-moda-maschile\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/al-via-su-menstyle-it-la-kermesse-della-moda-maschile\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.area-press.eu\/comunicati\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al via su MenStyle.it la kermesse della moda maschile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/\",\"name\":\"area-press.eu - comunicati\",\"description\":\"Press releases e comunicati stampa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\",\"name\":\"Redazione area-press.eu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"caption\":\"Redazione area-press.eu\"},\"url\":\"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Al via su MenStyle.it la kermesse della moda maschile - area-press.eu - comunicati","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.area-press.eu\/comunicati\/al-via-su-menstyle-it-la-kermesse-della-moda-maschile\/","og_locale":"it_IT","og_type":"article","og_title":"Al via su MenStyle.it la kermesse della moda maschile - area-press.eu - comunicati","og_description":"Interviste esclusive, sfilate in tempo reale, inediti dietro le quinte, cronache e gossip dai luoghi pi\u00f9 glamour","og_url":"https:\/\/www.area-press.eu\/comunicati\/al-via-su-menstyle-it-la-kermesse-della-moda-maschile\/","og_site_name":"area-press.eu - comunicati","article_published_time":"2009-06-08T22:00:00+00:00","author":"Redazione area-press.eu","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione area-press.eu","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicati\/al-via-su-menstyle-it-la-kermesse-della-moda-maschile\/","url":"https:\/\/www.area-press.eu\/comunicati\/al-via-su-menstyle-it-la-kermesse-della-moda-maschile\/","name":"Al via su MenStyle.it la kermesse della moda maschile - area-press.eu - comunicati","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#website"},"datePublished":"2009-06-08T22:00:00+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicati\/al-via-su-menstyle-it-la-kermesse-della-moda-maschile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicati\/al-via-su-menstyle-it-la-kermesse-della-moda-maschile\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicati\/al-via-su-menstyle-it-la-kermesse-della-moda-maschile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Al via su MenStyle.it la kermesse della moda maschile"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicati\/#website","url":"https:\/\/www.area-press.eu\/comunicati\/","name":"area-press.eu - comunicati","description":"Press releases e comunicati stampa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4","name":"Redazione area-press.eu","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","caption":"Redazione area-press.eu"},"url":"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/6343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=6343"}],"version-history":[{"count":0,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/6343\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=6343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=6343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=6343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}