{"id":53814,"date":"2012-05-16T00:00:00","date_gmt":"2012-05-15T22:00:00","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicati\/direct-line-interroga-gli-automobilisti-14-italiani-su-100-confessano-ho-compiuto-un-atto-vandalico\/"},"modified":"2012-05-16T00:00:00","modified_gmt":"2012-05-15T22:00:00","slug":"direct-line-interroga-gli-automobilisti-14-italiani-su-100-confessano-ho-compiuto-un-atto-vandalico","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicati\/direct-line-interroga-gli-automobilisti-14-italiani-su-100-confessano-ho-compiuto-un-atto-vandalico\/","title":{"rendered":"DIRECT LINE INTERROGA GLI AUTOMOBILISTI. 14 ITALIANI SU 100 CONFESSANO: HO COMPIUTO UN ATTO VANDALICO"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><\/p>\n<p class=\"MsoNormal\"><em><span style=\"font-family: \">L&rsquo;8% delle donne ammette di aver rigato intenzionalmente la carrozzeria di un&rsquo;auto, mentre il 4% degli uomini riconosce di aver rovinato di proposito uno specchietto retrovisore.<\/span><\/em><\/p>\n<p class=\"MsoNormal\"><em><span style=\"font-family: \">A sorpresa non sono i giovanissimi i principali protagonisti degli atti vandalici: solo il 5% degli under25 contro il 10% dei 25-35enni confessa di aver danneggiato una carrozzeria.<\/span><\/em><\/p>\n<p class=\"MsoNormal\">\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-family: \">Alzi la mano chi non ha mai trovato la propria auto parcheggiata danneggiata da qualche vandalo. Purtroppo in questi casi al malumore per le conseguenze economiche del danno si aggiunge la tristezza per gesti che tra persone civili non dovrebbero mai verificarsi. Gli atti vandalici spesso per&ograve; non sono ragazzate ad opera di bulli: questo &egrave; quanto emerge da un&rsquo;indagine del <strong>Centro Studi e Documentazione Direct Line<\/strong>, la pi&ugrave; grande compagnia di <strong>assicurazioni online<\/strong>. La ricerca svela che <strong>pi&ugrave; di un italiano su 10<\/strong> (<strong>14%<\/strong>) confessa di <strong>aver compiuto atti vandalici su un&rsquo;altra auto<\/strong>. C&rsquo;&egrave; chi ha danneggiato una vettura <strong>rigando la carrozzeria<\/strong> (<strong>7%<\/strong>), chi ha colpito uno <strong>specchietto<\/strong> retrovisore (<strong>3%<\/strong>) e chi ha rotto <strong>tergicristalli<\/strong> (<strong>2%<\/strong>). Altri bersagli, fortunatamente meno gettonati, sono i <strong>vetri <\/strong>e le <strong>gomme dell&rsquo;auto<\/strong> (entrambi con l&rsquo;<strong>1%<\/strong>).<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-family: \"> <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-family: \">Analizzando i risultati dello studio si scopre che le <strong>donne<\/strong> riconoscono nell&rsquo;<strong>8%<\/strong> dei casi di <strong>aver rigato almeno una volta la carrozzeria di un&rsquo;auto<\/strong>, mentre il <strong>4%<\/strong> degli <strong>uomini <\/strong>ammette di aver danneggiato <strong>uno degli specchietti<\/strong>. Se si sposta l&rsquo;attenzione sull&rsquo;et&agrave; degli intervistati a sorpresa emerge che il <strong>5%<\/strong> degli <em>under25<\/em> confessa di aver provocato <strong>danni ad una carrozzeria<\/strong>, <strong>percentuale che sale a 10%<\/strong> tra i <em>25-35enni<\/em>, a sottolineare che l&rsquo;atto vandalico non sempre viene compiuto in giovane et&agrave; o per istinto di ribellione.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-family: \"> <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-family: \">Secondo i risultati della ricerca l&rsquo;<strong>86%<\/strong> degli italiani <strong>assicura di non aver mai causato volontariamente danni ad un&rsquo;altra auto<\/strong>, anche se i <strong>dati Direct Line<\/strong> riguardo le <strong>denunce per atti vandalici<\/strong> fanno registrare un <strong>aumento del 22% nel 2012<\/strong> rispetto allo stesso periodo dell&rsquo;anno precedente.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-family: \"> <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-family: \">L&rsquo;analisi della compagnia di assicurazioni <strong>Direct Line<\/strong> offre anche uno spaccato regionale, da cui emerge che <strong>cagliaritani<\/strong> (<strong>8%<\/strong>) e dei <strong>romani<\/strong> (<strong>6%<\/strong>) detengono il primato tra quelli che hanno <strong>rigato almeno una volta la carrozzeria<\/strong>, <strong>palermitani<\/strong> (<strong>10%<\/strong>) e <strong>bolognesi <\/strong>(<strong>7%<\/strong>) il primato per danneggiamento degli <strong>specchietti<\/strong>, mentre <strong>torinesi<\/strong> (<strong>3%<\/strong>) e <strong>fiorentini <\/strong>(<strong>2%<\/strong>) il triste primato del taglio delle gomme. Non si sono salvati <strong>bresciani<\/strong> (<strong>4%<\/strong>) e <strong>veronesi <\/strong>(<strong>4%<\/strong>) che preferiscono accanirsi pi&ugrave; di altri su vetri e tergicristalli.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-family: \"> <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><em><span style=\"font-family: \">&lsquo;Che sia colpa di una delusione d&rsquo;amore, di un risentimento personale o anche solo di uno stupido gioco, gli atti vandalici confessati in questo sondaggio non sono in alcun modo giustificabili e vengono considerati reato penale &#8211; afferma <strong>Barbara Panzeri, Direttore Marketing Direct Line<\/strong> &ndash; Purtroppo per&ograve; accadono creando notevoli disagi al malcapitato di turno che si trova a dover affrontare una spesa imprevista per ripristinare carrozzeria e accessori della propria auto. Per tutelarsi, quindi, basterebbe sempre aggiungere nel pacchetto della polizza auto la garanzia contro gli atti vandalici, copertura che tutela anche in caso di eventi o sommosse popolari, dove spesso le auto vengono danneggiate in maniera assai grave&rsquo;. <\/span><\/em><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-family: \"> <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-family: \"> <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><span style=\"font-family: \">Segui Direct Line su Facebook: <a href=\"http:\/\/www.facebook.com\/directlineitalia\" class=\"broken_link\">www.facebook.com\/directlineitalia<\/a><\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; border: none; mso-border-bottom-alt: solid windowtext .75pt; padding: 0cm; mso-padding-alt: 0cm 0cm 1.0pt 0cm;\"><em><span style=\"font-family: \"> <\/span><\/em><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><strong><span style=\"font-size: 8.0pt; font-family: \"> <\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><strong><span style=\"font-size: 8.0pt; font-family: \">Direct Line<\/span><\/strong><span style=\"font-size: 8.0pt; font-family: \"> <strong><span style=\"font-weight: normal;\">&egrave; la pi&ugrave; grande compagnia di <\/span><\/strong><strong><span style=\"font-weight: normal;\">assicurazioni auto<\/span><\/strong><strong><span style=\"font-weight: normal;\"> on line in Italia.<\/span><\/strong> Direct Line ha rivoluzionato il mercato delle assicurazioni lanciando nel 1985 nel Regno Unito la vendita di polizze auto senza intermediari. Oggi &egrave; leader in Europa con oltre 6 milioni di clienti. <a href=\"http:\/\/www.directline.it\/\" class=\"broken_link\">www.directline.it<\/a>.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u20198% delle donne ammette di aver rigato intenzionalmente la carrozzeria di un\u2019auto, mentre il 4% degli uomini riconosce di aver rovinato di proposito uno specchietto retrovisore. A sorpresa non sono i giovanissimi i principali protagonisti degli atti<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7553],"tags":[8595],"class_list":["post-53814","post","type-post","status-publish","format-standard","hentry","category-comunicati_stampa","tag-assicurazioni-online"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>DIRECT LINE INTERROGA GLI AUTOMOBILISTI. 14 ITALIANI SU 100 CONFESSANO: HO COMPIUTO UN ATTO VANDALICO - area-press.eu - comunicati<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.area-press.eu\/comunicati\/direct-line-interroga-gli-automobilisti-14-italiani-su-100-confessano-ho-compiuto-un-atto-vandalico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DIRECT LINE INTERROGA GLI AUTOMOBILISTI. 14 ITALIANI SU 100 CONFESSANO: HO COMPIUTO UN ATTO VANDALICO - area-press.eu - comunicati\" \/>\n<meta property=\"og:description\" content=\"L\u20198% delle donne ammette di aver rigato intenzionalmente la carrozzeria di un\u2019auto, mentre il 4% degli uomini riconosce di aver rovinato di proposito uno specchietto retrovisore. A sorpresa non sono i giovanissimi i principali protagonisti degli atti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicati\/direct-line-interroga-gli-automobilisti-14-italiani-su-100-confessano-ho-compiuto-un-atto-vandalico\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu - comunicati\" \/>\n<meta property=\"article:published_time\" content=\"2012-05-15T22:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione area-press.eu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione area-press.eu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/direct-line-interroga-gli-automobilisti-14-italiani-su-100-confessano-ho-compiuto-un-atto-vandalico\/\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/direct-line-interroga-gli-automobilisti-14-italiani-su-100-confessano-ho-compiuto-un-atto-vandalico\/\",\"name\":\"DIRECT LINE INTERROGA GLI AUTOMOBILISTI. 14 ITALIANI SU 100 CONFESSANO: HO COMPIUTO UN ATTO VANDALICO - area-press.eu - comunicati\",\"isPartOf\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\"},\"datePublished\":\"2012-05-15T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/direct-line-interroga-gli-automobilisti-14-italiani-su-100-confessano-ho-compiuto-un-atto-vandalico\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.area-press.eu\/comunicati\/direct-line-interroga-gli-automobilisti-14-italiani-su-100-confessano-ho-compiuto-un-atto-vandalico\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/direct-line-interroga-gli-automobilisti-14-italiani-su-100-confessano-ho-compiuto-un-atto-vandalico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.area-press.eu\/comunicati\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DIRECT LINE INTERROGA GLI AUTOMOBILISTI. 14 ITALIANI SU 100 CONFESSANO: HO COMPIUTO UN ATTO VANDALICO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/\",\"name\":\"area-press.eu - comunicati\",\"description\":\"Press releases e comunicati stampa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\",\"name\":\"Redazione area-press.eu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"caption\":\"Redazione area-press.eu\"},\"url\":\"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DIRECT LINE INTERROGA GLI AUTOMOBILISTI. 14 ITALIANI SU 100 CONFESSANO: HO COMPIUTO UN ATTO VANDALICO - area-press.eu - comunicati","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.area-press.eu\/comunicati\/direct-line-interroga-gli-automobilisti-14-italiani-su-100-confessano-ho-compiuto-un-atto-vandalico\/","og_locale":"it_IT","og_type":"article","og_title":"DIRECT LINE INTERROGA GLI AUTOMOBILISTI. 14 ITALIANI SU 100 CONFESSANO: HO COMPIUTO UN ATTO VANDALICO - area-press.eu - comunicati","og_description":"L\u20198% delle donne ammette di aver rigato intenzionalmente la carrozzeria di un\u2019auto, mentre il 4% degli uomini riconosce di aver rovinato di proposito uno specchietto retrovisore. A sorpresa non sono i giovanissimi i principali protagonisti degli atti","og_url":"https:\/\/www.area-press.eu\/comunicati\/direct-line-interroga-gli-automobilisti-14-italiani-su-100-confessano-ho-compiuto-un-atto-vandalico\/","og_site_name":"area-press.eu - comunicati","article_published_time":"2012-05-15T22:00:00+00:00","author":"Redazione area-press.eu","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione area-press.eu","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicati\/direct-line-interroga-gli-automobilisti-14-italiani-su-100-confessano-ho-compiuto-un-atto-vandalico\/","url":"https:\/\/www.area-press.eu\/comunicati\/direct-line-interroga-gli-automobilisti-14-italiani-su-100-confessano-ho-compiuto-un-atto-vandalico\/","name":"DIRECT LINE INTERROGA GLI AUTOMOBILISTI. 14 ITALIANI SU 100 CONFESSANO: HO COMPIUTO UN ATTO VANDALICO - area-press.eu - comunicati","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#website"},"datePublished":"2012-05-15T22:00:00+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicati\/direct-line-interroga-gli-automobilisti-14-italiani-su-100-confessano-ho-compiuto-un-atto-vandalico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicati\/direct-line-interroga-gli-automobilisti-14-italiani-su-100-confessano-ho-compiuto-un-atto-vandalico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicati\/direct-line-interroga-gli-automobilisti-14-italiani-su-100-confessano-ho-compiuto-un-atto-vandalico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"DIRECT LINE INTERROGA GLI AUTOMOBILISTI. 14 ITALIANI SU 100 CONFESSANO: HO COMPIUTO UN ATTO VANDALICO"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicati\/#website","url":"https:\/\/www.area-press.eu\/comunicati\/","name":"area-press.eu - comunicati","description":"Press releases e comunicati stampa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4","name":"Redazione area-press.eu","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","caption":"Redazione area-press.eu"},"url":"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/53814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=53814"}],"version-history":[{"count":0,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/53814\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=53814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=53814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=53814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}