{"id":52297,"date":"2012-04-05T00:00:00","date_gmt":"2012-04-04T22:00:00","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicati\/la-fatica-fa-tappa-su-gavia-e-mortirolo-in-bici-l8-a-granfondo-giordana\/"},"modified":"2012-04-05T00:00:00","modified_gmt":"2012-04-04T22:00:00","slug":"la-fatica-fa-tappa-su-gavia-e-mortirolo-in-bici-l8-a-granfondo-giordana","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicati\/la-fatica-fa-tappa-su-gavia-e-mortirolo-in-bici-l8-a-granfondo-giordana\/","title":{"rendered":"LA FATICA FA TAPPA SU GAVIA E MORTIROLO. IN\u2026 BICI L\u20198.a GRANFONDO GIORDANA"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><\/p>\n<p class=\"MsoNormal\">Il 24 giugno appuntamento irrinunciabile per gli amanti del ciclismo su strada<\/p>\n<p class=\"MsoNormal\">Ad Aprica (SO) scocca l&rsquo;ora dell&rsquo;8.a Granfondo Internazionale Giordana<\/p>\n<p class=\"MsoNormal\">Tre percorsi tra cui scegliere, si salgono i Passi Gavia, Mortirolo e S. Cristina<\/p>\n<p class=\"MsoNormal\">Apre le porte ai granfondisti anche il Palazzetto dello Sport, allestito per il pernottamento<\/p>\n<p class=\"MsoNormal\">\n<p class=\"MsoNormal\">\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Tra un paio di mesi sar&agrave; ora di regolare i conti con le salite simbolo del ciclismo su strada.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">I Passi Gavia, Mortirolo e Santa Cristina sono tasselli immancabili nel curriculum sportivo degli amanti delle ruote magre, tre &ldquo;colossi&rdquo; che potranno essere messi in archivio il prossimo 24 giugno, quando da Aprica (Sondrio) scatter&agrave; l&rsquo;8.a Granfondo Internazionale Giordana.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">La gara lombarda torna anche quest&rsquo;anno con il sempre apprezzato menu sportivo in tre &ldquo;portate&rdquo;, con i percorsi Granfondo di 175 km e 4.500 metri di dislivello, Mediofondo di 155 km e 3.600 m\/dsl e Fondo di 85 km e 1.850 metri di dislivello.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Tre tracciati duri, selettivi e affascinanti, che ogni anno richiamano sulle strade della Valtellina sempre pi&ugrave; appassionati del settore, desiderosi di mettersi alla prova nei luoghi resi celebri dai grandi del ciclismo come Charly Gaul, Damiano Cunego, Ivan Basso e soprattutto Marco Pantani, a cui &egrave; dedicato il monumento che si trova all&rsquo;8&deg; km del Mortirolo.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Per l&rsquo;edizione numero 8 il team degli organizzatori ha pensato a diverse soluzioni per agevolare la trasferta dei tanti fedelissimi ciclisti e anche dei loro accompagnatori. Oltre alla possibilit&agrave; di soggiornare negli hotel della zona, sar&agrave; possibile anche pernottare (nella notte di sabato) all&rsquo;interno della struttura del Palazzetto dello Sport, opportunit&agrave; nata anche grazie alla collaborazione con la Protezione Civile locale. Chi vorr&agrave; sostare nel Palazzetto dello Sport potr&agrave; farlo al costo di 10 Euro, per la prima colazione ci saranno dei prezzi favorevoli nei bar e hotel convenzionati.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Tante idee diverse per andare incontro ai sempre pi&ugrave; numerosi partecipanti, gi&agrave; oltre quota 2.400 quando mancano ancora pi&ugrave; di due mesi al via. Un numero importante che premia le capacit&agrave; organizzative di un gruppo impegnato da anni nell&rsquo;universo sportivo, il collaudato GS Alpi di Vittorio Mevio, al quale si unisce il supporto dell&rsquo;azienda Giordana. L&rsquo;anno scorso erano scattati in 3.000 al via di Corso Roma all&rsquo;Aprica e, visto il trend di quest&rsquo;anno, la cifra sembra destinata ad aumentare, con conferme positive soprattutto dall&rsquo;estero.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Anche in questo 2012, infatti, la Granfondo Internazionale Giordana ha attratto granfondisti da tutta Europa ed oltre, tra i moduli d&rsquo;iscrizione pervenuti ne figurano diversi da Australia, Brasile, Canada, Nuova Zelanda e Stati Uniti, a simboleggiare che l&rsquo;&ldquo;internazionalit&agrave;&rdquo; della gara dell&rsquo;Aprica non &egrave; soltanto un nome ma un fatto. Del resto l&rsquo;opportunit&agrave; di pedalare su splendidi valichi alpini, tra natura incontaminata e salite che hanno fatto la storia del ciclismo, &egrave; di quelle da cogliere al volo, motivo per cui anche a livello nazionale la gara lombarda riscuote un ampio successo di presenze e recensioni.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Per i sempre numerosi concorrenti &egrave; stato confermato il pacco gara 2012, che conterr&agrave; la maglia commemorativa dell&rsquo;evento e una cartolina con lo speciale annullo filatelico dedicato alla corsa, oltre ad articoli tecnici e prodotti tipici del territorio.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">La Granfondo Internazionale Giordana fa parte dell&rsquo;omonimo Challenge, il Challenge Giordana appunto, circuito in 6 tappe tra Veneto, Lombardia e Trentino, inoltre &egrave; inserita nei circuiti Nobili\/Supernobili, Coppa Lombardia C-Performance e Gran Trofeo.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">In attesa del via &egrave; possibile visitare il sito dedicato alla granfondo (www.granfondogiordana.com), con tutte le novit&agrave; e i link per le iscrizioni, il cui costo sar&agrave; di 40 Euro fino al 16 giugno.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Info: <a href=\"http:\/\/www.granfondogiordana.com\/\" class=\"broken_link\"><span>www.granfondogiordana.com<\/span><\/a><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Il 24 giugno appuntamento irrinunciabile per gli amanti del ciclismo su strada Ad Aprica (SO) scocca l&rsquo;ora dell&rsquo;8.a Granfondo Internazionale Giordana Tre percorsi tra cui scegliere, si salgono i Passi Gavia, Mortirolo e S. Cristina Apre le porte ai granfondisti anche il Palazzetto dello Sport, allestito per il pernottamento Tra un paio di mesi sar&agrave; [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7595],"tags":[13511],"class_list":["post-52297","post","type-post","status-publish","format-standard","hentry","category-sport","tag-granfondo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>LA FATICA FA TAPPA SU GAVIA E MORTIROLO. IN\u2026 BICI L\u20198.a GRANFONDO GIORDANA - area-press.eu - comunicati<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.area-press.eu\/comunicati\/la-fatica-fa-tappa-su-gavia-e-mortirolo-in-bici-l8-a-granfondo-giordana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA FATICA FA TAPPA SU GAVIA E MORTIROLO. IN\u2026 BICI L\u20198.a GRANFONDO GIORDANA - area-press.eu - comunicati\" \/>\n<meta property=\"og:description\" content=\"Il 24 giugno appuntamento irrinunciabile per gli amanti del ciclismo su strada Ad Aprica (SO) scocca l&rsquo;ora dell&rsquo;8.a Granfondo Internazionale Giordana Tre percorsi tra cui scegliere, si salgono i Passi Gavia, Mortirolo e S. Cristina Apre le porte ai granfondisti anche il Palazzetto dello Sport, allestito per il pernottamento Tra un paio di mesi sar&agrave; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicati\/la-fatica-fa-tappa-su-gavia-e-mortirolo-in-bici-l8-a-granfondo-giordana\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu - comunicati\" \/>\n<meta property=\"article:published_time\" content=\"2012-04-04T22:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione area-press.eu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione area-press.eu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/la-fatica-fa-tappa-su-gavia-e-mortirolo-in-bici-l8-a-granfondo-giordana\/\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/la-fatica-fa-tappa-su-gavia-e-mortirolo-in-bici-l8-a-granfondo-giordana\/\",\"name\":\"LA FATICA FA TAPPA SU GAVIA E MORTIROLO. IN\u2026 BICI L\u20198.a GRANFONDO GIORDANA - area-press.eu - comunicati\",\"isPartOf\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\"},\"datePublished\":\"2012-04-04T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/la-fatica-fa-tappa-su-gavia-e-mortirolo-in-bici-l8-a-granfondo-giordana\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.area-press.eu\/comunicati\/la-fatica-fa-tappa-su-gavia-e-mortirolo-in-bici-l8-a-granfondo-giordana\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/la-fatica-fa-tappa-su-gavia-e-mortirolo-in-bici-l8-a-granfondo-giordana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.area-press.eu\/comunicati\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LA FATICA FA TAPPA SU GAVIA E MORTIROLO. IN\u2026 BICI L\u20198.a GRANFONDO GIORDANA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/\",\"name\":\"area-press.eu - comunicati\",\"description\":\"Press releases e comunicati stampa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\",\"name\":\"Redazione area-press.eu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"caption\":\"Redazione area-press.eu\"},\"url\":\"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LA FATICA FA TAPPA SU GAVIA E MORTIROLO. IN\u2026 BICI L\u20198.a GRANFONDO GIORDANA - area-press.eu - comunicati","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.area-press.eu\/comunicati\/la-fatica-fa-tappa-su-gavia-e-mortirolo-in-bici-l8-a-granfondo-giordana\/","og_locale":"it_IT","og_type":"article","og_title":"LA FATICA FA TAPPA SU GAVIA E MORTIROLO. IN\u2026 BICI L\u20198.a GRANFONDO GIORDANA - area-press.eu - comunicati","og_description":"Il 24 giugno appuntamento irrinunciabile per gli amanti del ciclismo su strada Ad Aprica (SO) scocca l&rsquo;ora dell&rsquo;8.a Granfondo Internazionale Giordana Tre percorsi tra cui scegliere, si salgono i Passi Gavia, Mortirolo e S. Cristina Apre le porte ai granfondisti anche il Palazzetto dello Sport, allestito per il pernottamento Tra un paio di mesi sar&agrave; [&hellip;]","og_url":"https:\/\/www.area-press.eu\/comunicati\/la-fatica-fa-tappa-su-gavia-e-mortirolo-in-bici-l8-a-granfondo-giordana\/","og_site_name":"area-press.eu - comunicati","article_published_time":"2012-04-04T22:00:00+00:00","author":"Redazione area-press.eu","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione area-press.eu","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicati\/la-fatica-fa-tappa-su-gavia-e-mortirolo-in-bici-l8-a-granfondo-giordana\/","url":"https:\/\/www.area-press.eu\/comunicati\/la-fatica-fa-tappa-su-gavia-e-mortirolo-in-bici-l8-a-granfondo-giordana\/","name":"LA FATICA FA TAPPA SU GAVIA E MORTIROLO. IN\u2026 BICI L\u20198.a GRANFONDO GIORDANA - area-press.eu - comunicati","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#website"},"datePublished":"2012-04-04T22:00:00+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicati\/la-fatica-fa-tappa-su-gavia-e-mortirolo-in-bici-l8-a-granfondo-giordana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicati\/la-fatica-fa-tappa-su-gavia-e-mortirolo-in-bici-l8-a-granfondo-giordana\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicati\/la-fatica-fa-tappa-su-gavia-e-mortirolo-in-bici-l8-a-granfondo-giordana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"LA FATICA FA TAPPA SU GAVIA E MORTIROLO. IN\u2026 BICI L\u20198.a GRANFONDO GIORDANA"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicati\/#website","url":"https:\/\/www.area-press.eu\/comunicati\/","name":"area-press.eu - comunicati","description":"Press releases e comunicati stampa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4","name":"Redazione area-press.eu","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","caption":"Redazione area-press.eu"},"url":"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/52297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=52297"}],"version-history":[{"count":0,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/52297\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=52297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=52297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=52297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}