{"id":43458,"date":"2011-07-19T00:00:00","date_gmt":"2011-07-18T22:00:00","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicati\/val-di-cembra-alpina-nel-paesaggio-mediterranea-nel-clima\/"},"modified":"2011-07-19T00:00:00","modified_gmt":"2011-07-18T22:00:00","slug":"val-di-cembra-alpina-nel-paesaggio-mediterranea-nel-clima","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicati\/val-di-cembra-alpina-nel-paesaggio-mediterranea-nel-clima\/","title":{"rendered":"Val di Cembra: alpina nel paesaggio, mediterranea nel clima"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><\/p>\n<p><p class=\"MsoNormal\" style=\"text-align: justify;\">Elio Antonelli ha saputo regalarci una splendida descrizione della Val di Cembra che definisce cos&igrave;: &ldquo;alpina nel paesaggio, mediterraneo nel clima, silenziosa, selvaggia&rdquo;. Ed in parte &egrave; ancora cos&igrave;. Questa valle situata al lato sinistro del fiume Adige custodisce ancora una cultura ed una tradizione profondamente radicate nel passato. I suoi splendidi paesaggi, incontaminati sanno regalare pace, tranquillit&agrave; e serenit&agrave; come pochi altri luoghi.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Il pregio ed il valore naturalistico della Val di Cembra &egrave; custodito nell&rsquo;amore della popolazione che ancora parla un dialetto di origine ladina. Questa Valle &egrave; ricca di curiosit&agrave; ed attrattive come le Piramidi di Segonzano: delle sculture naturali fatte di terra ed altri materiali sedimentari a forma di cono e protette da un sasso a forma di cappello.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Il castello di Segonzano, risalente al XIII sec, &egrave; un altro piccolo gioiello da scoprire, la storia millenaria di questa fortezza costruita per difendere le rive del ruscello, si incrocia con la storia di uno dei pi&ugrave; grandi esponenti della pittura tedesca rinascimentale: Albrecht Durer.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Nel lontano 1945 Durer pass&ograve; per la Val di Cembra e resosi conto della peculiare bellezza della valle, la ritrasse in due acquerelli, uno di questi lo troviamo custodito in un museo di Oxford. Il lago di Sales e il Lago Santo sono ottimi rifugi per gli amanti della pesca e della balneazione. Per saperne di pi&ugrave; clicca la voce &ldquo;<strong style=\"mso-bidi-font-weight: normal;\"><a href=\"http:\/\/www.visittrentino.it\/it\/dove_dormire\/strutture\/risultati?accoCatType.accoType=CAMPSITE&amp;destination=altopiano-di-pine-e-valle-di-cembra&amp;clubs=campeggi-trentino-totale&amp;stx=Ricerca%20campeggi:%20Altopiano%20di%20Pine%27%20e%20Valle%20di%20Cembra\" target=\"_blank\" class=\"broken_link\">campeggi Val di Cembra<\/a>&rdquo;<\/strong>. Se invece preferisci una meta pi&ugrave; &ldquo;battuta&rdquo; dal turismo estivo allo clicca &ldquo;<strong style=\"mso-bidi-font-weight: normal;\"><a href=\"http:\/\/www.visittrentino.it\/it\/dove_dormire\/strutture\/risultati?accoCatType.accoType=CAMPSITE&amp;destination=s-martino-di-castrozza-primiero-e-vanoi&amp;clubs=campeggi-trentino-totale&amp;stx=Ricerca%20campeggi:%20San%20Martino%20di%20Castrozza,%20Passo%20Rolle,%20Primiero%20e%20Vanoi\" target=\"_blank\" class=\"broken_link\">campeggi Primiero<\/a>&rdquo;<\/strong>: <span style=\"mso-spacerun: yes;\"> <\/span>poco distante dal Parco Naturale Pavaneggio Pale di San Martino e dalla catena dolomitica del Lagorai. <\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La val di Cembra, situata nel cuore del Trentino Occidentale, \u00e8 stata luogo d\u2019ispirazione per l\u2019artista tedesco Albrecht Durer. I suo paesaggi mozzafiato, i suoi laghi e le caratteristiche piramidi di Segonzano la rendono una valle unica e magica.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7559],"tags":[42322,42321],"class_list":["post-43458","post","type-post","status-publish","format-standard","hentry","category-turismo","tag-campeggi-primiero","tag-campeggi-val-di-cembra"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Val di Cembra: alpina nel paesaggio, mediterranea nel clima - area-press.eu - comunicati<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.area-press.eu\/comunicati\/val-di-cembra-alpina-nel-paesaggio-mediterranea-nel-clima\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Val di Cembra: alpina nel paesaggio, mediterranea nel clima - area-press.eu - comunicati\" \/>\n<meta property=\"og:description\" content=\"La val di Cembra, situata nel cuore del Trentino Occidentale, \u00e8 stata luogo d\u2019ispirazione per l\u2019artista tedesco Albrecht Durer. I suo paesaggi mozzafiato, i suoi laghi e le caratteristiche piramidi di Segonzano la rendono una valle unica e magica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicati\/val-di-cembra-alpina-nel-paesaggio-mediterranea-nel-clima\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu - comunicati\" \/>\n<meta property=\"article:published_time\" content=\"2011-07-18T22:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione area-press.eu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione area-press.eu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/val-di-cembra-alpina-nel-paesaggio-mediterranea-nel-clima\/\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/val-di-cembra-alpina-nel-paesaggio-mediterranea-nel-clima\/\",\"name\":\"Val di Cembra: alpina nel paesaggio, mediterranea nel clima - area-press.eu - comunicati\",\"isPartOf\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\"},\"datePublished\":\"2011-07-18T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/val-di-cembra-alpina-nel-paesaggio-mediterranea-nel-clima\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.area-press.eu\/comunicati\/val-di-cembra-alpina-nel-paesaggio-mediterranea-nel-clima\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/val-di-cembra-alpina-nel-paesaggio-mediterranea-nel-clima\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.area-press.eu\/comunicati\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Val di Cembra: alpina nel paesaggio, mediterranea nel clima\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/\",\"name\":\"area-press.eu - comunicati\",\"description\":\"Press releases e comunicati stampa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\",\"name\":\"Redazione area-press.eu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"caption\":\"Redazione area-press.eu\"},\"url\":\"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Val di Cembra: alpina nel paesaggio, mediterranea nel clima - area-press.eu - comunicati","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.area-press.eu\/comunicati\/val-di-cembra-alpina-nel-paesaggio-mediterranea-nel-clima\/","og_locale":"it_IT","og_type":"article","og_title":"Val di Cembra: alpina nel paesaggio, mediterranea nel clima - area-press.eu - comunicati","og_description":"La val di Cembra, situata nel cuore del Trentino Occidentale, \u00e8 stata luogo d\u2019ispirazione per l\u2019artista tedesco Albrecht Durer. I suo paesaggi mozzafiato, i suoi laghi e le caratteristiche piramidi di Segonzano la rendono una valle unica e magica.","og_url":"https:\/\/www.area-press.eu\/comunicati\/val-di-cembra-alpina-nel-paesaggio-mediterranea-nel-clima\/","og_site_name":"area-press.eu - comunicati","article_published_time":"2011-07-18T22:00:00+00:00","author":"Redazione area-press.eu","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione area-press.eu","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicati\/val-di-cembra-alpina-nel-paesaggio-mediterranea-nel-clima\/","url":"https:\/\/www.area-press.eu\/comunicati\/val-di-cembra-alpina-nel-paesaggio-mediterranea-nel-clima\/","name":"Val di Cembra: alpina nel paesaggio, mediterranea nel clima - area-press.eu - comunicati","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#website"},"datePublished":"2011-07-18T22:00:00+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicati\/val-di-cembra-alpina-nel-paesaggio-mediterranea-nel-clima\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicati\/val-di-cembra-alpina-nel-paesaggio-mediterranea-nel-clima\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicati\/val-di-cembra-alpina-nel-paesaggio-mediterranea-nel-clima\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Val di Cembra: alpina nel paesaggio, mediterranea nel clima"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicati\/#website","url":"https:\/\/www.area-press.eu\/comunicati\/","name":"area-press.eu - comunicati","description":"Press releases e comunicati stampa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4","name":"Redazione area-press.eu","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","caption":"Redazione area-press.eu"},"url":"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/43458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=43458"}],"version-history":[{"count":0,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/43458\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=43458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=43458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=43458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}