{"id":40644,"date":"2011-04-29T00:00:00","date_gmt":"2011-04-28T22:00:00","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicati\/ponte-2-giugno-2011-in-toscana-ad-erboli-residence-per-coppie-famiglie-e-amici\/"},"modified":"2011-04-29T00:00:00","modified_gmt":"2011-04-28T22:00:00","slug":"ponte-2-giugno-2011-in-toscana-ad-erboli-residence-per-coppie-famiglie-e-amici","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicati\/ponte-2-giugno-2011-in-toscana-ad-erboli-residence-per-coppie-famiglie-e-amici\/","title":{"rendered":"Ponte 2 Giugno 2011 in Toscana ad Erboli Residence per coppie, famiglie e amici"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><\/p>\n<p>Se &egrave; vero che all&rsquo;estate bisogna dare un benvenuto come si deve, come ogni anno questa regola &egrave; onorata puntualmente dalla <strong>casa vacanze con piscina in Toscana Erboli Residence<\/strong> che presenta la sua <strong><a title=\"offerta Ponte 2 Giugno 2011 in Toscana\" href=\"http:\/\/www.erboliresidence.it\/offerta-ponte-2-giugno-2011-toscana.php\" target=\"_blank\" class=\"broken_link\">Offerta Ponte 2 Giugno 2011 in Toscana<\/a><\/strong>, ideale da cogliere per iniziare la stagione estiva all&rsquo;insegna del benessere e del gusto.<\/p>\n<p>Ubicato nell&#8217;assolata <strong>campagna tra Arezzo e Siena<\/strong> il residence Erboli &egrave; ormai da anni una felice meta per tutti coloro che amano trascorrere un <strong>weekend, una vacanza o una villeggiatura in Toscana<\/strong> anche perch&egrave; la casa vacanze dispone di comodi ed eleganti appartamenti per ogni tipologia di visitatori, ovvero coppie, famiglie e gruppi di amici, e perch&egrave; offre spazi solari come una graziosa piscina all&rsquo;aperto a disposizione di tutti gli ospiti, un ampio parco, un giardino con gazebo e tavolini, e un angolo barbecue.<\/p>\n<p>L&rsquo;<strong>Offerta Ponte 2 Giugno 2011 in Toscana<\/strong> di Erboli Residence &egrave; per tutti, talmente per tutti che <strong>pi&ugrave; siete e meno spendete<\/strong>, ma &egrave; rivolta in particolar modo a tutti coloro che vogliono abbracciare la nuova estate con colore e fantasia in un luogo che ha la straordinaria peculiarit&agrave; di essere molto vicino alle sopra citate citt&agrave; di <strong>Arezzo<\/strong> e <strong>Siena<\/strong>, ma anche ad altri centri come il <strong>Chianti Classico<\/strong> e <strong>Firenze<\/strong>.<\/p>\n<p><strong>Valida dal 01\/06\/2011 al 06\/06\/2011<\/strong> l&rsquo;Offerta prevede:<\/p>\n<ul>\n<li><strong>Soggiorno di 4 giorni e 3 notti ad Erboli Residence<\/strong>.<\/li>\n<\/ul>\n<ul>\n<li><strong>Degustazione vini e prodotti tipici presso azienda agricola a Cavriglia.<\/strong><\/li>\n<\/ul>\n<ul>\n<li><strong>Cena tipica presso ristorante Pitena, a pochi minuti dal residence.<\/strong><\/li>\n<\/ul>\n<p>Visitando il sito del residence &egrave; possibile conoscere nei minimi dettagli i convenienti termini del soggiorno, la ricchezza della degustazione proposta, e il men&ugrave; di prelibate pietanze che verr&agrave; servito al ristorante.<\/p>\n<p>Per prenotazioni e informazioni:<\/p>\n<p><strong>Erboli Residence di Cannoni Snc<\/strong><br \/> Localit&agrave; Erboli, 166<br \/> 52022 &ndash; Cavriglia (AREZZO)<br \/> Tel: +39 055\/96.61.00 &ndash; +39 055\/95.91.87<br \/> Mobile: +39 348\/86.31.828<br \/> Fax: + 39 055\/95.44.659<br \/> Web: <a title=\"www.erboliresidence.it\" href=\"http:\/\/www.erboliresidence.it\/\" target=\"_blank\" class=\"broken_link\">www.erboliresidence.it<\/a><br \/> E-Mail: info@erboliresidence.it<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;offerta Ponte 2 Giugno 2011 in Toscana di Erboli Residence si compone di soggiorno, degustazione prodotti tipici e cena in ristorante toscano.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7559],"tags":[9770,8483,10448,665,1344,1076,332,1373],"class_list":["post-40644","post","type-post","status-publish","format-standard","hentry","category-turismo","tag-chianti","tag-degustazione","tag-giugno","tag-menu","tag-offerta","tag-ponte","tag-soggiorno","tag-toscana"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ponte 2 Giugno 2011 in Toscana ad Erboli Residence per coppie, famiglie e amici - area-press.eu - comunicati<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.area-press.eu\/comunicati\/ponte-2-giugno-2011-in-toscana-ad-erboli-residence-per-coppie-famiglie-e-amici\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ponte 2 Giugno 2011 in Toscana ad Erboli Residence per coppie, famiglie e amici - area-press.eu - comunicati\" \/>\n<meta property=\"og:description\" content=\"L&#039;offerta Ponte 2 Giugno 2011 in Toscana di Erboli Residence si compone di soggiorno, degustazione prodotti tipici e cena in ristorante toscano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicati\/ponte-2-giugno-2011-in-toscana-ad-erboli-residence-per-coppie-famiglie-e-amici\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu - comunicati\" \/>\n<meta property=\"article:published_time\" content=\"2011-04-28T22:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione area-press.eu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione area-press.eu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/ponte-2-giugno-2011-in-toscana-ad-erboli-residence-per-coppie-famiglie-e-amici\/\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/ponte-2-giugno-2011-in-toscana-ad-erboli-residence-per-coppie-famiglie-e-amici\/\",\"name\":\"Ponte 2 Giugno 2011 in Toscana ad Erboli Residence per coppie, famiglie e amici - area-press.eu - comunicati\",\"isPartOf\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\"},\"datePublished\":\"2011-04-28T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/ponte-2-giugno-2011-in-toscana-ad-erboli-residence-per-coppie-famiglie-e-amici\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.area-press.eu\/comunicati\/ponte-2-giugno-2011-in-toscana-ad-erboli-residence-per-coppie-famiglie-e-amici\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/ponte-2-giugno-2011-in-toscana-ad-erboli-residence-per-coppie-famiglie-e-amici\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.area-press.eu\/comunicati\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ponte 2 Giugno 2011 in Toscana ad Erboli Residence per coppie, famiglie e amici\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/\",\"name\":\"area-press.eu - comunicati\",\"description\":\"Press releases e comunicati stampa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\",\"name\":\"Redazione area-press.eu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"caption\":\"Redazione area-press.eu\"},\"url\":\"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ponte 2 Giugno 2011 in Toscana ad Erboli Residence per coppie, famiglie e amici - area-press.eu - comunicati","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.area-press.eu\/comunicati\/ponte-2-giugno-2011-in-toscana-ad-erboli-residence-per-coppie-famiglie-e-amici\/","og_locale":"it_IT","og_type":"article","og_title":"Ponte 2 Giugno 2011 in Toscana ad Erboli Residence per coppie, famiglie e amici - area-press.eu - comunicati","og_description":"L'offerta Ponte 2 Giugno 2011 in Toscana di Erboli Residence si compone di soggiorno, degustazione prodotti tipici e cena in ristorante toscano.","og_url":"https:\/\/www.area-press.eu\/comunicati\/ponte-2-giugno-2011-in-toscana-ad-erboli-residence-per-coppie-famiglie-e-amici\/","og_site_name":"area-press.eu - comunicati","article_published_time":"2011-04-28T22:00:00+00:00","author":"Redazione area-press.eu","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione area-press.eu","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicati\/ponte-2-giugno-2011-in-toscana-ad-erboli-residence-per-coppie-famiglie-e-amici\/","url":"https:\/\/www.area-press.eu\/comunicati\/ponte-2-giugno-2011-in-toscana-ad-erboli-residence-per-coppie-famiglie-e-amici\/","name":"Ponte 2 Giugno 2011 in Toscana ad Erboli Residence per coppie, famiglie e amici - area-press.eu - comunicati","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#website"},"datePublished":"2011-04-28T22:00:00+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicati\/ponte-2-giugno-2011-in-toscana-ad-erboli-residence-per-coppie-famiglie-e-amici\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicati\/ponte-2-giugno-2011-in-toscana-ad-erboli-residence-per-coppie-famiglie-e-amici\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicati\/ponte-2-giugno-2011-in-toscana-ad-erboli-residence-per-coppie-famiglie-e-amici\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Ponte 2 Giugno 2011 in Toscana ad Erboli Residence per coppie, famiglie e amici"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicati\/#website","url":"https:\/\/www.area-press.eu\/comunicati\/","name":"area-press.eu - comunicati","description":"Press releases e comunicati stampa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4","name":"Redazione area-press.eu","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","caption":"Redazione area-press.eu"},"url":"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/40644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=40644"}],"version-history":[{"count":0,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/40644\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=40644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=40644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=40644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}