{"id":38854,"date":"2011-03-09T00:00:00","date_gmt":"2011-03-08T23:00:00","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicati\/f-e-m-m-e\/"},"modified":"2011-03-09T00:00:00","modified_gmt":"2011-03-08T23:00:00","slug":"f-e-m-m-e","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicati\/f-e-m-m-e\/","title":{"rendered":"F.E.M.M.E."},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><\/p>\n<p style=\"margin-bottom: 0cm;\" lang=\"fr-FR\" align=\"CENTER\"><span style=\"color: #ff00ff;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: medium;\"><strong>F.E.M.M.E.<\/strong><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,Times New Roman;\"><span style=\"font-size: small;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\"><strong>f<\/strong><\/span><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\">atale. <\/span><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\"><strong>&eacute;<\/strong><\/span><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\">l&eacute;gante. <\/span><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\"><strong>m<\/strong><\/span><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\">&eacute;lancolique. <\/span><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\"><strong>m<\/strong><\/span><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\">auvaise. <\/span><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\"><strong>&eacute;<\/strong><\/span><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: medium;\"><span lang=\"fr-FR\">ternelle<\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"fr-FR\" align=\"CENTER\">\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: small;\">Mostra &ndash; Evento a cura di Indira Fassioni<\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: small;\"><em>Un dionisiaco omaggio al mondo femminile tra arte, musica, moda e vino<\/em><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\" align=\"CENTER\">\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\" align=\"CENTER\">\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: small;\"><strong>Giusa<\/strong><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\" align=\"CENTER\"><span style=\"color: #000000;\"> <span style=\"font-family: Calibri,Times New Roman;\"><span style=\"font-size: small;\"><span style=\"font-family: Calibri,sans-serif;\"><strong>11 falsi d&rsquo;autore <\/strong><\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\" align=\"CENTER\">\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\" align=\"CENTER\">\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: small;\">Spazio Concept, Via Forcella 7, Zona Tortona, Milano<\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: small;\">Da Mercoled&igrave; 16 Marzo a Sabato 19 Marzo 2011 <\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: small;\">Dalle 18.30 alle 21.00<\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\" align=\"CENTER\">\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,Times New Roman;\"><span style=\"font-size: small;\"><span style=\"font-family: Calibri,sans-serif;\"><em>Vernissage<\/em><\/span><span style=\"font-family: Calibri,sans-serif;\">: Mercoled&igrave; 16 Marzo ore 18.30<\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,Times New Roman;\"><span style=\"font-size: small;\"><span style=\"font-family: Calibri,sans-serif;\"><em>Aperitivo con degustazione: V<\/em><\/span><span style=\"font-family: Calibri,sans-serif;\">enerd&igrave; 18 Marzo ore 18.30<\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,Times New Roman;\"><span style=\"font-size: small;\"><span style=\"font-family: Calibri,sans-serif;\"><em>Finissage<\/em><\/span><span style=\"font-family: Calibri,sans-serif;\">: Sabato 19 Marzo ore 18.30<\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\">\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\">\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\">\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,Times New Roman;\"><span style=\"font-size: small;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><span lang=\"fr-FR\"><em>Cherchez la F.E.M.M.E.!<\/em><\/span><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><span lang=\"fr-FR\"> <\/span><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">E&rsquo; l&rsquo;invito a esplorare l&rsquo;infinito e sempre mutevole universo femminile.<\/span><\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,Times New Roman;\"><span style=\"font-size: small;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Cos&igrave; come volubili e seducenti sono gli aggettivi che svelano lettera dopo lettera la F.E.M.M.E. (<\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><em>fatale, &eacute;l&eacute;gante, m&eacute;lancolique, mauvaise, &eacute;ternelle<\/em><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">) mostra-evento in programma da Mercoled&igrave; 16 Marzo a Sabato 19 Marzo 2011 presso Spazio Concept di Via Forcella, 7 a Milano.<\/span><\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Lo spirito di F.E.M.M.E. &egrave; quello di rendere omaggio alla donna ed ai suoi sensi, musa di arte e perfezione, s-oggetto di ricerca e creativit&agrave; in tutti i campi. <\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\">\n<p style=\"margin-bottom: 0cm;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">L&rsquo;esposizione &egrave; organizzata dall&rsquo;Associazione Culturale Rosaspinto in partnership con VirgoImage agenzia di consulenza d&rsquo;Immagine e Personal shopping di Milano.<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\">\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Pittura, musica, arte e vino: questi i dionisiaci protagonisti che per quattro giorni accompagneranno le suggestioni del pubblico partecipante.<\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\">\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\"><span style=\"color: #000000;\">&lsquo;<span style=\"font-family: Calibri,Times New Roman;\"><span style=\"font-size: small;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Ragazza vestita di rose&rsquo; &egrave; il lavoro inedito che <\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><strong>Giusa<\/strong><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">, artista friulano, al secolo Giuseppe Bianchi, esporr&agrave; assieme a undici in-credibili falsi d&rsquo;autore dei pi&ugrave; grandi artisti: da Degas a Modigliani, da Da Vinci a Botticelli.<\/span><\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Le opere di Giusa hanno affascinato e conquistato il pubblico di tutto il mondo; troviamo i suoi lavori in Italia, Francia, Inghilterra, Stati Uniti, Guatemala e Serbia.<\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\"><span style=\"color: #000000;\">&ldquo;<span style=\"font-family: Calibri,Times New Roman;\"><span style=\"font-size: small;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">La mia passione per la pittura&rdquo; &ndash; spiega Giusa &ndash; &ldquo;intesa come realizzazione di un qualcosa che prima non c&rsquo;era, sorto dal nulla su una tela bianca, come un neonato che nasce e cresce, come un miracolo, un&rsquo;epifania che si manifesta davanti ai miei occhi, &egrave; sempre stata pura volont&agrave; di dipingere solo per me stesso. Alla mia passione per la pittura e alla scelta di realizzare falsi d&rsquo;autore, si unisce la volont&agrave; di rendere anche gli altri partecipi di queste creazioni e di dare la possibilit&agrave; di godere quotidianamente della bellezza di veri e propri capolavori&rdquo;<\/span><\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\">\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Ad accompagnare la prima personale di Giusa a Milano, si alterneranno eleganti ed originali appuntamenti nel corso dell&rsquo;evento F.E.M.M.E.<\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\">\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,Times New Roman;\"><span style=\"font-size: small;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">&#8211; M<\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><span style=\"text-decoration: underline;\">ercoled&igrave; 16 Marzo: <\/span><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">VERNISSAGE<\/span><\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,Times New Roman;\"><span style=\"font-size: small;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Chantal Nava inaugurer&agrave; la manifestazione spiegando gli intriganti legami tra arte, immagine femminile e psicoanalisi. L&rsquo;intervento &egrave; a cura di <\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><strong>Jonas Onlus<\/strong><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"> Centro di clinica psicoanalitica per i Nuovi Sintomi.<\/span><\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Seguir&agrave; il brindisi gentilmente offerto dalla Cantina friulana <\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><strong>Ronc dai Luchis<\/strong><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"> che presenter&agrave; il suo spumante metodo classico (3 anni di affinamento).<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Il resto della serata sar&agrave; dedicato all&rsquo;esibizione dell&rsquo;incantevole violinista <\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><strong>Elsa Martignoni. <\/strong><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Una suggestiva scenografia di video-proiezioni <\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"> accompagner&agrave; un inedito unplugged di musiche classiche e contemporanee.<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,Times New Roman;\"><span style=\"font-size: small;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">&#8211; V<\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><span style=\"text-decoration: underline;\">enerd&igrave; 18 Marzo<\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">I sensi degli ospiti di F.E.M.M.E. saranno avvolti e gratificati dalla degustazione dell&rsquo;ottimo olio della casa vinicola Ronc dai Luchis.<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\">\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,Times New Roman;\"><span style=\"font-size: small;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">&#8211; S<\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><span style=\"text-decoration: underline;\">abato 19 Marzo: <\/span><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">FINISSAGE<\/span><\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,Times New Roman;\"><span style=\"font-size: small;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">F.E.M.M.E. &egrave; anche moda e bellezza. Sabato si potr&agrave; assistere all&rsquo;esclusiva sfilata di <\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><strong>StefiErre<\/strong><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"> in collaborazione con <\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><strong>SoStylish<\/strong><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"> Make-up e Hair Styling.<\/span><\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Saranno presenti all&#8217;evento i brand: L&#8217;Al&igrave; accessories, Play-Shirt, Zushii.<\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Per salutare tutti coloro che hanno partecipato all&#8217;evento, il finissage sar&agrave; celebrato con la degustazione del Refosco riserva e del Verduzzo passito della casa vinicola Ronc dai Luchis. <\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\">\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\">\n<p style=\"margin-bottom: 0cm;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Durante la mostra-evento saranno, inoltre, presentate 30 paia di occhiali da sole di grandi marche e dal design retr&ograve; provenienti dalla collezione privata della moglie dell&rsquo;artista Giusa selezionati e messi in vendita per l&rsquo;occasione.<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 2; orphans: 2;\" lang=\"it-IT\">\n<p style=\"margin-bottom: 0cm;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">E, in esclusiva, VirgoImage riserver&agrave; il 50% di sconto a tutti gli ospiti di F.E.M.M.E.<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\">\n<p style=\"margin-bottom: 0cm;\">\n<p style=\"margin-bottom: 0cm;\">\n<p style=\"margin-bottom: 0cm;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><strong>RONC dai Luchis<\/strong><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"> &egrave; la piccola realt&agrave; vitivinicola nel cuore dei Colli Orientali del Friuli che vanta una storia di oltre 250 anni.<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">I prodotti spaziano dal tanto discusso Friulano, al tipico Refosco di Faedis, al nobile Picolit sino ad un pregiato olio extravergine molito a freddo.<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Da 12 anni, recuperando diversi casali contadini, l&rsquo;azienda si &egrave; anche specializzata nel settore dell&rsquo;accoglienza agrituristica, offrendo cos&igrave; la possibilit&agrave; di soggiornare a stretto contatto con la natura.<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\"><span style=\"color: #0000ff;\"><span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.roncdailuchis.com\/\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">www.roncdailuchis.com<\/span><\/span><\/a><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\">\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><strong>Jonas Onlus<\/strong><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"> &#8211; <\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Centro di clinica psicoanalitica per i nuovi sintomi<\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"> &#8211; &egrave; un&#8217;Associazione senza fini di lucro nata nel gennaio del 2003 da un&rsquo;idea di Massimo Recalcati e attiva sul territorio nazionale con sedici sedi.<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Jonas Onlus si occupa della cura di anoressia, bulimia, obesit&agrave;, depressione, ansia, attacchi di panico e dipendenze patologiche proponendo <\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">percorsi di psicoterapia<\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"> individuale o di gruppo <\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">a tariffe &ldquo;sociali&rdquo;<\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"> per rendere la cura accessibile a tutti e sostenibile nel tempo.<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Oltre alla cura, l&rsquo;<\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">operato<\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"> di Jonas Onlus si estende <\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">nel campo sociale<\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"> con attivit&agrave; di <\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">divulgazione<\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">, di <\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">formazione<\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"> e di <\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">prevenzione<\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"> sul territorio e in collaborazione con la rete delle istituzioni.<\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"> <\/span><\/span><span style=\"color: #0000ff;\"><span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.jonasonlus.it\/\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">www.jonasonlus.it<\/span><\/span><\/a><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"> <\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\">\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><strong>SOStylish<\/strong><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">&hellip;&egrave; l&rsquo;agenzia di servizi luxury, vanta di esperienza nel settore del Make-Up\/Hair Style\/Styling per shooting fotografici, produzioni tv e Wedding Consulting .<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\">&ldquo;<span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><em>Siamo consapevoli che al giorno d&rsquo;oggi l&rsquo;immagine sia un valore importante, ed &egrave; per questo che abbiamo deciso di creare una serie di servizi mirati a perfezionare il look della persona.&rdquo;<\/em><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Grazie all&rsquo;esperienza maturata nel tempo e alla continua formazione, SOStylish &egrave; in grado di offrire consulenza d&rsquo;immagine, corsi di auto maquillage, sedute trucco e brides make-up, oltre ai classici servizi per lo spettacolo.<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\">\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><strong>L&#8217;Al&igrave; <\/strong><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">&egrave; una <\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">giovane stilista bresciana, l&#8217;omonimo marchio nasce nel 2004 e da sempre le particolari forme e l&rsquo;uso ironico delle stampe sono gli ingredienti base delle sue collezioni. <\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Borse ed accessori che si contraddistinguono per creativit&agrave; e qualit&agrave;. Un gusto volutamente retr&ograve; racconta ogni volta una storia diversa, ogni pezzo nella sua unicit&agrave; ne compone una parte. <\/span><\/span><span style=\"color: #1a1718;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Dal 2007 la moda L&rsquo;al&igrave; si lega all&rsquo;Arte: nascono intensi e particolari rapporti di collaborazione con affermati artisti italiani del nostro tempo (fra cui: Alda Merini, Ugo Nespolo, Marco Lodola). <\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\"><span style=\"color: #0000ff;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">w<\/span><\/span><\/span><span style=\"color: #0000ff;\"><span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.lali.it\/\" class=\"broken_link\"><span style=\"font-family: Calibri,sans-serif;\">ww.lali.it<\/span><\/a><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"> \/ <\/span><\/span><\/span><span style=\"color: #0000ff;\"><span style=\"text-decoration: underline;\"><a href=\"mailto:info@lali.it\"><span style=\"font-family: Calibri,sans-serif;\">info@lali.it<\/span><\/a><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\">\n<p style=\"margin-bottom: 0cm;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><strong>Zushii<\/strong><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"> trasforma le idee pi&ugrave; stravaganti in concrete realt&agrave; da indossare.<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Rappresenta la libert&agrave; di espressione creando prodotti fuori dagli schemi del diktat della moda stagionale; irriverente e non conventional, per promuovere le sue creazioni Zushii si affida al guerrilla marketing.<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Zushii realizza bijoux e non solo, piccoli e significativi pezzi di design artigianale, opere fatte a mano, confezionate con cura e vendute a prezzi da stock. <\/span><\/span><span style=\"color: #0000ff;\"><span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.zushii.com\/\" class=\"broken_link\"><span style=\"font-family: Calibri,sans-serif;\">http:\/\/www.zushii.com\/<\/span><\/a><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\">\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><strong>Play-Shirt <\/strong><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">&egrave; un brand nato in Italia, che ha per prodotto-simbolo una t-shirt &ldquo;manifesto&rdquo; con le caratteristiche di una lavagna riscrivibile. La particolarit&agrave; della prima Play-Shirt sta nel fatto che &egrave; possibile scrivere sul capo quello che si vuole, e modificare in qualunque momento la scritta. Come? Utilizzando delle letterine stampate su Velcro &ldquo;uncino&rdquo; (vendute assieme al prodotto) da applicare sulla striscia di Velcro &ldquo;asola&rdquo; cucita sulla t-shirt.<\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Play-Shirt &egrave; u<\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">n <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><em>social network<\/em><\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"> cucito su un capo di abbigliamento, &egrave; un evento nato dal passaparola, <\/span><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">un <\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><em>media<\/em><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">, uno strumento pop per esprimere uno status, un cambiamento: nella vita, nella giornata, nella serata, o nel modo di pensare di ogni persona. <\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Semplice, diretto, e s<\/span><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">enza censure.<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\"><span style=\"color: #0000ff;\"><span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.playshirt.net\/\" class=\"broken_link\"><span style=\"font-family: Calibri,sans-serif;\">http:\/\/www.playshirt.net\/<\/span><\/a><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\">\n<p style=\"margin-bottom: 0cm;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><strong>StefiErre<\/strong><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">, nasce nel 2008 grazie alla passione di Stefania Riboni per l&rsquo;abbigliamento, ma non solo.<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Passando attraverso il vintage remake, lavorando per studi stile diversi, partecipando a mercatini e fiere con piccole creazioni artigianali, accessori e capi in maglieria, Stefania, infine, giunge a disegnare Stefierre, collezione dopo collezione. Poco alla volta s&rsquo;inserisce in quella che viene oggi definita come &ldquo;moda critica&rdquo;, diventa una stilista indipendente, le cui produzioni valorizzano la micro e piccola economia del sistema moda attraverso il recupero di capacit&agrave; manuali e creative.<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Le collezioni si compongono di abiti semplici, dal design essenziale, talvolta con volumi e tagli geometrici, altre volte con linee pi&ugrave; romantiche e una particolare attenzione alle rifiniture. <\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">www.stefierre.com<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\">\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><strong>Spazio Concept, <\/strong><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">spazio espositivo ubicato nel cuore della &ldquo;Zona Tortona&rdquo;, &egrave; una location <\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">concepita come centro Polifunzionale, nata con la pretesa di fungere da recipiente ideale per ogni manifestazione Artistica e Culturale, al fine di coniugare differenti forme d&rsquo;aggregazione conviviale che abbiano quale comune denominatore l&rsquo;amore per l&rsquo;Arte, la Musica e la Cultura. <\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">http:\/\/www.spazioconcept.org\/<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\">\n<p style=\"margin-bottom: 0cm;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><strong>Rosaspinto<\/strong><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">, associazione culturale fondata da Indira Fassioni opera nel mondo della comunicazione dal 2002, attraverso ufficio stampa, direzione artistica e organizzazione di eventi, con una particolare attenzione al design, moda, beauty, ristorazione e night life.<\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\">\n<p style=\"margin-bottom: 0cm;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><strong>VirgoImage<\/strong><\/span><\/span><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">, agenzia di consulenza d&rsquo;immagine e personal shopping di Milano fondata da Angela Bianchi nel 2010 offre servizi personalizzati di studio della propria immagine personale, studio del colore e delle fantasie, riorganizzazione del guardaroba, personal shopping e shopping on demand e packing.<\/span><\/span><span style=\"color: #444444;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"> <\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\">\n<p style=\"margin-bottom: 0cm;\" align=\"JUSTIFY\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><strong>Parte del ricavato della vendita delle opere in mostra verr&agrave; devoluto a sostegno dell&rsquo;attivit&agrave; dell&rsquo;Associazione Jonas Onlus.<\/strong><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\">\n<p style=\"margin-bottom: 0cm;\">\n<p style=\"margin-bottom: 0cm; widows: 0; orphans: 0;\" align=\"CENTER\"><span style=\"color: #ff00ff;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"><strong>Ufficio Stampa e Direzione Artistica Rosaspinto<\/strong><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 0; orphans: 0;\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">Indira Fassioni<\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm; widows: 0; orphans: 0;\" align=\"CENTER\"><span style=\"color: #0000ff;\"><span style=\"text-decoration: underline;\"><a href=\"mailto:press@rosaspinto.it\"><span style=\"font-family: Calibri,sans-serif;\">press@rosaspinto.it<\/span><\/a><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\"> <\/span><\/span><\/span><span style=\"color: #0000ff;\"><span style=\"text-decoration: underline;\"><a href=\"mailto:info@rosaspinto.it\"><span style=\"font-family: Calibri,sans-serif;\">info@rosaspinto.it<\/span><\/a><\/span><\/span><\/p>\n<p style=\"margin-bottom: 0cm;\" align=\"CENTER\"><span style=\"color: #000000;\"><span style=\"font-family: Calibri,sans-serif;\"><span style=\"font-size: x-small;\">+39\/3338864490<\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>F.E.M.M.E. fatale. &eacute;l&eacute;gante. m&eacute;lancolique. mauvaise. &eacute;ternelle Mostra &ndash; Evento a cura di Indira Fassioni Un dionisiaco omaggio al mondo femminile tra arte, musica, moda e vino Giusa 11 falsi d&rsquo;autore Spazio Concept, Via Forcella 7, Zona Tortona, Milano Da Mercoled&igrave; 16 Marzo a Sabato 19 Marzo 2011 Dalle 18.30 alle 21.00 Vernissage: Mercoled&igrave; 16 Marzo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7621],"tags":[9149,36014,36015,2110,36013,875],"class_list":["post-38854","post","type-post","status-publish","format-standard","hentry","category-arte_cultura","tag-aperitivo","tag-femme","tag-giusa","tag-rosaspinto","tag-spazio-concept","tag-vernissage"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>F.E.M.M.E. - area-press.eu - comunicati<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.area-press.eu\/comunicati\/f-e-m-m-e\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F.E.M.M.E. - area-press.eu - comunicati\" \/>\n<meta property=\"og:description\" content=\"F.E.M.M.E. fatale. &eacute;l&eacute;gante. m&eacute;lancolique. mauvaise. &eacute;ternelle Mostra &ndash; Evento a cura di Indira Fassioni Un dionisiaco omaggio al mondo femminile tra arte, musica, moda e vino Giusa 11 falsi d&rsquo;autore Spazio Concept, Via Forcella 7, Zona Tortona, Milano Da Mercoled&igrave; 16 Marzo a Sabato 19 Marzo 2011 Dalle 18.30 alle 21.00 Vernissage: Mercoled&igrave; 16 Marzo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicati\/f-e-m-m-e\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu - comunicati\" \/>\n<meta property=\"article:published_time\" content=\"2011-03-08T23:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione area-press.eu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione area-press.eu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/f-e-m-m-e\/\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/f-e-m-m-e\/\",\"name\":\"F.E.M.M.E. - area-press.eu - comunicati\",\"isPartOf\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\"},\"datePublished\":\"2011-03-08T23:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/f-e-m-m-e\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.area-press.eu\/comunicati\/f-e-m-m-e\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/f-e-m-m-e\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.area-press.eu\/comunicati\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F.E.M.M.E.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/\",\"name\":\"area-press.eu - comunicati\",\"description\":\"Press releases e comunicati stampa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\",\"name\":\"Redazione area-press.eu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"caption\":\"Redazione area-press.eu\"},\"url\":\"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F.E.M.M.E. - area-press.eu - comunicati","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.area-press.eu\/comunicati\/f-e-m-m-e\/","og_locale":"it_IT","og_type":"article","og_title":"F.E.M.M.E. - area-press.eu - comunicati","og_description":"F.E.M.M.E. fatale. &eacute;l&eacute;gante. m&eacute;lancolique. mauvaise. &eacute;ternelle Mostra &ndash; Evento a cura di Indira Fassioni Un dionisiaco omaggio al mondo femminile tra arte, musica, moda e vino Giusa 11 falsi d&rsquo;autore Spazio Concept, Via Forcella 7, Zona Tortona, Milano Da Mercoled&igrave; 16 Marzo a Sabato 19 Marzo 2011 Dalle 18.30 alle 21.00 Vernissage: Mercoled&igrave; 16 Marzo [&hellip;]","og_url":"https:\/\/www.area-press.eu\/comunicati\/f-e-m-m-e\/","og_site_name":"area-press.eu - comunicati","article_published_time":"2011-03-08T23:00:00+00:00","author":"Redazione area-press.eu","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione area-press.eu","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicati\/f-e-m-m-e\/","url":"https:\/\/www.area-press.eu\/comunicati\/f-e-m-m-e\/","name":"F.E.M.M.E. - area-press.eu - comunicati","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#website"},"datePublished":"2011-03-08T23:00:00+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicati\/f-e-m-m-e\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicati\/f-e-m-m-e\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicati\/f-e-m-m-e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"F.E.M.M.E."}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicati\/#website","url":"https:\/\/www.area-press.eu\/comunicati\/","name":"area-press.eu - comunicati","description":"Press releases e comunicati stampa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4","name":"Redazione area-press.eu","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","caption":"Redazione area-press.eu"},"url":"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/38854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=38854"}],"version-history":[{"count":0,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/38854\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=38854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=38854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=38854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}