{"id":3613,"date":"2009-11-30T00:00:00","date_gmt":"2009-11-29T23:00:00","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicati\/silfab-spa-completati-nel-sud-italia-i-primi-parchi-solari-di-nuova-generazione\/"},"modified":"2009-11-30T00:00:00","modified_gmt":"2009-11-29T23:00:00","slug":"silfab-spa-completati-nel-sud-italia-i-primi-parchi-solari-di-nuova-generazione","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicati\/silfab-spa-completati-nel-sud-italia-i-primi-parchi-solari-di-nuova-generazione\/","title":{"rendered":"SILFAB SpA: COMPLETATI NEL SUD ITALIA I PRIMI PARCHI SOLARI DI NUOVA GENERAZIONE"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><\/p>\n<p>Padova, 25 novembre 2009 &ndash; Una rete di parchi solari, pronti entro il 2010, per una capacit&agrave; totale di oltre 60 MW. E&rsquo; questa l&rsquo;attivit&agrave; che <strong>Silfab<\/strong> <strong>SpA<\/strong> sta portando avanti in Italia parallelamente allo sviluppo del suo progetto di realizzazione dell&rsquo;intera filiera del fotovoltaico a partire dal polysilicon di grado solare. Proprio in questi giorni Silfab ha completato, con un investimento completamente finanziato dall&rsquo;azienda di oltre 20 milioni di euro, i primi 5 parchi fotovoltaici di nuova generazione, da 1 MW ciascuno, ad Acquaviva delle Fonti (Bari) e Fragagnano (Taranto) mentre altri quattro si concluderanno entro la fine dell&rsquo;anno in provincia di Bari, a Gioia del Colle, Sammichele e Turi per un investimento complessivo vicino ai 40 milioni di euro.<br \/>Per il suo progetto pi&ugrave; ambizioso, la costruzione della filiera fotovoltaica integrata, Silfab si sta orientando verso il Nord America, allontanandosi sempre pi&ugrave; dall&rsquo;ipotesi di insediamento a Borgofranco d&rsquo;Ivrea in Piemonte, dove sta tuttavia studiando nuove iniziative nel settore. <br \/>Nella valutazione dell&rsquo;opportunit&agrave; di insediamento oltre oceano ha un grande peso l&rsquo;abbondanza di energia idroelettrica. L&rsquo;utilizzo esclusivo di tale energia, pulita e rinnovabile, nell&rsquo;intero processo produttivo, dal polysilicon al modulo, far&agrave; di Silfab una realt&agrave; industriale &ldquo;Green-to-Green&rdquo; unica al mondo grazie anche al suo effetto &ldquo;moltiplicativo&rdquo;: ogni singolo kWh (chilowattora) di energia idroelettrica utilizzato nel processo produttivo si trasformer&agrave; in oltre 15 kWh di energia fotovoltaica prodotta dal pannello durante il suo ciclo di vita.<br \/>Nel frattempo l&rsquo;attivit&agrave; in Europa dell&rsquo;azienda padovana si concentra sulla realizzazione di parchi fotovoltaici da 1 a 5 megawatt, caratterizzati da elevatissima efficienza produttiva e da lunga durata (tipicamente oltre 30 anni) che si traducono in un maggiore e piu&#8217; sicuro rendimento per l&#8217;investitore.<br \/>Nell&rsquo;attuale convulsa fase del mercato la valutazione dei costi di un impianto fotovoltaico viene spesso effettuata considerando semplicemente la potenza nominale e quindi il costo a kWp (chilowatt picco). Ci&ograve; che invece ha pi&ugrave; importanza &egrave; l&rsquo;effettiva capacit&agrave; di produzione dell&rsquo;impianto lungo il suo intero ciclo di vita: &egrave; infatti il costo del chilowattora (kWh) ad essere l&rsquo;elemento cardine di una corretta valutazione economica. Non a caso &egrave; l&rsquo;energia effettivamente prodotta che beneficia per 20 anni dell&rsquo;incentivazione in Conto Energia. <br \/>Ed &egrave; proprio sul fronte dell&rsquo;efficienza e della lunga durata che Silfab focalizza la propria attenzione, proponendo impianti con soluzioni tecniche di eccellenza che derivano dal know-how trentennale di Franco Traverso, fondatore di Silfab e pioniere del fotovoltaico in Italia, nonch&eacute; dalla competenza specifica dei suoi partner tecnologici. <\/p>\n<p>I parchi fotovoltaici di Silfab, dotati di inseguitori solari monoassiali, sono in grado di incrementare del 25-30% la produzione di kWh rispetto ai tradizionali sistemi fotovoltaici fissi, mantenendo al contempo una elevatissima affidabilita&#8217; e durata nel tempo.<br \/>Oltre ai suoi due soci, SAS Inc. (azienda leader internazionale nella produzione di wafer) e PanAsia Solar Ltd. (societ&agrave; privata di investimenti con una importante produzione di celle fotovoltaiche ad altissima efficienza), Franco Traverso pu&ograve; contare infatti anche su partner come Solaris d.o.o. (di cui &egrave; azionista di maggioranza), che da 10 anni produce moduli fotovoltaici ad alte performance, ed Espe Srl, EPC contractor e produttore di inseguitori solari monoassiali brevettati. <br \/>Nella realizzazione dei propri parchi Silfab ha ideato un particolare business model che prevede anche un sistema di co-investimento di lungo periodo sia dell&rsquo;azienda stessa che dei propri soci. Si tratta di un nuovo approccio finanziario, ideato soprattutto per dimostrare la solidit&agrave; imprenditoriale e gestionale di questa nuova generazione di parchi messi a punto dall&rsquo;azienda.<br \/>Nel prossimo anno verranno realizzate nuove &ldquo;solar farm&rdquo; prevalentemente nelle regioni del centro-sud Italia, per un totale di oltre 60 MW di potenza installata.<br \/>Contemporaneamente &egrave; stata avviata un&rsquo;intensa attivit&agrave; di sviluppo internazionale nei paesi emergenti nel campo della generazione elettrica da fonti rinnovabili.<br \/>L&rsquo;azienda, che ad oggi ha una capitalizzazione di 84 milioni di euro, avvier&agrave; a breve una attivit&agrave; di aumento del capitale sociale in modo da incrementare la capacit&agrave; di investimento nei due business in cui &egrave; impegnata.<\/p>\n<p><strong>Silfab SpA<\/strong><br \/>Silfab SpA, con sede legale a Padova, &egrave; una societ&agrave; specializzata in componenti e sistemi che abbracciano l&#8217;intera filiera (Supply Chain) del fotovoltaico, dal polysilicon ad elevata purezza, ai moduli solari, alla costruzione di parchi solari chiavi in mano. Fondata dal pioniere del fotovoltaico italiano, Franco Traverso, Silfab conta sull&rsquo;esperienza commerciale e tecnologica di due partner internazionali, Pan Asia Solar Ltd. e Sino-American Silicon Product Inc. (SAS). SAS &egrave; un&rsquo;azienda taiwanese che dal 1981 produce lingotti e wafer di silicio per i mercati asiatici, americani ed europei. Pan Asia Solar Ltd. &egrave; una societ&agrave; privata di investimenti con sedi a New York, Hong Kong e Londra, attiva nel settore delle energie rinnovabili, con un team che vanta una specifica esperienza di oltre 25 anni nel solare fotovoltaico.<br \/>Per informazioni visita il sito di Silfab all&rsquo;indirizzo www.silfab.eu.<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<br \/>Ufficio stampa: Dr. Laura Ceccon Quid Comunicazione <br \/>tel. +39 0444 512733 &ndash; mob. +39 347 3775409<br \/>laura@quidonline.it &#8211; l.ceccon@silfab.eu &#8211; skype name: quidlaura<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mentre per la realizzazione dell\u2019intera filiera del fotovoltaico, dal polysilicon all\u2019impianto finito, l\u2019azienda padovana si sta orientando verso il Nord America con un progetto \u201cGreen-to-Green\u201d, in Italia realizza parchi solari di nuova generaz<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7584],"tags":[7954,7955,958,955],"class_list":["post-3613","post","type-post","status-publish","format-standard","hentry","category-aziendali","tag-fotovoltaico","tag-franco-traverso","tag-parchi-solari","tag-silfab"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SILFAB SpA: COMPLETATI NEL SUD ITALIA I PRIMI PARCHI SOLARI DI NUOVA GENERAZIONE - area-press.eu - comunicati<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.area-press.eu\/comunicati\/silfab-spa-completati-nel-sud-italia-i-primi-parchi-solari-di-nuova-generazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SILFAB SpA: COMPLETATI NEL SUD ITALIA I PRIMI PARCHI SOLARI DI NUOVA GENERAZIONE - area-press.eu - comunicati\" \/>\n<meta property=\"og:description\" content=\"Mentre per la realizzazione dell\u2019intera filiera del fotovoltaico, dal polysilicon all\u2019impianto finito, l\u2019azienda padovana si sta orientando verso il Nord America con un progetto \u201cGreen-to-Green\u201d, in Italia realizza parchi solari di nuova generaz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicati\/silfab-spa-completati-nel-sud-italia-i-primi-parchi-solari-di-nuova-generazione\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu - comunicati\" \/>\n<meta property=\"article:published_time\" content=\"2009-11-29T23:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione area-press.eu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione area-press.eu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/silfab-spa-completati-nel-sud-italia-i-primi-parchi-solari-di-nuova-generazione\/\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/silfab-spa-completati-nel-sud-italia-i-primi-parchi-solari-di-nuova-generazione\/\",\"name\":\"SILFAB SpA: COMPLETATI NEL SUD ITALIA I PRIMI PARCHI SOLARI DI NUOVA GENERAZIONE - area-press.eu - comunicati\",\"isPartOf\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\"},\"datePublished\":\"2009-11-29T23:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/silfab-spa-completati-nel-sud-italia-i-primi-parchi-solari-di-nuova-generazione\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.area-press.eu\/comunicati\/silfab-spa-completati-nel-sud-italia-i-primi-parchi-solari-di-nuova-generazione\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/silfab-spa-completati-nel-sud-italia-i-primi-parchi-solari-di-nuova-generazione\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.area-press.eu\/comunicati\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SILFAB SpA: COMPLETATI NEL SUD ITALIA I PRIMI PARCHI SOLARI DI NUOVA GENERAZIONE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/\",\"name\":\"area-press.eu - comunicati\",\"description\":\"Press releases e comunicati stampa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\",\"name\":\"Redazione area-press.eu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"caption\":\"Redazione area-press.eu\"},\"url\":\"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SILFAB SpA: COMPLETATI NEL SUD ITALIA I PRIMI PARCHI SOLARI DI NUOVA GENERAZIONE - area-press.eu - comunicati","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.area-press.eu\/comunicati\/silfab-spa-completati-nel-sud-italia-i-primi-parchi-solari-di-nuova-generazione\/","og_locale":"it_IT","og_type":"article","og_title":"SILFAB SpA: COMPLETATI NEL SUD ITALIA I PRIMI PARCHI SOLARI DI NUOVA GENERAZIONE - area-press.eu - comunicati","og_description":"Mentre per la realizzazione dell\u2019intera filiera del fotovoltaico, dal polysilicon all\u2019impianto finito, l\u2019azienda padovana si sta orientando verso il Nord America con un progetto \u201cGreen-to-Green\u201d, in Italia realizza parchi solari di nuova generaz","og_url":"https:\/\/www.area-press.eu\/comunicati\/silfab-spa-completati-nel-sud-italia-i-primi-parchi-solari-di-nuova-generazione\/","og_site_name":"area-press.eu - comunicati","article_published_time":"2009-11-29T23:00:00+00:00","author":"Redazione area-press.eu","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione area-press.eu","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicati\/silfab-spa-completati-nel-sud-italia-i-primi-parchi-solari-di-nuova-generazione\/","url":"https:\/\/www.area-press.eu\/comunicati\/silfab-spa-completati-nel-sud-italia-i-primi-parchi-solari-di-nuova-generazione\/","name":"SILFAB SpA: COMPLETATI NEL SUD ITALIA I PRIMI PARCHI SOLARI DI NUOVA GENERAZIONE - area-press.eu - comunicati","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#website"},"datePublished":"2009-11-29T23:00:00+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicati\/silfab-spa-completati-nel-sud-italia-i-primi-parchi-solari-di-nuova-generazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicati\/silfab-spa-completati-nel-sud-italia-i-primi-parchi-solari-di-nuova-generazione\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicati\/silfab-spa-completati-nel-sud-italia-i-primi-parchi-solari-di-nuova-generazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"SILFAB SpA: COMPLETATI NEL SUD ITALIA I PRIMI PARCHI SOLARI DI NUOVA GENERAZIONE"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicati\/#website","url":"https:\/\/www.area-press.eu\/comunicati\/","name":"area-press.eu - comunicati","description":"Press releases e comunicati stampa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4","name":"Redazione area-press.eu","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","caption":"Redazione area-press.eu"},"url":"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/3613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=3613"}],"version-history":[{"count":0,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/3613\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=3613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=3613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=3613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}