{"id":30715,"date":"2010-07-06T00:00:00","date_gmt":"2010-07-05T22:00:00","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicati\/conto-alla-rovescia-per-iscriversi-a-nanochallenge-and-polymerchallenge-2010\/"},"modified":"2010-07-06T00:00:00","modified_gmt":"2010-07-05T22:00:00","slug":"conto-alla-rovescia-per-iscriversi-a-nanochallenge-and-polymerchallenge-2010","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicati\/conto-alla-rovescia-per-iscriversi-a-nanochallenge-and-polymerchallenge-2010\/","title":{"rendered":"Conto alla rovescia per iscriversi a Nanochallenge and Polymerchallenge 2010"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><\/p>\n<p>Entro il 20 settembre 2010 ricercatori e scienziati di tutto il mondo possono iscriversi alla competizione internazionale di business Nanochallenge and Polymerchallenge e inviare la descrizione del proprio progetto imprenditoriale per <strong><a href=\"http:\/\/www.nanochallenge.com\/\">avviare una start up<\/a><\/strong> attraverso il sito per il finanziamento di <strong><a href=\"http:\/\/www.nanochallenge.com\/en-US\/guidelines\/competition-overview\" class=\"broken_link\">idee imprenditoriali<\/a><\/strong>. <\/p>\n<p> I distretti tecnologici Veneto Nanotech ed IMAST sono pronti per valutare le migliori innovazioni tecnologiche nel settore delle nanotecnologie e dei materiali polimerici e a investire nelle idee imprenditoriali pi&ugrave; promettenti, fornendo inoltre il supporto operativo e manageriale alle start-up. <\/p>\n<p> I team che si registreranno e invieranno l&rsquo;executive summary entro il 20 settembre 20101 verranno valutati in due fasi: una giuria scientifica selezioner&agrave; le migliori idee scientifiche, mentre la giuria della fase finale valuter&agrave; le migliori idee d&rsquo;impresa. I vincitori riceveranno un investimento iniziale di 300.000 euro da parte di Veneto Nanotech ed IMAST e saranno successivamente assistiti nel reperimento di nuovi capitali per far crescere la start-up. <\/p>\n<p> Durante l&rsquo;evento finale, che si terr&agrave; all&rsquo;Universit&agrave; di Padova il 25 e 26 novembre 2010, si riuniranno investitori, venture capitalists, direttori di multinazionali e esperti del settore delle nanotecnologie per assistere alle presentazioni dei team finalisti. <\/p>\n<p> Nanochallenge and Poymerchallenge 2010 &egrave; organizzata con il contributo della Fondazione Cassa di Risparmio di Padova e Rovigo e di Veneto Sviluppo e grazie alle aziende partner: Basf, Dainese, Carel, GearWorld, Eurotech, Jeol, Italementi, Sapio, Lux Research, PricewaterhouseCoopers.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>600.000 euro in palio per avviare la propria star-up nelle nanotecnologie  o nei materiali polimerici. I distretti tecnologici Veneto Nanotech ed IMAST investiranno nelle innovazioni tecnologiche pi\u00f9 promettenti presentate entro il 20 settembre 2010.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7585],"tags":[25503,3723],"class_list":["post-30715","post","type-post","status-publish","format-standard","hentry","category-eventi","tag-avviare-start-up","tag-idee-imprenditoriali"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Conto alla rovescia per iscriversi a Nanochallenge and Polymerchallenge 2010 - area-press.eu - comunicati<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.area-press.eu\/comunicati\/conto-alla-rovescia-per-iscriversi-a-nanochallenge-and-polymerchallenge-2010\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conto alla rovescia per iscriversi a Nanochallenge and Polymerchallenge 2010 - area-press.eu - comunicati\" \/>\n<meta property=\"og:description\" content=\"600.000 euro in palio per avviare la propria star-up nelle nanotecnologie o nei materiali polimerici. I distretti tecnologici Veneto Nanotech ed IMAST investiranno nelle innovazioni tecnologiche pi\u00f9 promettenti presentate entro il 20 settembre 2010.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicati\/conto-alla-rovescia-per-iscriversi-a-nanochallenge-and-polymerchallenge-2010\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu - comunicati\" \/>\n<meta property=\"article:published_time\" content=\"2010-07-05T22:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione area-press.eu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione area-press.eu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/conto-alla-rovescia-per-iscriversi-a-nanochallenge-and-polymerchallenge-2010\/\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/conto-alla-rovescia-per-iscriversi-a-nanochallenge-and-polymerchallenge-2010\/\",\"name\":\"Conto alla rovescia per iscriversi a Nanochallenge and Polymerchallenge 2010 - area-press.eu - comunicati\",\"isPartOf\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\"},\"datePublished\":\"2010-07-05T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/conto-alla-rovescia-per-iscriversi-a-nanochallenge-and-polymerchallenge-2010\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.area-press.eu\/comunicati\/conto-alla-rovescia-per-iscriversi-a-nanochallenge-and-polymerchallenge-2010\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/conto-alla-rovescia-per-iscriversi-a-nanochallenge-and-polymerchallenge-2010\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.area-press.eu\/comunicati\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conto alla rovescia per iscriversi a Nanochallenge and Polymerchallenge 2010\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/\",\"name\":\"area-press.eu - comunicati\",\"description\":\"Press releases e comunicati stampa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\",\"name\":\"Redazione area-press.eu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"caption\":\"Redazione area-press.eu\"},\"url\":\"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conto alla rovescia per iscriversi a Nanochallenge and Polymerchallenge 2010 - area-press.eu - comunicati","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.area-press.eu\/comunicati\/conto-alla-rovescia-per-iscriversi-a-nanochallenge-and-polymerchallenge-2010\/","og_locale":"it_IT","og_type":"article","og_title":"Conto alla rovescia per iscriversi a Nanochallenge and Polymerchallenge 2010 - area-press.eu - comunicati","og_description":"600.000 euro in palio per avviare la propria star-up nelle nanotecnologie o nei materiali polimerici. I distretti tecnologici Veneto Nanotech ed IMAST investiranno nelle innovazioni tecnologiche pi\u00f9 promettenti presentate entro il 20 settembre 2010.","og_url":"https:\/\/www.area-press.eu\/comunicati\/conto-alla-rovescia-per-iscriversi-a-nanochallenge-and-polymerchallenge-2010\/","og_site_name":"area-press.eu - comunicati","article_published_time":"2010-07-05T22:00:00+00:00","author":"Redazione area-press.eu","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione area-press.eu","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicati\/conto-alla-rovescia-per-iscriversi-a-nanochallenge-and-polymerchallenge-2010\/","url":"https:\/\/www.area-press.eu\/comunicati\/conto-alla-rovescia-per-iscriversi-a-nanochallenge-and-polymerchallenge-2010\/","name":"Conto alla rovescia per iscriversi a Nanochallenge and Polymerchallenge 2010 - area-press.eu - comunicati","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#website"},"datePublished":"2010-07-05T22:00:00+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicati\/conto-alla-rovescia-per-iscriversi-a-nanochallenge-and-polymerchallenge-2010\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicati\/conto-alla-rovescia-per-iscriversi-a-nanochallenge-and-polymerchallenge-2010\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicati\/conto-alla-rovescia-per-iscriversi-a-nanochallenge-and-polymerchallenge-2010\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Conto alla rovescia per iscriversi a Nanochallenge and Polymerchallenge 2010"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicati\/#website","url":"https:\/\/www.area-press.eu\/comunicati\/","name":"area-press.eu - comunicati","description":"Press releases e comunicati stampa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4","name":"Redazione area-press.eu","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","caption":"Redazione area-press.eu"},"url":"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/30715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=30715"}],"version-history":[{"count":0,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/30715\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=30715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=30715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=30715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}