{"id":28971,"date":"2010-05-03T00:00:00","date_gmt":"2010-05-02T22:00:00","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicati\/il-brand-glamoo-opera-dei-creativi-della-rete\/"},"modified":"2010-05-03T00:00:00","modified_gmt":"2010-05-02T22:00:00","slug":"il-brand-glamoo-opera-dei-creativi-della-rete","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicati\/il-brand-glamoo-opera-dei-creativi-della-rete\/","title":{"rendered":"Il Brand Glamoo opera dei creativi della Rete"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><\/p>\n<p style=\"text-align: justify;\">Roma, 30 Aprile 2010 &ndash; Fanno sistema le Start-Up del web 2.0. Entrambe frutto delle idee di imprenditori italiani con esperienza internazionale, Glamoo e BootB danno vita ad una collaborazione <em>win-win<\/em> che proseguir&agrave; nel futuro con altre sfide progettuali legate al marketing del brand.<\/p>\n<p><em>&laquo;Glamoo &egrave; il nuovo modo di dire Glamour <\/em>&ndash; cos&igrave; <strong>Alessandro Lorica, <\/strong>Direttore Generale di <strong><a href=\"http:\/\/www.glamoo.it\" target=\"_self\" class=\"broken_link\">Glamoo<\/a> Italia <\/strong>&#8211;<em> Il nostro brand identifica la nuova attitudine all&rsquo;acquisto dei consumatori della rete. Oggi non &egrave; pi&ugrave; &ldquo;di moda&rdquo; spendere tanto per l&rsquo;acquisto di un bene, &egrave; invece &laquo;Glamoo&raquo; spendere il giusto per un&rsquo;esperienza selezionata, ovvero acquistare in maniera intelligente&raquo;.<\/em><\/p>\n<p>Come nasce Glamoo? &laquo;<em>Glamoo rappresenta la volont&agrave; di gruppi di consumatori che ovunque si trovino, si uniscono per cercare un prodotto o servizio esclusivo a prezzo unico&raquo; <\/em>&ndash; afferma Lorica. <em>&laquo;Per questo abbiamo scelto il creative engine di BootB, agenzia online con pi&ugrave; di 20.000 creativi sparsi in tutto il mondo e garanzia di massima eterogeneit&agrave; dei contributi: BootB infatti, non oppone alcun filtro alla creazione di idee, incentivando deliberatamente la creativit&agrave;. Come risposta alla nostra richiesta, BootB ha prodotto oltre 150 risultati con contributi provenienti da pi&ugrave; di 10 paesi nel mondo&raquo;.<\/em><\/p>\n<p><a href=\"http:\/\/www.BootB.com\" target=\"_self\" class=\"broken_link\"><strong>BootB<\/strong><\/a>, gi&agrave; definito <em>&ldquo;primo motore di ricerca della creativit&agrave;&rdquo;, <\/em>ha rivoluzionato globalmente il processo di produzione e distribuzione di nuovo idee. Il CEO <strong>Pier Ludovico Bancale, <\/strong>commenta cos&igrave; la sinergia con Glamoo:<em> &laquo;E&rsquo; un progetto affascinante: Glamoo appare l&rsquo;unica piattaforma di collective buying capace di offrire acquisti esclusivi, grazie a un brand emozionale che propone il concetto di glamour in una veste 2.0&raquo;.<\/em> BootB ha generato il nome Glamoo, basando il suo percorso sul termine-concetto francese, riconosciuto per rappresentare un fascino irresistibile. <em>&laquo;Il termine glamour&raquo; <\/em>&ndash; prosegue Bancale &#8211; <em>&laquo;concentra l&#8217;attenzione su elementi comportamentali che caratterizzano uno stile di vita smart e che, in ultima ratio, ci rendono affascinanti. Il glamour diviene Glamoo quando il web offre esperienze uniche grazie all&rsquo;acquisto esclusivo&raquo;. <\/em><br \/>Denominatore comune fra le societ&agrave; &egrave; l&rsquo;empowerment, ovvero la volont&agrave; di abbattere barriere precostituite e come tali superate: nel caso di BootB, passare dal limitato modello di outsourcing, a quello illimitato di crowdsourcing; nel caso di Glamoo, il muovere dal potere d&rsquo;acquisto del singolo a quello enormemente superiore del gruppo.<\/p>\n<p><strong>GLAMOO<\/strong><br \/><strong>Glamoo <\/strong>&egrave; il Club di Acquisti Esclusivi la cui missione &egrave; fornire ai propri Soci i migliori servizi e prodotti nazionali e locali a prezzi unici, offrendo un valore aggiunto di esperienza emozionale. Glamoo nasce nel marzo 2010 su iniziativa di un gruppo di manager internazionali desiderosi di offrire una nuova esperienza di &#8220;Glam&#8221;, ovvero l&#8217;accesso al meglio in termini di Lifestyle e di prodotti: cosa comprare, cosa fare, vedere, dove mangiare, ascoltare musica, divertirsi. <\/p>\n<p><strong>BootB<\/strong><br \/><strong>www.BootB.com <\/strong>e&rsquo; un sito internet creato a San Francisco per permettere ad aziende e agenzie di soddisfare le loro necessit&agrave; creative incontrandosi su una piattaforma al 100% online. Attualmente sono registrati su BootB oltre 20.000 creativi da 145 paesi al mondo, di cui circa il 15% sono agenzie, 65% creativi di professione e il restante 20% amateurs. Oggi BootB e&rsquo; controllata da BootBe Spa, i cui fondatori sono Matteo Marzotto, Francesco Trapani, Luca e Mauro Guzzini.<\/p>\n<p>Ufficio Stampa Glamoo<br \/>Email: press@glamoo.com <br \/>Phone: 06.90254261<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cGlamoo\u201d sintesi di glamour e web 2.0 &#8211; BootB firma il Brand degli Acquisti Esclusivi<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7553],"tags":[22883,22881,22882,22880,8143,22884,12548,2326],"class_list":["post-28971","post","type-post","status-publish","format-standard","hentry","category-comunicati_stampa","tag-acquisti-di-gruppo","tag-bootb","tag-collective-buying","tag-glamoo","tag-glamour","tag-gruppi-di-acquisto","tag-lifestyle","tag-web-2-0"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Il Brand Glamoo opera dei creativi della Rete - area-press.eu - comunicati<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.area-press.eu\/comunicati\/il-brand-glamoo-opera-dei-creativi-della-rete\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Brand Glamoo opera dei creativi della Rete - area-press.eu - comunicati\" \/>\n<meta property=\"og:description\" content=\"\u201cGlamoo\u201d sintesi di glamour e web 2.0 - BootB firma il Brand degli Acquisti Esclusivi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicati\/il-brand-glamoo-opera-dei-creativi-della-rete\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu - comunicati\" \/>\n<meta property=\"article:published_time\" content=\"2010-05-02T22:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione area-press.eu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione area-press.eu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/il-brand-glamoo-opera-dei-creativi-della-rete\/\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/il-brand-glamoo-opera-dei-creativi-della-rete\/\",\"name\":\"Il Brand Glamoo opera dei creativi della Rete - area-press.eu - comunicati\",\"isPartOf\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\"},\"datePublished\":\"2010-05-02T22:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/il-brand-glamoo-opera-dei-creativi-della-rete\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.area-press.eu\/comunicati\/il-brand-glamoo-opera-dei-creativi-della-rete\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/il-brand-glamoo-opera-dei-creativi-della-rete\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.area-press.eu\/comunicati\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Brand Glamoo opera dei creativi della Rete\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/\",\"name\":\"area-press.eu - comunicati\",\"description\":\"Press releases e comunicati stampa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\",\"name\":\"Redazione area-press.eu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"caption\":\"Redazione area-press.eu\"},\"url\":\"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Brand Glamoo opera dei creativi della Rete - area-press.eu - comunicati","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.area-press.eu\/comunicati\/il-brand-glamoo-opera-dei-creativi-della-rete\/","og_locale":"it_IT","og_type":"article","og_title":"Il Brand Glamoo opera dei creativi della Rete - area-press.eu - comunicati","og_description":"\u201cGlamoo\u201d sintesi di glamour e web 2.0 - BootB firma il Brand degli Acquisti Esclusivi","og_url":"https:\/\/www.area-press.eu\/comunicati\/il-brand-glamoo-opera-dei-creativi-della-rete\/","og_site_name":"area-press.eu - comunicati","article_published_time":"2010-05-02T22:00:00+00:00","author":"Redazione area-press.eu","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione area-press.eu","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicati\/il-brand-glamoo-opera-dei-creativi-della-rete\/","url":"https:\/\/www.area-press.eu\/comunicati\/il-brand-glamoo-opera-dei-creativi-della-rete\/","name":"Il Brand Glamoo opera dei creativi della Rete - area-press.eu - comunicati","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#website"},"datePublished":"2010-05-02T22:00:00+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicati\/il-brand-glamoo-opera-dei-creativi-della-rete\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicati\/il-brand-glamoo-opera-dei-creativi-della-rete\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicati\/il-brand-glamoo-opera-dei-creativi-della-rete\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Il Brand Glamoo opera dei creativi della Rete"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicati\/#website","url":"https:\/\/www.area-press.eu\/comunicati\/","name":"area-press.eu - comunicati","description":"Press releases e comunicati stampa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4","name":"Redazione area-press.eu","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","caption":"Redazione area-press.eu"},"url":"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/28971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=28971"}],"version-history":[{"count":0,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/28971\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=28971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=28971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=28971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}