{"id":27012,"date":"2010-02-10T00:00:00","date_gmt":"2010-02-09T23:00:00","guid":{"rendered":"http:\/\/www.area-press.eu\/comunicati\/good-technology-acquisisce-cloudsync\/"},"modified":"2010-02-10T00:00:00","modified_gmt":"2010-02-09T23:00:00","slug":"good-technology-acquisisce-cloudsync","status":"publish","type":"post","link":"https:\/\/www.area-press.eu\/comunicati\/good-technology-acquisisce-cloudsync\/","title":{"rendered":"Good Technology acquisisce CloudSync"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><\/p>\n<p><a href=\"http:\/\/www.good.com\"><strong>Good Technology<\/strong><\/a>&trade; ha annunciato l&rsquo;acquisizione di <a href=\"https:\/\/cloudsync.com\/\"><strong>CloudSync<\/strong><\/a>, azienda specializzata nella gestione di dispositivi mobile con sede a Denver, Colorado, Stati Uniti. L&rsquo;acquisizione promuove ulteriormente la mission di Good di offrire alle aziende la possibilit&agrave; di adottare il device che meglio risponde alle loro esigenze, garantendo al contempo una gestione ottimale per una vasta gamma di dispositivi inclusi laptop, tablet, palmari resistenti agli urti e per le principali piattaforme di smartphone. Il tutto attraverso l&rsquo;offerta di un servizio semplice, sicuro, cloud-based, che non obbliga le aziende a dotarsi e gestire ulteriori componenti hardware o software. <\/p>\n<p>L&rsquo;acquisizione di CloudSync va a completare <strong>Good for Enterprise<\/strong>&trade; che diventa cos&igrave; la soluzione ottimale per le aziende che hanno elevate esigenze di sicurezza per i dispositivi mobile, gestione, collaboration e accesso alle applicazioni. Good for Enterprise &egrave; costituita da tre componenti:<\/p>\n<p>&bull; Good Mobile Control&trade; per la gestione dei dispositivi mobile <br \/>&bull; Good Mobile Messaging&trade; per il messaging e la collaboration aziendali sicuri<br \/>&bull; Good Mobile Access&trade; per l&rsquo;accesso sicuro alle applicazioni <\/p>\n<p>&ldquo;I giorni in cui le aziende sceglievano un unico dispositivo mobile per i dipendenti sono finiti. Le aziende di tutte le dimensioni sono costrette a fronteggiare una richiesta sempre maggiore di supporto a una gamma di dispositivi mobile, piattaforme e applicazioni sempre pi&ugrave; ampia&rdquo; ha affermato Brian A. Bogosian, chairman, CEO and president di Good Technology. &ldquo;L&rsquo;obiettivo di Good Technology &egrave; di offrire alle aziende tutto ci&ograve; di cui hanno bisogno per consentire ai propri dipendenti di connettersi e lavorare in modo sicuro con qualunque device scelgano. Con CloudSync Good semplifica e migliora ulteriormente la gestione dei dispositivi mobile con un&rsquo;opzione aggiuntiva per un&rsquo;offerta SaaS (software as a service) sicura&rdquo;.<\/p>\n<p>CloudSync consente agli utenti di installare, gestire, controllare, localizzare e supportare una vasta gamma di dispositivi mobile ovunque si trovino attraverso la convenienza di un sistema di gestione web-based. La linea di prodotto CludSync include una console di gestione, un&rsquo;applicazione di help desk da remoto, un sofisticato sistema di controllo degli accessi web-based e CloudLocate, l&rsquo;esclusiva applicazione di localizzazione basata su GPS che fornisce agli IT manager una visione in tempo reale di tutti i dispositivi mobile di una flotta compresa la loro posizione. CloudSync supporta tutti i dispositivi mobile con sistema operativo Microsoft Windows, i computer portatili Windows, gli smartphone BlackBerry di RIM e, grazie a Good, nei prossimi mesi estender&agrave; il supporto anche a iPhone&reg; e ai dispositivi con sistema operativo Android&trade;, Symbian e webOS.<\/p>\n<p>&ldquo;Grazie a questa acquisizione Good risponde alla crescente domanda di servizi cloud-based per arricchire ulteriormente la sua offerta di alto livello di soluzioni per la mobilit&agrave; aziendale. Gli azionisti di CloudSync sono molto soddisfatti di essere entrati a far parte di un&rsquo;azienda tra i leader mondiali nel mercato della mobility&rdquo;, ha affermato Nigel Thompson, CEO di CloudSync. &ldquo;Qualsiasi azienda che pianifichi di dotarsi di una strategia mobile dovr&agrave; tenere in considerazione Good per l&rsquo;ampia offerta di soluzioni per la sicurezza, la collaboration e la gestione mobile di dispositivi a prescindere dal sistema operativo&rdquo;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con l\u2019acquisizione Good rafforza ulteriormente la posizione di leader nella gestione dei dispositivi mobile aziendali in tutta sicurezza<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7594],"tags":[19639,19638,19637,19636],"class_list":["post-27012","post","type-post","status-publish","format-standard","hentry","category-telefonia","tag-cloud-computing","tag-cloudsync","tag-good-technology","tag-mobility"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Good Technology acquisisce CloudSync - area-press.eu - comunicati<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.area-press.eu\/comunicati\/good-technology-acquisisce-cloudsync\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Good Technology acquisisce CloudSync - area-press.eu - comunicati\" \/>\n<meta property=\"og:description\" content=\"Con l\u2019acquisizione Good rafforza ulteriormente la posizione di leader nella gestione dei dispositivi mobile aziendali in tutta sicurezza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.area-press.eu\/comunicati\/good-technology-acquisisce-cloudsync\/\" \/>\n<meta property=\"og:site_name\" content=\"area-press.eu - comunicati\" \/>\n<meta property=\"article:published_time\" content=\"2010-02-09T23:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione area-press.eu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione area-press.eu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/good-technology-acquisisce-cloudsync\/\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/good-technology-acquisisce-cloudsync\/\",\"name\":\"Good Technology acquisisce CloudSync - area-press.eu - comunicati\",\"isPartOf\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\"},\"datePublished\":\"2010-02-09T23:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/good-technology-acquisisce-cloudsync\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.area-press.eu\/comunicati\/good-technology-acquisisce-cloudsync\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/good-technology-acquisisce-cloudsync\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.area-press.eu\/comunicati\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Good Technology acquisisce CloudSync\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#website\",\"url\":\"https:\/\/www.area-press.eu\/comunicati\/\",\"name\":\"area-press.eu - comunicati\",\"description\":\"Press releases e comunicati stampa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4\",\"name\":\"Redazione area-press.eu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g\",\"caption\":\"Redazione area-press.eu\"},\"url\":\"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Good Technology acquisisce CloudSync - area-press.eu - comunicati","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.area-press.eu\/comunicati\/good-technology-acquisisce-cloudsync\/","og_locale":"it_IT","og_type":"article","og_title":"Good Technology acquisisce CloudSync - area-press.eu - comunicati","og_description":"Con l\u2019acquisizione Good rafforza ulteriormente la posizione di leader nella gestione dei dispositivi mobile aziendali in tutta sicurezza","og_url":"https:\/\/www.area-press.eu\/comunicati\/good-technology-acquisisce-cloudsync\/","og_site_name":"area-press.eu - comunicati","article_published_time":"2010-02-09T23:00:00+00:00","author":"Redazione area-press.eu","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione area-press.eu","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.area-press.eu\/comunicati\/good-technology-acquisisce-cloudsync\/","url":"https:\/\/www.area-press.eu\/comunicati\/good-technology-acquisisce-cloudsync\/","name":"Good Technology acquisisce CloudSync - area-press.eu - comunicati","isPartOf":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#website"},"datePublished":"2010-02-09T23:00:00+00:00","author":{"@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4"},"breadcrumb":{"@id":"https:\/\/www.area-press.eu\/comunicati\/good-technology-acquisisce-cloudsync\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.area-press.eu\/comunicati\/good-technology-acquisisce-cloudsync\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.area-press.eu\/comunicati\/good-technology-acquisisce-cloudsync\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.area-press.eu\/comunicati\/"},{"@type":"ListItem","position":2,"name":"Good Technology acquisisce CloudSync"}]},{"@type":"WebSite","@id":"https:\/\/www.area-press.eu\/comunicati\/#website","url":"https:\/\/www.area-press.eu\/comunicati\/","name":"area-press.eu - comunicati","description":"Press releases e comunicati stampa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.area-press.eu\/comunicati\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/c7a82e1cf7b2d105ee3708fcc74461f4","name":"Redazione area-press.eu","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.area-press.eu\/comunicati\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/261e5fa13cfbce1e53c026c833f5e36744f89dcb35e4578439e7ced7c9b89537?s=96&d=mm&r=g","caption":"Redazione area-press.eu"},"url":"https:\/\/www.area-press.eu\/comunicati\/author\/redazione-area-press-eu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/27012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/comments?post=27012"}],"version-history":[{"count":0,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/posts\/27012\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/media?parent=27012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/categories?post=27012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.area-press.eu\/comunicati\/wp-json\/wp\/v2\/tags?post=27012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}